{"text_format":"1","workbook":"xlsx","n_sheets":43,"sheets":["START","Instructions","Template names","Lookup and lists","Org structure","Contacts","B1-Sum","B2-FinPerf SC","B2B","B3-FinPerf V","B3B","B4-FinPerf RE","B5-Capex","B5B","B6-FinPos","B7-CFlow","B8-ResRecon","B9-Asset","B10-SerDel","SB1","SB2","SB3","SB4","SB5","SB6","SB7","SB8","SB9","SB10","SB11","SB12","SB13","SB14","SB15","SB16","SB17","SB18a","SB18b","SB18c","SB18d","SB18e","SB19","SB20"],"not_rendered":{"charts":0,"images":9,"macros":1,"external_links":7,"defined_names":1922,"comments":1,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"START","index":0,"n_rows":1,"n_cols":1,"rows_kept":1,"cut":false,"hidden":false,"merged":[]}
[{"$f":"muni","v":"NW375 Moses Kotane"}]

{"sheet":"Instructions","index":1,"n_rows":38,"n_cols":24,"rows_kept":38,"cut":false,"hidden":false,"merged":[]}
[]
[null,null,null,2020]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yes"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"No"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Type of Entities Range:","Parent Municipality"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Consolidated Information"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Date of Adjustment","2020-12-06"]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"MTREF Range:",2008]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2009]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2010]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2011]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2012]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2013]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2014]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2015]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2016]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2017]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2018]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2019]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2020]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,2021]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"MTREF Linked:",2022]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"MTREF:"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,12]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fin Year:",{"$f":"INDEX(X19:X33,X35,1)","v":2019}]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"MTREF&\"/\"&RIGHT(MTREF,2)+1","v":"2019/20"}]

{"sheet":"Template names","index":2,"n_rows":101,"n_cols":6,"rows_kept":101,"cut":false,"hidden":true,"merged":[[0,0,0,3],[61,0,61,3],[65,0,65,1]]}
["Common sheet headings"]
["Head1",{"$f":"HLOOKUP(MTREF,Headings,2)","v":"2018/19"},"Prior year -1"]
["Head1A",{"$f":"HLOOKUP(MTREF,Headings,3)","v":"2017/18"},"Prior year -2"]
["Head1B",{"$f":"HLOOKUP(MTREF,Headings,4)","v":"2016/17"},"Prior year -3"]
["Head2",{"$f":"HLOOKUP(MTREF,Headings,7)","v":"Budget Year 2019/20"},"Year of approved budget"]
["Head2A",{"$f":"HLOOKUP(MTREF,Headings,6)","v":"2019/20"},"Approved budget year"]
["Head3",{"$f":"HLOOKUP(MTREF,Headings,5)","v":"2019/20 Medium Term Revenue & Expenditure Framework"},"MTREF header name"]
["Head3A","Medium Term Revenue and Expenditure Framework"]
["Head4","Current year"]
["Head5","Audited Outcome"]
["Head5A","Outcome"]
["Head5B","Pre-audit outcome"]
["Head6","Original Budget"]
["Head7","Adjusted Budget"]
["Head8","Full Year Forecast"]
["Head9",{"$f":"HLOOKUP(MTREF,Headings,7)","v":"Budget Year 2019/20"},"1st year of MTREF","Year1"]
["Head10",{"$f":"HLOOKUP(MTREF,Headings,8)","v":"Budget Year +1 2020/21"},"2nd year of MTREF","Year2"]
["Head11",{"$f":"HLOOKUP(MTREF,Headings,9)","v":"Budget Year +2 2021/22"},"3rd year of MTREF","Year3"]
["Head24","Description",null,"Desc"]
["Head26","Vote Description",null,"VDesc"]
["Head27","Ref"]
["Head27a","References"]
["Head28","Surplus/ (Deficit) for the year",null,"Result"]
["Head29","Annual target 2007/08"]
["Head30","Revised target 2007/08"]
["Head31","Quarter ended 30 September"]
["Head32","Quarter ended 31 December"]
["Head33","Quarter ended 31 March"]
["Head34","Quarter ended 30 June"]
["Head35","Variance explanation"]
["Head36","YTD  Actual 31 Dec"]
["Head37","YTD  Budget 31 Dec"]
["Head38","Monthly actual"]
["Head39","YearTD actual"]
["Head40","YearTD budget"]
["Head41","YTD variance"]
["Head42","Surplus/ (Deficit) for the yr/period"]
["Head43",{"$f":"Head3&\" Summary\"","v":"2019/20 Medium Term Revenue & Expenditure Framework Summary"}]
["Head44","2001 Census"]
["Head45","2011 Census"]
["Head46"," - Adjustments Budget - January 2007"]
["Head47","Previous target year to complete"]
["Head48","Present value"]
["Head49"]
["Head50","Other Adjusts."]
["Head51","Accum. Funds"]
["Head52","Multi-year capital"]
["Head53","Unfore. Unavoid."]
["Head54","Prior Adjusted"]
["Head55","Nat. or Prov. Govt"]
["Head56","Total Adjusts."]
["Head57","Month DD, YYYY - "]
["Head58","Parent muni."]
["Head59","Downward adjusts"]
["SFPerf1","Budgeted Financial Performance"]
["SFPerf2","Forecast Financial Performance"]
["SFPos1","Budgeted Financial Position"]
["SFPos2","Forecast Financial Position"]
["Cash1","Budget Cash Flow"]
["Cash2","Forecast Cash Flow"]
["RandM","Expenditure includes repairs & maintenance of R'000"]
["Standard nomenclature"]
["Muni",{"$f":"'Lookup and lists'!B28","v":"NW375 Moses Kotane"}]
["Municipal Entities",2,"Type of report:",1]
[{"$f":"IF((MuniEntities=1)*(MuniType=2),\"YES\",\"NO\")","v":"NO"},"Does this municipality have entities (consolidated budget and entity budgets required)? YES/NO"]
["Mid Year Review/Adjustment Budget schedules & tables",null,null,null,"Consolidated header","Parent municipality header"]
["ADJSum",{"$f":"D67&IF(Consolques=\"YES\",E67,F67)","v":"Table B1 Adjustments Budget Summary"},null,"Table B1 ",{"$f":"\"Consolidated \"&F67","v":"Consolidated Adjustments Budget Summary"},{"$f":"\"Adjustments Budget Summary\"","v":"Adjustments Budget Summary"}]
["ADJ2","Table B3 Adjustments Budget Financial Performance (revenue and expenditure by municipal vote)",null,"Table B3 ",{"$f":"\"Consolidated \"&F68","v":"Consolidated Adjustments Budget Financial Performance (revenue and expenditure by municipal vote)"},{"$f":"\"Adjustments Budget Financial Performance (revenue and expenditure by municipal vote)\"","v":"Adjustments Budget Financial Performance (revenue and expenditure by municipal vote)"}]
["ADJ3","Table B2 Adjustments Budget Financial Performance (functional classification)",null,"Table B2 ","Consolidated Adjustments Budget Financial Performance (functional classification)",{"$f":"\"Adjustments Budget Financial Performance (functional classification)\"","v":"Adjustments Budget Financial Performance (functional classification)"}]
["ADJ4","Table B4 Adjustments Budget Financial Performance (revenue and expenditure)",null,"Table B4 ","Consolidated Adjustments Budget Financial Performance (revenue and expenditure)",{"$f":"\"Adjustments Budget Financial Performance (revenue and expenditure)\"","v":"Adjustments Budget Financial Performance (revenue and expenditure)"}]
["ADJ5","Table B5 Adjustments Capital Expenditure Budget by vote and funding",null,"Table B5 ","Consolidated Adjustments Capital Expenditure Budget by vote and funding",{"$f":"\"Adjustments Capital Expenditure Budget by vote and funding\"","v":"Adjustments Capital Expenditure Budget by vote and funding"}]
["ADJ6","Table B6 Adjustments Budget Financial Position",null,"Table B6 ","Consolidated Adjustments Budget Financial Position",{"$f":"\"Adjustments Budget Financial Position\"","v":"Adjustments Budget Financial Position"}]
["ADJ7","Table B7 Adjustments Budget Cash Flows",null,"Table B7 ","Consolidated Adjustments Budget Cash Flows",{"$f":"\"Adjustments Budget Cash Flows\"","v":"Adjustments Budget Cash Flows"}]
["ADJ8","Table B8 Cash backed reserves/accumulated surplus reconciliation",null,"Table B8 ","Consolidated Cash backed reserves/accumulated surplus reconciliation",{"$f":"\"Cash backed reserves/accumulated surplus reconciliation\"","v":"Cash backed reserves/accumulated surplus reconciliation"}]
["ADJ9","Table B9 Asset Management",null,"Table B9 ","Consolidated Asset Management",{"$f":"\"Asset Management\"","v":"Asset Management"}]
["ADJ10","Table B10 Basic service delivery measurement",null,"Table B10 ","Consolidated Basic service delivery measurement",{"$f":"\"Basic service delivery measurement\"","v":"Basic service delivery measurement"}]
["ADJB1","Supporting Table SB1 Supporting detail to 'Budgeted Financial Performance'",null,{"$f":"D101&\"Table SB1 \"","v":"Supporting Table SB1 "},"Consolidated Supporting detail to 'Budgeted Financial Performance'",{"$f":"\"Supporting detail to 'Budgeted Financial Performance'\"","v":"Supporting detail to 'Budgeted Financial Performance'"}]
["ADJB2","Supporting Table SB2 Supporting detail to 'Financial Position Budget'",null,{"$f":"D101&\"Table SB2 \"","v":"Supporting Table SB2 "},"Consolidated Supporting detail to 'Financial Position Budget'",{"$f":"\"Supporting detail to 'Financial Position Budget'\"","v":"Supporting detail to 'Financial Position Budget'"}]
["ADJB3","Supporting Table SB3 Adjustments to the SDBIP - performance objectives",null,{"$f":"D101&\"Table SB3 \"","v":"Supporting Table SB3 "},"Consolidated Adjustments to the SDBIP - performance objectives",{"$f":"\"Adjustments to the SDBIP - performance objectives\"","v":"Adjustments to the SDBIP - performance objectives"}]
["ADJB4","Supporting Table SB4 Adjustments to budgeted performance indicators and benchmarks",null,{"$f":"D101&\"Table SB4 \"","v":"Supporting Table SB4 "},"Consolidated Adjustments to budgeted performance indicators and benchmarks",{"$f":"\"Adjustments to budgeted performance indicators and benchmarks\"","v":"Adjustments to budgeted performance indicators and benchmarks"}]
["ADJB5","Supporting Table SB5 Adjustments Budget - social, economic and demographic statistics and assumptions",null,{"$f":"D101&\"Table SB5 \"","v":"Supporting Table SB5 "},"Consolidated Adjustments Budget - social, economic and demographic statistics and assumptions",{"$f":"\"Adjustments Budget - social, economic and demographic statistics and assumptions\"","v":"Adjustments Budget - social, economic and demographic statistics and assumptions"}]
["ADJB6","Supporting Table SB6 Adjustments Budget - funding measurement",null,{"$f":"D101&\"Table SB6 \"","v":"Supporting Table SB6 "},"Consolidated Adjustments Budget - funding measurement",{"$f":"\"Adjustments Budget - funding measurement\"","v":"Adjustments Budget - funding measurement"}]
["ADJB7","Supporting Table SB7 Adjustments Budget - transfers and grant receipts",null,{"$f":"D101&\"Table SB7 \"","v":"Supporting Table SB7 "},"Consolidated Adjustments Budget - transfers and grant receipts",{"$f":"\"Adjustments Budget - transfers and grant receipts\"","v":"Adjustments Budget - transfers and grant receipts"}]
["ADJB8","Supporting Table SB8 Adjustments Budget - expenditure on transfers and grant programme",null,{"$f":"D101&\"Table SB8 \"","v":"Supporting Table SB8 "},"Consolidated Adjustments Budget - expenditure on transfers and grant programme",{"$f":"\"Adjustments Budget - expenditure on transfers and grant programme\"","v":"Adjustments Budget - expenditure on transfers and grant programme"}]
["ADJB9","Supporting Table SB9 Adjustments Budget - reconciliation of transfers, grant receipts, and unspent funds",null,{"$f":"D101&\"Table SB9 \"","v":"Supporting Table SB9 "},"Consolidated Adjustments Budget - reconciliation of transfers, grant receipts, and unspent funds",{"$f":"\"Adjustments Budget - reconciliation of transfers, grant receipts, and unspent funds\"","v":"Adjustments Budget - reconciliation of transfers, grant receipts, and unspent funds"}]
["ADJB10","Supporting Table SB10 Adjustments Budget - transfers and grants made by the municipality",null,{"$f":"D101&\"Table SB10 \"","v":"Supporting Table SB10 "},"Consolidated Adjustments Budget - transfers and grants made by the municipality",{"$f":"\"Adjustments Budget - transfers and grants made by the municipality\"","v":"Adjustments Budget - transfers and grants made by the municipality"}]
["ADJB11","Supporting Table SB11 Adjustments Budget - councillor and staff benefits",null,{"$f":"D101&\"Table SB11 \"","v":"Supporting Table SB11 "},"Consolidated Adjustments Budget - councillor and staff benefits",{"$f":"\"Adjustments Budget - councillor and staff benefits\"","v":"Adjustments Budget - councillor and staff benefits"}]
["ADJB12","Supporting Table SB12 Adjustments Budget - monthly revenue and expenditure (municipal vote)",null,{"$f":"D101&\"Table SB12 \"","v":"Supporting Table SB12 "},"Consolidated Adjustments Budget - monthly revenue and expenditure (municipal vote)",{"$f":"\"Adjustments Budget - monthly revenue and expenditure (municipal vote)\"","v":"Adjustments Budget - monthly revenue and expenditure (municipal vote)"}]
["ADJB13","Supporting Table SB13 Adjustments Budget - monthly revenue and expenditure (functional classification)",null,{"$f":"D101&\"Table SB13 \"","v":"Supporting Table SB13 "},"Consolidated Adjustments Budget - monthly revenue and expenditure (functional classification)",{"$f":"\"Adjustments Budget - monthly revenue and expenditure (functional classification)\"","v":"Adjustments Budget - monthly revenue and expenditure (functional classification)"}]
["ADJB14","Supporting Table SB14 Adjustments Budget - monthly revenue and expenditure",null,{"$f":"D101&\"Table SB14 \"","v":"Supporting Table SB14 "},"Consolidated Adjustments Budget - monthly revenue and expenditure",{"$f":"\"Adjustments Budget - monthly revenue and expenditure\"","v":"Adjustments Budget - monthly revenue and expenditure"}]
["ADJB15","Supporting Table SB15 Adjustments Budget - monthly cash flow",null,{"$f":"D101&\"Table SB15 \"","v":"Supporting Table SB15 "},"Consolidated Adjustments Budget - monthly cash flow",{"$f":"\"Adjustments Budget - monthly cash flow\"","v":"Adjustments Budget - monthly cash flow"}]
["ADJB16","Supporting Table SB16 Adjustments Budget - monthly capital expenditure (municipal vote)",null,{"$f":"D101&\"Table SB16 \"","v":"Supporting Table SB16 "},"Consolidated Adjustments Budget - monthly capital expenditure (municipal vote)",{"$f":"\"Adjustments Budget - monthly capital expenditure (municipal vote)\"","v":"Adjustments Budget - monthly capital expenditure (municipal vote)"}]
["ADJB17","Supporting Table SB17 Adjustments Budget - monthly capital expenditure (functional classification)",null,{"$f":"D101&\"Table SB17 \"","v":"Supporting Table SB17 "},"Consolidated Adjustments Budget - monthly capital expenditure (functional classification)",{"$f":"\"Adjustments Budget - monthly capital expenditure (functional classification)\"","v":"Adjustments Budget - monthly capital expenditure (functional classification)"}]
["ADJB18a","Supporting Table SB18a Adjustments Budget - capital expenditure on new assets by asset class",null,{"$f":"D101&\"Table SB18a \"","v":"Supporting Table SB18a "},"Consolidated Adjustments Budget - capital expenditure on new assets by asset class",{"$f":"\"Adjustments Budget - capital expenditure on new assets by asset class\"","v":"Adjustments Budget - capital expenditure on new assets by asset class"}]
["ADJB18b","Supporting Table SB18b Adjustments Budget - capital expenditure on renewal of existing assets by asset class",null,{"$f":"D101&\"Table SB18b \"","v":"Supporting Table SB18b "},{"$f":"\"Consolidated \"&F95","v":"Consolidated Adjustments Budget - capital expenditure on renewal of existing assets by asset class"},{"$f":"\"Adjustments Budget - capital expenditure on renewal of existing assets by asset class\"","v":"Adjustments Budget - capital expenditure on renewal of existing assets by asset class"}]
["ADJB18c","Supporting Table SB18c Adjustments Budget - expenditure on repairs and maintenance by asset class",null,{"$f":"D101&\"Table SB18c \"","v":"Supporting Table SB18c "},{"$f":"\"Consolidated \"&F96","v":"Consolidated Adjustments Budget - expenditure on repairs and maintenance by asset class"},{"$f":"\"Adjustments Budget - expenditure on repairs and maintenance by asset class\"","v":"Adjustments Budget - expenditure on repairs and maintenance by asset class"}]
["ADJB18d","Supporting Table SB18d Adjustments Budget - depreciation by asset class",null,{"$f":"D101&\"Table SB18d \"","v":"Supporting Table SB18d "},{"$f":"\"Consolidated \"&F97","v":"Consolidated Adjustments Budget - depreciation by asset class"},{"$f":"\"Adjustments Budget - depreciation by asset class\"","v":"Adjustments Budget - depreciation by asset class"}]
["ADJB18e","Supporting Table SB18d Adjustments Budget - capital expenditure on upgrading of existing assets by asset class",null,{"$f":"D101&\"Table SB18d \"","v":"Supporting Table SB18d "},{"$f":"\"Consolidated \"&F98","v":"Consolidated Adjustments Budget - capital expenditure on upgrading of existing assets by asset class"},{"$f":"\"Adjustments Budget - capital expenditure on upgrading of existing assets by asset class\"","v":"Adjustments Budget - capital expenditure on upgrading of existing assets by asset class"}]
["ADJB19","Supporting Table SB19 List of capital programmes and projects affected by Adjustments Budget",null,{"$f":"D101&\"Table SB19 \"","v":"Supporting Table SB19 "},"Consolidated List of capital programmes and projects affected by Adjustments Budget",{"$f":"\"List of capital programmes and projects affected by Adjustments Budget\"","v":"List of capital programmes and projects affected by Adjustments Budget"}]
["ADJB20","Supporting Table SB20 Not required",null,{"$f":"D101&\"Table SB20 \"","v":"Supporting Table SB20 "},{"$f":"\"Adjusted Budget Municipal Entity Performance Summary\"","v":"Adjusted Budget Municipal Entity Performance Summary"},"Not required"]
[null,null,null,"Supporting "]

{"sheet":"Lookup and lists","index":3,"n_rows":308,"n_cols":22,"rows_kept":308,"cut":false,"hidden":true,"merged":[]}
["Description",2007,2008,2009,2010,2011,2012,2013,2014,2015,2016,2017,2018,2019,2020,null,"Grants:","National - opex","Provincial - opex","National - capex","Provincial - capex","YESNO"]
[{"$f":"'Template names'!C2","v":"Prior year -1"},"2006/07","2007/08","2008/09",{"$f":"E1-1&\"/\"&RIGHT(E1,2)-0","v":"2009/10"},"2010/11","2011/12","2012/13","2013/14","2014/15","2015/16","2016/17","2017/18","2018/19","2019/20",null,null,"Local Government Equitable Share","Health subsidy"," Municipal Infrastructure Grant (MIG)","Agriculture","Yes"]
[{"$f":"'Template names'!C3","v":"Prior year -2"},"2005/06","2006/07","2007/08",{"$f":"E1-2&\"/\"&RIGHT(E1,2)-1","v":"2008/9"},"2009/10","2010/11","2011/12","2012/13","2013/14","2014/15","2015/16","2016/17","2017/18","2018/19",null,null,"RSC Levy Replacement ","Ambulance subsidy"," Public Transport and Systems","Education","No"]
[{"$f":"'Template names'!C4","v":"Prior year -3"},"2004/05","2005/06","2006/07",{"$f":"E1-3&\"/\"&RIGHT(E1,2)-2","v":"2007/8"},"2008/9","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15","2015/16","2016/17","2017/18",null,null,"Finance Management ","Housing","Rural Transport Services and Infrastructure","Health"]
[{"$f":"'Template names'!C7","v":"MTREF header name"},"2007/08 Medium Term Revenue & Expenditure Framework","2008/09 Medium Term Revenue & Expenditure Framework","2009/10 Medium Term Revenue & Expenditure Framework",{"$f":"E1&\"/\"&RIGHT(E1,2)+1&\" Medium Term Revenue & Expenditure Framework\"","v":"2010/11 Medium Term Revenue & Expenditure Framework"},"2011/12 Medium Term Revenue & Expenditure Framework","2012/13 Medium Term Revenue & Expenditure Framework","2013/14 Medium Term Revenue & Expenditure Framework","2014/15 Medium Term Revenue & Expenditure Framework","2015/16 Medium Term Revenue & Expenditure Framework","2016/17 Medium Term Revenue & Expenditure Framework","2017/18 Medium Term Revenue & Expenditure Framework","2018/19 Medium Term Revenue & Expenditure Framework","2019/20 Medium Term Revenue & Expenditure Framework","2020/21 Medium Term Revenue & Expenditure Framework",null,null,"Municipal Systems Improvement","Sport and Recreation","Regional Bulk Infrastructure","Housing and Local Government "]
[{"$f":"'Template names'!C6","v":"Approved budget year"},"2007/08","2008/09","2009/10",{"$f":"E1&\"/\"&RIGHT(E1,2)+1","v":"2010/11"},"2011/12","2012/13","2013/14","2014/15","2015/16","2016/17","2017/18","2018/19","2019/20","2020/21",null,null,"Water Services Operating Subsidy ",null,"Rural Households Infrastructure ","Other Departments"]
[{"$f":"'Template names'!C16","v":"1st year of MTREF"},"Budget Year 2007/08","Budget Year 2008/09","Budget Year 2009/10",{"$f":"\"Budget Year \"&E1&\"/\"&RIGHT(E1,2)+1","v":"Budget Year 2010/11"},"Budget Year 2011/12","Budget Year 2012/13","Budget Year 2013/14","Budget Year 2014/15","Budget Year 2015/16","Budget Year 2016/17","Budget Year 2017/18","Budget Year 2018/19","Budget Year 2019/20","Budget Year 2020/21",null,null,"Energy Efficiency  and Demand Management",null,"Neighbourhood Development Partnership","Public Works, Roads, Transport "]
[{"$f":"'Template names'!C17","v":"2nd year of MTREF"},"Budget Year +1 2008/09","Budget Year +1 2009/10","Budget Year +1 2010/11",{"$f":"\"Budget Year +1 \"&E1+1&\"/\"&RIGHT(E1,2)+2","v":"Budget Year +1 2011/12"},"Budget Year +1 2012/13","Budget Year +1 2013/14","Budget Year +1 2014/15","Budget Year +1 2015/16","Budget Year +1 2016/17","Budget Year +1 2017/18","Budget Year +1 2018/19","Budget Year +1 2019/20","Budget Year +1 2020/21","Budget Year +1 2021/22",null,null,"Integrated National Electrification Programme",null,"2010 FIFA World Cup Stadiums Development","Sport and Recreation"]
[{"$f":"'Template names'!C18","v":"3rd year of MTREF"},"Budget Year +2 2009/10","Budget Year +2 2010/11","Budget Year +2 2011/12",{"$f":"\"Budget Year +2 \"&E1+2&\"/\"&RIGHT(E1,2)+3","v":"Budget Year +2 2012/13"},"Budget Year +2 2013/14","Budget Year +2 2014/15","Budget Year +2 2015/16","Budget Year +2 2016/17","Budget Year +2 2017/18","Budget Year +2 2018/19","Budget Year +2 2019/20","Budget Year +2 2020/21","Budget Year +2 2021/22","Budget Year +2 2022/23",null,null,"Municipal Drought Relief "]
["Adjustments Budget","Annual target 2007/08","Annual target 2008/09","Annual target 2009/10",{"$f":"\"Annual target \" & E1&\"/\"&RIGHT(E1,2)+1","v":"Annual target 2010/11"},"Annual target 2011/12","Annual target 2012/13","Annual target 2013/14","Annual target 2014/15","Annual target 2015/16","Annual target 2016/17","Annual target 2017/18","Annual target 2018/19","Annual target 2019/20","Annual target 2020/21",null,null,"2010 FIFA World Cup Operating"]
["NOTE: This sheet should not be directly amended - select headings from sheet 'S'",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Electricity Demand Side Management"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"EPWP Incentive"]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Asset Class","Asset sub-class Old","Asset sub-class","IUDF","MTSF"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Roads Infrastructure","Roads, Pavements & Bridges","Roads","Spatial integration","Quality basic education"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Storm water Infrastructure","Storm water","Road Structures","Inclusion and access","A long and healthy life for all South Africans"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Electrical Infrastructure","Generation","Road Furniture","Growth","All people in South Africa are and feel safe"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Water Supply Infrastructure","Transmission & Reticulation","Capital Spares","Governance","Decent employment through inclusive growth"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sanitation Infrastructure","Street Lighting","Drainage Collection",null,"A skilled and capable workforce to support an inclusive growth path"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solid Waste Infrastructure","Dams & Reservoirs","Storm water Conveyance",null,"An efficient, competitive and responsive economic infrastructure network"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rail Infrastructure","Water purification","Attenuation",null,"Vibrant, equitable, sustainable rural communities contributing towards food security for all"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Coastal Infrastructure","Reticulation","Power Plants",null,"Sustainable human settlements and improved quality of household life"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Information and Communication Infrastructure","Sewerage purification","HV Substations",null,"Responsive, accountable, effective and efficient local government"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Community Facilities","Waste Management","HV Switching Station",null,"Protect and enhance our environmental assets and natural resources"]
["Name link",211,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sport and Recreation Facilities","Transportation","HV Transmission Conductors",null,"Create a better South Africa and contribute to a better Africa and a better world"]
["Name of Muni",{"$f":"INDEX(B29:B312,B27,1)","v":"NW375 Moses Kotane"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Heritage assets","Gas","MV Substations",null,"An efficient, effective and development-oriented public service"]
[null,"Choose name from list","Set name on 'Instructions' sheet",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Revenue Generating","Parks & gardens","MV Switching Stations",null,"A comprehensive, responsive and sustainable social protection system"]
[null,"BUF Buffalo City","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Non-revenue Generating","Sportsfields & stadia","MV Networks",null,"A diverse, socially cohesive society with a common national identity"]
[null,"NMA Nelson Mandela Bay","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Operational Buildings","Swimming pools","LV Networks"]
[null,"EC101 Dr Beyers Naude","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Housing","Community halls","Capital Spares"]
[null,"EC102 Blue Crane Route","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Biological or Cultivated Assets","Libraries","Dams and Weirs"]
[null,"EC104 Makana","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Servitudes","Recreational facilities","Boreholes"]
[null,"EC105 Ndlambe","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Licences and Rights","Fire, safety & emergency","Reservoirs"]
[null,"EC106 Sundays River Valley","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Computer Equipment","Security and policing","Pump Stations"]
[null,"EC108 Kouga","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Furniture and Office Equipment","Buses","Water Treatment Works"]
[null,"EC109 Kou-Kamma","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Machinery and Equipment","Clinics","Bulk Mains"]
[null,"DC10 Sarah Baartman","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Transport Assets","Museums & Art Galleries","Distribution"]
[null,"EC121 Mbhashe","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Land","Cemeteries","Distribution Points"]
[null,"EC122 Mnquma","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Zoo's, Marine and Non-biological Animals","Social rental housing","PRV Stations"]
[null,"EC123 Great Kei","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Buildings","Capital Spares"]
[null,"EC124 Amahlathi","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Housing development","Pump Station"]
[null,"EC126 Ngqushwa","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"General vehicles","Reticulation"]
[null,"EC129 Raymond Mhlaba","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Specialised vehicles - Refuse","Waste Water Treatment Works"]
[null,"DC12 Amathole","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Specialised vehicles - Fire","Outfall Sewers"]
[null,"EC131 Inxuba Yethemba","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Specialised vehicles - Conservancy","Toilet Facilities"]
[null,"EC135 Intsika Yethu","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Specialised vehicles - Ambulances","Capital Spares"]
[null,"EC136 Emalahleni (Ec)","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Plant & equipment","Landfill Sites"]
[null,"EC137 Engcobo","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Computers - hardware/equipment","Waste Transfer Stations"]
[null,"EC138 Sakhisizwe","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Furniture and other office equipment","Waste Processing Facilities"]
[null,"EC139 Enoch Mgijima","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Abattoirs","Waste Drop-off Points"]
[null,"DC13 Chris Hani","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Markets","Waste Separation Facilities"]
[null,"EC141 Elundini","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Civic Land and Buildings","Electricity Generation Facilities"]
[null,"EC142 Senqu","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Other Buildings","Capital Spares"]
[null,"EC145 Walter Sisulu","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Other Land","Rail Lines"]
[null,"DC14 Joe Gqabi","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Surplus Assets - (Investment or Inventory)","Rail Structures"]
[null,"EC153 Ngquza Hills","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Computers - software & programming","Rail Furniture"]
[null,"EC154 Port St Johns","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Other","Drainage Collection"]
[null,"EC155 Nyandeni","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Storm water Conveyance"]
[null,"EC156 Mhlontlo","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"SB 19",null,"Attenuation"]
[null,"EC157 King Sabata Dalindyebo","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yes",null,"MV Substations"]
[null,"DC15 O .R. Tambo","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"No",null,"LV Networks"]
[null,"EC441 Matatiele","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Capital Spares"]
[null,"EC442 Umzimvubu","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sand Pumps"]
[null,"EC443 Mbizana","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Piers"]
[null,"EC444 Ntabankulu","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Revetments"]
[null,"DC44 Alfred Nzo","EC EASTERN CAPE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Promenades"]
[null,"MAN Mangaung","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Capital Spares"]
[null,"FS161 Letsemeng","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Data Centres"]
[null,"FS162 Kopanong","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Core Layers"]
[null,"FS163 Mohokare","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Distribution Layers"]
[null,"DC16 Xhariep","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Capital Spares"]
[null,"FS181 Masilonyana","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Halls"]
[null,"FS182 Tokologo","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Centres"]
[null,"FS183 Tswelopele","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Crèches"]
[null,"FS184 Matjhabeng","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Clinics/Care Centres"]
[null,"FS185 Nala","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Fire/Ambulance Stations"]
[null,"DC18 Lejweleputswa","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Testing Stations"]
[null,"FS191 Setsoto","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Museums"]
[null,"FS192 Dihlabeng","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Galleries"]
[null,"FS193 Nketoana","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Theatres"]
[null,"FS194 Maluti-a-Phofung","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Libraries"]
[null,"FS195 Phumelela","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Cemeteries/Crematoria"]
[null,"FS196 Mantsopa","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Police"]
[null,"DC19 Thabo Mofutsanyana","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Purls"]
[null,"FS201 Moqhaka","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Public Open Space"]
[null,"FS203 Ngwathe","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Nature Reserves"]
[null,"FS204 Metsimaholo","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Public Ablution Facilities"]
[null,"FS205 Mafube","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Markets"]
[null,"DC20 Fezile Dabi","FS FREE STATE",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Stalls"]
[null,"EKU City of Ekurhuleni","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Abattoirs"]
[null,"JHB City Of Johannesburg","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Airports"]
[null,"TSH City Of Tshwane","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Taxi Ranks/Bus Terminals"]
[null,"GT421 Emfuleni","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Capital Spares"]
[null,"GT422 Midvaal","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Indoor Facilities"]
[null,"GT423 Lesedi","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Outdoor Facilities"]
[null,"DC42 Sedibeng","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Capital Spares"]
[null,"GT481 Mogale City","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Monuments"]
[null,"GT484 Merafong City","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Historic Buildings"]
[null,"GT485 Rand West City","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Works of Art"]
[null,"DC48 West Rand","GT GAUTENG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Conservation Areas"]
[null,"ETH eThekwini","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Other Heritage"]
[null,"KZN212 Umdoni","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Improved Property"]
[null,"KZN213 Umzumbe","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Unimproved Property"]
[null,"KZN214 uMuziwabantu","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Municipal Offices"]
[null,"KZN216 Ray Nkonyeni","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Pay/Enquiry Points"]
[null,"DC21 Ugu","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Building Plan Offices"]
[null,"KZN221 uMshwathi","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Workshops"]
[null,"KZN222 uMngeni","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Yards"]
[null,"KZN223 Mpofana","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Stores"]
[null,"KZN224 Impendle","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Laboratories"]
[null,"KZN225 Msunduzi","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Training Centres"]
[null,"KZN226 Mkhambathini","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Manufacturing Plant"]
[null,"KZN227 Richmond","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Depots"]
[null,"DC22 uMgungundlovu","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Capital Spares"]
[null,"KZN235 Okhahlamba","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Staff Housing"]
[null,"KZN237 Inkosi Langalibalele","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Social Housing"]
[null,"KZN238 Alfred Duma","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Capital Spares"]
[null,"DC23 Uthukela","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Water Rights"]
[null,"KZN241 Endumeni","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Effluent Licenses"]
[null,"KZN242 Nquthu","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Solid Waste Licenses"]
[null,"KZN244 Msinga","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Computer Software and Applications"]
[null,"KZN245 Umvoti","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Load Settlement Software Applications"]
[null,"DC24 Umzinyathi","KZN KWAZULU-NATAL",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Unspecified"]
[null,"KZN252 Newcastle","KZN KWAZULU-NATAL"]
[null,"KZN253 Emadlangeni","KZN KWAZULU-NATAL"]
[null,"KZN254 Dannhauser","KZN KWAZULU-NATAL"]
[null,"DC25 Amajuba","KZN KWAZULU-NATAL"]
[null,"KZN261 eDumbe","KZN KWAZULU-NATAL"]
[null,"KZN262 uPhongolo","KZN KWAZULU-NATAL"]
[null,"KZN263 Abaqulusi","KZN KWAZULU-NATAL"]
[null,"KZN265 Nongoma","KZN KWAZULU-NATAL"]
[null,"KZN266 Ulundi","KZN KWAZULU-NATAL"]
[null,"DC26 Zululand","KZN KWAZULU-NATAL"]
[null,"KZN271 Umhlabuyalingana","KZN KWAZULU-NATAL"]
[null,"KZN272 Jozini","KZN KWAZULU-NATAL"]
[null,"KZN275 Mtubatuba","KZN KWAZULU-NATAL"]
[null,"KZN276 Hlabisa Big Five","KZN KWAZULU-NATAL"]
[null,"DC27 Umkhanyakude","KZN KWAZULU-NATAL"]
[null,"KZN281 Mfolozi","KZN KWAZULU-NATAL"]
[null,"KZN282 uMhlathuze","KZN KWAZULU-NATAL"]
[null,"KZN284 uMlalazi","KZN KWAZULU-NATAL"]
[null,"KZN285 Mthonjaneni","KZN KWAZULU-NATAL"]
[null,"KZN286 Nkandla","KZN KWAZULU-NATAL"]
[null,"DC28 King Cetshwayo","KZN KWAZULU-NATAL"]
[null,"KZN291 Mandeni","KZN KWAZULU-NATAL"]
[null,"KZN292 KwaDukuza","KZN KWAZULU-NATAL"]
[null,"KZN293 Ndwedwe","KZN KWAZULU-NATAL"]
[null,"KZN294 Maphumulo","KZN KWAZULU-NATAL"]
[null,"DC29 iLembe","KZN KWAZULU-NATAL"]
[null,"KZN433 Greater Kokstad","KZN KWAZULU-NATAL"]
[null,"KZN434 Ubuhlebezwe","KZN KWAZULU-NATAL"]
[null,"KZN435 Umzimkhulu","KZN KWAZULU-NATAL"]
[null,"KZN436 Dr Nkosazana Dlamini Zuma","KZN KWAZULU-NATAL"]
[null,"DC43 Harry Gwala","KZN KWAZULU-NATAL"]
[null,"LIM331 Greater Giyani","LIM LIMPOPO"]
[null,"LIM332 Greater Letaba","LIM LIMPOPO"]
[null,"LIM333 Greater Tzaneen","LIM LIMPOPO"]
[null,"LIM334 Ba-Phalaborwa","LIM LIMPOPO"]
[null,"LIM335 Maruleng","LIM LIMPOPO"]
[null,"DC33 Mopani","LIM LIMPOPO"]
[null,"LIM341 Musina","LIM LIMPOPO"]
[null,"LIM343 Thulamela","LIM LIMPOPO"]
[null,"LIM344 Makhado","LIM LIMPOPO"]
[null,"LIM345 Collins Chabane","LIM LIMPOPO"]
[null,"DC34 Vhembe","LIM LIMPOPO"]
[null,"LIM351 Blouberg","LIM LIMPOPO"]
[null,"LIM353 Molemole","LIM LIMPOPO"]
[null,"LIM354 Polokwane","LIM LIMPOPO"]
[null,"LIM355 Lepelle-Nkumpi","LIM LIMPOPO"]
[null,"DC35 Capricorn","LIM LIMPOPO"]
[null,"LIM361 Thabazimbi","LIM LIMPOPO"]
[null,"LIM362 Lephalale","LIM LIMPOPO"]
[null,"LIM366 Bela Bela","LIM LIMPOPO"]
[null,"LIM367 Mogalakwena","LIM LIMPOPO"]
[null,"LIM368 Modimolle-Mookgopong","LIM LIMPOPO"]
[null,"DC36 Waterberg","LIM LIMPOPO"]
[null,"LIM471 Ephraim Mogale","LIM LIMPOPO"]
[null,"LIM472 Elias Motsoaledi","LIM LIMPOPO"]
[null,"LIM473 Makhuduthamaga","LIM LIMPOPO"]
[null,"LIM476 Tubatse Fetakgomo","LIM LIMPOPO"]
[null,"DC47 Sekhukhune","LIM LIMPOPO"]
[null,"MP301 Albert Luthuli","MP MPUMALANGA"]
[null,"MP302 Msukaligwa","MP MPUMALANGA"]
[null,"MP303 Mkhondo","MP MPUMALANGA"]
[null,"MP304 Pixley Ka Seme (MP)","MP MPUMALANGA"]
[null,"MP305 Lekwa","MP MPUMALANGA"]
[null,"MP306 Dipaleseng","MP MPUMALANGA"]
[null,"MP307 Govan Mbeki","MP MPUMALANGA"]
[null,"DC30 Gert Sibande","MP MPUMALANGA"]
[null,"MP311 Victor Khanye","MP MPUMALANGA"]
[null,"MP312 Emalahleni (Mp)","MP MPUMALANGA"]
[null,"MP313 Steve Tshwete","MP MPUMALANGA"]
[null,"MP314 Emakhazeni","MP MPUMALANGA"]
[null,"MP315 Thembisile Hani","MP MPUMALANGA"]
[null,"MP316 Dr J.S. Moroka","MP MPUMALANGA"]
[null,"DC31 Nkangala","MP MPUMALANGA"]
[null,"MP321 Thaba Chweu","MP MPUMALANGA"]
[null,"MP324 Nkomazi","MP MPUMALANGA"]
[null,"MP325 Bushbuckridge","MP MPUMALANGA"]
[null,"MP326 City of Mbombela","MP MPUMALANGA"]
[null,"DC32 Ehlanzeni","MP MPUMALANGA"]
[null,"NC451 Joe Morolong","NC NORTHERN CAPE"]
[null,"NC452 Ga-Segonyana","NC NORTHERN CAPE"]
[null,"NC453 Gamagara","NC NORTHERN CAPE"]
[null,"DC45 John Taolo Gaetsewe","NC NORTHERN CAPE"]
[null,"NC061 Richtersveld","NC NORTHERN CAPE"]
[null,"NC062 Nama Khoi","NC NORTHERN CAPE"]
[null,"NC064 Kamiesberg","NC NORTHERN CAPE"]
[null,"NC065 Hantam","NC NORTHERN CAPE"]
[null,"NC066 Karoo Hoogland","NC NORTHERN CAPE"]
[null,"NC067 Khai-Ma","NC NORTHERN CAPE"]
[null,"DC6 Namakwa","NC NORTHERN CAPE"]
[null,"NC071 Ubuntu","NC NORTHERN CAPE"]
[null,"NC072 Umsobomvu","NC NORTHERN CAPE"]
[null,"NC073 Emthanjeni","NC NORTHERN CAPE"]
[null,"NC074 Kareeberg","NC NORTHERN CAPE"]
[null,"NC075 Renosterberg","NC NORTHERN CAPE"]
[null,"NC076 Thembelihle","NC NORTHERN CAPE"]
[null,"NC077 Siyathemba","NC NORTHERN CAPE"]
[null,"NC078 Siyancuma","NC NORTHERN CAPE"]
[null,"DC7 Pixley Ka Seme (Nc)","NC NORTHERN CAPE"]
[null,"NC082 !Kai! Garib","NC NORTHERN CAPE"]
[null,"NC084 !Kheis","NC NORTHERN CAPE"]
[null,"NC085 Tsantsabane","NC NORTHERN CAPE"]
[null,"NC086 Kgatelopele","NC NORTHERN CAPE"]
[null,"NC087 Dawid Kruiper","NC NORTHERN CAPE"]
[null,"DC8 Z F Mgcawu","NC NORTHERN CAPE"]
[null,"NC091 Sol Plaatje","NC NORTHERN CAPE"]
[null,"NC092 Dikgatlong","NC NORTHERN CAPE"]
[null,"NC093 Magareng","NC NORTHERN CAPE"]
[null,"NC094 Phokwane","NC NORTHERN CAPE"]
[null,"DC9 Frances Baard","NC NORTHERN CAPE"]
[null,"NW371 Moretele","NW NORTH WEST"]
[null,"NW372 Madibeng","NW NORTH WEST"]
[null,"NW373 Rustenburg","NW NORTH WEST"]
[null,"NW374 Kgetlengrivier","NW NORTH WEST"]
[null,"NW375 Moses Kotane","NW NORTH WEST"]
[null,"DC37 Bojanala Platinum","NW NORTH WEST"]
[null,"NW381 Ratlou","NW NORTH WEST"]
[null,"NW382 Tswaing","NW NORTH WEST"]
[null,"NW383 Mafikeng","NW NORTH WEST"]
[null,"NW384 Ditsobotla","NW NORTH WEST"]
[null,"NW385 Ramotshere Moiloa","NW NORTH WEST"]
[null,"DC38 Ngaka Modiri Molema","NW NORTH WEST"]
[null,"NW392 Naledi (Nw)","NW NORTH WEST"]
[null,"NW393 Mamusa","NW NORTH WEST"]
[null,"NW394 Greater Taung","NW NORTH WEST"]
[null,"NW396 Lekwa-Teemane","NW NORTH WEST"]
[null,"NW397 Kagisano-Molopo","NW NORTH WEST"]
[null,"DC39 Dr Ruth Segomotsi Mompati","NW NORTH WEST"]
[null,"NW403 City Of Matlosana","NW NORTH WEST"]
[null,"NW404 Maquassi Hills","NW NORTH WEST"]
[null,"NW405 J B Marks","NW NORTH WEST"]
[null,"DC40 Dr Kenneth Kaunda","NW NORTH WEST"]
[null,"CPT Cape Town","WC WESTERN CAPE"]
[null,"WC011 Matzikama","WC WESTERN CAPE"]
[null,"WC012 Cederberg","WC WESTERN CAPE"]
[null,"WC013 Bergrivier","WC WESTERN CAPE"]
[null,"WC014 Saldanha Bay","WC WESTERN CAPE"]
[null,"WC015 Swartland","WC WESTERN CAPE"]
[null,"DC1 West Coast","WC WESTERN CAPE"]
[null,"WC022 Witzenberg","WC WESTERN CAPE"]
[null,"WC023 Drakenstein","WC WESTERN CAPE"]
[null,"WC024 Stellenbosch","WC WESTERN CAPE"]
[null,"WC025 Breede Valley","WC WESTERN CAPE"]
[null,"WC026 Langeberg","WC WESTERN CAPE"]
[null,"DC2 Cape Winelands DM","WC WESTERN CAPE"]
[null,"WC031 Theewaterskloof","WC WESTERN CAPE"]
[null,"WC032 Overstrand","WC WESTERN CAPE"]
[null,"WC033 Cape Agulhas","WC WESTERN CAPE"]
[null,"WC034 Swellendam","WC WESTERN CAPE"]
[null,"DC3 Overberg","WC WESTERN CAPE"]
[null,"WC041 Kannaland","WC WESTERN CAPE"]
[null,"WC042 Hessequa","WC WESTERN CAPE"]
[null,"WC043 Mossel Bay","WC WESTERN CAPE"]
[null,"WC044 George","WC WESTERN CAPE"]
[null,"WC045 Oudtshoorn","WC WESTERN CAPE"]
[null,"WC047 Bitou","WC WESTERN CAPE"]
[null,"WC048 Knysna","WC WESTERN CAPE"]
[null,"DC4 Garden Route","WC WESTERN CAPE"]
[null,"WC051 Laingsburg","WC WESTERN CAPE"]
[null,"WC052 Prince Albert","WC WESTERN CAPE"]
[null,"WC053 Beaufort West","WC WESTERN CAPE"]
[null,"DC5 Central Karoo","WC WESTERN CAPE"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,{"$f":"COUNTA(C30:C307)","v":257}]

{"sheet":"Org structure","index":4,"n_rows":85,"n_cols":5,"rows_kept":85,"cut":false,"hidden":false,"merged":[]}
["Organisational Structure Votes",null,"Organisational Structure Sub-Votes",null,"Display Sub-Votes"]
[{"$f":"B2&\" - \"&C2","v":"Vote 01 - Municipal Council"},"Vote 01","Municipal Council"]
[{"$f":"B8&\" - \"&C8","v":"Vote 02 - Office Of The Accounting Officer"},"01.1","Office Of The Mayor",{"$f":"CONCATENATE(B3, \" - \", C3)","v":"01.1 - Office Of The Mayor"},"01.1 - Office Of The Mayor"]
[{"$f":"B15&\" - \"&C15","v":"Vote 03 - Budget And Treasury Office"},"01.2","Office Of The Speaker",{"$f":"CONCATENATE(B4, \" - \", C4)","v":"01.2 - Office Of The Speaker"},"01.2 - Office Of The Speaker"]
[{"$f":"B23&\" - \"&C23","v":"Vote 04 - Corporate Services"},"01.3","Office Of The Chief Whip",{"$f":"CONCATENATE(B5, \" - \", C5)","v":"01.3 - Office Of The Chief Whip"},"01.3 - Office Of The Chief Whip"]
[{"$f":"B32&\" - \"&C32","v":"Vote 05 - Community Services"},"01.4","Mpac",{"$f":"CONCATENATE(B6, \" - \", C6)","v":"01.4 - Mpac"},"01.4 - Mpac"]
[{"$f":"B47&\" - \"&C47","v":"Vote 06 - Planning & Development"},"01.5","Council General Administration",{"$f":"CONCATENATE(B7, \" - \", C7)","v":"01.5 - Council General Administration"},"01.5 - Council General Administration"]
[{"$f":"B58&\" - \"&C58","v":"Vote 07 - Infrastructure & Technical Services"},"Vote 02","Office Of The Accounting Officer"]
[{"$f":"B78&\" - \"&C78","v":"Vote 08 - "},"02.1","Office Of The Ao Admin",{"$f":"CONCATENATE(B9, \" - \", C9)","v":"02.1 - Office Of The Ao Admin"},"02.1 - Office Of The Ao Admin"]
["Vote 09 - ","02.2","Strategic Planning Monitoring & Evaluat","02.2 - Strategic Planning Monitoring & Evaluat","02.2 - Strategic Planning Monitoring & Evaluat"]
["Vote 10 - ","02.3","Perfomance Management System","02.3 - Perfomance Management System","02.3 - Perfomance Management System"]
["Vote 11 - ","02.4","Internal Audit","02.4 - Internal Audit","02.4 - Internal Audit"]
["Vote 12 - ","02.5","Municipal Planning Idp","02.5 - Municipal Planning Idp","02.5 - Municipal Planning Idp"]
["Vote 13 - ","02.6","Risk","02.6 - Risk","02.6 - Risk"]
["Vote 14 - ","Vote 03","Budget And Treasury Office"]
["Vote 15 - Other","03.1","Chief Financial Officer Admin",{"$f":"CONCATENATE(B16, \" - \", C16)","v":"03.1 - Chief Financial Officer Admin"},"03.1 - Chief Financial Officer Admin"]
[null,"03.2","Budget Expenditure & Reporting","03.2 - Budget Expenditure & Reporting","03.2 - Budget Expenditure & Reporting"]
[null,"03.3","Budget Expenditure & Reporting","03.3 - Budget Expenditure & Reporting","03.3 - Budget Expenditure & Reporting"]
[null,"03.4","Revenue Management","03.4 - Revenue Management","03.4 - Revenue Management"]
[null,"03.5","Supply Chain Management","03.5 - Supply Chain Management","03.5 - Supply Chain Management"]
[null,"03.6","Assets Management","03.6 - Assets Management","03.6 - Assets Management"]
[null,"03.7","Expenditure","03.7 - Expenditure","03.7 - Expenditure"]
[null,"Vote 04","Corporate Services"]
[null,"04.1","Legal Services",{"$f":"CONCATENATE(B24, \" - \", C24)","v":"04.1 - Legal Services"},"04.1 - Legal Services"]
[null,"04.2","Corporate Service Administration","04.2 - Corporate Service Administration","04.2 - Corporate Service Administration"]
[null,"04.3","Human Resources","04.3 - Human Resources","04.3 - Human Resources"]
[null,"04.4","Media & Communication","04.4 - Media & Communication","04.4 - Media & Communication"]
[null,"04.5","Organisational Development","04.5 - Organisational Development","04.5 - Organisational Development"]
[null,"04.6","Labour Relations","04.6 - Labour Relations","04.6 - Labour Relations"]
[null,"04.7","Legal Services","04.7 - Legal Services","04.7 - Legal Services"]
[null,"04.8","Information Technology Services","04.8 - Information Technology Services","04.8 - Information Technology Services"]
[null,"Vote 05","Community Services"]
[null,"05.1","Municipal Buildings",{"$f":"CONCATENATE(B33, \" - \", C33)","v":"05.1 - Municipal Buildings"},"05.1 - Municipal Buildings"]
[null,"05.2","Fleet Management","05.2 - Fleet Management","05.2 - Fleet Management"]
[null,"05.3","Community Services Administration","05.3 - Community Services Administration","05.3 - Community Services Administration"]
[null,"05.4","Cemeteries","05.4 - Cemeteries","05.4 - Cemeteries"]
[null,"05.5","Disaster Management","05.5 - Disaster Management","05.5 - Disaster Management"]
[null,"05.6","Fires Service","05.6 - Fires Service","05.6 - Fires Service"]
[null,"05.7","Libraries","05.7 - Libraries","05.7 - Libraries"]
[null,"05.8","Municipal Buildings","05.8 - Municipal Buildings","05.8 - Municipal Buildings"]
[null,"05.9","Sports Recreation & Social Amenitie","05.9 - Sports Recreation & Social Amenitie","05.9 - Sports Recreation & Social Amenitie"]
[null,"05.10","Waste Management Solid Waste","05.10 - Waste Management Solid Waste","05.10 - Waste Management Solid Waste"]
[null,"05.11","Safety And Security","05.11 - Safety And Security","05.11 - Safety And Security"]
[null,"05.12","Traffic Service","05.12 - Traffic Service","05.12 - Traffic Service"]
[null,"05.13","Traffic Service","05.13 - Traffic Service","05.13 - Traffic Service"]
[null,"05.14","Fleet Management","05.14 - Fleet Management","05.14 - Fleet Management"]
[null,"Vote 06","Planning & Development"]
[null,"06.1","Planning And Development Admin",{"$f":"CONCATENATE(B48, \" - \", C48)","v":"06.1 - Planning And Development Admin"},"06.1 - Planning And Development Admin"]
[null,"06.2","Municipal Planning Idp","06.2 - Municipal Planning Idp","06.2 - Municipal Planning Idp"]
[null,"06.3","Pms","06.3 - Pms","06.3 - Pms"]
[null,"06.4","Town Planning","06.4 - Town Planning","06.4 - Town Planning"]
[null,"06.5","Land Use And Housing Admin","06.5 - Land Use And Housing Admin","06.5 - Land Use And Housing Admin"]
[null,"06.6","Local Economic Development","06.6 - Local Economic Development","06.6 - Local Economic Development"]
[null,"06.7","Led","06.7 - Led","06.7 - Led"]
[null,"06.8","Agriculture & Rural Development","06.8 - Agriculture & Rural Development","06.8 - Agriculture & Rural Development"]
[null,"06.9","Tourism & Business Development","06.9 - Tourism & Business Development","06.9 - Tourism & Business Development"]
[null,"06.10","Arts & Culture","06.10 - Arts & Culture","06.10 - Arts & Culture"]
[null,"Vote 07","Infrastructure & Technical Services"]
[null,"07.1","Infrastructure Admin & Tech Admin",{"$f":"CONCATENATE(B59, \" - \", C59)","v":"07.1 - Infrastructure Admin & Tech Admin"},"07.1 - Infrastructure Admin & Tech Admin"]
[null,"07.2","Fleet Management","07.2 - Fleet Management","07.2 - Fleet Management"]
[null,"07.3","Roads","07.3 - Roads","07.3 - Roads"]
[null,"07.4","Storm Water","07.4 - Storm Water","07.4 - Storm Water"]
[null,"07.5","Street Lighting","07.5 - Street Lighting","07.5 - Street Lighting"]
[null,"07.6","Project Management Unit","07.6 - Project Management Unit","07.6 - Project Management Unit"]
[null,"07.7","Sanitation Treatment Plant: Mogwase","07.7 - Sanitation Treatment Plant: Mogwase","07.7 - Sanitation Treatment Plant: Mogwase"]
[null,"07.8","Sanitation Treatment Plant: Madikwe","07.8 - Sanitation Treatment Plant: Madikwe","07.8 - Sanitation Treatment Plant: Madikwe"]
[null,"07.9","Sanitation Reticulation","07.9 - Sanitation Reticulation","07.9 - Sanitation Reticulation"]
[null,"07.10","Water Administration","07.10 - Water Administration","07.10 - Water Administration"]
[null,"07.11","Water Madikwe: Water Treatment Work","07.11 - Water Madikwe: Water Treatment Work","07.11 - Water Madikwe: Water Treatment Work"]
[null,"07.12","Water: Pella Water Treatment Works","07.12 - Water: Pella Water Treatment Works","07.12 - Water: Pella Water Treatment Works"]
[null,"07.13","Water: Madikwe Retail & Bulk Lines","07.13 - Water: Madikwe Retail & Bulk Lines","07.13 - Water: Madikwe Retail & Bulk Lines"]
[null,"07.14","Water: Madikwe Rural","07.14 - Water: Madikwe Rural","07.14 - Water: Madikwe Rural"]
[null,"07.15","Water: Molatedi","07.15 - Water: Molatedi","07.15 - Water: Molatedi"]
[null,"07.16","Water Eastern: Retail Mankwe","07.16 - Water Eastern: Retail Mankwe","07.16 - Water Eastern: Retail Mankwe"]
[null,"07.17","Water Vaalkopdam: Mankwe","07.17 - Water Vaalkopdam: Mankwe","07.17 - Water Vaalkopdam: Mankwe"]
[null,"07.18","Water Eastern: Retail Mankwe","07.18 - Water Eastern: Retail Mankwe","07.18 - Water Eastern: Retail Mankwe"]
[null,"07.19","Reporting Function Electricity","07.19 - Reporting Function Electricity","07.19 - Reporting Function Electricity"]
[null,"Vote 08"]
[null,"Vote 09"]
[null,"Vote 10"]
[null,"Vote 11"]
[null,"Vote 12"]
[null,"Vote 13"]
[null,"Vote 14"]
[null,"Vote 15","Other"]

{"sheet":"Contacts","index":5,"n_rows":170,"n_cols":8,"rows_kept":170,"cut":false,"hidden":false,"merged":[[30,2,30,3],[39,0,39,1],[7,2,7,3],[10,2,10,3],[12,2,12,3],[13,0,13,1],[29,0,29,1],[29,2,29,3],[39,2,39,3],[48,0,48,1],[48,2,48,3],[57,0,57,1],[57,2,57,3],[58,2,58,3],[67,2,67,3],[76,0,76,1],[76,2,76,3],[84,0,84,1],[84,2,84,3],[92,0,92,1],[92,2,92,3],[124,0,124,1],[124,2,124,3],[132,0,132,1],[132,2,132,3],[100,0,100,1],[100,2,100,3],[108,0,108,1],[108,2,108,3],[116,0,116,1],[116,2,116,3]]}
[{"$f":"'Template names'!$B$63&\" - \"&\" Contact Information\"","v":"NW375 Moses Kotane -  Contact Information"}]
[]
["A. GENERAL INFORMATION"]
["Municipality",{"$f":"'Template names'!$B$63","v":"NW375 Moses Kotane"},"Set name on 'Instructions' sheet"]
[]
["Grade",2,"1 Grade in terms of the Remuneration of Public Office Bearers Act."]
[]
["Province",{"$f":"IF(B4>\" \",VLOOKUP(B4,'Lookup and lists'!B29:C312,2, FALSE),\" \")","v":"NW NORTH WEST"}]
[]
["Web Address","www.moseskotane.gov.za"]
[]
["e-mail Address","municipalmanager@moseskotane.gov.za"]
[]
["B. CONTACT INFORMATION"]
["Postal address:"]
["P.O. Box",1011]
["City / Town","Mogwase"]
["Postal Code","0314"]
[]
["Street address"]
["Building","Mogwase Shopping Complex"]
["Street No. & Name","935 Station Road"]
["City / Town","Mogwase"]
["Postal Code","0314"]
[]
["General Contacts"]
["Telephone number","014 555 1300"]
["Fax number","014 555 6368"]
[]
["C. POLITICAL LEADERSHIP"]
["Speaker:",null,"Secretary/PA to the Speaker:"]
["ID Number","7206135791081","ID Number",""]
["Title","Clr","Title","Ms"]
["Name","Sipho Vava ","Name","D MANAME"]
["Telephone number","014 555 1309","Telephone number","014 555 1309"]
["Cell number","0823079727","Cell number","073 973 7862"]
["Fax number","014 555 6368","Fax number","014 555 7635"]
["E-mail address","speakersecretary@moseskotane.gov.za","E-mail address","speakersecretary@moseskotane.gov.za"]
[]
["Mayor/Executive Mayor:",null,"Secretary/PA to the Mayor/Executive Mayor:"]
["ID Number","","ID Number",""]
["Title","Clr","Title","Mrs"]
["Name","A R DIALE","Name","M MORUPI"]
["Telephone number","014 555 1305","Telephone number","014 555 1305"]
["Cell number","082 467 2895","Cell number","079 342 0861"]
["Fax number","014 555 6368","Fax number","014 555 6368"]
["E-mail address","mayorssecretary@moseskotane.gov.za","E-mail address","mayorsecretary@moseskotane.gov.za"]
[]
["Deputy Mayor/Executive Mayor:",null,"Secretary/PA to the Deputy Mayor/Executive Mayor:"]
["ID Number",null,"ID Number"]
["Title",null,"Title"]
["Name",null,"Name"]
["Telephone number",null,"Telephone number"]
["Cell number",null,"Cell number"]
["Fax number",null,"Fax number"]
["E-mail address",null,"E-mail address"]
[]
["D. MANAGEMENT LEADERSHIP"]
["Municipal Manager:",null,"Secretary/PA to the Municipal Manager:"]
["ID Number","","ID Number",""]
["Title","Mr ","Title","Ms"]
["Name","M V LETSOALO","Name","WINNIE MABALANE"]
["Telephone number","014 555 1307","Telephone number","014 555 1307"]
["Cell number","066 300 6349","Cell number","082 543 4845"]
["Fax number","086 654 5962","Fax number","086 654 5962"]
["E-mail address","066 300 6349","E-mail address","municipalmanager@moseskotane.gov.za"]
[]
["Chief Financial Officer",null,"Secretary/PA to the Chief Financial Officer"]
["ID Number","8409265857081","ID Number"]
["Title","Mr","Title"]
["Name","MR Mkhize ","Name"]
["Telephone number","014 555 1332","Telephone number"]
["Cell number","0609782021","Cell number"]
["Fax number","","Fax number"]
["E-mail address","cfo@moseskotane.gov.za","E-mail address"]
[]
["Official responsible for submitting financial information",null,"Official responsible for submitting financial information"]
["ID Number","","ID Number"]
["Title","Ms T Lebusa","Title"]
["Name","T LEBUSA","Name"]
["Telephone number","014 555 1333","Telephone number"]
["Cell number","082 051 2347","Cell number"]
["Fax number","086 232 1786","Fax number"]
["E-mail address","tlebusa@moseskotane.gov.za","E-mail address"]
["Official responsible for submitting financial information",null,"Official responsible for submitting financial information"]
["ID Number",null,"ID Number"]
["Title",null,"Title"]
["Name",null,"Name"]
["Telephone number",null,"Telephone number"]
["Cell number",null,"Cell number"]
["Fax number",null,"Fax number"]
["E-mail address",null,"E-mail address"]
["Official responsible for submitting financial information",null,"Official responsible for submitting financial information"]
["ID Number",null,"ID Number"]
["Title",null,"Title"]
["Name",null,"Name"]
["Telephone number",null,"Telephone number"]
["Cell number",null,"Cell number"]
["Fax number",null,"Fax number"]
["E-mail address",null,"E-mail address"]
["Official responsible for submitting financial information",null,"Official responsible for submitting financial information"]
["ID Number",null,"ID Number"]
["Title",null,"Title"]
["Name",null,"Name"]
["Telephone number",null,"Telephone number"]
["Cell number",null,"Cell number"]
["Fax number",null,"Fax number"]
["E-mail address",null,"E-mail address"]
["Official responsible for submitting financial information",null,"Official responsible for submitting financial information"]
["ID Number",null,"ID Number"]
["Title",null,"Title"]
["Name",null,"Name"]
["Telephone number",null,"Telephone number"]
["Cell number",null,"Cell number"]
["Fax number",null,"Fax number"]
["E-mail address",null,"E-mail address"]
["Official responsible for submitting financial information",null,"Official responsible for submitting financial information"]
["ID Number",null,"ID Number"]
["Title",null,"Title"]
["Name",null,"Name"]
["Telephone number",null,"Telephone number"]
["Cell number",null,"Cell number"]
["Fax number",null,"Fax number"]
["E-mail address",null,"E-mail address"]
["Official responsible for submitting financial information",null,"Official responsible for submitting financial information"]
["ID Number",null,"ID Number"]
["Title",null,"Title"]
["Name",null,"Name"]
["Telephone number",null,"Telephone number"]
["Cell number",null,"Cell number"]
["Fax number",null,"Fax number"]
["E-mail address",null,"E-mail address"]
["Official responsible for submitting financial information"]
["ID Number"]
["Title"]
["Name"]
["Telephone number"]
["Cell number"]
["Fax number"]
["E-mail address"]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,null,null,null,null,null,"12/06/2020"]

{"sheet":"B1-Sum","index":6,"n_rows":77,"n_cols":12,"rows_kept":77,"cut":false,"hidden":false,"merged":[[74,0,74,12],[76,0,76,12],[1,1,1,9],[1,0,3,0],[69,0,69,12],[70,0,70,12],[71,0,71,12],[72,0,72,12]]}
[{"$f":"muni&\" - \"&adjsum&\" - \"&Date","v":"NW375 Moses Kotane - Table B1 Adjustments Budget Summary - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,1,2,3,4,5,6,7,8]
["R thousands","A","A1","B","C","D","E","F","G","H"]
["Financial Performance"]
["Property rates",{"$f":"SUM('B4-FinPerf RE'!C7:C7)","v":142163600},{"$f":"SUM('B4-FinPerf RE'!D7:D7)","v":142163600},{"$f":"SUM('B4-FinPerf RE'!E7:E7)","v":0},{"$f":"SUM('B4-FinPerf RE'!F7:F7)","v":0},{"$f":"SUM('B4-FinPerf RE'!G7:G7)","v":0},{"$f":"SUM('B4-FinPerf RE'!H7:H7)","v":0},{"$f":"SUM('B4-FinPerf RE'!I7:I7)","v":0},{"$f":"SUM(D7:H7)","v":0},{"$f":"IF(C7=0,B7+I7,C7+I7)","v":142163600},{"$f":"SUM('B4-FinPerf RE'!L7:L7)","v":169026146},{"$f":"SUM('B4-FinPerf RE'!M7:M7)","v":176817777}]
["Service charges",{"$f":"SUM('B4-FinPerf RE'!C8:C11)","v":184251428},{"$f":"SUM('B4-FinPerf RE'!D8:D11)","v":184251428},{"$f":"SUM('B4-FinPerf RE'!E8:E11)","v":0},{"$f":"SUM('B4-FinPerf RE'!F8:F11)","v":0},{"$f":"SUM('B4-FinPerf RE'!G8:G11)","v":0},{"$f":"SUM('B4-FinPerf RE'!H8:H11)","v":0},{"$f":"SUM('B4-FinPerf RE'!I8:I11)","v":0},{"$f":"SUM('B4-FinPerf RE'!J8:J11)","v":0},{"$f":"SUM('B4-FinPerf RE'!K8:K11)","v":184251428},{"$f":"SUM('B4-FinPerf RE'!L8:L11)","v":186492720},{"$f":"SUM('B4-FinPerf RE'!M8:M11)","v":186680737}]
["Investment revenue",{"$f":"'B4-FinPerf RE'!C14","v":5400000},{"$f":"'B4-FinPerf RE'!D14","v":6400000},{"$f":"'B4-FinPerf RE'!E14","v":0},{"$f":"'B4-FinPerf RE'!F14","v":0},{"$f":"'B4-FinPerf RE'!G14","v":0},{"$f":"'B4-FinPerf RE'!H14","v":0},{"$f":"'B4-FinPerf RE'!I14","v":0},0,6400000,{"$f":"'B4-FinPerf RE'!L14","v":5400000},{"$f":"'B4-FinPerf RE'!M14","v":5200000}]
["Transfers recognised - operational",{"$f":"'B4-FinPerf RE'!C20","v":437829637},{"$f":"'B4-FinPerf RE'!D20","v":374462124},{"$f":"'B4-FinPerf RE'!E20","v":0},{"$f":"'B4-FinPerf RE'!F20","v":0},{"$f":"'B4-FinPerf RE'!G20","v":0},{"$f":"'B4-FinPerf RE'!H20","v":0},{"$f":"'B4-FinPerf RE'!I20","v":88513},88513,374550637,{"$f":"'B4-FinPerf RE'!L20","v":467694767},{"$f":"'B4-FinPerf RE'!M20","v":500553630}]
["Other own revenue",{"$f":"'B4-FinPerf RE'!C13+'B4-FinPerf RE'!C15+'B4-FinPerf RE'!C16+'B4-FinPerf RE'!C17+'B4-FinPerf RE'!C18+'B4-FinPerf RE'!C19+'B4-FinPerf RE'!C21+'B4-FinPerf RE'!C22","v":66921500},{"$f":"'B4-FinPerf RE'!D13+'B4-FinPerf RE'!D15+'B4-FinPerf RE'!D16+'B4-FinPerf RE'!D17+'B4-FinPerf RE'!D18+'B4-FinPerf RE'!D19+'B4-FinPerf RE'!D21+'B4-FinPerf RE'!D22","v":66628290},{"$f":"'B4-FinPerf RE'!E13+'B4-FinPerf RE'!E15+'B4-FinPerf RE'!E16+'B4-FinPerf RE'!E17+'B4-FinPerf RE'!E18+'B4-FinPerf RE'!E19+'B4-FinPerf RE'!E21+'B4-FinPerf RE'!E22","v":0},{"$f":"'B4-FinPerf RE'!F13+'B4-FinPerf RE'!F15+'B4-FinPerf RE'!F16+'B4-FinPerf RE'!F17+'B4-FinPerf RE'!F18+'B4-FinPerf RE'!F19+'B4-FinPerf RE'!F21+'B4-FinPerf RE'!F22","v":0},{"$f":"'B4-FinPerf RE'!G13+'B4-FinPerf RE'!G15+'B4-FinPerf RE'!G16+'B4-FinPerf RE'!G17+'B4-FinPerf RE'!G18+'B4-FinPerf RE'!G19+'B4-FinPerf RE'!G21+'B4-FinPerf RE'!G22","v":0},{"$f":"'B4-FinPerf RE'!H13+'B4-FinPerf RE'!H15+'B4-FinPerf RE'!H16+'B4-FinPerf RE'!H17+'B4-FinPerf RE'!H18+'B4-FinPerf RE'!H19+'B4-FinPerf RE'!H21+'B4-FinPerf RE'!H22","v":0},{"$f":"'B4-FinPerf RE'!I13+'B4-FinPerf RE'!I15+'B4-FinPerf RE'!I16+'B4-FinPerf RE'!I17+'B4-FinPerf RE'!I18+'B4-FinPerf RE'!I19+'B4-FinPerf RE'!I21+'B4-FinPerf RE'!I22","v":290000},290000,66918290,{"$f":"'B4-FinPerf RE'!L13+'B4-FinPerf RE'!L15+'B4-FinPerf RE'!L16+'B4-FinPerf RE'!L17+'B4-FinPerf RE'!L18+'B4-FinPerf RE'!L19+'B4-FinPerf RE'!L21+'B4-FinPerf RE'!L22","v":67591050},{"$f":"'B4-FinPerf RE'!M13+'B4-FinPerf RE'!M15+'B4-FinPerf RE'!M16+'B4-FinPerf RE'!M17+'B4-FinPerf RE'!M18+'B4-FinPerf RE'!M19+'B4-FinPerf RE'!M21+'B4-FinPerf RE'!M22","v":70515156}]
["Total Revenue (excluding capital transfers and contributions)",{"$f":"SUM(B7:B11)","v":836566165},773905442,0,0,0,0,378513,378513,774283955,896204683,939767300]
["Employee costs",{"$f":"'B4-FinPerf RE'!C26","v":270274660},{"$f":"'B4-FinPerf RE'!D26","v":248852359.38},{"$f":"'B4-FinPerf RE'!E26","v":0},{"$f":"'B4-FinPerf RE'!F26","v":0},{"$f":"'B4-FinPerf RE'!G26","v":0},{"$f":"'B4-FinPerf RE'!H26","v":0},{"$f":"'B4-FinPerf RE'!I26","v":-2300000},{"$f":"SUM(D13:H13)","v":-2300000},{"$f":"IF(C13=0,B13+I13,C13+I13)","v":246552359.38},{"$f":"'B4-FinPerf RE'!L26","v":278331407},{"$f":"'B4-FinPerf RE'!M26","v":293509032}]
["Remuneration of councillors",{"$f":"'B4-FinPerf RE'!C27","v":25371420},{"$f":"'B4-FinPerf RE'!D27","v":25371420},{"$f":"'B4-FinPerf RE'!E27","v":0},{"$f":"'B4-FinPerf RE'!F27","v":0},{"$f":"'B4-FinPerf RE'!G27","v":0},{"$f":"'B4-FinPerf RE'!H27","v":0},{"$f":"'B4-FinPerf RE'!I27","v":2300000},2300000,27671420,{"$f":"'B4-FinPerf RE'!L27","v":24819114},{"$f":"'B4-FinPerf RE'!M27","v":26060071}]
["Depreciation & asset impairment",{"$f":"'B4-FinPerf RE'!C29","v":154536733},{"$f":"'B4-FinPerf RE'!D29","v":154536733},{"$f":"'B4-FinPerf RE'!E29","v":0},{"$f":"'B4-FinPerf RE'!F29","v":0},{"$f":"'B4-FinPerf RE'!G29","v":0},{"$f":"'B4-FinPerf RE'!H29","v":0},{"$f":"'B4-FinPerf RE'!I29","v":0},0,154536733,{"$f":"'B4-FinPerf RE'!L29","v":133503316},{"$f":"'B4-FinPerf RE'!M29","v":139644469}]
["Finance charges",{"$f":"'B4-FinPerf RE'!C30","v":3688959},{"$f":"'B4-FinPerf RE'!D30","v":3688959},{"$f":"'B4-FinPerf RE'!E30","v":0},{"$f":"'B4-FinPerf RE'!F30","v":0},{"$f":"'B4-FinPerf RE'!G30","v":0},{"$f":"'B4-FinPerf RE'!H30","v":0},{"$f":"'B4-FinPerf RE'!I30","v":0},0,3688959,{"$f":"'B4-FinPerf RE'!L30","v":3043808},{"$f":"'B4-FinPerf RE'!M30","v":2729218}]
["Materials and bulk purchases",{"$f":"SUM('B4-FinPerf RE'!C31:C32)","v":109277250},{"$f":"SUM('B4-FinPerf RE'!D31:D32)","v":92304189.019999996},{"$f":"SUM('B4-FinPerf RE'!E31:E32)","v":0},{"$f":"SUM('B4-FinPerf RE'!F31:F32)","v":0},{"$f":"SUM('B4-FinPerf RE'!G31:G32)","v":0},{"$f":"SUM('B4-FinPerf RE'!H31:H32)","v":0},{"$f":"SUM('B4-FinPerf RE'!I31:I32)","v":268000},268000,92572189.019999996,{"$f":"SUM('B4-FinPerf RE'!L31:L32)","v":116127300},{"$f":"SUM('B4-FinPerf RE'!M31:M32)","v":121467500}]
["Transfers and grants",{"$f":"'B4-FinPerf RE'!C34","v":0},{"$f":"'B4-FinPerf RE'!D34","v":0},{"$f":"'B4-FinPerf RE'!E34","v":0},{"$f":"'B4-FinPerf RE'!F34","v":0},{"$f":"'B4-FinPerf RE'!G34","v":0},{"$f":"'B4-FinPerf RE'!H34","v":0},{"$f":"'B4-FinPerf RE'!I34","v":0},0,0,{"$f":"'B4-FinPerf RE'!L34","v":0},{"$f":"'B4-FinPerf RE'!M34","v":0}]
["Other expenditure",{"$f":"'B4-FinPerf RE'!C37-SUM('B1-Sum'!B13:B18)","v":404091300},{"$f":"'B4-FinPerf RE'!D37-SUM('B1-Sum'!C13:C18)","v":380833574.47000003},{"$f":"'B4-FinPerf RE'!E37-SUM('B1-Sum'!D13:D18)","v":0},{"$f":"'B4-FinPerf RE'!F37-SUM('B1-Sum'!E13:E18)","v":0},{"$f":"'B4-FinPerf RE'!G37-SUM('B1-Sum'!F13:F18)","v":0},{"$f":"'B4-FinPerf RE'!H37-SUM('B1-Sum'!G13:G18)","v":0},{"$f":"'B4-FinPerf RE'!I37-SUM('B1-Sum'!H13:H18)","v":-179487},-179487,380654087.47000003,{"$f":"'B4-FinPerf RE'!L37-SUM('B1-Sum'!K13:K18)","v":382680317},{"$f":"'B4-FinPerf RE'!M37-SUM('B1-Sum'!L13:L18)","v":396878502}]
["Total Expenditure",{"$f":"SUM(B13:B19)","v":967240322},905587234.87,0,0,0,0,88513,88513,905675747.87,938505262,980288792]
["Surplus/(Deficit)",{"$f":"B12-B20","v":-130674157},-131681792.87,0,0,0,0,290000,290000,-131391792.87,-42300579,-40521492]
[{"$f":"'B4-FinPerf RE'!A40","v":"Transfers and subsidies - capital (monetary allocations) (National / Provincial and District)"},{"$f":"'B4-FinPerf RE'!C40","v":87086153},{"$f":"'B4-FinPerf RE'!D40","v":93773318},{"$f":"'B4-FinPerf RE'!E40","v":0},{"$f":"'B4-FinPerf RE'!F40","v":0},{"$f":"'B4-FinPerf RE'!G40","v":0},{"$f":"'B4-FinPerf RE'!H40","v":0},{"$f":"'B4-FinPerf RE'!I40","v":0},{"$f":"SUM(D22:H22)","v":0},{"$f":"IF(C22=0,B22+I22,C22+I22)","v":93773318},{"$f":"'B4-FinPerf RE'!L40","v":202495233},{"$f":"'B4-FinPerf RE'!M40","v":218925370}]
[{"$f":"'B4-FinPerf RE'!A41&\" & \"&'B4-FinPerf RE'!A42","v":"Transfers and subsidies - capital (monetary allocations) (National / Provincial Departmental Agencies, Households, Non-profit Institutions, Private Enterprises, Public Corporatons, Higher Educational Institutions) & Transfers and subsidies - capital (in-kind - all) "},{"$f":"SUM('B4-FinPerf RE'!C41:C42)","v":112438210},{"$f":"SUM('B4-FinPerf RE'!D41:D42)","v":112332044.98999999},{"$f":"SUM('B4-FinPerf RE'!E41:E42)","v":0},{"$f":"SUM('B4-FinPerf RE'!F41:F42)","v":0},{"$f":"SUM('B4-FinPerf RE'!G41:G42)","v":0},{"$f":"SUM('B4-FinPerf RE'!H41:H42)","v":0},{"$f":"SUM('B4-FinPerf RE'!I41:I42)","v":0},{"$f":"SUM(D23:H23)","v":0},{"$f":"IF(C23=0,B23+I23,C23+I23)","v":112332044.98999999},{"$f":"SUM('B4-FinPerf RE'!L41:L42)","v":0},{"$f":"SUM('B4-FinPerf RE'!M41:M42)","v":0}]
["Surplus/(Deficit) after capital transfers & contributions",{"$f":"B21+SUM(B22:B23)","v":68850206},74423570.120000005,0,0,0,0,290000,{"$f":"SUM(D24:H24)","v":290000},{"$f":"IF(C24=0,B24+I24,C24+I24)","v":74713570.120000005},160194654,178403878]
["Share of surplus/ (deficit) of associate",{"$f":"'B4-FinPerf RE'!C48","v":0},{"$f":"'B4-FinPerf RE'!D48","v":0},{"$f":"'B4-FinPerf RE'!E48","v":0},{"$f":"'B4-FinPerf RE'!F48","v":0},{"$f":"'B4-FinPerf RE'!G48","v":0},{"$f":"'B4-FinPerf RE'!H48","v":0},{"$f":"'B4-FinPerf RE'!I48","v":0},{"$f":"SUM(D25:H25)","v":0},{"$f":"IF(C25=0,B25+I25,C25+I25)","v":0},{"$f":"'B4-FinPerf RE'!L48","v":0},{"$f":"'B4-FinPerf RE'!M48","v":0}]
["Surplus/ (Deficit) for the year",{"$f":"B24+B25","v":68850206},74423570.120000005,0,0,0,0,290000,290000,74713570.120000005,160194654,178403878]
[]
["Capital expenditure & funds sources"]
["Capital expenditure",{"$f":"'B5-Capex'!C42","v":204802147},{"$f":"'B5-Capex'!D42","v":206105362.19},{"$f":"'B5-Capex'!E42","v":0},{"$f":"'B5-Capex'!F42","v":0},{"$f":"'B5-Capex'!G42","v":0},{"$f":"'B5-Capex'!H42","v":0},{"$f":"'B5-Capex'!I42","v":113975},{"$f":"SUM(D29:H29)","v":113975},{"$f":"IF(C29=0,B29+I29,C29+I29)","v":206219337.19},{"$f":"'B5-Capex'!L42","v":202495233},{"$f":"'B5-Capex'!M42","v":218925369}]
["Transfers recognised - capital",{"$f":"'B5-Capex'!C72","v":201361894},{"$f":"'B5-Capex'!D72","v":206105362.13},{"$f":"'B5-Capex'!E72","v":0},{"$f":"'B5-Capex'!F72","v":0},{"$f":"'B5-Capex'!G72","v":0},{"$f":"'B5-Capex'!H72","v":0},{"$f":"'B5-Capex'!I72","v":0},{"$f":"SUM(D30:H30)","v":0},{"$f":"IF(C30=0,B30+I30,C30+I30)","v":206105362.13},{"$f":"'B5-Capex'!L72","v":202495233},{"$f":"'B5-Capex'!M72","v":218925369}]
[]
["Borrowing",{"$f":"'B5-Capex'!C74","v":0},{"$f":"'B5-Capex'!D74","v":0},{"$f":"'B5-Capex'!E74","v":0},{"$f":"'B5-Capex'!F74","v":0},{"$f":"'B5-Capex'!G74","v":0},{"$f":"'B5-Capex'!H74","v":0},{"$f":"'B5-Capex'!I74","v":0},{"$f":"SUM(D32:H32)","v":0},{"$f":"IF(C32=0,B32+I32,C32+I32)","v":0},{"$f":"'B5-Capex'!L74","v":0},{"$f":"'B5-Capex'!M74","v":0}]
["Internally generated funds",{"$f":"'B5-Capex'!C75","v":3440253},{"$f":"'B5-Capex'!D75","v":0.06},{"$f":"'B5-Capex'!E75","v":0},{"$f":"'B5-Capex'!F75","v":0},{"$f":"'B5-Capex'!G75","v":0},{"$f":"'B5-Capex'!H75","v":0},{"$f":"'B5-Capex'!I75","v":113975},{"$f":"SUM(D33:H33)","v":113975},{"$f":"IF(C33=0,B33+I33,C33+I33)","v":113975.06},{"$f":"'B5-Capex'!L75","v":0},{"$f":"'B5-Capex'!M75","v":0}]
["Total sources of capital funds",{"$f":"+B30+B32+B33","v":204802147},{"$f":"+C30+C32+C33","v":206105362.19},0,0,0,0,113975,{"$f":"SUM(D34:H34)","v":113975},{"$f":"IF(C34=0,B34+I34,C34+I34)","v":206219337.19},202495233,218925369]
[]
["Financial position"]
["Total current assets",{"$f":"'B6-FinPos'!C14","v":572098000},{"$f":"'B6-FinPos'!D14","v":572098000},{"$f":"'B6-FinPos'!E14","v":0},{"$f":"'B6-FinPos'!F14","v":0},{"$f":"'B6-FinPos'!G14","v":0},{"$f":"'B6-FinPos'!H14","v":0},{"$f":"'B6-FinPos'!I14","v":0},{"$f":"SUM(D37:H37)","v":0},{"$f":"IF(C37=0,B37+I37,C37+I37)","v":572098000},{"$f":"'B6-FinPos'!L14","v":469097414},{"$f":"'B6-FinPos'!M14","v":777478912}]
["Total non current assets",{"$f":"'B6-FinPos'!C26","v":1785427147},{"$f":"'B6-FinPos'!D26","v":1786730362.1900001},{"$f":"'B6-FinPos'!E26","v":0},{"$f":"'B6-FinPos'!F26","v":0},{"$f":"'B6-FinPos'!G26","v":0},{"$f":"'B6-FinPos'!H26","v":0},{"$f":"'B6-FinPos'!I26","v":113975},{"$f":"SUM(D38:H38)","v":113975},{"$f":"IF(C38=0,B38+I38,C38+I38)","v":1786844337.1900001},{"$f":"'B6-FinPos'!L26","v":3685970409},{"$f":"'B6-FinPos'!M26","v":3945578770}]
["Total current liabilities",{"$f":"'B6-FinPos'!C36","v":172503000},{"$f":"'B6-FinPos'!D36","v":172503000},{"$f":"'B6-FinPos'!E36","v":0},{"$f":"'B6-FinPos'!F36","v":0},{"$f":"'B6-FinPos'!G36","v":0},{"$f":"'B6-FinPos'!H36","v":0},{"$f":"'B6-FinPos'!I36","v":0},{"$f":"SUM(D39:H39)","v":0},{"$f":"IF(C39=0,B39+I39,C39+I39)","v":172503000},{"$f":"'B6-FinPos'!L36","v":86362000},{"$f":"'B6-FinPos'!M36","v":88264652}]
["Total non current liabilities",{"$f":"'B6-FinPos'!C41","v":24600000},{"$f":"'B6-FinPos'!D41","v":24600000},{"$f":"'B6-FinPos'!E41","v":0},{"$f":"'B6-FinPos'!F41","v":0},{"$f":"'B6-FinPos'!G41","v":0},{"$f":"'B6-FinPos'!H41","v":0},{"$f":"'B6-FinPos'!I41","v":0},{"$f":"SUM(D40:H40)","v":0},{"$f":"IF(C40=0,B40+I40,C40+I40)","v":24600000},{"$f":"'B6-FinPos'!L41","v":29829314},{"$f":"'B6-FinPos'!M41","v":31171633}]
["Community wealth/Equity",{"$f":"'B6-FinPos'!C50","v":2160422147},{"$f":"'B6-FinPos'!D50","v":2190922327.1199999},{"$f":"'B6-FinPos'!E50","v":0},{"$f":"'B6-FinPos'!F50","v":0},{"$f":"'B6-FinPos'!G50","v":0},{"$f":"'B6-FinPos'!H50","v":0},{"$f":"'B6-FinPos'!I50","v":290000},{"$f":"SUM(D41:H41)","v":290000},{"$f":"IF(C41=0,B41+I41,C41+I41)","v":2191212327.1199999},{"$f":"'B6-FinPos'!L50","v":4038876509},{"$f":"'B6-FinPos'!M50","v":4603621397}]
[]
["Cash flows"]
["Net cash from (used) operating",{"$f":"'B7-CFlow'!C19","v":215041000},{"$f":"'B7-CFlow'!D19","v":211101051},{"$f":"'B7-CFlow'!E19","v":0},{"$f":"'B7-CFlow'!F19","v":0},{"$f":"'B7-CFlow'!G19","v":0},{"$f":"'B7-CFlow'!H19","v":0},{"$f":"'B7-CFlow'!I19","v":-61155776},{"$f":"SUM(D44:H44)","v":-61155776},{"$f":"IF(C44=0,B44+I44,C44+I44)","v":149945275},{"$f":"'B7-CFlow'!L19","v":15083177.399999976},{"$f":"'B7-CFlow'!M19","v":27403786.269999981}]
["Net cash from (used) investing",{"$f":"'B7-CFlow'!C29","v":200374000},{"$f":"'B7-CFlow'!D29","v":-206106150},{"$f":"'B7-CFlow'!E29","v":0},{"$f":"'B7-CFlow'!F29","v":0},{"$f":"'B7-CFlow'!G29","v":0},{"$f":"'B7-CFlow'!H29","v":0},{"$f":"'B7-CFlow'!I29","v":-113975},{"$f":"SUM(D45:H45)","v":-113975},{"$f":"IF(C45=0,B45+I45,C45+I45)","v":-206220125},{"$f":"'B7-CFlow'!L29","v":211771000},{"$f":"'B7-CFlow'!M29","v":227138000}]
["Net cash from (used) financing",{"$f":"'B7-CFlow'!C38","v":-7960000},{"$f":"'B7-CFlow'!D38","v":0},{"$f":"'B7-CFlow'!E38","v":0},{"$f":"'B7-CFlow'!F38","v":0},{"$f":"'B7-CFlow'!G38","v":0},{"$f":"'B7-CFlow'!H38","v":0},{"$f":"'B7-CFlow'!I38","v":0},{"$f":"SUM(D46:H46)","v":0},{"$f":"IF(C46=0,B46+I46,C46+I46)","v":-7960000},{"$f":"'B7-CFlow'!L38","v":-8425000},{"$f":"'B7-CFlow'!M38","v":-8722000}]
["Cash/cash equivalents at the year end",{"$f":"'B7-CFlow'!C42","v":454854000},{"$f":"'B7-CFlow'!D42","v":69688047},{"$f":"'B7-CFlow'!E42","v":0},{"$f":"'B7-CFlow'!F42","v":0},{"$f":"'B7-CFlow'!G42","v":0},{"$f":"'B7-CFlow'!H42","v":0},{"$f":"'B7-CFlow'!I42","v":-61269751},{"$f":"SUM(D47:H47)","v":-61269751},{"$f":"IF(C47=0,B47+I47,C47+I47)","v":8418296},{"$f":"'B7-CFlow'!L42","v":218887473.39999998},{"$f":"'B7-CFlow'!M42","v":890274082.26999998}]
[]
["Cash backing/surplus reconciliation"]
["Cash and investments available",{"$f":"'B8-ResRecon'!C10","v":24377000},{"$f":"'B8-ResRecon'!D10","v":24377000},{"$f":"'B8-ResRecon'!E10","v":0},{"$f":"'B8-ResRecon'!F10","v":0},{"$f":"'B8-ResRecon'!G10","v":0},{"$f":"'B8-ResRecon'!H10","v":0},{"$f":"'B8-ResRecon'!I10","v":0},{"$f":"SUM(D50:H50)","v":0},{"$f":"IF(C50=0,B50+I50,C50+I50)","v":24377000},{"$f":"'B8-ResRecon'!L10","v":18712753},{"$f":"'B8-ResRecon'!M10","v":24851089}]
["Application of cash and investments",{"$f":"'B8-ResRecon'!C20","v":-301620816},{"$f":"'B8-ResRecon'!D20","v":-189181134},{"$f":"'B8-ResRecon'!E20","v":0},{"$f":"'B8-ResRecon'!F20","v":0},{"$f":"'B8-ResRecon'!G20","v":0},{"$f":"'B8-ResRecon'!H20","v":0},{"$f":"'B8-ResRecon'!I20","v":43561982},{"$f":"SUM(D51:H51)","v":43561982},{"$f":"IF(C51=0,B51+I51,C51+I51)","v":-145619152},{"$f":"'B8-ResRecon'!L20","v":-78173331},{"$f":"'B8-ResRecon'!M20","v":-184062299}]
["Balance - surplus (shortfall)",{"$f":"B50-B51","v":325997816},213558134,0,0,0,0,-43561982,-43561982,169996152,96886084,208913388]
[]
["Asset Management"]
["Asset register summary (WDV)",{"$f":"'B9-Asset'!C167","v":1785427147},{"$f":"'B9-Asset'!D167","v":1786730362.1900001},{"$f":"'B9-Asset'!E167","v":0},{"$f":"'B9-Asset'!F167","v":0},{"$f":"'B9-Asset'!G167","v":0},{"$f":"'B9-Asset'!H167","v":0},{"$f":"'B9-Asset'!I167","v":113975},{"$f":"SUM(D55:H55)","v":113975},{"$f":"IF(C55=0,B55+I55,C55+I55)","v":1786844337.1900001},{"$f":"'B9-Asset'!L167","v":3685970409},{"$f":"'B9-Asset'!M167","v":3945578770}]
["Depreciation & asset impairment",{"$f":"'B9-Asset'!C170","v":154536733},{"$f":"'B9-Asset'!D170","v":154536733},{"$f":"'B9-Asset'!E170","v":0},{"$f":"'B9-Asset'!F170","v":0},{"$f":"'B9-Asset'!G170","v":0},{"$f":"'B9-Asset'!H170","v":0},{"$f":"'B9-Asset'!I170","v":0},{"$f":"SUM(D56:H56)","v":0},{"$f":"IF(C56=0,B56+I56,C56+I56)","v":154536733},{"$f":"'B9-Asset'!L170","v":133503316},{"$f":"'B9-Asset'!M170","v":139644469}]
["Renewal and Upgrading of Existing Assets",{"$f":"'B9-Asset'!C39+'B9-Asset'!C71","v":70840253},{"$f":"'B9-Asset'!D39+'B9-Asset'!D71","v":102838664.02},{"$f":"'B9-Asset'!E39+'B9-Asset'!E71","v":0},{"$f":"'B9-Asset'!F39+'B9-Asset'!F71","v":0},{"$f":"'B9-Asset'!G39+'B9-Asset'!G71","v":0},{"$f":"'B9-Asset'!H39+'B9-Asset'!H71","v":0},{"$f":"'B9-Asset'!I39+'B9-Asset'!I71","v":0},{"$f":"SUM(D57:H57)","v":0},{"$f":"IF(C57=0,B57+I57,C57+I57)","v":102838664.02},{"$f":"'B9-Asset'!L39+'B9-Asset'!L71","v":70846258},{"$f":"'B9-Asset'!M39+'B9-Asset'!M71","v":68000000}]
["Repairs and Maintenance",{"$f":"'B9-Asset'!C171","v":65140000},{"$f":"'B9-Asset'!D171","v":47038475.019999996},{"$f":"'B9-Asset'!E171","v":0},{"$f":"'B9-Asset'!F171","v":0},{"$f":"'B9-Asset'!G171","v":0},{"$f":"'B9-Asset'!H171","v":0},{"$f":"'B9-Asset'!I171","v":0},{"$f":"SUM(D58:H58)","v":0},{"$f":"IF(C58=0,B58+I58,C58+I58)","v":47038475.019999996},{"$f":"'B9-Asset'!L171","v":42480000},{"$f":"'B9-Asset'!M171","v":46588800}]
[]
["Free services"]
["Cost of Free Basic Services provided",{"$f":"'B10-SerDel'!C62","v":66033000},{"$f":"'B10-SerDel'!D62","v":35533000},{"$f":"'B10-SerDel'!E62","v":0},{"$f":"'B10-SerDel'!F62","v":0},{"$f":"'B10-SerDel'!G62","v":0},{"$f":"'B10-SerDel'!H62","v":0},{"$f":"'B10-SerDel'!I62","v":0},{"$f":"'B10-SerDel'!J62","v":0},{"$f":"'B10-SerDel'!K62","v":66033000},{"$f":"'B10-SerDel'!L62","v":67010735},{"$f":"'B10-SerDel'!M62","v":38015217}]
["Revenue cost of free services provided",{"$f":"'B10-SerDel'!C81","v":4261000},{"$f":"'B10-SerDel'!D81","v":2668000},{"$f":"'B10-SerDel'!E81","v":0},{"$f":"'B10-SerDel'!F81","v":0},{"$f":"'B10-SerDel'!G81","v":0},{"$f":"'B10-SerDel'!H81","v":0},{"$f":"'B10-SerDel'!I81","v":0},{"$f":"'B10-SerDel'!J81","v":0},{"$f":"'B10-SerDel'!K81","v":4261000},{"$f":"'B10-SerDel'!L81","v":4339947},{"$f":"'B10-SerDel'!M81","v":4449879}]
["Households below minimum service level"]
["Water:",{"$f":"'B10-SerDel'!C16","v":12000},{"$f":"'B10-SerDel'!D16","v":0},{"$f":"'B10-SerDel'!E16","v":0},{"$f":"'B10-SerDel'!F16","v":0},{"$f":"'B10-SerDel'!G16","v":0},{"$f":"'B10-SerDel'!H16","v":0},{"$f":"'B10-SerDel'!I16","v":0},{"$f":"SUM(D64:H64)","v":0},{"$f":"IF(C64=0,B64+I64,C64+I64)","v":12000},{"$f":"'B10-SerDel'!L16","v":12000},{"$f":"'B10-SerDel'!M16","v":12000}]
["Sanitation/sewerage:",{"$f":"'B10-SerDel'!C28","v":39000},{"$f":"'B10-SerDel'!D28","v":0},{"$f":"'B10-SerDel'!E28","v":0},{"$f":"'B10-SerDel'!F28","v":0},{"$f":"'B10-SerDel'!G28","v":0},{"$f":"'B10-SerDel'!H28","v":0},{"$f":"'B10-SerDel'!I28","v":0},{"$f":"SUM(D65:H65)","v":0},{"$f":"IF(C65=0,B65+I65,C65+I65)","v":39000},{"$f":"'B10-SerDel'!L28","v":39000},{"$f":"'B10-SerDel'!M28","v":39000}]
["Energy:",{"$f":"'B10-SerDel'!C37","v":0},{"$f":"'B10-SerDel'!D37","v":0},{"$f":"'B10-SerDel'!E37","v":0},{"$f":"'B10-SerDel'!F37","v":0},{"$f":"'B10-SerDel'!G37","v":0},{"$f":"'B10-SerDel'!H37","v":0},{"$f":"'B10-SerDel'!I37","v":0},{"$f":"SUM(D66:H66)","v":0},{"$f":"IF(C66=0,B66+I66,C66+I66)","v":0},{"$f":"'B10-SerDel'!L37","v":0},{"$f":"'B10-SerDel'!M37","v":0}]
["Refuse:",{"$f":"'B10-SerDel'!C47","v":0},{"$f":"'B10-SerDel'!D47","v":0},{"$f":"'B10-SerDel'!E47","v":0},{"$f":"'B10-SerDel'!F47","v":0},{"$f":"'B10-SerDel'!G47","v":0},{"$f":"'B10-SerDel'!H47","v":0},{"$f":"'B10-SerDel'!I47","v":0},{"$f":"SUM(D67:H67)","v":0},{"$f":"IF(C67=0,B67+I67,C67+I67)","v":0},{"$f":"'B10-SerDel'!L47","v":0},{"$f":"'B10-SerDel'!M47","v":0}]
[]
["References"]
["1. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["2. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["3. Increases of funds approved under MFMA section 31"]
["4. Adjustments approved in accordance with MFMA section 29 "]
["5. Adjustments to transfers from National or Provincial Government"]
["6. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["7. G = B + C + D + E + F"]
["8. Adjusted Budget H = (A or A1/2 etc) + G"]

{"sheet":"B2-FinPerf SC","index":7,"n_rows":64,"n_cols":13,"rows_kept":64,"cut":false,"hidden":false,"merged":[[63,0,63,12],[58,0,58,12],[59,0,59,12],[61,0,61,12],[1,0,2,0],[1,1,2,1],[56,0,56,12],[57,0,57,12],[54,0,54,12],[1,2,1,10],[55,0,55,10]]}
[{"$f":"muni&\" - \"&_ADJ3&\" - \"&Date","v":"NW375 Moses Kotane - Table B2 Adjustments Budget Financial Performance (functional classification) - 44171"}]
[{"$f":"\"Standard \"&desc","v":"Standard Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,5,{"$f":"D4+1","v":6},7,8,9,10,11,12]
["R thousands","1, 4","A","A1","B","C","D","E","F","G","H"]
["Revenue - Functional"]
["Governance and administration",null,{"$f":"SUM(C8:C10)","v":481392100},{"$f":"SUM(D8:D10)","v":420101890},0,0,0,0,558000,{"$f":"SUM(J8:J10)","v":558000},{"$f":"SUM(K8:K10)","v":420659890},{"$f":"SUM(L8:L10)","v":528562196},{"$f":"SUM(M8:M10)","v":556613433}]
["Executive and council",null,{"$f":"B2B!C8","v":1695000},{"$f":"B2B!D8","v":1695000},{"$f":"B2B!E8","v":0},{"$f":"B2B!F8","v":0},{"$f":"B2B!G8","v":0},{"$f":"B2B!H8","v":0},{"$f":"B2B!I8","v":0},{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":1695000},{"$f":"B2B!L8","v":1827000},{"$f":"B2B!M8","v":940}]
["Finance and administration",null,{"$f":"B2B!C11","v":479697100},{"$f":"B2B!D11","v":418406890},{"$f":"B2B!E11","v":0},{"$f":"B2B!F11","v":0},{"$f":"B2B!G11","v":0},{"$f":"B2B!H11","v":0},{"$f":"B2B!I11","v":558000},{"$f":"SUM(E9:I9)","v":558000},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":418964890},{"$f":"B2B!L11","v":526735196},{"$f":"B2B!M11","v":556612493}]
["Internal audit",null,{"$f":"B2B!C25","v":0},{"$f":"B2B!D25","v":0},{"$f":"B2B!E25","v":0},{"$f":"B2B!F25","v":0},{"$f":"B2B!G25","v":0},{"$f":"B2B!H25","v":0},{"$f":"B2B!I25","v":0},{"$f":"SUM(E10:I10)","v":0},{"$f":"IF(D10=0,C10+J10,D10+J10)","v":0},{"$f":"B2B!L25","v":0},{"$f":"B2B!M25","v":0}]
["Community and public safety",null,{"$f":"SUM(C12:C16)","v":19245253},{"$f":"SUM(D12:D16)","v":35546241},0,0,0,0,-179487,{"$f":"SUM(J12:J16)","v":-179487},{"$f":"SUM(K12:K16)","v":35366754},{"$f":"SUM(L12:L16)","v":12998475},{"$f":"SUM(M12:M16)","v":11134000}]
["Community and social services",null,{"$f":"B2B!C28","v":14640253},{"$f":"B2B!D28","v":31941241},{"$f":"B2B!E28","v":0},{"$f":"B2B!F28","v":0},{"$f":"B2B!G28","v":0},{"$f":"B2B!H28","v":0},{"$f":"B2B!I28","v":-179487},{"$f":"SUM(E12:I12)","v":-179487},{"$f":"IF(D12=0,C12+J12,D12+J12)","v":31761754},{"$f":"B2B!L28","v":50000},{"$f":"B2B!M28","v":8050000}]
["Sport and recreation",null,{"$f":"B2B!C50","v":55000},{"$f":"B2B!D50","v":55000},{"$f":"B2B!E50","v":0},{"$f":"B2B!F50","v":0},{"$f":"B2B!G50","v":0},{"$f":"B2B!H50","v":0},{"$f":"B2B!I50","v":0},{"$f":"SUM(E13:I13)","v":0},{"$f":"IF(D13=0,C13+J13,D13+J13)","v":55000},{"$f":"B2B!L50","v":9898475},{"$f":"B2B!M50","v":34000}]
["Public safety",null,{"$f":"B2B!C56","v":4550000},{"$f":"B2B!D56","v":3550000},{"$f":"B2B!E56","v":0},{"$f":"B2B!F56","v":0},{"$f":"B2B!G56","v":0},{"$f":"B2B!H56","v":0},{"$f":"B2B!I56","v":0},{"$f":"SUM(E14:I14)","v":0},{"$f":"IF(D14=0,C14+J14,D14+J14)","v":3550000},{"$f":"B2B!L56","v":3050000},{"$f":"B2B!M56","v":3050000}]
["Housing",null,{"$f":"B2B!C65","v":0},{"$f":"B2B!D65","v":0},{"$f":"B2B!E65","v":0},{"$f":"B2B!F65","v":0},{"$f":"B2B!G65","v":0},{"$f":"B2B!H65","v":0},{"$f":"B2B!I65","v":0},{"$f":"SUM(E15:I15)","v":0},{"$f":"IF(D15=0,C15+J15,D15+J15)","v":0},{"$f":"B2B!L65","v":0},{"$f":"B2B!M65","v":0}]
["Health",null,{"$f":"B2B!C68","v":0},{"$f":"B2B!D68","v":0},{"$f":"B2B!E68","v":0},{"$f":"B2B!F68","v":0},{"$f":"B2B!G68","v":0},{"$f":"B2B!H68","v":0},{"$f":"B2B!I68","v":0},{"$f":"SUM(E16:I16)","v":0},{"$f":"IF(D16=0,C16+J16,D16+J16)","v":0},{"$f":"B2B!L68","v":0},{"$f":"B2B!M68","v":0}]
["Economic and environmental services",null,{"$f":"SUM(C18:C20)","v":67460875},{"$f":"SUM(D18:D20)","v":64920955},0,0,0,0,0,{"$f":"SUM(J18:J20)","v":0},{"$f":"SUM(K18:K20)","v":64920955},{"$f":"SUM(L18:L20)","v":65260549},{"$f":"SUM(M18:M20)","v":64504631}]
["Planning and development",null,{"$f":"B2B!C77","v":5267637},{"$f":"B2B!D77","v":3732637},{"$f":"B2B!E77","v":0},{"$f":"B2B!F77","v":0},{"$f":"B2B!G77","v":0},{"$f":"B2B!H77","v":0},{"$f":"B2B!I77","v":0},{"$f":"SUM(E18:I18)","v":0},{"$f":"IF(D18=0,C18+J18,D18+J18)","v":3732637},{"$f":"B2B!L77","v":4278767},{"$f":"B2B!M77","v":4504630}]
["Road transport",null,{"$f":"B2B!C88","v":62193238},{"$f":"B2B!D88","v":61188318},{"$f":"B2B!E88","v":0},{"$f":"B2B!F88","v":0},{"$f":"B2B!G88","v":0},{"$f":"B2B!H88","v":0},{"$f":"B2B!I88","v":0},{"$f":"SUM(E19:I19)","v":0},{"$f":"IF(D19=0,C19+J19,D19+J19)","v":61188318},{"$f":"B2B!L88","v":60981782},{"$f":"B2B!M88","v":60000001}]
["Environmental protection",null,{"$f":"B2B!C93","v":0},{"$f":"B2B!D93","v":0},{"$f":"B2B!E93","v":0},{"$f":"B2B!F93","v":0},{"$f":"B2B!G93","v":0},{"$f":"B2B!H93","v":0},{"$f":"B2B!I93","v":0},{"$f":"SUM(E20:I20)","v":0},{"$f":"IF(D20=0,C20+J20,D20+J20)","v":0},{"$f":"B2B!L93","v":0},{"$f":"B2B!M93","v":0}]
["Trading services",null,{"$f":"SUM(C22:C25)","v":467992300},{"$f":"SUM(D22:D25)","v":459441718.99000001},0,0,0,0,0,0,459441718.99000001,491878696,526440606]
["Energy sources",null,{"$f":"B2B!C101","v":19857810},{"$f":"B2B!D101","v":20416973},{"$f":"B2B!E101","v":0},{"$f":"B2B!F101","v":0},{"$f":"B2B!G101","v":0},{"$f":"B2B!H101","v":0},{"$f":"B2B!I101","v":0},{"$f":"SUM(E22:I22)","v":0},{"$f":"IF(D22=0,C22+J22,D22+J22)","v":20416973},{"$f":"B2B!L101","v":11577741},{"$f":"B2B!M101","v":12557370}]
["Water management",null,{"$f":"B2B!C105","v":324371603},{"$f":"B2B!D105","v":340838082},{"$f":"B2B!E105","v":0},{"$f":"B2B!F105","v":0},{"$f":"B2B!G105","v":0},{"$f":"B2B!H105","v":0},{"$f":"B2B!I105","v":0},{"$f":"SUM(E23:I23)","v":0},{"$f":"IF(D23=0,C23+J23,D23+J23)","v":340838082},{"$f":"B2B!L105","v":358598493},{"$f":"B2B!M105","v":371165069}]
["Waste water management",null,{"$f":"B2B!C109","v":43021550},{"$f":"B2B!D109","v":33242236},{"$f":"B2B!E109","v":0},{"$f":"B2B!F109","v":0},{"$f":"B2B!G109","v":0},{"$f":"B2B!H109","v":0},{"$f":"B2B!I109","v":0},{"$f":"SUM(E24:I24)","v":0},{"$f":"IF(D24=0,C24+J24,D24+J24)","v":33242236},{"$f":"B2B!L109","v":47377755},{"$f":"B2B!M109","v":47595969}]
["Waste management",null,{"$f":"B2B!C114","v":80741337},{"$f":"B2B!D114","v":64944427.990000002},{"$f":"B2B!E114","v":0},{"$f":"B2B!F114","v":0},{"$f":"B2B!G114","v":0},{"$f":"B2B!H114","v":0},{"$f":"B2B!I114","v":0},{"$f":"SUM(E25:I25)","v":0},{"$f":"IF(D25=0,C25+J25,D25+J25)","v":64944427.990000002},{"$f":"B2B!L114","v":74324707},{"$f":"B2B!M114","v":95122198}]
["Other",null,{"$f":"B2B!C119","v":0},{"$f":"B2B!D119","v":0},{"$f":"B2B!E119","v":0},{"$f":"B2B!F119","v":0},{"$f":"B2B!G119","v":0},{"$f":"B2B!H119","v":0},{"$f":"B2B!I119","v":0},{"$f":"SUM(E26:I26)","v":0},{"$f":"IF(D26=0,C26+J26,D26+J26)","v":0},{"$f":"B2B!L119","v":0},{"$f":"B2B!M119","v":0}]
[{"$f":"\"Total \"&A6","v":"Total Revenue - Functional"},2,{"$f":"C7+C11+C17+C21+C26","v":1036090528},{"$f":"D7+D11+D17+D21+D26","v":980010804.99000001},0,0,0,0,378513,378513,980389317.99000001,1098699916,1158692670]
[]
["Expenditure - Functional"]
["Governance and administration",null,{"$f":"SUM(C31:C33)","v":395399683},{"$f":"SUM(D31:D33)","v":330043524.45999998},0,0,0,0,2568000,{"$f":"SUM(J31:J33)","v":2568000},{"$f":"SUM(K31:K33)","v":332611524.45999998},{"$f":"SUM(L31:L33)","v":349715191},{"$f":"SUM(M31:M33)","v":368351423}]
["Executive and council",null,{"$f":"B2B!C130","v":107752328},{"$f":"B2B!D130","v":83503014.239999995},{"$f":"B2B!E130","v":0},{"$f":"B2B!F130","v":0},{"$f":"B2B!G130","v":0},{"$f":"B2B!H130","v":0},{"$f":"B2B!I130","v":2300000},{"$f":"SUM(E31:I31)","v":2300000},{"$f":"IF(D31=0,C31+J31,D31+J31)","v":85803014.239999995},{"$f":"B2B!L130","v":87162222},{"$f":"B2B!M130","v":93378791}]
["Finance and administration",null,{"$f":"B2B!C133","v":283949994},{"$f":"B2B!D133","v":243078499.21000001},{"$f":"B2B!E133","v":0},{"$f":"B2B!F133","v":0},{"$f":"B2B!G133","v":0},{"$f":"B2B!H133","v":0},{"$f":"B2B!I133","v":268000},{"$f":"SUM(E32:I32)","v":268000},{"$f":"IF(D32=0,C32+J32,D32+J32)","v":243346499.21000001},{"$f":"B2B!L133","v":258527601},{"$f":"B2B!M133","v":270737504}]
["Internal audit",null,{"$f":"B2B!C147","v":3697361},{"$f":"B2B!D147","v":3462011.01},{"$f":"B2B!E147","v":0},{"$f":"B2B!F147","v":0},{"$f":"B2B!G147","v":0},{"$f":"B2B!H147","v":0},{"$f":"B2B!I147","v":0},{"$f":"SUM(E33:I33)","v":0},{"$f":"IF(D33=0,C33+J33,D33+J33)","v":3462011.01},{"$f":"B2B!L147","v":4025368},{"$f":"B2B!M147","v":4235128}]
["Community and public safety",null,{"$f":"SUM(C35:C39)","v":101814686},{"$f":"SUM(D35:D39)","v":81103906.040000007},0,0,0,0,-179487,{"$f":"SUM(J35:J39)","v":-179487},{"$f":"SUM(K35:K39)","v":80924419.040000007},{"$f":"SUM(L35:L39)","v":103872294},{"$f":"SUM(M35:M39)","v":108711163}]
["Community and social services",null,{"$f":"B2B!C150","v":30482848},{"$f":"B2B!D150","v":23105416},{"$f":"B2B!E150","v":0},{"$f":"B2B!F150","v":0},{"$f":"B2B!G150","v":0},{"$f":"B2B!H150","v":0},{"$f":"B2B!I150","v":-179487},{"$f":"SUM(E35:I35)","v":-179487},{"$f":"IF(D35=0,C35+J35,D35+J35)","v":22925929},{"$f":"B2B!L150","v":26180426},{"$f":"B2B!M150","v":27495935}]
["Sport and recreation",null,{"$f":"B2B!C172","v":29288851},{"$f":"B2B!D172","v":25715503.010000002},{"$f":"B2B!E172","v":0},{"$f":"B2B!F172","v":0},{"$f":"B2B!G172","v":0},{"$f":"B2B!H172","v":0},{"$f":"B2B!I172","v":0},{"$f":"SUM(E36:I36)","v":0},{"$f":"IF(D36=0,C36+J36,D36+J36)","v":25715503.010000002},{"$f":"B2B!L172","v":42725232},{"$f":"B2B!M172","v":44784178}]
["Public safety",null,{"$f":"B2B!C178","v":42042987},{"$f":"B2B!D178","v":32282987.030000001},{"$f":"B2B!E178","v":0},{"$f":"B2B!F178","v":0},{"$f":"B2B!G178","v":0},{"$f":"B2B!H178","v":0},{"$f":"B2B!I178","v":0},{"$f":"SUM(E37:I37)","v":0},{"$f":"IF(D37=0,C37+J37,D37+J37)","v":32282987.030000001},{"$f":"B2B!L178","v":34966636},{"$f":"B2B!M178","v":36431050}]
["Housing",null,{"$f":"B2B!C187","v":0},{"$f":"B2B!D187","v":0},{"$f":"B2B!E187","v":0},{"$f":"B2B!F187","v":0},{"$f":"B2B!G187","v":0},{"$f":"B2B!H187","v":0},{"$f":"B2B!I187","v":0},{"$f":"SUM(E38:I38)","v":0},{"$f":"IF(D38=0,C38+J38,D38+J38)","v":0},{"$f":"B2B!L187","v":0},{"$f":"B2B!M187","v":0}]
["Health",null,{"$f":"B2B!C190","v":0},{"$f":"B2B!D190","v":0},{"$f":"B2B!E190","v":0},{"$f":"B2B!F190","v":0},{"$f":"B2B!G190","v":0},{"$f":"B2B!H190","v":0},{"$f":"B2B!I190","v":0},{"$f":"SUM(E39:I39)","v":0},{"$f":"IF(D39=0,C39+J39,D39+J39)","v":0},{"$f":"B2B!L190","v":0},{"$f":"B2B!M190","v":0}]
["Economic and environmental services",null,{"$f":"SUM(C41:C43)","v":115203608},{"$f":"SUM(D41:D43)","v":97236854.060000002},0,0,0,0,0,{"$f":"SUM(J41:J43)","v":0},{"$f":"SUM(K41:K43)","v":97236854.060000002},{"$f":"SUM(L41:L43)","v":86089149},{"$f":"SUM(M41:M43)","v":90942754}]
["Planning and development",null,{"$f":"B2B!C199","v":31369359},{"$f":"B2B!D199","v":25454605.020000003},{"$f":"B2B!E199","v":0},{"$f":"B2B!F199","v":0},{"$f":"B2B!G199","v":0},{"$f":"B2B!H199","v":0},{"$f":"B2B!I199","v":0},{"$f":"SUM(E41:I41)","v":0},{"$f":"IF(D41=0,C41+J41,D41+J41)","v":25454605.020000003},{"$f":"B2B!L199","v":24460808},{"$f":"B2B!M199","v":26477739}]
["Road transport",null,{"$f":"B2B!C210","v":83834249},{"$f":"B2B!D210","v":71782249.040000007},{"$f":"B2B!E210","v":0},{"$f":"B2B!F210","v":0},{"$f":"B2B!G210","v":0},{"$f":"B2B!H210","v":0},{"$f":"B2B!I210","v":0},{"$f":"SUM(E42:I42)","v":0},{"$f":"IF(D42=0,C42+J42,D42+J42)","v":71782249.040000007},{"$f":"B2B!L210","v":61628341},{"$f":"B2B!M210","v":64465015}]
["Environmental protection",null,{"$f":"B2B!C215","v":0},{"$f":"B2B!D215","v":0},{"$f":"B2B!E215","v":0},{"$f":"B2B!F215","v":0},{"$f":"B2B!G215","v":0},{"$f":"B2B!H215","v":0},{"$f":"B2B!I215","v":0},{"$f":"SUM(E43:I43)","v":0},{"$f":"IF(D43=0,C43+J43,D43+J43)","v":0},{"$f":"B2B!L215","v":0},{"$f":"B2B!M215","v":0}]
["Trading services",null,{"$f":"SUM(C45:C48)","v":354822345},{"$f":"SUM(D45:D48)","v":397202950.30999994},0,0,0,0,-2300000,-2300000,394902950.30999994,398828628,412283452]
["Energy sources",null,{"$f":"B2B!C223","v":31908720},{"$f":"B2B!D223","v":31753758},{"$f":"B2B!E223","v":0},{"$f":"B2B!F223","v":0},{"$f":"B2B!G223","v":0},{"$f":"B2B!H223","v":0},{"$f":"B2B!I223","v":0},{"$f":"SUM(E45:I45)","v":0},{"$f":"IF(D45=0,C45+J45,D45+J45)","v":31753758},{"$f":"B2B!L223","v":19598588},{"$f":"B2B!M223","v":20384798}]
["Water management",null,{"$f":"B2B!C227","v":241659927},{"$f":"B2B!D227","v":290898577.25999999},{"$f":"B2B!E227","v":0},{"$f":"B2B!F227","v":0},{"$f":"B2B!G227","v":0},{"$f":"B2B!H227","v":0},{"$f":"B2B!I227","v":-2300000},{"$f":"SUM(E46:I46)","v":-2300000},{"$f":"IF(D46=0,C46+J46,D46+J46)","v":288598577.25999999},{"$f":"B2B!L227","v":306488832},{"$f":"B2B!M227","v":314139435}]
["Waste water management",null,{"$f":"B2B!C231","v":18784460},{"$f":"B2B!D231","v":24789565.030000001},{"$f":"B2B!E231","v":0},{"$f":"B2B!F231","v":0},{"$f":"B2B!G231","v":0},{"$f":"B2B!H231","v":0},{"$f":"B2B!I231","v":0},{"$f":"SUM(E47:I47)","v":0},{"$f":"IF(D47=0,C47+J47,D47+J47)","v":24789565.030000001},{"$f":"B2B!L231","v":21228371},{"$f":"B2B!M231","v":22743337}]
["Waste management",null,{"$f":"B2B!C236","v":62469238},{"$f":"B2B!D236","v":49761050.020000003},{"$f":"B2B!E236","v":0},{"$f":"B2B!F236","v":0},{"$f":"B2B!G236","v":0},{"$f":"B2B!H236","v":0},{"$f":"B2B!I236","v":0},{"$f":"SUM(E48:I48)","v":0},{"$f":"IF(D48=0,C48+J48,D48+J48)","v":49761050.020000003},{"$f":"B2B!L236","v":51512837},{"$f":"B2B!M236","v":55015882}]
["Other",null,{"$f":"B2B!C241","v":0},{"$f":"B2B!D241","v":0},{"$f":"B2B!E241","v":0},{"$f":"B2B!F241","v":0},{"$f":"B2B!G241","v":0},{"$f":"B2B!H241","v":0},{"$f":"B2B!I241","v":0},{"$f":"SUM(E49:I49)","v":0},{"$f":"IF(D49=0,C49+J49,D49+J49)","v":0},{"$f":"B2B!L241","v":0},{"$f":"B2B!M241","v":0}]
[{"$f":"\"Total \"&A29","v":"Total Expenditure - Functional"},3,{"$f":"C30+C34+C40+C44+C49","v":967240322},{"$f":"D30+D34+D40+D44+D49","v":905587234.86999989},0,0,0,0,88513,88513,905675747.86999989,938505262,980288792]
["Surplus/ (Deficit) for the year",null,{"$f":"C27-C50","v":68850206},74423570.120000124,0,0,0,0,290000,290000,74713570.120000124,160194654,178403878]
[{"$f":"head27a","v":"References"}]
["1. Government Finance Statistics Functions and Sub-functions are standardised to assist the compilation of national and international accounts for comparison purposes"]
["2. Total Revenue by standard classification must reconcile to Total Operating Revenue shown in the Adjustments Budget Financial Performance (revenue and expenditure)"]
["3. Total Operating Expenditure by standard classification must reconcile to Total Operating Expenditure shown in the Adjustments Budget Financial Performance (revenue and expenditure)"]
["4. All amounts must be classified under a standard classification (modified GFS). The GFS function 'Other' is only for Abbatoirs, Air Transport, Markets and Tourism - and if used must be supported by footnotes. Nothing else may be placed under 'Other'. Assign associate share to relevant classification"]
["5. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["6. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["7. Increases of funds approved under MFMA section 31"]
["8. Adjustments approved in accordance with MFMA section 29 "]
["9. Adjustments to transfers from National or Provincial Government"]
["10. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["11. G = B + C + D + E + F"]
["12. Adjusted Budget H = (A or A1/2 etc) + G"]

{"sheet":"B2B","index":8,"n_rows":254,"n_cols":13,"rows_kept":254,"cut":false,"hidden":false,"merged":[[253,0,253,10],[1,2,1,10]]}
[{"$f":"muni&\" - \"&_ADJ3&\" - B\"&\" - \"&Date","v":"NW375 Moses Kotane - Table B2 Adjustments Budget Financial Performance (functional classification) - B - 44171"}]
[{"$f":"\"Standard Classification \"&desc","v":"Standard Classification Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,5,{"$f":"D4+1","v":6},7,8,9,10,11,12]
["R thousand",1,"A","A1","B","C","D","E","F","G","H"]
["Revenue - Functional"]
["Municipal governance and administration",null,{"$f":"C8+C11+C25","v":481392100},420101890,0,0,0,0,558000,{"$f":"SUM(E7:I7)","v":558000},{"$f":"IF(D7=0,C7+J7,D7+J7)","v":420659890},{"$f":"L8+L11+L25","v":528562196},{"$f":"M8+M11+M25","v":556613433}]
["Executive and council",null,{"$f":"SUM(C9:C10)","v":1695000},{"$f":"SUM(D9:D10)","v":1695000},0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":1695000},{"$f":"SUM(L9:L10)","v":1827000},{"$f":"SUM(M9:M10)","v":940}]
["Mayor and Council",null,1695000,1695000,0,0,0,0,0,{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":1695000},1827000,940]
["Municipal Manager, Town Secretary and Chief Executive",null,null,null,null,null,null,null,null,{"$f":"SUM(E10:I10)","v":0},{"$f":"IF(D10=0,C10+J10,D10+J10)","v":0}]
["Finance and administration",null,{"$f":"SUM(C12:C24)","v":479697100},418406890,0,0,0,0,558000,558000,418964890,{"$f":"SUM(L12:L24)","v":526735196},{"$f":"SUM(M12:M24)","v":556612493}]
["Administrative and Corporate Support",null,0,0,0,0,0,0,0,0,0,0,0]
["Asset Management",null,null,null,null,null,null,null,null,0,0]
["Finance",null,479197100,417906890,0,0,0,0,290000,290000,418196890,526235196,556112493]
["Fleet Management",null,0,0,0,0,0,0,0,0,0,0,0]
["Human Resources",null,500000,500000,0,0,0,0,268000,268000,768000,500000,500000]
["Information Technology",null,0,0,0,0,0,0,0,0,0,0,0]
["Legal Services",null,null,null,null,null,null,null,null,0,0]
["Marketing, Customer Relations, Publicity and Media Co-ordination",null,null,null,null,null,null,null,null,0,0]
["Property Services",null,null,null,null,null,null,null,null,0,0]
["Risk Management",null,null,null,null,null,null,null,null,0,0]
["Security Services",null,null,null,null,null,null,null,null,0,0]
["Supply Chain Management ",null,null,null,null,null,null,null,null,0,0]
["Valuation Service",null,null,null,null,null,null,null,null,0,0]
["Internal audit",null,{"$f":"SUM(C26:C26)","v":0},0,0,0,0,0,0,0,0,0,0]
["Governance Function",null,null,null,null,null,null,null,null,0,0]
["Community and public safety",null,{"$f":"C28+C50+C56+C65+C68","v":19245253},35546241,0,0,0,0,-179487,-179487,35366754,{"$f":"L28+L50+L56+L65+L68","v":12998475},{"$f":"M28+M50+M56+M65+M68","v":11134000}]
["Community and social services",null,{"$f":"SUM(C29:C49)","v":14640253},31941241,0,0,0,0,-179487,-179487,31761754,50000,8050000]
["Aged Care",null,null,null,null,null,null,null,null,0,0]
["Agricultural",null,null,null,null,null,null,null,null,0,0]
["Animal Care and Diseases",null,null,null,null,null,null,null,null,0,0]
["Cemeteries, Funeral Parlours and Crematoriums",null,10000,10000,0,0,0,0,0,0,10000,10000,10000]
["Child Care Facilities",null,null,null,null,null,null,null,null,0,0]
["Community Halls and Facilities",null,14590253,30726754,0,0,0,0,0,0,30726754,0,8000000]
["Consumer Protection",null,null,null,null,null,null,null,null,0,0]
["Cultural Matters",null,null,null,null,null,null,null,null,0,0]
["Disaster Management",null,null,null,null,null,null,null,null,0,0]
["Education",null,null,null,null,null,null,null,null,0,0]
["Indigenous and Customary Law",null,null,null,null,null,null,null,null,0,0]
["Industrial Promotion",null,null,null,null,null,null,null,null,0,0]
["Language Policy",null,null,null,null,null,null,null,null,0,0]
["Libraries and Archives",null,40000,1204487,0,0,0,0,-179487,-179487,1025000,40000,40000]
["Literacy Programmes",null,null,null,null,null,null,null,null,0,0]
["Media Services",null,null,null,null,null,null,null,null,0,0]
["Museums and Art Galleries",null,null,null,null,null,null,null,null,0,0]
["Population Development",null,null,null,null,null,null,null,null,0,0]
["Provincial Cultural Matters",null,null,null,null,null,null,null,null,0,0]
["Theatres",null,null,null,null,null,null,null,null,0,0]
["Zoo's",null,null,null,null,null,null,null,null,0,0]
["Sport and recreation",null,{"$f":"SUM(C51:C55)","v":55000},55000,0,0,0,0,0,0,55000,9898475,34000]
["Beaches and Jetties ",null,null,null,null,null,null,null,null,0,0]
["Casinos, Racing, Gambling, Wagering",null,null,null,null,null,null,null,null,0,0]
["Community Parks (including Nurseries)",null,null,null,null,null,null,null,null,0,0]
["Recreational Facilities",null,55000,55000,0,0,0,0,0,0,55000,9898475,34000]
["Sports Grounds and Stadiums",null,null,null,null,null,null,null,null,0,0]
["Public safety",null,{"$f":"SUM(C57:C64)","v":4550000},3550000,0,0,0,0,0,0,3550000,3050000,3050000]
["Civil Defence",null,0,0,0,0,0,0,0,0,0,0,0]
["Cleansing",null,null,null,null,null,null,null,null,0,0]
["Control of Public Nuisances",null,null,null,null,null,null,null,null,0,0]
["Fencing and Fences ",null,null,null,null,null,null,null,null,0,0]
["Fire Fighting and Protection",null,null,null,null,null,null,null,null,0,0]
["Licensing and Control of Animals",null,null,null,null,null,null,null,null,0,0]
["Police Forces, Traffic and Street Parking Control",null,4550000,3550000,0,0,0,0,0,{"$f":"SUM(E63:I63)","v":0},{"$f":"IF(D63=0,C63+J63,D63+J63)","v":3550000},3050000,3050000]
["Pounds",null,null,null,null,null,null,null,null,0,0]
["Housing",null,{"$f":"SUM(C66:C67)","v":0},{"$f":"SUM(D66:D67)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(L66:L67)","v":0},{"$f":"SUM(M66:M67)","v":0}]
["Housing",null,null,null,null,null,null,null,null,0,0]
["Informal Settlements",null,null,null,null,null,null,null,null,0,0]
["Health",null,{"$f":"SUM(C69:C75)","v":0},{"$f":"SUM(D69:D75)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(L69:L75)","v":0},{"$f":"SUM(M69:M75)","v":0}]
["Ambulance",null,null,null,null,null,null,null,null,0,0]
["Health Services",null,null,null,null,null,null,null,null,0,0]
["Laboratory Services",null,null,null,null,null,null,null,null,0,0]
["Food Control",null,null,null,null,null,null,null,null,0,0]
["Health Surveillance and Prevention of Communicable Diseases including immunizations",null,null,null,null,null,null,null,null,0,0]
["Vector Control",null,null,null,null,null,null,null,null,0,0]
["Chemical Safety",null,null,null,null,null,null,null,null,{"$f":"SUM(E75:I75)","v":0},{"$f":"IF(D75=0,C75+J75,D75+J75)","v":0}]
["Economic and environmental services",null,{"$f":"C77+C88+C93","v":67460875},64920955,0,0,0,0,0,0,64920955,{"$f":"L77+L88+L93","v":65260549},{"$f":"M77+M88+M93","v":64504631}]
["Planning and development",null,{"$f":"SUM(C78:C87)","v":5267637},{"$f":"SUM(D78:D87)","v":3732637},0,0,0,0,0,0,3732637,{"$f":"SUM(L78:L87)","v":4278767},{"$f":"SUM(M78:M87)","v":4504630}]
["Billboards",null,null,null,null,null,null,null,null,0,0]
["Corporate Wide Strategic Planning (IDPs, LEDs)",null,null,null,null,null,null,null,null,0,0]
["Central City Improvement District",null,null,null,null,null,null,null,null,0,0]
["Development Facilitation",null,null,null,null,null,null,null,null,0,0]
["Economic Development/Planning",null,0,0,0,0,0,0,0,0,0,0,0]
["Regional Planning and Development",null,null,null,null,null,null,null,null,0,0]
["Town Planning, Building Regulations and Enforcement, and City Engineer",null,100000,150000,0,0,0,0,0,0,150000,100000,100000]
["Project Management Unit",null,5167637,3582637,0,0,0,0,0,0,3582637,4178767,4404630]
["Provincial Planning",null,null,null,null,null,null,null,null,0,0]
["Support to Local Municipalities",null,null,null,null,null,null,null,null,0,0]
["Road transport",null,{"$f":"SUM(C89:C92)","v":62193238},61188318,0,0,0,0,0,0,61188318,{"$f":"SUM(L89:L92)","v":60981782},{"$f":"SUM(M89:M92)","v":60000001}]
["Public Transport",null,null,null,null,null,null,null,null,0,0]
["Road and Traffic Regulation",null,null,null,null,null,null,null,null,0,0]
["Roads",null,62193238,61188318,0,0,0,0,0,0,61188318,60981782,60000001]
["Taxi Ranks",null,null,null,null,null,null,null,null,0,0]
["Environmental protection",null,{"$f":"SUM(C94:C99)","v":0},{"$f":"SUM(D94:D99)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(L94:L99)","v":0},{"$f":"SUM(M94:M99)","v":0}]
["Biodiversity and Landscape",null,null,null,null,null,null,null,null,0,0]
["Coastal Protection",null,null,null,null,null,null,null,null,0,0]
["Indigenous Forests",null,null,null,null,null,null,null,null,0,0]
["Nature Conservation",null,null,null,null,null,null,null,null,0,0]
["Pollution Control",null,null,null,null,null,null,null,null,0,0]
["Soil Conservation",null,null,null,null,null,null,null,null,0,0]
["Trading services",null,{"$f":"C101+C105+C109+C114","v":467992300},{"$f":"D101+D105+D109+D114","v":459441718.99000001},0,0,0,0,0,0,459441718.99000001,491878696,526440606]
["Energy sources",null,{"$f":"SUM(C102:C104)","v":19857810},{"$f":"SUM(D102:D104)","v":20416973},0,0,0,0,0,0,20416973,{"$f":"SUM(L102:L104)","v":11577741},{"$f":"SUM(M102:M104)","v":12557370}]
["Electricity ",null,null,null,null,null,null,null,null,0,0]
["Street Lighting and Signal Systems",null,19857810,20416973,0,0,0,0,0,0,20416973,11577741,12557370]
["Nonelectric Energy",null,null,null,null,null,null,null,null,0,0]
["Water management",null,{"$f":"SUM(C106:C108)","v":324371603},{"$f":"SUM(D106:D108)","v":340838082},0,0,0,0,0,0,340838082,{"$f":"SUM(L106:L108)","v":358598493},{"$f":"SUM(M106:M108)","v":371165069}]
["Water Treatment",null,236371603,252838082,0,0,0,0,0,0,252838082,262711493,265760069]
["Water Distribution",null,88000000,88000000,0,0,0,0,0,0,88000000,95887000,105405000]
["Water Storage",null,null,null,null,null,null,null,null,0,0]
["Waste water management",null,{"$f":"SUM(C110:C113)","v":43021550},{"$f":"SUM(D110:D113)","v":33242236},0,0,0,0,0,0,33242236,{"$f":"SUM(L110:L113)","v":47377755},{"$f":"SUM(M110:M113)","v":47595969}]
["Public Toilets",null,null,null,null,null,null,null,null,0,0]
["Sewerage",null,43021550,33242236,0,0,0,0,0,0,33242236,47377755,47595969]
["Storm Water Management",null,0,0,0,0,0,0,0,0,0,0,0]
["Waste Water Treatment",null,null,null,null,null,null,null,null,0,0]
["Waste management",null,{"$f":"SUM(C115:C118)","v":80741337},{"$f":"SUM(D115:D118)","v":64944427.990000002},0,0,0,0,0,0,64944427.990000002,74324707,{"$f":"SUM(M115:M118)","v":95122198}]
["Recycling",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Disposal (Landfill Sites)",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Removal",null,80741337,64944427.990000002,0,0,0,0,0,0,64944427.990000002,74324707,95122198]
["Street Cleaning",null,null,null,null,null,null,null,null,0,0]
["Other",null,{"$f":"SUM(C120:C125)","v":0},0,0,0,0,0,0,0,0,0,0]
["Abattoirs",null,null,null,null,null,null,null,null,0,0]
["Air Transport",null,null,null,null,null,null,null,null,0,0]
["Forestry ",null,null,null,null,null,null,null,null,0,0]
["Licensing and Regulation",null,null,null,null,null,null,null,null,0,0]
["Markets",null,null,null,null,null,null,null,null,0,0]
["Tourism",null,null,null,null,null,null,null,null,0,0]
[{"$f":"\"Total \"&A6","v":"Total Revenue - Functional"},2,{"$f":"C7+C27+C76+C100+C119","v":1036090528},980010804.99000001,0,0,0,0,378513,378513,980389317.99000001,{"$f":"L7+L27+L76+L100+L119","v":1098699916},{"$f":"M7+M27+M76+M100+M119","v":1158692670}]
[null,null,null,null,null,null,null,null,null,0,0]
["Expenditure - Functional",null,null,null,null,null,null,null,null,0,0]
[{"$f":"A7","v":"Municipal governance and administration"},null,{"$f":"C130+C133+C147","v":395399683},330043524.45999998,0,0,0,0,2568000,2568000,332611524.45999998,{"$f":"L130+L133+L147","v":349715191},{"$f":"M130+M133+M147","v":368351423}]
["Executive and council",null,{"$f":"SUM(C131:C132)","v":107752328},83503014.239999995,0,0,0,0,2300000,2300000,85803014.239999995,{"$f":"SUM(L131:L132)","v":87162222},{"$f":"SUM(M131:M132)","v":93378791}]
["Mayor and Council",null,82049260,66834252.140000001,0,0,0,0,2300000,2300000,69134252.140000001,69748020,74930833]
["Municipal Manager, Town Secretary and Chief Executive",null,25703068,16668762.1,0,0,0,0,0,0,16668762.1,17414202,18447958]
["Finance and administration",null,{"$f":"SUM(C134:C146)","v":283949994},243078499.21000001,0,0,0,0,268000,268000,243346499.21000001,{"$f":"SUM(L134:L146)","v":258527601},{"$f":"SUM(M134:M146)","v":270737504}]
["Administrative and Corporate Support",null,46926909,39692827.020000003,0,0,0,0,0,0,39692827.020000003,44617622,46699544]
["Asset Management",null,11318519,6766219,0,0,0,0,0,0,6766219,13650935,14219330]
["Finance",null,108624212,107446118.08,0,0,0,0,0,{"$f":"SUM(E136:I136)","v":0},{"$f":"IF(D136=0,C136+J136,D136+J136)","v":107446118.08},123655478,129584839]
["Fleet Management",null,17935850,15293850.029999999,0,0,0,0,0,0,15293850.029999999,19271527,20217468]
["Human Resources",null,16861620,11699680.02,0,0,0,0,268000,268000,11967680.02,14849578,15695857]
["Information Technology",null,74955189,54785380.039999999,0,0,0,0,0,0,54785380.039999999,32329546,33659955]
["Legal Services",null,1178495,1148495.02,0,0,0,0,0,0,1148495.02,1309413,1374883]
["Marketing, Customer Relations, Publicity and Media Co-ordination",null,null,null,null,null,null,null,null,0,0]
["Property Services",null,null,null,null,null,null,null,null,0,0]
["Risk Management",null,0,0,0,0,0,0,0,0,0,941888,988982]
["Security Services",null,null,null,null,null,null,null,null,0,0]
["Supply Chain Management ",null,6149200,6245930,0,0,0,0,0,0,6245930,7901614,8296646]
["Valuation Service",null,null,null,null,null,null,null,null,0,0]
["Internal audit",null,{"$f":"SUM(C148:C148)","v":3697361},3462011.01,0,0,0,0,0,0,3462011.01,4025368,4235128]
["Governance Function",null,3697361,3462011.01,0,0,0,0,0,0,3462011.01,4025368,4235128]
["Community and public safety",null,{"$f":"C150+C172+C178+C187+C190","v":101814686},81103906.040000007,0,0,0,0,-179487,-179487,80924419.040000007,{"$f":"L150+L172+L178+L187+L190","v":103872294},{"$f":"M150+M172+M178+M187+M190","v":108711163}]
["Community and social services",null,{"$f":"SUM(C151:C171)","v":30482848},23105416,0,0,0,0,-179487,-179487,22925929,{"$f":"SUM(L151:L171)","v":26180426},{"$f":"SUM(M151:M171)","v":27495935}]
["Aged Care",null,null,null,null,null,null,null,null,0,0]
["Agricultural",null,0,0,0,0,0,0,0,0,0,8157250,8565113]
["Animal Care and Diseases",null,null,null,null,null,null,null,null,0,0]
["Cemeteries, Funeral Parlours and Crematoriums",null,605000,605000,0,0,0,0,0,0,605000,3978010,4165699]
["Child Care Facilities",null,null,null,null,null,null,null,null,0,0]
["Community Halls and Facilities",null,26561133,19069214,0,0,0,0,0,0,19069214,9784996,10271545]
["Consumer Protection",null,null,null,null,null,null,null,null,0,0]
["Cultural Matters",null,null,null,null,null,null,null,null,0,0]
["Disaster Management",null,660000,110000,0,0,0,0,0,0,110000,2486022,2624448]
["Education",null,null,null,null,null,null,null,null,0,0]
[{"$f":"A39","v":"Indigenous and Customary Law"},null,null,null,null,null,null,null,null,0,0]
["Industrial Promotion",null,null,null,null,null,null,null,null,0,0]
["Language Policy",null,null,null,null,null,null,null,null,0,0]
["Libraries and Archives",null,2656715,3321202,0,0,0,0,-179487,-179487,3141715,1774148,1869130]
["Literacy Programmes",null,null,null,null,null,null,null,null,0,0]
["Media Services",null,0,0,0,0,0,0,0,0,0,0,0]
["Museums and Art Galleries",null,0,0,0,0,0,0,0,0,0,0,0]
["Population Development",null,null,null,null,null,null,null,null,0,0]
["Provincial Cultural Matters",null,null,null,null,null,null,null,null,0,0]
["Theatres",null,null,null,null,null,null,null,null,0,0]
["Zoo's",null,null,null,null,null,null,null,null,0,0]
["Sport and recreation",null,{"$f":"SUM(C173:C177)","v":29288851},25715503.010000002,0,0,0,0,0,0,25715503.010000002,{"$f":"SUM(L173:L177)","v":42725232},{"$f":"SUM(M173:M177)","v":44784178}]
["Beaches and Jetties ",null,null,null,null,null,null,null,null,0,0]
["Casinos, Racing, Gambling, Wagering",null,null,null,null,null,null,null,null,0,0]
["Community Parks (including Nurseries)",null,null,null,null,null,null,null,null,0,0]
["Recreational Facilities",null,29288851,25715503.010000002,0,0,0,0,0,0,25715503.010000002,42725232,44784178]
["Sports Grounds and Stadiums",null,null,null,null,null,null,null,null,0,0]
["Public safety",null,{"$f":"SUM(C179:C186)","v":42042987},32282987.030000001,0,0,0,0,0,0,32282987.030000001,{"$f":"SUM(L179:L186)","v":34966636},{"$f":"SUM(M179:M186)","v":36431050}]
["Civil Defence",null,29150069,21620069.02,0,0,0,0,0,0,21620069.02,24897500,25944375]
["Cleansing",null,null,null,null,null,null,null,null,0,0]
["Control of Public Nuisances",null,null,null,null,null,null,null,null,0,0]
["Fencing and Fences ",null,null,null,null,null,null,null,null,0,0]
["Fire Fighting and Protection",null,0,0,0,0,0,0,0,0,0,0,0]
["Licensing and Control of Animals",null,null,null,null,null,null,null,null,{"$f":"SUM(E184:I184)","v":0},{"$f":"IF(D184=0,C184+J184,D184+J184)","v":0}]
["Police Forces, Traffic and Street Parking Control",null,12892918,10662918.01,0,0,0,0,0,{"$f":"SUM(E185:I185)","v":0},{"$f":"IF(D185=0,C185+J185,D185+J185)","v":10662918.01},10069136,10486675]
["Pounds",null,null,null,null,null,null,null,null,0,0]
["Housing",null,{"$f":"SUM(C188:C189)","v":0},{"$f":"SUM(D188:D189)","v":0},0,0,0,0,0,0,0,0,0]
["Housing",null,null,null,null,null,null,null,null,0,0]
["Informal Settlements",null,null,null,null,null,null,null,null,0,0]
["Health",null,{"$f":"SUM(C191:C197)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L191:L197)","v":0},{"$f":"SUM(M191:M197)","v":0}]
["Ambulance",null,null,null,null,null,null,null,null,0,0]
["Health Services",null,null,null,null,null,null,null,null,0,0]
[{"$f":"A71","v":"Laboratory Services"},null,null,null,null,null,null,null,null,0,0]
["Food Control",null,null,null,null,null,null,null,null,0,0]
["Health Surveillance and Prevention of Communicable Diseases including immunizations",null,null,null,null,null,null,null,null,0,0]
["Vector Control",null,null,null,null,null,null,null,null,0,0]
["Chemical Safety",null,null,null,null,null,null,null,null,0,0]
["Economic and environmental services",null,{"$f":"C199+C210+C215","v":115203608},97236854.060000002,0,0,0,0,0,0,97236854.060000002,{"$f":"L199+L210+L215","v":86089149},{"$f":"M199+M210+M215","v":90942754}]
["Planning and development",null,{"$f":"SUM(C200:C209)","v":31369359},25454605.020000003,0,0,0,0,0,0,25454605.020000003,{"$f":"SUM(L200:L209)","v":24460808},{"$f":"SUM(M200:M209)","v":26477739}]
["Billboards",null,null,null,null,null,null,null,null,0,0]
["Corporate Wide Strategic Planning (IDPs, LEDs)",null,0,0,0,0,0,0,0,0,0,7630884,8322429]
["Central City Improvement District",null,null,null,null,null,null,null,null,{"$f":"SUM(E202:I202)","v":0},{"$f":"IF(D202=0,C202+J202,D202+J202)","v":0}]
["Development Facilitation",null,0,0,0,0,0,0,0,0,0,0,0]
["Economic Development/Planning",null,21780864,18378110.010000002,0,0,0,0,0,0,18378110.010000002,8681821,9109377]
["Regional Planning and Development",null,null,null,null,null,null,null,null,0,0]
["Town Planning, Building Regulations and Enforcement, and City Engineer",null,4420858,3493858.01,0,0,0,0,0,0,3493858.01,3969336,4641303]
["Project Management Unit",null,5167637,3582637,0,0,0,0,0,0,3582637,4178767,4404630]
["Provincial Planning",null,null,null,null,null,null,null,null,0,0]
["Support to Local Municipalities",null,null,null,null,null,null,null,null,0,0]
["Road transport",null,{"$f":"SUM(C211:C214)","v":83834249},71782249.040000007,0,0,0,0,0,0,71782249.040000007,{"$f":"SUM(L211:L214)","v":61628341},{"$f":"SUM(M211:M214)","v":64465015}]
["Public Transport",null,null,null,null,null,null,null,null,0,0]
["Road and Traffic Regulation",null,null,null,null,null,null,null,null,0,0]
["Roads",null,83834249,71782249.040000007,0,0,0,0,0,0,71782249.040000007,61628341,64465015]
["Taxi Ranks",null,null,null,null,null,null,null,null,0,0]
["Environmental protection",null,{"$f":"SUM(C216:C221)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L216:L221)","v":0},{"$f":"SUM(M216:M221)","v":0}]
["Biodiversity and Landscape",null,null,null,null,null,null,null,null,0,0]
["Coastal Protection",null,null,null,null,null,null,null,null,0,0]
["Indigenous Forests",null,null,null,null,null,null,null,null,0,0]
["Nature Conservation",null,null,null,null,null,null,null,null,0,0]
["Pollution Control",null,null,null,null,null,null,null,null,0,0]
["Soil Conservation",null,null,null,null,null,null,null,null,0,0]
["Trading services",null,{"$f":"C223+C227+C231+C236","v":354822345},{"$f":"D223+D227+D231+D236","v":397202950.30999994},0,0,0,0,-2300000,-2300000,394902950.30999994,398828628,412283452]
["Energy sources",null,{"$f":"SUM(C224:C226)","v":31908720},31753758,0,0,0,0,0,0,31753758,{"$f":"SUM(L224:L226)","v":19598588},{"$f":"SUM(M224:M226)","v":20384798}]
["Electricity ",null,12700000,18145038,0,0,0,0,0,0,18145038,11000000,11506000]
[{"$f":"A103","v":"Street Lighting and Signal Systems"},null,19208720,13608720,0,0,0,0,0,0,13608720,8598588,8878798]
["Nonelectric Energy",null,null,null,null,null,null,null,null,0,0]
["Water management",null,{"$f":"SUM(C228:C230)","v":241659927},290898577.25999999,0,0,0,0,-2300000,-2300000,288598577.25999999,{"$f":"SUM(L228:L230)","v":306488832},{"$f":"SUM(M228:M230)","v":314139435}]
["Water Treatment",null,19990502,49243465.020000003,0,0,0,0,-2300000,-2300000,46943465.020000003,47597321,50739188]
["Water Distribution",null,220302760,241655112.16999999,0,0,0,0,0,0,241655112.16999999,258891511,263400247]
["Water Storage",null,1366665,7.0000000000000007E-2,0,0,0,0,0,0,7.0000000000000007E-2,0,0]
["Waste water management",null,{"$f":"SUM(C232:C235)","v":18784460},24789565.030000001,0,0,0,0,0,0,24789565.030000001,{"$f":"SUM(L232:L235)","v":21228371},{"$f":"SUM(M232:M235)","v":22743337}]
["Public Toilets",null,null,null,null,null,null,null,null,0,0]
["Sewerage",null,18784460,24789565.030000001,0,0,0,0,0,0,24789565.030000001,21228371,22743337]
["Storm Water Management",null,0,0,0,0,0,0,0,0,0,0,0]
["Waste Water Treatment",null,null,null,null,null,null,null,null,0,0]
["Waste management",null,{"$f":"SUM(C237:C240)","v":62469238},{"$f":"SUM(D237:D240)","v":49761050.020000003},{"$f":"SUM(E237:E240)","v":0},{"$f":"SUM(F237:F240)","v":0},0,0,0,0,49761050.020000003,51512837,55015882]
["Recycling",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Disposal (Landfill Sites)",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Removal",null,62469238,49761050.020000003,0,0,0,0,0,0,49761050.020000003,51512837,55015882]
["Street Cleaning",null,null,null,null,null,null,null,null,0,0]
["Other",null,{"$f":"SUM(C242:C247)","v":0},{"$f":"SUM(D242:D247)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(L242:L247)","v":0},{"$f":"SUM(M242:M247)","v":0}]
["Abattoirs",null,null,null,null,null,null,null,null,0,0]
["Air Transport",null,null,null,null,null,null,null,null,0,0]
["Forestry ",null,null,null,null,null,null,null,null,0,0]
["Licensing and Regulation",null,null,null,null,null,null,null,null,0,0]
["Markets",null,null,null,null,null,null,null,null,0,0]
["Tourism",null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"\"Total \"&A128","v":"Total Expenditure - Functional"},3,{"$f":"C129+C149+C198+C222+C241","v":967240322},905587234.86999989,0,0,0,0,88513,88513,905675747.86999989,{"$f":"L129+L149+L198+L222+L241","v":938505262},{"$f":"M129+M149+M198+M222+M241","v":980288792}]
[{"$f":"result","v":"Surplus/ (Deficit) for the year"},null,{"$f":"C126-C248","v":68850206},74423570.120000124,0,0,0,0,290000,290000,74713570.120000124,{"$f":"L126-L248","v":160194654},{"$f":"M126-M248","v":178403878}]
[{"$f":"head27a","v":"References"}]
["1. Government Finance Statistics Functions and Sub-functions are standardised to assist national and international accounts and comparison"]
["2. Total Revenue by Functional Classification must reconcile to total operating revenue shown in Financial Performance (revenue and expenditure)"]
["3. Total Expenditure by Functional Classification must reconcile to total operating expenditure shown in Financial Performance (revenue and expenditure)"]
["4. All amounts must be classified under a Functional classification. The GFS function 'Other' is only for Abbatoirs, Air Transport, Licensing and Regulation, Markets and Tourism - and if used must be supported by footnotes. Nothing else may be placed under 'Other'. Assign associate share to relevant classification"]

{"sheet":"B3-FinPerf V","index":9,"n_rows":55,"n_cols":13,"rows_kept":55,"cut":false,"hidden":false,"merged":[[51,0,51,12],[47,0,47,12],[49,0,49,12],[1,0,2,0],[1,1,4,1],[1,2,1,10],[44,0,44,12],[45,0,45,12],[46,0,46,12]]}
[{"$f":"muni&\" - \"&_ADJ2&\" - \"&Date","v":"NW375 Moses Kotane - Table B3 Adjustments Budget Financial Performance (revenue and expenditure by municipal vote) - 44171"}]
[{"$f":"Vdesc","v":"Vote Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["[Insert departmental structure etc]",null,null,3,4,5,6,7,8,9,10]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Revenue by Vote",1]
[{"$f":"B3B!A7","v":"Vote 01 - Municipal Council"},null,{"$f":"B3B!C7","v":1695000},{"$f":"B3B!D7","v":1695000},{"$f":"B3B!E7","v":0},{"$f":"B3B!F7","v":0},{"$f":"B3B!G7","v":0},{"$f":"B3B!H7","v":0},{"$f":"B3B!I7","v":0},{"$f":"B3B!J7","v":0},{"$f":"B3B!K7","v":1695000},{"$f":"B3B!L7","v":1827000},{"$f":"B3B!M7","v":940}]
[{"$f":"B3B!A13","v":"Vote 02 - Office Of The Accounting Officer"},null,{"$f":"B3B!C13","v":0},{"$f":"B3B!D13","v":0},{"$f":"B3B!E13","v":0},{"$f":"B3B!F13","v":0},{"$f":"B3B!G13","v":0},{"$f":"B3B!H13","v":0},{"$f":"B3B!I13","v":0},{"$f":"B3B!J13","v":0},{"$f":"B3B!K13","v":0},{"$f":"B3B!L13","v":0},{"$f":"B3B!M13","v":0}]
[{"$f":"B3B!A20","v":"Vote 03 - Budget And Treasury Office"},null,{"$f":"B3B!C20","v":479197100},{"$f":"B3B!D20","v":417906890},{"$f":"B3B!E20","v":0},{"$f":"B3B!F20","v":0},{"$f":"B3B!G20","v":0},{"$f":"B3B!H20","v":0},{"$f":"B3B!I20","v":290000},{"$f":"B3B!J20","v":290000},{"$f":"B3B!K20","v":418196890},{"$f":"B3B!L20","v":526235196},{"$f":"B3B!M20","v":556112493}]
[{"$f":"B3B!A28","v":"Vote 04 - Corporate Services"},null,{"$f":"B3B!C28","v":500000},{"$f":"B3B!D28","v":500000},{"$f":"B3B!E28","v":0},{"$f":"B3B!F28","v":0},{"$f":"B3B!G28","v":0},{"$f":"B3B!H28","v":0},{"$f":"B3B!I28","v":268000},{"$f":"B3B!J28","v":268000},{"$f":"B3B!K28","v":768000},{"$f":"B3B!L28","v":500000},{"$f":"B3B!M28","v":500000}]
[{"$f":"B3B!A37","v":"Vote 05 - Community Services"},null,{"$f":"B3B!C37","v":99986590},{"$f":"B3B!D37","v":100490668.99000001},{"$f":"B3B!E37","v":0},{"$f":"B3B!F37","v":0},{"$f":"B3B!G37","v":0},{"$f":"B3B!H37","v":0},{"$f":"B3B!I37","v":-179487},{"$f":"B3B!J37","v":-179487},{"$f":"B3B!K37","v":100311181.99000001},{"$f":"B3B!L37","v":87323182},{"$f":"B3B!M37","v":106256198}]
[{"$f":"B3B!A52","v":"Vote 06 - Planning & Development"},null,{"$f":"B3B!C52","v":100000},{"$f":"B3B!D52","v":150000},{"$f":"B3B!E52","v":0},{"$f":"B3B!F52","v":0},{"$f":"B3B!G52","v":0},{"$f":"B3B!H52","v":0},{"$f":"B3B!I52","v":0},{"$f":"B3B!J52","v":0},{"$f":"B3B!K52","v":150000},{"$f":"B3B!L52","v":100000},{"$f":"B3B!M52","v":100000}]
[{"$f":"B3B!A63","v":"Vote 07 - Infrastructure & Technical Services"},null,{"$f":"B3B!C63","v":454611838},{"$f":"B3B!D63","v":459268246},{"$f":"B3B!E63","v":0},{"$f":"B3B!F63","v":0},{"$f":"B3B!G63","v":0},{"$f":"B3B!H63","v":0},{"$f":"B3B!I63","v":0},{"$f":"B3B!J63","v":0},{"$f":"B3B!K63","v":459268246},{"$f":"B3B!L63","v":482714538},{"$f":"B3B!M63","v":495723039}]
[{"$f":"'Org structure'!A9","v":"Vote 08 - "},null,{"$f":"B3B!C83","v":0},{"$f":"B3B!D83","v":0},{"$f":"B3B!E83","v":0},{"$f":"B3B!F83","v":0},{"$f":"B3B!G83","v":0},{"$f":"B3B!H83","v":0},{"$f":"B3B!I83","v":0},{"$f":"SUM(E14:I14)","v":0},{"$f":"IF(D14=0,C14+J14,D14+J14)","v":0},{"$f":"B3B!L83","v":0},{"$f":"B3B!M83","v":0}]
[{"$f":"'Org structure'!A10","v":"Vote 09 - "},null,{"$f":"B3B!C84","v":0},{"$f":"B3B!D84","v":0},{"$f":"B3B!E84","v":0},{"$f":"B3B!F84","v":0},{"$f":"B3B!G84","v":0},{"$f":"B3B!H84","v":0},{"$f":"B3B!I84","v":0},0,0,{"$f":"B3B!L84","v":0},{"$f":"B3B!M84","v":0}]
[{"$f":"'Org structure'!A11","v":"Vote 10 - "},null,{"$f":"B3B!C85","v":0},{"$f":"B3B!D85","v":0},{"$f":"B3B!E85","v":0},{"$f":"B3B!F85","v":0},{"$f":"B3B!G85","v":0},{"$f":"B3B!H85","v":0},{"$f":"B3B!I85","v":0},0,0,{"$f":"B3B!L85","v":0},{"$f":"B3B!M85","v":0}]
[{"$f":"'Org structure'!A12","v":"Vote 11 - "},null,{"$f":"B3B!C86","v":0},{"$f":"B3B!D86","v":0},{"$f":"B3B!E86","v":0},{"$f":"B3B!F86","v":0},{"$f":"B3B!G86","v":0},{"$f":"B3B!H86","v":0},{"$f":"B3B!I86","v":0},0,0,{"$f":"B3B!L86","v":0},{"$f":"B3B!M86","v":0}]
[{"$f":"'Org structure'!A13","v":"Vote 12 - "},null,{"$f":"B3B!C87","v":0},{"$f":"B3B!D87","v":0},{"$f":"B3B!E87","v":0},{"$f":"B3B!F87","v":0},{"$f":"B3B!G87","v":0},{"$f":"B3B!H87","v":0},{"$f":"B3B!I87","v":0},0,0,{"$f":"B3B!L87","v":0},{"$f":"B3B!M87","v":0}]
[{"$f":"'Org structure'!A14","v":"Vote 13 - "},null,{"$f":"B3B!C88","v":0},{"$f":"B3B!D88","v":0},{"$f":"B3B!E88","v":0},{"$f":"B3B!F88","v":0},{"$f":"B3B!G88","v":0},{"$f":"B3B!H88","v":0},{"$f":"B3B!I88","v":0},0,0,{"$f":"B3B!L88","v":0},{"$f":"B3B!M88","v":0}]
[{"$f":"'Org structure'!A15","v":"Vote 14 - "},null,{"$f":"B3B!C89","v":0},{"$f":"B3B!D89","v":0},{"$f":"B3B!E89","v":0},{"$f":"B3B!F89","v":0},{"$f":"B3B!G89","v":0},{"$f":"B3B!H89","v":0},{"$f":"B3B!I89","v":0},0,0,{"$f":"B3B!L89","v":0},{"$f":"B3B!M89","v":0}]
[{"$f":"'Org structure'!A16","v":"Vote 15 - Other"},null,{"$f":"B3B!C90","v":0},{"$f":"B3B!D90","v":0},{"$f":"B3B!E90","v":0},{"$f":"B3B!F90","v":0},{"$f":"B3B!G90","v":0},{"$f":"B3B!H90","v":0},{"$f":"B3B!I90","v":0},0,0,{"$f":"B3B!L90","v":0},{"$f":"B3B!M90","v":0}]
["Total Revenue by Vote",2,{"$f":"SUM(C7:C21)","v":1036090528},{"$f":"SUM(D7:D21)","v":980010804.99000001},0,0,0,0,378513,{"$f":"SUM(J7:J21)","v":378513},980389317.99000001,{"$f":"SUM(L7:L21)","v":1098699916},{"$f":"SUM(M7:M21)","v":1158692670}]
[]
["Expenditure by Vote",1]
[{"$f":"B3B!A94","v":"Vote 01 - Municipal Council"},null,{"$f":"B3B!C94","v":86146330},{"$f":"B3B!D94","v":67177252.219999999},{"$f":"B3B!E94","v":0},{"$f":"B3B!F94","v":0},{"$f":"B3B!G94","v":0},{"$f":"B3B!H94","v":0},{"$f":"B3B!I94","v":2300000},{"$f":"B3B!J94","v":2300000},{"$f":"B3B!K94","v":69477252.219999999},{"$f":"B3B!L94","v":70271020},{"$f":"B3B!M94","v":75483033}]
[{"$f":"B3B!A100","v":"Vote 02 - Office Of The Accounting Officer"},null,{"$f":"B3B!C100","v":25303359},{"$f":"B3B!D100","v":19787773.030000001},{"$f":"B3B!E100","v":0},{"$f":"B3B!F100","v":0},{"$f":"B3B!G100","v":0},{"$f":"B3B!H100","v":0},{"$f":"B3B!I100","v":0},{"$f":"B3B!J100","v":0},{"$f":"B3B!K100","v":19787773.030000001},{"$f":"B3B!L100","v":25008311},{"$f":"B3B!M100","v":26427215}]
[{"$f":"B3B!A107","v":"Vote 03 - Budget And Treasury Office"},null,{"$f":"B3B!C107","v":126091931},{"$f":"B3B!D107","v":120458267.08},{"$f":"B3B!E107","v":0},{"$f":"B3B!F107","v":0},{"$f":"B3B!G107","v":0},{"$f":"B3B!H107","v":0},{"$f":"B3B!I107","v":0},{"$f":"B3B!J107","v":0},{"$f":"B3B!K107","v":120458267.08},{"$f":"B3B!L107","v":145208027},{"$f":"B3B!M107","v":152100815}]
[{"$f":"B3B!A115","v":"Vote 04 - Corporate Services"},null,{"$f":"B3B!C115","v":137336122},{"$f":"B3B!D115","v":104950279.09},{"$f":"B3B!E115","v":0},{"$f":"B3B!F115","v":0},{"$f":"B3B!G115","v":0},{"$f":"B3B!H115","v":0},{"$f":"B3B!I115","v":268000},{"$f":"B3B!J115","v":268000},{"$f":"B3B!K115","v":105218279.09},{"$f":"B3B!L115","v":90642312},{"$f":"B3B!M115","v":94844362}]
[{"$f":"B3B!A124","v":"Vote 05 - Community Services"},null,{"$f":"B3B!C124","v":182219774},{"$f":"B3B!D124","v":146158806.09},{"$f":"B3B!E124","v":0},{"$f":"B3B!F124","v":0},{"$f":"B3B!G124","v":0},{"$f":"B3B!H124","v":0},{"$f":"B3B!I124","v":-179487},{"$f":"B3B!J124","v":-179487},{"$f":"B3B!K124","v":145979319.09},{"$f":"B3B!L124","v":166499408},{"$f":"B3B!M124","v":175379400}]
[{"$f":"B3B!A139","v":"Vote 06 - Planning & Development"},null,{"$f":"B3B!C139","v":26201722},{"$f":"B3B!D139","v":21871968.02},{"$f":"B3B!E139","v":0},{"$f":"B3B!F139","v":0},{"$f":"B3B!G139","v":0},{"$f":"B3B!H139","v":0},{"$f":"B3B!I139","v":0},{"$f":"B3B!J139","v":0},{"$f":"B3B!K139","v":21871968.02},{"$f":"B3B!L139","v":25289438},{"$f":"B3B!M139","v":27330875}]
[{"$f":"B3B!A150","v":"Vote 07 - Infrastructure & Technical Services"},null,{"$f":"B3B!C150","v":383941084},{"$f":"B3B!D150","v":425182889.33999997},{"$f":"B3B!E150","v":0},{"$f":"B3B!F150","v":0},{"$f":"B3B!G150","v":0},{"$f":"B3B!H150","v":0},{"$f":"B3B!I150","v":-2300000},{"$f":"B3B!J150","v":-2300000},{"$f":"B3B!K150","v":422882889.33999997},{"$f":"B3B!L150","v":415586746},{"$f":"B3B!M150","v":428723092}]
[{"$f":"'Org structure'!A9","v":"Vote 08 - "},null,{"$f":"B3B!C170","v":0},{"$f":"B3B!D170","v":0},{"$f":"B3B!E170","v":0},{"$f":"B3B!F170","v":0},{"$f":"B3B!G170","v":0},{"$f":"B3B!H170","v":0},{"$f":"B3B!I170","v":0},{"$f":"SUM(E32:I32)","v":0},{"$f":"IF(D32=0,C32+J32,D32+J32)","v":0},{"$f":"B3B!L170","v":0},{"$f":"B3B!M170","v":0}]
[{"$f":"'Org structure'!A10","v":"Vote 09 - "},null,{"$f":"B3B!C171","v":0},{"$f":"B3B!D171","v":0},{"$f":"B3B!E171","v":0},{"$f":"B3B!F171","v":0},{"$f":"B3B!G171","v":0},{"$f":"B3B!H171","v":0},{"$f":"B3B!I171","v":0},0,0,{"$f":"B3B!L171","v":0},{"$f":"B3B!M171","v":0}]
[{"$f":"'Org structure'!A11","v":"Vote 10 - "},null,{"$f":"B3B!C172","v":0},{"$f":"B3B!D172","v":0},{"$f":"B3B!E172","v":0},{"$f":"B3B!F172","v":0},{"$f":"B3B!G172","v":0},{"$f":"B3B!H172","v":0},{"$f":"B3B!I172","v":0},0,0,{"$f":"B3B!L172","v":0},{"$f":"B3B!M172","v":0}]
[{"$f":"'Org structure'!A12","v":"Vote 11 - "},null,{"$f":"B3B!C173","v":0},{"$f":"B3B!D173","v":0},{"$f":"B3B!E173","v":0},{"$f":"B3B!F173","v":0},{"$f":"B3B!G173","v":0},{"$f":"B3B!H173","v":0},{"$f":"B3B!I173","v":0},0,0,{"$f":"B3B!L173","v":0},{"$f":"B3B!M173","v":0}]
[{"$f":"'Org structure'!A13","v":"Vote 12 - "},null,{"$f":"B3B!C174","v":0},{"$f":"B3B!D174","v":0},{"$f":"B3B!E174","v":0},{"$f":"B3B!F174","v":0},{"$f":"B3B!G174","v":0},{"$f":"B3B!H174","v":0},{"$f":"B3B!I174","v":0},0,0,{"$f":"B3B!L174","v":0},{"$f":"B3B!M174","v":0}]
[{"$f":"'Org structure'!A14","v":"Vote 13 - "},null,{"$f":"B3B!C175","v":0},{"$f":"B3B!D175","v":0},{"$f":"B3B!E175","v":0},{"$f":"B3B!F175","v":0},{"$f":"B3B!G175","v":0},{"$f":"B3B!H175","v":0},{"$f":"B3B!I175","v":0},0,0,{"$f":"B3B!L175","v":0},{"$f":"B3B!M175","v":0}]
[{"$f":"'Org structure'!A15","v":"Vote 14 - "},null,{"$f":"B3B!C176","v":0},{"$f":"B3B!D176","v":0},{"$f":"B3B!E176","v":0},{"$f":"B3B!F176","v":0},{"$f":"B3B!G176","v":0},{"$f":"B3B!H176","v":0},{"$f":"B3B!I176","v":0},0,0,{"$f":"B3B!L176","v":0},{"$f":"B3B!M176","v":0}]
[{"$f":"'Org structure'!A16","v":"Vote 15 - Other"},null,{"$f":"B3B!C177","v":0},{"$f":"B3B!D177","v":0},{"$f":"B3B!E177","v":0},{"$f":"B3B!F177","v":0},{"$f":"B3B!G177","v":0},{"$f":"B3B!H177","v":0},{"$f":"B3B!I177","v":0},0,0,{"$f":"B3B!L177","v":0},{"$f":"B3B!M177","v":0}]
["Total Expenditure by Vote",2,{"$f":"SUM(C25:C39)","v":967240322},{"$f":"SUM(D25:D39)","v":905587234.86999989},0,0,0,0,88513,{"$f":"SUM(J25:J39)","v":88513},{"$f":"SUM(K25:K39)","v":905675747.86999989},{"$f":"SUM(L25:L39)","v":938505262},{"$f":"SUM(M25:M39)","v":980288792}]
[{"$f":"result","v":"Surplus/ (Deficit) for the year"},2,{"$f":"C22-C40","v":68850206},{"$f":"D22-D40","v":74423570.120000124},0,0,0,0,290000,290000,74713570.120000124,160194654,178403878]
[{"$f":"head27a","v":"References"}]
["1. Insert 'Vote'; e.g. Department, if different to standard classification structure"]
["2. Must reconcile to Budgeted Financial Performance (revenue and expenditure)"]
["3. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["4. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["5. Increases of funds approved under MFMA section 31"]
["6. Adjustments approved in accordance with MFMA section 29 "]
["7. Adjustments to transfers from National or Provincial Government"]
["8. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["9. G = B + C + D + E + F"]
["10. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
["check revenue",null,{"$f":"C22-'B4-FinPerf RE'!C62","v":0},{"$f":"D22-'B4-FinPerf RE'!D62","v":0},{"$f":"E22-'B4-FinPerf RE'!E62","v":0},{"$f":"F22-'B4-FinPerf RE'!F62","v":0},{"$f":"G22-'B4-FinPerf RE'!G62","v":0},{"$f":"H22-'B4-FinPerf RE'!H62","v":0},{"$f":"I22-'B4-FinPerf RE'!I62","v":0},{"$f":"J22-'B4-FinPerf RE'!J62","v":0},{"$f":"K22-'B4-FinPerf RE'!K62","v":0},{"$f":"L22-'B4-FinPerf RE'!L62","v":0},{"$f":"M22-'B4-FinPerf RE'!M62","v":0}]
["check expenditure",null,{"$f":"C40-'B4-FinPerf RE'!C37","v":0},{"$f":"D40-'B4-FinPerf RE'!D37","v":0},{"$f":"E40-'B4-FinPerf RE'!E37","v":0},{"$f":"F40-'B4-FinPerf RE'!F37","v":0},{"$f":"G40-'B4-FinPerf RE'!G37","v":0},{"$f":"H40-'B4-FinPerf RE'!H37","v":0},{"$f":"I40-'B4-FinPerf RE'!I37","v":0},{"$f":"J40-'B4-FinPerf RE'!J37","v":0},{"$f":"K40-'B4-FinPerf RE'!K37","v":0},{"$f":"L40-'B4-FinPerf RE'!L37","v":0},{"$f":"M40-'B4-FinPerf RE'!M37","v":0}]

{"sheet":"B3B","index":10,"n_rows":184,"n_cols":13,"rows_kept":184,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,1,4,1],[1,2,1,10]]}
[{"$f":"muni&\" - \"&_ADJ2&\" - B\"&\" - \"&Date","v":"NW375 Moses Kotane - Table B3 Adjustments Budget Financial Performance (revenue and expenditure by municipal vote) - B - 44171"}]
[{"$f":"Vdesc","v":"Vote Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["[Insert departmental structure etc]",null,null,3,4,5,6,7,8,9,10]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Revenue by Vote",1]
[{"$f":"'Org structure'!A2","v":"Vote 01 - Municipal Council"},null,{"$f":"SUM(C8:C12)","v":1695000},1695000,0,0,0,0,0,{"$f":"SUM(E7:I7)","v":0},{"$f":"IF(D7=0,C7+J7,D7+J7)","v":1695000},{"$f":"SUM(L8:L12)","v":1827000},{"$f":"SUM(M8:M12)","v":940}]
[{"$f":"'Org structure'!E3","v":"01.1 - Office Of The Mayor"},null,1695000,1695000,0,0,0,0,0,0,1695000,1827000,0]
[{"$f":"'Org structure'!E4","v":"01.2 - Office Of The Speaker"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E5","v":"01.3 - Office Of The Chief Whip"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E6","v":"01.4 - Mpac"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E7","v":"01.5 - Council General Administration"},null,0,0,0,0,0,0,0,0,0,0,940]
[{"$f":"'Org structure'!A3","v":"Vote 02 - Office Of The Accounting Officer"},null,{"$f":"SUM(C14:C19)","v":0},0,0,0,0,0,0,{"$f":"SUM(E13:I13)","v":0},{"$f":"IF(D13=0,C13+J13,D13+J13)","v":0},{"$f":"SUM(L14:L19)","v":0},{"$f":"SUM(M14:M19)","v":0}]
[{"$f":"'Org structure'!E9","v":"02.1 - Office Of The Ao Admin"},null,0,0,0,0,0,0,0,{"$f":"SUM(E14:I14)","v":0},{"$f":"IF(D14=0,C14+J14,D14+J14)","v":0},0,0]
[{"$f":"'Org structure'!E10","v":"02.2 - Strategic Planning Monitoring & Evaluat"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E11","v":"02.3 - Perfomance Management System"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E12","v":"02.4 - Internal Audit"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E13","v":"02.5 - Municipal Planning Idp"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E14","v":"02.6 - Risk"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A4","v":"Vote 03 - Budget And Treasury Office"},null,{"$f":"SUM(C21:C27)","v":479197100},417906890,0,0,0,0,290000,290000,418196890,{"$f":"SUM(L21:L27)","v":526235196},{"$f":"SUM(M21:M27)","v":556112493}]
[{"$f":"'Org structure'!E16","v":"03.1 - Chief Financial Officer Admin"},null,142163600,142163600,0,0,0,0,0,{"$f":"SUM(E21:I21)","v":0},{"$f":"IF(D21=0,C21+J21,D21+J21)","v":142163600},169026146,176816837]
[{"$f":"'Org structure'!E17","v":"03.2 - Budget Expenditure & Reporting"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E18","v":"03.3 - Budget Expenditure & Reporting"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E19","v":"03.4 - Revenue Management"},null,337033500,275743290,0,0,0,0,290000,290000,276033290,357209050,379295656]
[{"$f":"'Org structure'!E20","v":"03.5 - Supply Chain Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E21","v":"03.6 - Assets Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E22","v":"03.7 - Expenditure"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A5","v":"Vote 04 - Corporate Services"},null,{"$f":"SUM(C29:C36)","v":500000},500000,0,0,0,0,268000,268000,768000,{"$f":"SUM(L29:L36)","v":500000},{"$f":"SUM(M29:M36)","v":500000}]
[{"$f":"'Org structure'!E24","v":"04.1 - Legal Services"},null,0,0,0,0,0,0,0,{"$f":"SUM(E29:I29)","v":0},{"$f":"IF(D29=0,C29+J29,D29+J29)","v":0},0,0]
[{"$f":"'Org structure'!E25","v":"04.2 - Corporate Service Administration"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E26","v":"04.3 - Human Resources"},null,500000,500000,0,0,0,0,268000,268000,768000,500000,500000]
[{"$f":"'Org structure'!E27","v":"04.4 - Media & Communication"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E28","v":"04.5 - Organisational Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E29","v":"04.6 - Labour Relations"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E30","v":"04.7 - Legal Services"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E31","v":"04.8 - Information Technology Services"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A6","v":"Vote 05 - Community Services"},null,{"$f":"SUM(C38:C51)","v":99986590},100490668.99000001,0,0,0,0,-179487,-179487,100311181.99000001,{"$f":"SUM(L38:L51)","v":87323182},{"$f":"SUM(M38:M51)","v":106256198}]
[{"$f":"'Org structure'!E33","v":"05.1 - Municipal Buildings"},null,14590253,30726754,0,0,0,0,0,{"$f":"SUM(E38:I38)","v":0},{"$f":"IF(D38=0,C38+J38,D38+J38)","v":30726754},0,8000000]
[{"$f":"'Org structure'!E34","v":"05.2 - Fleet Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E35","v":"05.3 - Community Services Administration"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E36","v":"05.4 - Cemeteries"},null,10000,10000,0,0,0,0,0,0,10000,10000,10000]
[{"$f":"'Org structure'!E37","v":"05.5 - Disaster Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E38","v":"05.6 - Fires Service"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E39","v":"05.7 - Libraries"},null,40000,1204487,0,0,0,0,-179487,-179487,1025000,40000,40000]
[{"$f":"'Org structure'!E40","v":"05.8 - Municipal Buildings"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E41","v":"05.9 - Sports Recreation & Social Amenitie"},null,55000,55000,0,0,0,0,0,0,55000,9898475,34000]
[{"$f":"'Org structure'!E42","v":"05.10 - Waste Management Solid Waste"},null,80741337,64944427.990000002,0,0,0,0,0,0,64944427.990000002,74324707,95122198]
[{"$f":"'Org structure'!E43","v":"05.11 - Safety And Security"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E44","v":"05.12 - Traffic Service"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E45","v":"05.13 - Traffic Service"},null,4550000,3550000,0,0,0,0,0,0,3550000,3050000,3050000]
[{"$f":"'Org structure'!E46","v":"05.14 - Fleet Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A7","v":"Vote 06 - Planning & Development"},null,{"$f":"SUM(C53:C62)","v":100000},150000,0,0,0,0,0,0,150000,{"$f":"SUM(L53:L62)","v":100000},{"$f":"SUM(M53:M62)","v":100000}]
[{"$f":"'Org structure'!E48","v":"06.1 - Planning And Development Admin"},null,0,0,0,0,0,0,0,{"$f":"SUM(E53:I53)","v":0},{"$f":"IF(D53=0,C53+J53,D53+J53)","v":0},0,0]
[{"$f":"'Org structure'!E49","v":"06.2 - Municipal Planning Idp"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E50","v":"06.3 - Pms"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E51","v":"06.4 - Town Planning"},null,100000,150000,0,0,0,0,0,0,150000,100000,100000]
[{"$f":"'Org structure'!E52","v":"06.5 - Land Use And Housing Admin"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E53","v":"06.6 - Local Economic Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E54","v":"06.7 - Led"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E55","v":"06.8 - Agriculture & Rural Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E56","v":"06.9 - Tourism & Business Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E57","v":"06.10 - Arts & Culture"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A8","v":"Vote 07 - Infrastructure & Technical Services"},null,{"$f":"SUM(C64:C82)","v":454611838},459268246,0,0,0,0,0,{"$f":"SUM(E63:I63)","v":0},{"$f":"IF(D63=0,C63+J63,D63+J63)","v":459268246},{"$f":"SUM(L64:L82)","v":482714538},{"$f":"SUM(M64:M82)","v":495723039}]
[{"$f":"'Org structure'!E59","v":"07.1 - Infrastructure Admin & Tech Admin"},null,0,0,0,0,0,0,0,{"$f":"SUM(E64:I64)","v":0},{"$f":"IF(D64=0,C64+J64,D64+J64)","v":0},0,0]
[{"$f":"'Org structure'!E60","v":"07.2 - Fleet Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E61","v":"07.3 - Roads"},null,62193238,61188318,0,0,0,0,0,0,61188318,60981782,60000001]
[{"$f":"'Org structure'!E62","v":"07.4 - Storm Water"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E63","v":"07.5 - Street Lighting"},null,19857810,20416973,0,0,0,0,0,0,20416973,11577741,12557370]
[{"$f":"'Org structure'!E64","v":"07.6 - Project Management Unit"},null,5167637,3582637,0,0,0,0,0,0,3582637,4178767,4404630]
[{"$f":"'Org structure'!E65","v":"07.7 - Sanitation Treatment Plant: Mogwase"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E66","v":"07.8 - Sanitation Treatment Plant: Madikwe"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E67","v":"07.9 - Sanitation Reticulation"},null,43021550,33242236,0,0,0,0,0,0,33242236,47377755,47595969]
[{"$f":"'Org structure'!E68","v":"07.10 - Water Administration"},null,236371603,252838082,0,0,0,0,0,0,252838082,262711493,265760069]
[{"$f":"'Org structure'!E69","v":"07.11 - Water Madikwe: Water Treatment Work"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E70","v":"07.12 - Water: Pella Water Treatment Works"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E71","v":"07.13 - Water: Madikwe Retail & Bulk Lines"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E72","v":"07.14 - Water: Madikwe Rural"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E73","v":"07.15 - Water: Molatedi"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E74","v":"07.16 - Water Eastern: Retail Mankwe"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E75","v":"07.17 - Water Vaalkopdam: Mankwe"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E76","v":"07.18 - Water Eastern: Retail Mankwe"},null,88000000,88000000,0,0,0,0,0,0,88000000,95887000,105405000]
[{"$f":"'Org structure'!E77","v":"07.19 - Reporting Function Electricity"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A9","v":"Vote 08 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A10","v":"Vote 09 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A11","v":"Vote 10 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A12","v":"Vote 11 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A13","v":"Vote 12 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A14","v":"Vote 13 - "},null,0,0,0,0,0,0,0,{"$f":"SUM(E88:I88)","v":0},{"$f":"IF(D88=0,C88+J88,D88+J88)","v":0},0,0]
[{"$f":"'Org structure'!A15","v":"Vote 14 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A16","v":"Vote 15 - Other"},null,0,0,0,0,0,0,0,0,0,0,0]
["Total Revenue by Vote",2,{"$f":"C7+C13+C20+C28+C37+C52+C63+C83+C84+C85+C86+C87+C88+C89+C90","v":1036090528},980010804.99000001,0,0,0,0,378513,378513,980389317.99000001,1098699916,1158692670]
[]
["Expenditure by Vote",1]
[{"$f":"'Org structure'!A2","v":"Vote 01 - Municipal Council"},null,{"$f":"SUM(C95:C99)","v":86146330},67177252.219999999,0,0,0,0,2300000,{"$f":"SUM(E94:I94)","v":2300000},{"$f":"IF(D94=0,C94+J94,D94+J94)","v":69477252.219999999},{"$f":"SUM(L95:L99)","v":70271020},{"$f":"SUM(M95:M99)","v":75483033}]
[{"$f":"'Org structure'!E3","v":"01.1 - Office Of The Mayor"},null,11081407,7965947.0800000001,0,0,0,0,0,0,7965947.0800000001,8528021,10198930]
[{"$f":"'Org structure'!E4","v":"01.2 - Office Of The Speaker"},null,10550463,8665463.0299999993,0,0,0,0,0,0,8665463.0299999993,6651849,6979089]
[{"$f":"'Org structure'!E5","v":"01.3 - Office Of The Chief Whip"},null,1641146,1596146.01,0,0,0,0,0,0,1596146.01,3311676,3477260]
[{"$f":"'Org structure'!E6","v":"01.4 - Mpac"},null,4097070,343000.08,0,0,0,0,0,0,343000.08,523000,552200]
[{"$f":"'Org structure'!E7","v":"01.5 - Council General Administration"},null,58776244,48606696.020000003,0,0,0,0,2300000,2300000,50906696.020000003,51256474,54275554]
[{"$f":"'Org structure'!A3","v":"Vote 02 - Office Of The Accounting Officer"},null,{"$f":"SUM(C101:C106)","v":25303359},19787773.030000001,0,0,0,0,0,{"$f":"SUM(E100:I100)","v":0},{"$f":"IF(D100=0,C100+J100,D100+J100)","v":19787773.030000001},{"$f":"SUM(L101:L106)","v":25008311},{"$f":"SUM(M101:M106)","v":26427215}]
[{"$f":"'Org structure'!E9","v":"02.1 - Office Of The Ao Admin"},null,18771203,13790967,0,0,0,0,0,{"$f":"SUM(E101:I101)","v":0},{"$f":"IF(D101=0,C101+J101,D101+J101)","v":13790967},13987364,14794729]
[{"$f":"'Org structure'!E10","v":"02.2 - Strategic Planning Monitoring & Evaluat"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E11","v":"02.3 - Perfomance Management System"},null,2834795,2534795.02,0,0,0,0,0,0,2534795.02,2903838,3101029]
[{"$f":"'Org structure'!E12","v":"02.4 - Internal Audit"},null,3697361,3462011.01,0,0,0,0,0,0,3462011.01,4025368,4235128]
[{"$f":"'Org structure'!E13","v":"02.5 - Municipal Planning Idp"},null,0,0,0,0,0,0,0,0,0,3149853,3307347]
[{"$f":"'Org structure'!E14","v":"02.6 - Risk"},null,0,0,0,0,0,0,0,0,0,941888,988982]
[{"$f":"'Org structure'!A4","v":"Vote 03 - Budget And Treasury Office"},null,{"$f":"SUM(C108:C114)","v":126091931},120458267.08,0,0,0,0,0,0,120458267.08,{"$f":"SUM(L108:L114)","v":145208027},{"$f":"SUM(M108:M114)","v":152100815}]
[{"$f":"'Org structure'!E16","v":"03.1 - Chief Financial Officer Admin"},null,7608358,10349464.02,0,0,0,0,0,{"$f":"SUM(E108:I108)","v":0},{"$f":"IF(D108=0,C108+J108,D108+J108)","v":10349464.02},7963583,8185261]
[{"$f":"'Org structure'!E17","v":"03.2 - Budget Expenditure & Reporting"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E18","v":"03.3 - Budget Expenditure & Reporting"},null,14019292,8176292.0300000003,0,0,0,0,0,0,8176292.0300000003,9443932,9916213]
[{"$f":"'Org structure'!E19","v":"03.4 - Revenue Management"},null,86996562,88920362.030000001,0,0,0,0,0,0,88920362.030000001,106247963,111483365]
[{"$f":"'Org structure'!E20","v":"03.5 - Supply Chain Management"},null,6149200,6245930,0,0,0,0,0,0,6245930,7901614,8296646]
[{"$f":"'Org structure'!E21","v":"03.6 - Assets Management"},null,11318519,6766219,0,0,0,0,0,0,6766219,13650935,14219330]
[{"$f":"'Org structure'!E22","v":"03.7 - Expenditure"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A5","v":"Vote 04 - Corporate Services"},null,{"$f":"SUM(C116:C123)","v":137336122},104950279.09,0,0,0,0,268000,268000,105218279.09,{"$f":"SUM(L116:L123)","v":90642312},{"$f":"SUM(M116:M123)","v":94844362}]
[{"$f":"'Org structure'!E24","v":"04.1 - Legal Services"},null,1178495,1148495.02,0,0,0,0,0,{"$f":"SUM(E116:I116)","v":0},{"$f":"IF(D116=0,C116+J116,D116+J116)","v":1148495.02},1309413,1374883]
[{"$f":"'Org structure'!E25","v":"04.2 - Corporate Service Administration"},null,44340818,37316724.009999998,0,0,0,0,0,0,37316724.009999998,42153775,44113667]
[{"$f":"'Org structure'!E26","v":"04.3 - Human Resources"},null,16861620,11699680.02,0,0,0,0,268000,268000,11967680.02,14849578,15695857]
[{"$f":"'Org structure'!E27","v":"04.4 - Media & Communication"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E28","v":"04.5 - Organisational Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E29","v":"04.6 - Labour Relations"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E30","v":"04.7 - Legal Services"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E31","v":"04.8 - Information Technology Services"},null,74955189,54785380.039999999,0,0,0,0,0,0,54785380.039999999,32329546,33659955]
[{"$f":"'Org structure'!A6","v":"Vote 05 - Community Services"},null,{"$f":"SUM(C125:C138)","v":182219774},146158806.09,0,0,0,0,-179487,-179487,145979319.09,{"$f":"SUM(L125:L138)","v":166499408},{"$f":"SUM(M125:M138)","v":175379400}]
[{"$f":"'Org structure'!E33","v":"05.1 - Municipal Buildings"},null,26561133,19069214,0,0,0,0,0,{"$f":"SUM(E125:I125)","v":0},{"$f":"IF(D125=0,C125+J125,D125+J125)","v":19069214},9784996,10271545]
[{"$f":"'Org structure'!E34","v":"05.2 - Fleet Management"},null,17935850,15293850.029999999,0,0,0,0,0,0,15293850.029999999,19271527,20217468]
[{"$f":"'Org structure'!E35","v":"05.3 - Community Services Administration"},null,1829793,3161244,0,0,0,0,0,0,3161244,1981674,2080758]
[{"$f":"'Org structure'!E36","v":"05.4 - Cemeteries"},null,605000,605000,0,0,0,0,0,0,605000,3978010,4165699]
[{"$f":"'Org structure'!E37","v":"05.5 - Disaster Management"},null,660000,110000,0,0,0,0,0,0,110000,2486022,2624448]
[{"$f":"'Org structure'!E38","v":"05.6 - Fires Service"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E39","v":"05.7 - Libraries"},null,2656715,3321202,0,0,0,0,-179487,-179487,3141715,1774148,1869130]
[{"$f":"'Org structure'!E40","v":"05.8 - Municipal Buildings"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E41","v":"05.9 - Sports Recreation & Social Amenitie"},null,29288851,25715503.010000002,0,0,0,0,0,0,25715503.010000002,42725232,44784178]
[{"$f":"'Org structure'!E42","v":"05.10 - Waste Management Solid Waste"},null,60639445,46599806.020000003,0,0,0,0,0,0,46599806.020000003,49531163,52935124]
[{"$f":"'Org structure'!E43","v":"05.11 - Safety And Security"},null,29150069,21620069.02,0,0,0,0,0,0,21620069.02,24897500,25944375]
[{"$f":"'Org structure'!E44","v":"05.12 - Traffic Service"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E45","v":"05.13 - Traffic Service"},null,12892918,10662918.01,0,0,0,0,0,0,10662918.01,10069136,10486675]
[{"$f":"'Org structure'!E46","v":"05.14 - Fleet Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A7","v":"Vote 06 - Planning & Development"},null,{"$f":"SUM(C140:C149)","v":26201722},21871968.02,0,0,0,0,0,0,21871968.02,{"$f":"SUM(L140:L149)","v":25289438},{"$f":"SUM(M140:M149)","v":27330875}]
[{"$f":"'Org structure'!E48","v":"06.1 - Planning And Development Admin"},null,1909065,3011311.01,0,0,0,0,0,{"$f":"SUM(E140:I140)","v":0},{"$f":"IF(D140=0,C140+J140,D140+J140)","v":3011311.01},2004633,2103853]
[{"$f":"'Org structure'!E49","v":"06.2 - Municipal Planning Idp"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E50","v":"06.3 - Pms"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E51","v":"06.4 - Town Planning"},null,4420858,3493858.01,0,0,0,0,0,0,3493858.01,3969336,4641303]
[{"$f":"'Org structure'!E52","v":"06.5 - Land Use And Housing Admin"},null,5822286,5522286,0,0,0,0,0,0,5522286,6677188,7005524]
[{"$f":"'Org structure'!E53","v":"06.6 - Local Economic Development"},null,14049513,9844513,0,0,0,0,0,0,9844513,0,0]
[{"$f":"'Org structure'!E54","v":"06.7 - Led"},null,0,0,0,0,0,0,0,0,0,4481031,5015082]
[{"$f":"'Org structure'!E55","v":"06.8 - Agriculture & Rural Development"},null,0,0,0,0,0,0,0,0,0,8157250,8565113]
[{"$f":"'Org structure'!E56","v":"06.9 - Tourism & Business Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E57","v":"06.10 - Arts & Culture"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A8","v":"Vote 07 - Infrastructure & Technical Services"},null,{"$f":"SUM(C151:C169)","v":383941084},425182889.33999997,0,0,0,0,-2300000,{"$f":"SUM(E150:I150)","v":-2300000},{"$f":"IF(D150=0,C150+J150,D150+J150)","v":422882889.33999997},{"$f":"SUM(L151:L169)","v":415586746},{"$f":"SUM(M151:M169)","v":428723092}]
[{"$f":"'Org structure'!E59","v":"07.1 - Infrastructure Admin & Tech Admin"},null,2586091,2376103.0099999998,0,0,0,0,0,{"$f":"SUM(E151:I151)","v":0},{"$f":"IF(D151=0,C151+J151,D151+J151)","v":2376103.0099999998},2463847,2585877]
[{"$f":"'Org structure'!E60","v":"07.2 - Fleet Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E61","v":"07.3 - Roads"},null,83834249,71782249.040000007,0,0,0,0,0,0,71782249.040000007,61628341,64465015]
[{"$f":"'Org structure'!E62","v":"07.4 - Storm Water"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E63","v":"07.5 - Street Lighting"},null,19208720,13608720,0,0,0,0,0,0,13608720,8598588,8878798]
[{"$f":"'Org structure'!E64","v":"07.6 - Project Management Unit"},null,5167637,3582637,0,0,0,0,0,0,3582637,4178767,4404630]
[{"$f":"'Org structure'!E65","v":"07.7 - Sanitation Treatment Plant: Mogwase"},null,2979877,7635060.0300000003,0,0,0,0,0,0,7635060.0300000003,6330194,6727353]
[{"$f":"'Org structure'!E66","v":"07.8 - Sanitation Treatment Plant: Madikwe"},null,3878437,5543359,0,0,0,0,0,0,5543359,8369184,8787645]
[{"$f":"'Org structure'!E67","v":"07.9 - Sanitation Reticulation"},null,11926146,11611146,0,0,0,0,0,0,11611146,6528993,7228339]
[{"$f":"'Org structure'!E68","v":"07.10 - Water Administration"},null,17934502,45791014.009999998,0,0,0,0,-2300000,-2300000,43491014.009999998,46037321,48589188]
[{"$f":"'Org structure'!E69","v":"07.11 - Water Madikwe: Water Treatment Work"},null,1552000,1817737.01,0,0,0,0,0,0,1817737.01,1260000,1780000]
[{"$f":"'Org structure'!E70","v":"07.12 - Water: Pella Water Treatment Works"},null,504000,1634714,0,0,0,0,0,0,1634714,300000,370000]
[{"$f":"'Org structure'!E71","v":"07.13 - Water: Madikwe Retail & Bulk Lines"},null,2004000,3548178.01,0,0,0,0,0,0,3548178.01,2000000,2500000]
[{"$f":"'Org structure'!E72","v":"07.14 - Water: Madikwe Rural"},null,3403000,4096667,0,0,0,0,0,0,4096667,4200000,5000000]
[{"$f":"'Org structure'!E73","v":"07.15 - Water: Molatedi"},null,260000,306286,0,0,0,0,0,0,306286,210000,240000]
[{"$f":"'Org structure'!E74","v":"07.16 - Water Eastern: Retail Mankwe"},null,10904131,7.0000000000000007E-2,0,0,0,0,0,0,7.0000000000000007E-2,0,0]
[{"$f":"'Org structure'!E75","v":"07.17 - Water Vaalkopdam: Mankwe"},null,1366665,7.0000000000000007E-2,0,0,0,0,0,0,7.0000000000000007E-2,0,0]
[{"$f":"'Org structure'!E76","v":"07.18 - Water Eastern: Retail Mankwe"},null,203731629,233703981.09,0,0,0,0,0,0,233703981.09,252481511,255660247]
[{"$f":"'Org structure'!E77","v":"07.19 - Reporting Function Electricity"},null,12700000,18145038,0,0,0,0,0,0,18145038,11000000,11506000]
[{"$f":"'Org structure'!A9","v":"Vote 08 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A10","v":"Vote 09 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A11","v":"Vote 10 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A12","v":"Vote 11 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A13","v":"Vote 12 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A14","v":"Vote 13 - "},null,0,0,0,0,0,0,0,{"$f":"SUM(E175:I175)","v":0},{"$f":"IF(D175=0,C175+J175,D175+J175)","v":0},0,0]
[{"$f":"'Org structure'!A15","v":"Vote 14 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A16","v":"Vote 15 - Other"},null,0,0,0,0,0,0,0,0,0,0,0]
["Total Expenditure by Vote",2,{"$f":"C94+C100+C107+C115+C124+C139+C150+C170+C171+C172+C173+C174+C175+C176+C177","v":967240322},905587234.86999989,0,0,0,0,88513,88513,905675747.86999989,938505262,980288792]
[]
[{"$f":"result","v":"Surplus/ (Deficit) for the year"},2,{"$f":"C91-C178","v":68850206},74423570.120000124,0,0,0,0,290000,{"$f":"SUM(E180:I180)","v":290000},{"$f":"IF(D180=0,C180+J180,D180+J180)","v":74713570.120000124},{"$f":"L91-L178","v":160194654},{"$f":"M91-M178","v":178403878}]
[{"$f":"head27a","v":"References"}]
["1. Insert 'Vote'; e.g. Department, if different to standard structure"]
["2. Must reconcile to Financial Performance ('Revenue and Expenditure by Standard Classification' and 'Revenue and Expenditure')"]
["3. Assign share in 'associate' to relevant Vote"]

{"sheet":"B4-FinPerf RE","index":11,"n_rows":62,"n_cols":13,"rows_kept":62,"cut":false,"hidden":false,"merged":[[1,2,1,10],[1,1,3,1],[59,0,59,12],[60,0,60,12],[52,0,52,12],[53,0,53,12],[54,0,54,12],[55,0,55,12],[57,0,57,12],[1,0,3,0]]}
[{"$f":"muni&\" - \"&_ADJ4&\" - \"&Date","v":"NW375 Moses Kotane - Table B4 Adjustments Budget Financial Performance (revenue and expenditure) - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,3,4,5,6,7,8,9,10]
["R thousands",1,"A","A1","B","C","D","E","F","G","H"]
["Revenue By Source"]
["Property rates",2,{"$f":"'SB1'!C10","v":142163600},{"$f":"'SB1'!D10","v":142163600},{"$f":"'SB1'!E10","v":0},{"$f":"'SB1'!F10","v":0},{"$f":"'SB1'!G10","v":0},{"$f":"'SB1'!H10","v":0},{"$f":"'SB1'!I10","v":0},{"$f":"SUM(E7:I7)","v":0},{"$f":"IF(D7=0,C7+J7,D7+J7)","v":142163600},{"$f":"'SB1'!L10","v":169026146},{"$f":"'SB1'!M10","v":176817777}]
["Service charges - electricity revenue",2,{"$f":"'SB1'!C16","v":0},{"$f":"'SB1'!D16","v":0},{"$f":"'SB1'!E16","v":0},{"$f":"'SB1'!F16","v":0},{"$f":"'SB1'!G16","v":0},{"$f":"'SB1'!H16","v":0},{"$f":"'SB1'!I16","v":0},0,0,{"$f":"'SB1'!L16","v":0},{"$f":"'SB1'!M16","v":0}]
["Service charges - water revenue",2,{"$f":"'SB1'!C22","v":171557000},{"$f":"'SB1'!D22","v":171557000},{"$f":"'SB1'!E22","v":0},{"$f":"'SB1'!F22","v":0},{"$f":"'SB1'!G22","v":0},{"$f":"'SB1'!H22","v":0},{"$f":"'SB1'!I22","v":0},0,171557000,{"$f":"'SB1'!L22","v":171527615},{"$f":"'SB1'!M22","v":171036225}]
["Service charges - sanitation revenue",2,{"$f":"'SB1'!C28","v":2750000},{"$f":"'SB1'!D28","v":2750000},{"$f":"'SB1'!E28","v":0},{"$f":"'SB1'!F28","v":0},{"$f":"'SB1'!G28","v":0},{"$f":"'SB1'!H28","v":0},{"$f":"'SB1'!I28","v":0},0,2750000,{"$f":"'SB1'!L28","v":2490398},{"$f":"'SB1'!M28","v":2595969}]
["Service charges - refuse revenue",2,{"$f":"'SB1'!C35","v":9944428},{"$f":"'SB1'!D35","v":9944428},{"$f":"'SB1'!E35","v":0},{"$f":"'SB1'!F35","v":0},{"$f":"'SB1'!G35","v":0},{"$f":"'SB1'!H35","v":0},{"$f":"'SB1'!I35","v":0},0,9944428,{"$f":"'SB1'!L35","v":12474707},{"$f":"'SB1'!M35","v":13048543}]
[]
["Rental of facilities and equipment",null,51000,71000,0,0,0,0,0,0,71000,30000,30000]
["Interest earned - external investments",null,5400000,6400000,0,0,0,0,0,0,6400000,5400000,5200000]
["Interest earned - outstanding debtors",null,59790000,59576790,0,0,0,0,0,0,59576790,62480550,65354656]
["Dividends received",null,0,0,0,0,0,0,0,0,0,0,0]
["Fines, penalties and forfeits",null,4500000,3500000,0,0,0,0,0,0,3500000,3000000,3000000]
["Licences and permits",null,50000,50000,0,0,0,0,0,0,50000,50000,50000]
["Agency services",null,null,null,null,null,null,null,null,0,0]
["Transfers and subsidies",null,437829637,374462124,0,0,0,0,88513,88513,374550637,467694767,500553630]
["Other revenue",2,{"$f":"'SB1'!C50","v":2530500},{"$f":"'SB1'!D50","v":3430500},{"$f":"'SB1'!E50","v":0},{"$f":"'SB1'!F50","v":0},{"$f":"'SB1'!G50","v":0},{"$f":"'SB1'!H50","v":0},{"$f":"'SB1'!I50","v":290000},290000,3720500,{"$f":"'SB1'!L50","v":2030500},{"$f":"'SB1'!M50","v":2080500}]
["Gains",null,0,0,0,0,0,0,0,0,0,0,0]
["Total Revenue (excluding capital transfers and contributions)",null,{"$f":"SUM(C7:C11)+SUM(C13:C22)","v":836566165},{"$f":"SUM(D7:D11)+SUM(D13:D22)","v":773905442},0,0,0,0,378513,{"$f":"SUM(J7:J11)+SUM(J13:J22)","v":378513},{"$f":"SUM(K7:K11)+SUM(K13:K22)","v":774283955},{"$f":"SUM(L7:L11)+SUM(L13:L22)","v":896204683},{"$f":"SUM(M7:M11)+SUM(M13:M22)","v":939767300}]
[]
["Expenditure By Type"]
["Employee related costs",null,{"$f":"'SB1'!C68","v":270274660},{"$f":"'SB1'!D68","v":248852359.38},{"$f":"'SB1'!E68","v":0},{"$f":"'SB1'!F68","v":0},{"$f":"'SB1'!G68","v":0},{"$f":"'SB1'!H68","v":0},{"$f":"'SB1'!I68","v":-2300000},{"$f":"SUM(E26:I26)","v":-2300000},{"$f":"IF(D26=0,C26+J26,D26+J26)","v":246552359.38},{"$f":"'SB1'!L68","v":278331407},{"$f":"'SB1'!M68","v":293509032}]
["Remuneration of councillors",null,25371420,25371420,0,0,0,0,2300000,2300000,27671420,24819114,26060071]
["Debt impairment",null,122540000,180148200,0,0,0,0,0,0,180148200,194602817,195274984]
["Depreciation & asset impairment",null,{"$f":"'SB1'!C84","v":154536733},{"$f":"'SB1'!D84","v":154536733},{"$f":"'SB1'!E84","v":0},{"$f":"'SB1'!F84","v":0},{"$f":"'SB1'!G84","v":0},{"$f":"'SB1'!H84","v":0},{"$f":"'SB1'!I84","v":0},0,154536733,{"$f":"'SB1'!L84","v":133503316},{"$f":"'SB1'!M84","v":139644469}]
["Finance charges",null,3688959,3688959,0,0,0,0,0,0,3688959,3043808,2729218]
["Bulk purchases",null,{"$f":"'SB1'!C89","v":103700000},{"$f":"'SB1'!D89","v":89145038},{"$f":"'SB1'!E89","v":0},{"$f":"'SB1'!F89","v":0},{"$f":"'SB1'!G89","v":0},{"$f":"'SB1'!H89","v":0},{"$f":"'SB1'!I89","v":0},0,89145038,{"$f":"'SB1'!L89","v":111000000},{"$f":"'SB1'!M89","v":116106000}]
["Other materials",null,5577250,3159151.02,0,0,0,0,268000,268000,3427151.02,5127300,5361500]
["Contracted services",null,{"$f":"'SB1'!C128","v":151836500},{"$f":"'SB1'!D128","v":111042019.11999999},{"$f":"'SB1'!E128","v":0},{"$f":"'SB1'!F128","v":0},{"$f":"'SB1'!G128","v":0},{"$f":"'SB1'!H128","v":0},{"$f":"'SB1'!I128","v":0},0,111042019.11999999,{"$f":"'SB1'!L128","v":121189200},{"$f":"'SB1'!M128","v":131288734}]
["Transfers and subsidies",null,0,0,0,0,0,0,0,0,0,0,0]
["Other expenditure",null,{"$f":"'SB1'!C158","v":129714800},{"$f":"'SB1'!D158","v":89643355.349999994},{"$f":"'SB1'!E158","v":0},{"$f":"'SB1'!F158","v":0},{"$f":"'SB1'!G158","v":0},{"$f":"'SB1'!H158","v":0},{"$f":"'SB1'!I158","v":-179487},-179487,89463868.349999994,{"$f":"'SB1'!L158","v":66888300},{"$f":"'SB1'!M158","v":70314784}]
["Losses",null,0,0,0,0,0,0,0,0,0,0,0]
["Total Expenditure",null,{"$f":"SUM(C26:C36)","v":967240322},905587234.87,0,0,0,0,88513,88513,905675747.87,938505262,980288792]
[]
["Surplus/(Deficit)",null,{"$f":"C23-C37","v":-130674157},-131681792.87,0,0,0,0,290000,290000,-131391792.87,-42300579,-40521492]
["Transfers and subsidies - capital (monetary allocations) (National / Provincial and District)",null,87086153,93773318,0,0,0,0,0,{"$f":"SUM(E40:I40)","v":0},{"$f":"IF(D40=0,C40+J40,D40+J40)","v":93773318},202495233,218925370]
["Transfers and subsidies - capital (monetary allocations) (National / Provincial Departmental Agencies, Households, Non-profit Institutions, Private Enterprises, Public Corporatons, Higher Educational Institutions)",null,112438210,112332044.98999999,0,0,0,0,0,{"$f":"SUM(E41:I41)","v":0},{"$f":"IF(D41=0,C41+J41,D41+J41)","v":112332044.98999999},0,0]
["Transfers and subsidies - capital (in-kind - all) ",null,0,0,0,0,0,0,0,{"$f":"SUM(E42:I42)","v":0},{"$f":"IF(D42=0,C42+J42,D42+J42)","v":0},0,0]
["Surplus/(Deficit) before taxation",null,{"$f":"SUM(C39:C42)","v":68850206},74423570.11999999,0,0,0,0,290000,290000,74713570.11999999,160194654,178403878]
["Taxation",null,null,null,null,null,null,null,null,{"$f":"SUM(E44:I44)","v":0},{"$f":"IF(D44=0,C44+J44,D44+J44)","v":0}]
["Surplus/(Deficit) after taxation",null,{"$f":"C43-C44","v":68850206},74423570.11999999,0,0,0,0,290000,290000,74713570.11999999,160194654,178403878]
["Attributable to minorities",null,null,null,null,null,null,null,null,{"$f":"SUM(E46:I46)","v":0},{"$f":"IF(D46=0,C46+J46,D46+J46)","v":0}]
["Surplus/(Deficit) attributable to municipality",null,{"$f":"SUM(C45:C46)","v":68850206},74423570.11999999,0,0,0,0,290000,290000,74713570.11999999,160194654,178403878]
["Share of surplus/ (deficit) of associate",null,null,null,null,null,null,null,null,{"$f":"SUM(E48:I48)","v":0},{"$f":"IF(D48=0,C48+J48,D48+J48)","v":0}]
["Surplus/ (Deficit) for the year",null,{"$f":"C47+C48","v":68850206},74423570.11999999,0,0,0,0,290000,290000,74713570.11999999,160194654,178403878]
[{"$f":"head27a","v":"References"}]
["1. Classifications are revenue sources and expenditure type"]
["2. Detail to be provided in Table SB1"]
["3. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["4. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["5. Increases of funds approved under MFMA section 31"]
["6. Adjustments approved in accordance with MFMA section 29 "]
["7. Adjustments to transfers from National or Provincial Government"]
["8. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["9. G = B + C + D + E + F"]
["10. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
["Revenue total",null,{"$f":"C23+C40+C41+C42","v":1036090528},980010804.99000001,0,0,0,0,378513,378513,980389317.99000001,1098699916,1158692670]

{"sheet":"B5-Capex","index":12,"n_rows":91,"n_cols":13,"rows_kept":91,"cut":false,"hidden":false,"merged":[[82,0,82,12],[83,0,83,12],[84,0,84,12],[86,0,86,12],[88,0,88,12],[80,0,80,11],[81,0,81,12],[1,0,2,0],[1,1,2,1],[78,0,78,12],[1,2,1,10],[79,0,79,11]]}
[{"$f":"muni&\" - \"&_ADJ5&\" - \"&Date","v":"NW375 Moses Kotane - Table B5 Adjustments Capital Expenditure Budget by vote and funding - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,5,6,7,8,9,10,11,12]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Capital expenditure - Vote"]
["Multi-year expenditure to be adjusted",2]
[{"$f":"B5B!A8","v":"Vote 01 - Municipal Council"},null,{"$f":"B5B!C8","v":0},{"$f":"B5B!D8","v":0},{"$f":"B5B!E8","v":0},{"$f":"B5B!F8","v":0},{"$f":"B5B!G8","v":0},{"$f":"B5B!H8","v":0},{"$f":"B5B!I8","v":0},{"$f":"B5B!J8","v":0},{"$f":"B5B!K8","v":0},{"$f":"B5B!L8","v":0},{"$f":"B5B!M8","v":0}]
[{"$f":"B5B!A14","v":"Vote 02 - Office Of The Accounting Officer"},null,{"$f":"B5B!C14","v":0},{"$f":"B5B!D14","v":0},{"$f":"B5B!E14","v":0},{"$f":"B5B!F14","v":0},{"$f":"B5B!G14","v":0},{"$f":"B5B!H14","v":0},{"$f":"B5B!I14","v":0},{"$f":"B5B!J14","v":0},{"$f":"B5B!K14","v":0},{"$f":"B5B!L14","v":0},{"$f":"B5B!M14","v":0}]
[{"$f":"B5B!A21","v":"Vote 03 - Budget And Treasury Office"},null,{"$f":"B5B!C21","v":0},{"$f":"B5B!D21","v":0},{"$f":"B5B!E21","v":0},{"$f":"B5B!F21","v":0},{"$f":"B5B!G21","v":0},{"$f":"B5B!H21","v":0},{"$f":"B5B!I21","v":0},{"$f":"B5B!J21","v":0},{"$f":"B5B!K21","v":0},{"$f":"B5B!L21","v":0},{"$f":"B5B!M21","v":0}]
[{"$f":"B5B!A29","v":"Vote 04 - Corporate Services"},null,{"$f":"B5B!C29","v":0},{"$f":"B5B!D29","v":0},{"$f":"B5B!E29","v":0},{"$f":"B5B!F29","v":0},{"$f":"B5B!G29","v":0},{"$f":"B5B!H29","v":0},{"$f":"B5B!I29","v":0},{"$f":"B5B!J29","v":0},{"$f":"B5B!K29","v":0},{"$f":"B5B!L29","v":0},{"$f":"B5B!M29","v":0}]
[{"$f":"B5B!A38","v":"Vote 05 - Community Services"},null,{"$f":"B5B!C38","v":0},{"$f":"B5B!D38","v":0},{"$f":"B5B!E38","v":0},{"$f":"B5B!F38","v":0},{"$f":"B5B!G38","v":0},{"$f":"B5B!H38","v":0},{"$f":"B5B!I38","v":0},{"$f":"B5B!J38","v":0},{"$f":"B5B!K38","v":0},{"$f":"B5B!L38","v":0},{"$f":"B5B!M38","v":0}]
[{"$f":"B5B!A53","v":"Vote 06 - Planning & Development"},null,{"$f":"B5B!C53","v":0},{"$f":"B5B!D53","v":0},{"$f":"B5B!E53","v":0},{"$f":"B5B!F53","v":0},{"$f":"B5B!G53","v":0},{"$f":"B5B!H53","v":0},{"$f":"B5B!I53","v":0},{"$f":"B5B!J53","v":0},{"$f":"B5B!K53","v":0},{"$f":"B5B!L53","v":0},{"$f":"B5B!M53","v":0}]
[{"$f":"B5B!A64","v":"Vote 07 - Infrastructure & Technical Services"},null,{"$f":"B5B!C64","v":73297563},{"$f":"B5B!D64","v":77790502.019999996},{"$f":"B5B!E64","v":0},{"$f":"B5B!F64","v":0},{"$f":"B5B!G64","v":0},{"$f":"B5B!H64","v":0},{"$f":"B5B!I64","v":0},{"$f":"B5B!J64","v":0},{"$f":"B5B!K64","v":77790502.019999996},{"$f":"B5B!L64","v":11375458},{"$f":"B5B!M64","v":17503825}]
[{"$f":"'Org structure'!A9","v":"Vote 08 - "},null,{"$f":"B5B!C84","v":0},{"$f":"B5B!D84","v":0},{"$f":"B5B!E84","v":0},{"$f":"B5B!F84","v":0},{"$f":"B5B!G84","v":0},{"$f":"B5B!H84","v":0},{"$f":"B5B!I84","v":0},{"$f":"SUM(E15:I15)","v":0},{"$f":"IF(D15=0,C15+J15,D15+J15)","v":0},{"$f":"B5B!L84","v":0},{"$f":"B5B!M84","v":0}]
[{"$f":"'Org structure'!A10","v":"Vote 09 - "},null,{"$f":"B5B!C85","v":0},{"$f":"B5B!D85","v":0},{"$f":"B5B!E85","v":0},{"$f":"B5B!F85","v":0},{"$f":"B5B!G85","v":0},{"$f":"B5B!H85","v":0},{"$f":"B5B!I85","v":0},0,0,{"$f":"B5B!L85","v":0},{"$f":"B5B!M85","v":0}]
[{"$f":"'Org structure'!A11","v":"Vote 10 - "},null,{"$f":"B5B!C86","v":0},{"$f":"B5B!D86","v":0},{"$f":"B5B!E86","v":0},{"$f":"B5B!F86","v":0},{"$f":"B5B!G86","v":0},{"$f":"B5B!H86","v":0},{"$f":"B5B!I86","v":0},0,0,{"$f":"B5B!L86","v":0},{"$f":"B5B!M86","v":0}]
[{"$f":"'Org structure'!A12","v":"Vote 11 - "},null,{"$f":"B5B!C87","v":0},{"$f":"B5B!D87","v":0},{"$f":"B5B!E87","v":0},{"$f":"B5B!F87","v":0},{"$f":"B5B!G87","v":0},{"$f":"B5B!H87","v":0},{"$f":"B5B!I87","v":0},0,0,{"$f":"B5B!L87","v":0},{"$f":"B5B!M87","v":0}]
[{"$f":"'Org structure'!A13","v":"Vote 12 - "},null,{"$f":"B5B!C88","v":0},{"$f":"B5B!D88","v":0},{"$f":"B5B!E88","v":0},{"$f":"B5B!F88","v":0},{"$f":"B5B!G88","v":0},{"$f":"B5B!H88","v":0},{"$f":"B5B!I88","v":0},0,0,{"$f":"B5B!L88","v":0},{"$f":"B5B!M88","v":0}]
[{"$f":"'Org structure'!A14","v":"Vote 13 - "},null,{"$f":"B5B!C89","v":0},{"$f":"B5B!D89","v":0},{"$f":"B5B!E89","v":0},{"$f":"B5B!F89","v":0},{"$f":"B5B!G89","v":0},{"$f":"B5B!H89","v":0},{"$f":"B5B!I89","v":0},0,0,{"$f":"B5B!L89","v":0},{"$f":"B5B!M89","v":0}]
[{"$f":"'Org structure'!A15","v":"Vote 14 - "},null,{"$f":"B5B!C90","v":0},{"$f":"B5B!D90","v":0},{"$f":"B5B!E90","v":0},{"$f":"B5B!F90","v":0},{"$f":"B5B!G90","v":0},{"$f":"B5B!H90","v":0},{"$f":"B5B!I90","v":0},0,0,{"$f":"B5B!L90","v":0},{"$f":"B5B!M90","v":0}]
[{"$f":"'Org structure'!A16","v":"Vote 15 - Other"},null,{"$f":"B5B!C91","v":0},{"$f":"B5B!D91","v":0},{"$f":"B5B!E91","v":0},{"$f":"B5B!F91","v":0},{"$f":"B5B!G91","v":0},{"$f":"B5B!H91","v":0},{"$f":"B5B!I91","v":0},0,0,{"$f":"B5B!L91","v":0},{"$f":"B5B!M91","v":0}]
["Capital multi-year expenditure sub-total",3,{"$f":"SUM(C8:C22)","v":73297563},{"$f":"SUM(D8:D22)","v":77790502.019999996},0,0,0,0,0,{"$f":"SUM(J8:J22)","v":0},{"$f":"SUM(K8:K22)","v":77790502.019999996},{"$f":"SUM(L8:L22)","v":11375458},{"$f":"SUM(M8:M22)","v":17503825}]
[]
["Single-year expenditure to be adjusted",2]
[{"$f":"B5B!A96","v":"Vote 01 - Municipal Council"},null,{"$f":"B5B!C96","v":0},{"$f":"B5B!D96","v":0},{"$f":"B5B!E96","v":0},{"$f":"B5B!F96","v":0},{"$f":"B5B!G96","v":0},{"$f":"B5B!H96","v":0},{"$f":"B5B!I96","v":0},{"$f":"B5B!J96","v":0},{"$f":"B5B!K96","v":0},{"$f":"B5B!L96","v":0},{"$f":"B5B!M96","v":0}]
[{"$f":"B5B!A102","v":"Vote 02 - Office Of The Accounting Officer"},null,{"$f":"B5B!C102","v":0},{"$f":"B5B!D102","v":0},{"$f":"B5B!E102","v":0},{"$f":"B5B!F102","v":0},{"$f":"B5B!G102","v":0},{"$f":"B5B!H102","v":0},{"$f":"B5B!I102","v":0},{"$f":"B5B!J102","v":0},{"$f":"B5B!K102","v":0},{"$f":"B5B!L102","v":0},{"$f":"B5B!M102","v":0}]
[{"$f":"B5B!A109","v":"Vote 03 - Budget And Treasury Office"},null,{"$f":"B5B!C109","v":100000},{"$f":"B5B!D109","v":0.01},{"$f":"B5B!E109","v":0},{"$f":"B5B!F109","v":0},{"$f":"B5B!G109","v":0},{"$f":"B5B!H109","v":0},{"$f":"B5B!I109","v":0},{"$f":"B5B!J109","v":0},{"$f":"B5B!K109","v":0.01},{"$f":"B5B!L109","v":0},{"$f":"B5B!M109","v":0}]
[{"$f":"B5B!A117","v":"Vote 04 - Corporate Services"},null,{"$f":"B5B!C117","v":550000},{"$f":"B5B!D117","v":0.03},{"$f":"B5B!E117","v":0},{"$f":"B5B!F117","v":0},{"$f":"B5B!G117","v":0},{"$f":"B5B!H117","v":0},{"$f":"B5B!I117","v":113975},{"$f":"B5B!J117","v":113975},{"$f":"B5B!K117","v":113975.03},{"$f":"B5B!L117","v":0},{"$f":"B5B!M117","v":0}]
[{"$f":"B5B!A126","v":"Vote 05 - Community Services"},null,{"$f":"B5B!C126","v":30587162},{"$f":"B5B!D126","v":30726754.030000005},{"$f":"B5B!E126","v":0},{"$f":"B5B!F126","v":0},{"$f":"B5B!G126","v":0},{"$f":"B5B!H126","v":0},{"$f":"B5B!I126","v":0},{"$f":"B5B!J126","v":0},{"$f":"B5B!K126","v":30726754.030000005},{"$f":"B5B!L126","v":12864475},{"$f":"B5B!M126","v":27104155}]
[{"$f":"B5B!A141","v":"Vote 06 - Planning & Development"},null,{"$f":"B5B!C141","v":0},{"$f":"B5B!D141","v":0},{"$f":"B5B!E141","v":0},{"$f":"B5B!F141","v":0},{"$f":"B5B!G141","v":0},{"$f":"B5B!H141","v":0},{"$f":"B5B!I141","v":0},{"$f":"B5B!J141","v":0},{"$f":"B5B!K141","v":0},{"$f":"B5B!L141","v":0},{"$f":"B5B!M141","v":0}]
[{"$f":"B5B!A152","v":"Vote 07 - Infrastructure & Technical Services"},null,{"$f":"B5B!C152","v":100267422},{"$f":"B5B!D152","v":97588106.099999994},{"$f":"B5B!E152","v":0},{"$f":"B5B!F152","v":0},{"$f":"B5B!G152","v":0},{"$f":"B5B!H152","v":0},{"$f":"B5B!I152","v":0},{"$f":"B5B!J152","v":0},{"$f":"B5B!K152","v":97588106.099999994},{"$f":"B5B!L152","v":178255300},{"$f":"B5B!M152","v":174317389}]
[{"$f":"'Org structure'!A9","v":"Vote 08 - "},null,{"$f":"B5B!C172","v":0},{"$f":"B5B!D172","v":0},{"$f":"B5B!E172","v":0},{"$f":"B5B!F172","v":0},{"$f":"B5B!G172","v":0},{"$f":"B5B!H172","v":0},{"$f":"B5B!I172","v":0},{"$f":"SUM(E33:I33)","v":0},{"$f":"IF(D33=0,C33+J33,D33+J33)","v":0},{"$f":"B5B!L172","v":0},{"$f":"B5B!M172","v":0}]
[{"$f":"'Org structure'!A10","v":"Vote 09 - "},null,{"$f":"B5B!C173","v":0},{"$f":"B5B!D173","v":0},{"$f":"B5B!E173","v":0},{"$f":"B5B!F173","v":0},{"$f":"B5B!G173","v":0},{"$f":"B5B!H173","v":0},{"$f":"B5B!I173","v":0},0,0,{"$f":"B5B!L173","v":0},{"$f":"B5B!M173","v":0}]
[{"$f":"'Org structure'!A11","v":"Vote 10 - "},null,{"$f":"B5B!C174","v":0},{"$f":"B5B!D174","v":0},{"$f":"B5B!E174","v":0},{"$f":"B5B!F174","v":0},{"$f":"B5B!G174","v":0},{"$f":"B5B!H174","v":0},{"$f":"B5B!I174","v":0},0,0,{"$f":"B5B!L174","v":0},{"$f":"B5B!M174","v":0}]
[{"$f":"'Org structure'!A12","v":"Vote 11 - "},null,{"$f":"B5B!C175","v":0},{"$f":"B5B!D175","v":0},{"$f":"B5B!E175","v":0},{"$f":"B5B!F175","v":0},{"$f":"B5B!G175","v":0},{"$f":"B5B!H175","v":0},{"$f":"B5B!I175","v":0},0,0,{"$f":"B5B!L175","v":0},{"$f":"B5B!M175","v":0}]
[{"$f":"'Org structure'!A13","v":"Vote 12 - "},null,{"$f":"B5B!C176","v":0},{"$f":"B5B!D176","v":0},{"$f":"B5B!E176","v":0},{"$f":"B5B!F176","v":0},{"$f":"B5B!G176","v":0},{"$f":"B5B!H176","v":0},{"$f":"B5B!I176","v":0},0,{"$f":"IF(D37=0,C37+J37,D37+J37)","v":0},{"$f":"B5B!L176","v":0},{"$f":"B5B!M176","v":0}]
[{"$f":"'Org structure'!A14","v":"Vote 13 - "},null,{"$f":"B5B!C177","v":0},{"$f":"B5B!D177","v":0},{"$f":"B5B!E177","v":0},{"$f":"B5B!F177","v":0},{"$f":"B5B!G177","v":0},{"$f":"B5B!H177","v":0},{"$f":"B5B!I177","v":0},0,0,{"$f":"B5B!L177","v":0},{"$f":"B5B!M177","v":0}]
[{"$f":"'Org structure'!A15","v":"Vote 14 - "},null,{"$f":"B5B!C178","v":0},{"$f":"B5B!D178","v":0},{"$f":"B5B!E178","v":0},{"$f":"B5B!F178","v":0},{"$f":"B5B!G178","v":0},{"$f":"B5B!H178","v":0},{"$f":"B5B!I178","v":0},0,0,{"$f":"B5B!L178","v":0},{"$f":"B5B!M178","v":0}]
[{"$f":"'Org structure'!A16","v":"Vote 15 - Other"},null,{"$f":"B5B!C179","v":0},{"$f":"B5B!D179","v":0},{"$f":"B5B!E179","v":0},{"$f":"B5B!F179","v":0},{"$f":"B5B!G179","v":0},{"$f":"B5B!H179","v":0},{"$f":"B5B!I179","v":0},0,0,{"$f":"B5B!L179","v":0},{"$f":"B5B!M179","v":0}]
["Capital single-year expenditure sub-total",null,{"$f":"SUM(C26:C40)","v":131504584},{"$f":"SUM(D26:D40)","v":128314860.17},0,0,0,0,113975,{"$f":"SUM(J26:J40)","v":113975},{"$f":"SUM(K26:K40)","v":128428835.17},{"$f":"SUM(L26:L40)","v":191119775},{"$f":"SUM(M26:M40)","v":201421544}]
["Total Capital Expenditure - Vote",null,{"$f":"C41+C23","v":204802147},{"$f":"D41+D23","v":206105362.19},0,0,0,0,113975,{"$f":"J23+J41","v":113975},{"$f":"K23+K41","v":206219337.19},{"$f":"L41+L23","v":202495233},{"$f":"M41+M23","v":218925369}]
[]
["Capital Expenditure - Functional"]
["Governance and administration",null,{"$f":"SUM(C46:C48)","v":650000},0.04,0,0,0,0,113975,{"$f":"SUM(J46:J48)","v":113975},113975.03999999999,0,0]
["Executive and council",null,null,null,null,null,null,null,null,{"$f":"SUM(E46:I46)","v":0},{"$f":"IF(D46=0,C46+J46,D46+J46)","v":0}]
["Finance and administration",null,650000,0.04,0,0,0,0,113975,{"$f":"SUM(E47:I47)","v":113975},{"$f":"IF(D47=0,C47+J47,D47+J47)","v":113975.03999999999},0,0]
["Internal audit",null,null,null,null,null,null,null,null,{"$f":"SUM(E48:I48)","v":0},{"$f":"IF(D48=0,C48+J48,D48+J48)","v":0}]
["Community and public safety",null,{"$f":"SUM(C50:C54)","v":14790253},30726754.020000003,0,0,0,0,0,{"$f":"SUM(J50:J54)","v":0},30726754.020000003,9864475,8000000]
["Community and social services",null,14590253,30726754.010000002,0,0,0,0,0,{"$f":"SUM(E50:I50)","v":0},{"$f":"IF(D50=0,C50+J50,D50+J50)","v":30726754.010000002},0,8000000]
["Sport and recreation",null,200000,0.01,0,0,0,0,0,{"$f":"SUM(E51:I51)","v":0},{"$f":"IF(D51=0,C51+J51,D51+J51)","v":0.01},9864475,0]
["Public safety",null,0,0,0,0,0,0,0,{"$f":"SUM(E52:I52)","v":0},{"$f":"IF(D52=0,C52+J52,D52+J52)","v":0},0,0]
["Housing",null,null,null,null,null,null,null,null,{"$f":"SUM(E53:I53)","v":0},{"$f":"IF(D53=0,C53+J53,D53+J53)","v":0}]
["Health",null,null,null,null,null,null,null,null,{"$f":"SUM(E54:I54)","v":0},{"$f":"IF(D54=0,C54+J54,D54+J54)","v":0}]
["Economic and environmental services",null,{"$f":"SUM(C56:C58)","v":62193238},61188317.009999998,0,0,0,0,0,0,61188317.009999998,60981783,60000000]
["Planning and development",null,null,null,null,null,null,null,null,{"$f":"SUM(E56:I56)","v":0},{"$f":"IF(D56=0,C56+J56,D56+J56)","v":0}]
["Road transport",null,62193238,61188317.009999998,0,0,0,0,0,{"$f":"SUM(E57:I57)","v":0},{"$f":"IF(D57=0,C57+J57,D57+J57)","v":61188317.009999998},60981783,60000000]
["Environmental protection",null,null,null,null,null,null,null,null,{"$f":"SUM(E58:I58)","v":0},{"$f":"IF(D58=0,C58+J58,D58+J58)","v":0}]
["Trading services",null,{"$f":"SUM(C60:C63)","v":127168656},{"$f":"SUM(D60:D63)","v":114190291.12000002},0,0,0,0,{"$f":"SUM(I60:I63)","v":0},{"$f":"SUM(J60:J63)","v":0},114190291.12000002,131648975,150925369]
["Energy sources",null,22445688,20416973.030000001,0,0,0,0,0,{"$f":"SUM(E60:I60)","v":0},{"$f":"IF(D60=0,C60+J60,D60+J60)","v":20416973.030000001},11577740,12557370]
["Water management",null,64814603,81281082.010000005,0,0,0,0,0,{"$f":"SUM(E61:I61)","v":0},{"$f":"IF(D61=0,C61+J61,D61+J61)","v":81281082.010000005},91183878,94263844]
["Waste water management",null,24111456,12492236.07,0,0,0,0,0,{"$f":"SUM(E62:I62)","v":0},{"$f":"IF(D62=0,C62+J62,D62+J62)","v":12492236.07},25887357,25000000]
["Waste management",null,15796909,0.01,0,0,0,0,0,{"$f":"SUM(E63:I63)","v":0},{"$f":"IF(D63=0,C63+J63,D63+J63)","v":0.01},3000000,19104155]
["Other",null,null,null,null,null,null,null,null,{"$f":"SUM(E64:I64)","v":0},{"$f":"IF(D64=0,C64+J64,D64+J64)","v":0}]
["Total Capital Expenditure - Functional",3,{"$f":"C45+C49+C55+C59+C64","v":204802147},{"$f":"D45+D49+D55+D59+D64","v":206105362.19},0,0,0,0,{"$f":"I45+I49+I55+I59+I64","v":113975},113975,206219337.19,202495233,218925369]
[]
["Funded by:"]
["National Government",null,201361894,206105362.13,0,0,0,0,0,{"$f":"SUM(E68:I68)","v":0},{"$f":"IF(D68=0,C68+J68,D68+J68)","v":206105362.13},202495233,218925369]
["Provincial Government",null,null,null,null,null,null,null,null,{"$f":"SUM(E69:I69)","v":0},{"$f":"IF(D69=0,C69+J69,D69+J69)","v":0}]
["District Municipality",null,null,null,null,null,null,null,null,{"$f":"SUM(E70:I70)","v":0},{"$f":"IF(D70=0,C70+J70,D70+J70)","v":0}]
[{"$f":"'B4-FinPerf RE'!A41","v":"Transfers and subsidies - capital (monetary allocations) (National / Provincial Departmental Agencies, Households, Non-profit Institutions, Private Enterprises, Public Corporatons, Higher Educational Institutions)"},null,0,0,0,0,0,0,0,{"$f":"SUM(E71:I71)","v":0},{"$f":"IF(D71=0,C71+J71,D71+J71)","v":0},0,0]
["Transfers recognised - capital",4,{"$f":"SUM(C68:C71)","v":201361894},206105362.13,0,0,0,0,0,0,206105362.13,202495233,218925369]
[]
["Borrowing",null,null,null,null,null,null,null,null,{"$f":"SUM(E74:I74)","v":0},{"$f":"IF(D74=0,C74+J74,D74+J74)","v":0}]
["Internally generated funds",null,3440253,0.06,0,0,0,0,113975,{"$f":"SUM(E75:I75)","v":113975},{"$f":"IF(D75=0,C75+J75,D75+J75)","v":113975.06},0,0]
["Total Capital Funding",null,{"$f":"+C72+C74+C75","v":204802147},{"$f":"+D72+D74+D75","v":206105362.19},0,0,0,0,113975,113975,206219337.19,202495233,218925369]
[{"$f":"head27a","v":"References"}]
["1. Municipalities may choose to appropriate for capital expenditure for three years or for one year (if one year appropriation projected expenditure required for yr2 and yr3)."]
["2. Include capital component of PPP unitary payment. Note that capital transfers are only appropriated to municipalities for the budget year"]
["3. Capital expenditure by standard classification must reconcile to the appropriations by vote"]
["4. Must reconcile to supporting table SB7 and to Adjustments Budget Financial Performance (revenue and expenditure)"]
["5. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["6. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["7. Increases of funds approved under MFMA section 31"]
["8. Adjustments approved in accordance with MFMA section 29 "]
["9. Adjustments to transfers from National or Provincial Government"]
["10. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["11. G = B + C + D + E + F"]
["12. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
["check balance",null,{"$f":"C65-C76","v":0},{"$f":"D65-D76","v":0},{"$f":"E65-E76","v":0},null,null,{"$f":"H65-H76","v":0},{"$f":"I65-I76","v":0},{"$f":"J65-J76","v":0},{"$f":"K65-K76","v":0},{"$f":"L65-L76","v":0},{"$f":"K23-K76","v":-128428835.17}]

{"sheet":"B5B","index":13,"n_rows":187,"n_cols":13,"rows_kept":187,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,1,4,1],[1,2,1,10]]}
[{"$f":"muni&\" - \"&_ADJ5&\" - B\"&\" - \"&Date","v":"NW375 Moses Kotane - Table B5 Adjustments Capital Expenditure Budget by vote and funding - B - 44171"}]
[{"$f":"Vdesc","v":"Vote Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["[Insert departmental structure etc]",null,null,3,4,5,6,7,8,9,10]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Capital expenditure - Municipal Vote"]
["Multi-year expenditure appropriation",2]
[{"$f":"'Org structure'!A2","v":"Vote 01 - Municipal Council"},null,{"$f":"SUM(C9:C13)","v":0},0,0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":0},{"$f":"SUM(L9:L13)","v":0},{"$f":"SUM(M9:M13)","v":0}]
[{"$f":"'Org structure'!E3","v":"01.1 - Office Of The Mayor"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E4","v":"01.2 - Office Of The Speaker"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E5","v":"01.3 - Office Of The Chief Whip"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E6","v":"01.4 - Mpac"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E7","v":"01.5 - Council General Administration"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!A3","v":"Vote 02 - Office Of The Accounting Officer"},null,{"$f":"SUM(C15:C20)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L15:L20)","v":0},{"$f":"SUM(M15:M20)","v":0}]
[{"$f":"'Org structure'!E9","v":"02.1 - Office Of The Ao Admin"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E10","v":"02.2 - Strategic Planning Monitoring & Evaluat"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E11","v":"02.3 - Perfomance Management System"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E12","v":"02.4 - Internal Audit"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E13","v":"02.5 - Municipal Planning Idp"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E14","v":"02.6 - Risk"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!A4","v":"Vote 03 - Budget And Treasury Office"},null,{"$f":"SUM(C22:C28)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L22:L28)","v":0},{"$f":"SUM(M22:M28)","v":0}]
[{"$f":"'Org structure'!E16","v":"03.1 - Chief Financial Officer Admin"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E17","v":"03.2 - Budget Expenditure & Reporting"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E18","v":"03.3 - Budget Expenditure & Reporting"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E19","v":"03.4 - Revenue Management"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E20","v":"03.5 - Supply Chain Management"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E21","v":"03.6 - Assets Management"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E22","v":"03.7 - Expenditure"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!A5","v":"Vote 04 - Corporate Services"},null,{"$f":"SUM(C30:C37)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L30:L37)","v":0},{"$f":"SUM(M30:M37)","v":0}]
[{"$f":"'Org structure'!E24","v":"04.1 - Legal Services"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E25","v":"04.2 - Corporate Service Administration"},null,0,0,0,0,0,0,0,{"$f":"SUM(E31:I31)","v":0},{"$f":"IF(D31=0,C31+J31,D31+J31)","v":0},0,0]
[{"$f":"'Org structure'!E26","v":"04.3 - Human Resources"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E27","v":"04.4 - Media & Communication"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E28","v":"04.5 - Organisational Development"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E29","v":"04.6 - Labour Relations"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E30","v":"04.7 - Legal Services"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E31","v":"04.8 - Information Technology Services"},null,0,0,0,0,0,0,0,{"$f":"SUM(E37:I37)","v":0},{"$f":"IF(D37=0,C37+J37,D37+J37)","v":0},0,0]
[{"$f":"'Org structure'!A6","v":"Vote 05 - Community Services"},null,{"$f":"SUM(C39:C52)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L39:L52)","v":0},{"$f":"SUM(M39:M52)","v":0}]
[{"$f":"'Org structure'!E33","v":"05.1 - Municipal Buildings"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E34","v":"05.2 - Fleet Management"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E35","v":"05.3 - Community Services Administration"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E36","v":"05.4 - Cemeteries"},null,0,0,0,0,0,0,0,{"$f":"SUM(E42:I42)","v":0},{"$f":"IF(D42=0,C42+J42,D42+J42)","v":0},0,0]
[{"$f":"'Org structure'!E37","v":"05.5 - Disaster Management"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E38","v":"05.6 - Fires Service"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E39","v":"05.7 - Libraries"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E40","v":"05.8 - Municipal Buildings"},null,0,0,0,0,0,0,0,{"$f":"SUM(E46:I46)","v":0},{"$f":"IF(D46=0,C46+J46,D46+J46)","v":0},0,0]
[{"$f":"'Org structure'!E41","v":"05.9 - Sports Recreation & Social Amenitie"},null,0,0,0,0,0,0,0,{"$f":"SUM(E47:I47)","v":0},{"$f":"IF(D47=0,C47+J47,D47+J47)","v":0},0,0]
[{"$f":"'Org structure'!E42","v":"05.10 - Waste Management Solid Waste"},null,0,0,0,0,0,0,0,{"$f":"SUM(E48:I48)","v":0},{"$f":"IF(D48=0,C48+J48,D48+J48)","v":0},0,0]
[{"$f":"'Org structure'!E43","v":"05.11 - Safety And Security"},null,0,0,0,0,0,0,0,{"$f":"SUM(E49:I49)","v":0},{"$f":"IF(D49=0,C49+J49,D49+J49)","v":0},0,0]
[{"$f":"'Org structure'!E44","v":"05.12 - Traffic Service"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E45","v":"05.13 - Traffic Service"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E46","v":"05.14 - Fleet Management"},null,0,0,0,0,0,0,0,{"$f":"SUM(E52:I52)","v":0},{"$f":"IF(D52=0,C52+J52,D52+J52)","v":0},0,0]
[{"$f":"'Org structure'!A7","v":"Vote 06 - Planning & Development"},null,{"$f":"SUM(C54:C63)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L54:L63)","v":0},{"$f":"SUM(M54:M63)","v":0}]
[{"$f":"'Org structure'!E48","v":"06.1 - Planning And Development Admin"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E49","v":"06.2 - Municipal Planning Idp"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E50","v":"06.3 - Pms"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E51","v":"06.4 - Town Planning"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E52","v":"06.5 - Land Use And Housing Admin"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E53","v":"06.6 - Local Economic Development"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E54","v":"06.7 - Led"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E55","v":"06.8 - Agriculture & Rural Development"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E56","v":"06.9 - Tourism & Business Development"},null,null,null,null,null,null,null,null,{"$f":"SUM(E62:I62)","v":0},{"$f":"IF(D62=0,C62+J62,D62+J62)","v":0},0,0]
[{"$f":"'Org structure'!E57","v":"06.10 - Arts & Culture"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!A8","v":"Vote 07 - Infrastructure & Technical Services"},null,{"$f":"SUM(C65:C83)","v":73297563},77790502.019999996,0,0,0,0,0,0,77790502.019999996,{"$f":"SUM(L65:L83)","v":11375458},{"$f":"SUM(M65:M83)","v":17503825}]
[{"$f":"'Org structure'!E59","v":"07.1 - Infrastructure Admin & Tech Admin"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E60","v":"07.2 - Fleet Management"},null,0,0,0,0,0,0,0,{"$f":"SUM(E66:I66)","v":0},{"$f":"IF(D66=0,C66+J66,D66+J66)","v":0},0,0]
[{"$f":"'Org structure'!E61","v":"07.3 - Roads"},null,62193238,54731536.009999998,0,0,0,0,0,{"$f":"SUM(E67:I67)","v":0},{"$f":"IF(D67=0,C67+J67,D67+J67)","v":54731536.009999998},10456783,0]
[{"$f":"'Org structure'!E62","v":"07.4 - Storm Water"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E63","v":"07.5 - Street Lighting"},null,5604325,4767440.01,0,0,0,0,0,{"$f":"SUM(E69:I69)","v":0},{"$f":"IF(D69=0,C69+J69,D69+J69)","v":4767440.01},918675,837158]
[{"$f":"'Org structure'!E64","v":"07.6 - Project Management Unit"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E65","v":"07.7 - Sanitation Treatment Plant: Mogwase"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E66","v":"07.8 - Sanitation Treatment Plant: Madikwe"},null,null,null,null,null,null,null,null,0,0,0,0]
[{"$f":"'Org structure'!E67","v":"07.9 - Sanitation Reticulation"},null,0,0,0,0,0,0,0,{"$f":"SUM(E73:I73)","v":0},{"$f":"IF(D73=0,C73+J73,D73+J73)","v":0},0,16666667]
[{"$f":"'Org structure'!E68","v":"07.10 - Water Administration"},null,5500000,18291526,0,0,0,0,0,{"$f":"SUM(E74:I74)","v":0},{"$f":"IF(D74=0,C74+J74,D74+J74)","v":18291526},0,0]
[{"$f":"'Org structure'!E69","v":"07.11 - Water Madikwe: Water Treatment Work"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E70","v":"07.12 - Water: Pella Water Treatment Works"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E71","v":"07.13 - Water: Madikwe Retail & Bulk Lines"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E72","v":"07.14 - Water: Madikwe Rural"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E73","v":"07.15 - Water: Molatedi"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E74","v":"07.16 - Water Eastern: Retail Mankwe"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E75","v":"07.17 - Water Vaalkopdam: Mankwe"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E76","v":"07.18 - Water Eastern: Retail Mankwe"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!E77","v":"07.19 - Reporting Function Electricity"},null,null,null,null,null,null,null,null,null,null,0,0]
[{"$f":"'Org structure'!A9","v":"Vote 08 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A10","v":"Vote 09 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A11","v":"Vote 10 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A12","v":"Vote 11 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A13","v":"Vote 12 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A14","v":"Vote 13 - "},null,0,0,0,0,0,0,0,{"$f":"SUM(E89:I89)","v":0},{"$f":"IF(D89=0,C89+J89,D89+J89)","v":0},0,0]
[{"$f":"'Org structure'!A15","v":"Vote 14 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A16","v":"Vote 15 - Other"},null,0,0,0,0,0,0,0,0,0,0,0]
["Capital multi-year expenditure sub-total",null,{"$f":"C8+C14+C21+C29+C38+C53+C64+C84+C85+C86+C87+C88+C89+C90+C91","v":73297563},77790502.019999996,0,0,0,0,0,0,77790502.019999996,11375458,17503825]
[]
["Capital expenditure - Municipal Vote",2]
["Single-year expenditure appropriation"]
[{"$f":"'Org structure'!A2","v":"Vote 01 - Municipal Council"},null,{"$f":"SUM(C97:C101)","v":0},0,0,0,0,0,0,{"$f":"SUM(E96:I96)","v":0},{"$f":"IF(D96=0,C96+J96,D96+J96)","v":0},{"$f":"SUM(L97:L101)","v":0},{"$f":"SUM(M97:M101)","v":0}]
[{"$f":"'Org structure'!E3","v":"01.1 - Office Of The Mayor"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E4","v":"01.2 - Office Of The Speaker"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E5","v":"01.3 - Office Of The Chief Whip"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E6","v":"01.4 - Mpac"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E7","v":"01.5 - Council General Administration"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A3","v":"Vote 02 - Office Of The Accounting Officer"},null,{"$f":"SUM(C103:C108)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L103:L108)","v":0},{"$f":"SUM(M103:M108)","v":0}]
[{"$f":"'Org structure'!E9","v":"02.1 - Office Of The Ao Admin"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E10","v":"02.2 - Strategic Planning Monitoring & Evaluat"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E11","v":"02.3 - Perfomance Management System"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E12","v":"02.4 - Internal Audit"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E13","v":"02.5 - Municipal Planning Idp"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E14","v":"02.6 - Risk"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A4","v":"Vote 03 - Budget And Treasury Office"},null,{"$f":"SUM(C110:C116)","v":100000},0.01,0,0,0,0,0,0,0.01,{"$f":"SUM(L110:L116)","v":0},{"$f":"SUM(M110:M116)","v":0}]
[{"$f":"'Org structure'!E16","v":"03.1 - Chief Financial Officer Admin"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E17","v":"03.2 - Budget Expenditure & Reporting"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E18","v":"03.3 - Budget Expenditure & Reporting"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E19","v":"03.4 - Revenue Management"},null,100000,0.01,0,0,0,0,0,{"$f":"SUM(E113:I113)","v":0},{"$f":"IF(D113=0,C113+J113,D113+J113)","v":0.01},0,0]
[{"$f":"'Org structure'!E20","v":"03.5 - Supply Chain Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E21","v":"03.6 - Assets Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E22","v":"03.7 - Expenditure"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A5","v":"Vote 04 - Corporate Services"},null,{"$f":"SUM(C118:C125)","v":550000},0.03,0,0,0,0,113975,113975,113975.03,{"$f":"SUM(L118:L125)","v":0},{"$f":"SUM(M118:M125)","v":0}]
[{"$f":"'Org structure'!E24","v":"04.1 - Legal Services"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E25","v":"04.2 - Corporate Service Administration"},null,300000,0.02,0,0,0,0,113975,{"$f":"SUM(E119:I119)","v":113975},{"$f":"IF(D119=0,C119+J119,D119+J119)","v":113975.02},0,0]
[{"$f":"'Org structure'!E26","v":"04.3 - Human Resources"},null,0,0,0,0,0,0,0,{"$f":"SUM(E120:I120)","v":0},{"$f":"IF(D120=0,C120+J120,D120+J120)","v":0},0,0]
[{"$f":"'Org structure'!E27","v":"04.4 - Media & Communication"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E28","v":"04.5 - Organisational Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E29","v":"04.6 - Labour Relations"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E30","v":"04.7 - Legal Services"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E31","v":"04.8 - Information Technology Services"},null,250000,0.01,0,0,0,0,0,{"$f":"SUM(E125:I125)","v":0},{"$f":"IF(D125=0,C125+J125,D125+J125)","v":0.01},0,0]
[{"$f":"'Org structure'!A6","v":"Vote 05 - Community Services"},null,{"$f":"SUM(C127:C140)","v":30587162},30726754.030000005,0,0,0,0,0,0,30726754.030000005,{"$f":"SUM(L127:L140)","v":12864475},{"$f":"SUM(M127:M140)","v":27104155}]
[{"$f":"'Org structure'!E33","v":"05.1 - Municipal Buildings"},null,14590253,30726754.010000002,0,0,0,0,0,{"$f":"SUM(E127:I127)","v":0},{"$f":"IF(D127=0,C127+J127,D127+J127)","v":30726754.010000002},0,8000000]
[{"$f":"'Org structure'!E34","v":"05.2 - Fleet Management"},null,0,0,0,0,0,0,0,{"$f":"SUM(E128:I128)","v":0},{"$f":"IF(D128=0,C128+J128,D128+J128)","v":0},0,0]
[{"$f":"'Org structure'!E35","v":"05.3 - Community Services Administration"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E36","v":"05.4 - Cemeteries"},null,0,0,0,0,0,0,0,{"$f":"SUM(E130:I130)","v":0},{"$f":"IF(D130=0,C130+J130,D130+J130)","v":0},0,0]
[{"$f":"'Org structure'!E37","v":"05.5 - Disaster Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E38","v":"05.6 - Fires Service"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E39","v":"05.7 - Libraries"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E40","v":"05.8 - Municipal Buildings"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E41","v":"05.9 - Sports Recreation & Social Amenitie"},null,200000,0.01,0,0,0,0,0,{"$f":"SUM(E135:I135)","v":0},{"$f":"IF(D135=0,C135+J135,D135+J135)","v":0.01},9864475,0]
[{"$f":"'Org structure'!E42","v":"05.10 - Waste Management Solid Waste"},null,15796909,0.01,0,0,0,0,0,{"$f":"SUM(E136:I136)","v":0},{"$f":"IF(D136=0,C136+J136,D136+J136)","v":0.01},3000000,19104155]
[{"$f":"'Org structure'!E43","v":"05.11 - Safety And Security"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E44","v":"05.12 - Traffic Service"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E45","v":"05.13 - Traffic Service"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E46","v":"05.14 - Fleet Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A7","v":"Vote 06 - Planning & Development"},null,{"$f":"SUM(C142:C151)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L142:L151)","v":0},{"$f":"SUM(M142:M151)","v":0}]
[{"$f":"'Org structure'!E48","v":"06.1 - Planning And Development Admin"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E49","v":"06.2 - Municipal Planning Idp"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E50","v":"06.3 - Pms"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E51","v":"06.4 - Town Planning"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E52","v":"06.5 - Land Use And Housing Admin"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E53","v":"06.6 - Local Economic Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E54","v":"06.7 - Led"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E55","v":"06.8 - Agriculture & Rural Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E56","v":"06.9 - Tourism & Business Development"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E57","v":"06.10 - Arts & Culture"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A8","v":"Vote 07 - Infrastructure & Technical Services"},null,{"$f":"SUM(C153:C171)","v":100267422},97588106.099999994,0,0,0,0,0,{"$f":"SUM(E152:I152)","v":0},{"$f":"IF(D152=0,C152+J152,D152+J152)","v":97588106.099999994},{"$f":"SUM(L153:L171)","v":178255300},{"$f":"SUM(M153:M171)","v":174317389}]
[{"$f":"'Org structure'!E59","v":"07.1 - Infrastructure Admin & Tech Admin"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E60","v":"07.2 - Fleet Management"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E61","v":"07.3 - Roads"},null,0,6456781,0,0,0,0,0,{"$f":"SUM(E155:I155)","v":0},{"$f":"IF(D155=0,C155+J155,D155+J155)","v":6456781},50525000,60000000]
[{"$f":"'Org structure'!E62","v":"07.4 - Storm Water"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E63","v":"07.5 - Street Lighting"},null,16841363,15649533.02,0,0,0,0,0,{"$f":"SUM(E157:I157)","v":0},{"$f":"IF(D157=0,C157+J157,D157+J157)","v":15649533.02},10659065,11720212]
[{"$f":"'Org structure'!E64","v":"07.6 - Project Management Unit"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E65","v":"07.7 - Sanitation Treatment Plant: Mogwase"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E66","v":"07.8 - Sanitation Treatment Plant: Madikwe"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E67","v":"07.9 - Sanitation Reticulation"},null,24111456,12492236.07,0,0,0,0,0,{"$f":"SUM(E161:I161)","v":0},{"$f":"IF(D161=0,C161+J161,D161+J161)","v":12492236.07},25887357,8333333]
[{"$f":"'Org structure'!E68","v":"07.10 - Water Administration"},null,59314603,62989556.009999998,0,0,0,0,0,{"$f":"SUM(E162:I162)","v":0},{"$f":"IF(D162=0,C162+J162,D162+J162)","v":62989556.009999998},91183878,94263844]
[{"$f":"'Org structure'!E69","v":"07.11 - Water Madikwe: Water Treatment Work"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E70","v":"07.12 - Water: Pella Water Treatment Works"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E71","v":"07.13 - Water: Madikwe Retail & Bulk Lines"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E72","v":"07.14 - Water: Madikwe Rural"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E73","v":"07.15 - Water: Molatedi"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E74","v":"07.16 - Water Eastern: Retail Mankwe"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E75","v":"07.17 - Water Vaalkopdam: Mankwe"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E76","v":"07.18 - Water Eastern: Retail Mankwe"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!E77","v":"07.19 - Reporting Function Electricity"},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A9","v":"Vote 08 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A10","v":"Vote 09 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A11","v":"Vote 10 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A12","v":"Vote 11 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A13","v":"Vote 12 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A14","v":"Vote 13 - "},null,0,0,0,0,0,0,0,{"$f":"SUM(E177:I177)","v":0},{"$f":"IF(D177=0,C177+J177,D177+J177)","v":0},0,0]
[{"$f":"'Org structure'!A15","v":"Vote 14 - "},null,0,0,0,0,0,0,0,0,0,0,0]
[{"$f":"'Org structure'!A16","v":"Vote 15 - Other"},null,0,0,0,0,0,0,0,0,0,0,0]
["Capital single-year expenditure sub-total",null,{"$f":"C96+C102+C109+C117+C126+C141+C152+C172+C173+C174+C175+C176+C177+C178+C179","v":131504584},128314860.17,0,0,0,0,113975,113975,128428835.17,191119775,201421544]
["Total Capital Expenditure",null,{"$f":"C180+C92","v":204802147},206105362.19,0,0,0,0,113975,{"$f":"SUM(E181:I181)","v":113975},{"$f":"IF(D181=0,C181+J181,D181+J181)","v":206219337.19},{"$f":"L180+L92","v":202495233},{"$f":"M180+M92","v":218925369}]
[]
[]
[{"$f":"head27a","v":"References"}]
["1. Insert 'Vote'; e.g. Department, if different to standard structure"]
["2. Must reconcile to Financial Performance ('Revenue and Expenditure by Standard Classification' and 'Revenue and Expenditure')"]
["3. Assign share in 'associate' to relevant Vote"]

{"sheet":"B6-FinPos","index":14,"n_rows":63,"n_cols":13,"rows_kept":63,"cut":false,"hidden":false,"merged":[[1,2,1,10],[1,0,3,0],[1,1,3,1],[60,0,60,12],[56,0,56,12],[58,0,58,12],[54,0,54,12],[55,0,55,12],[53,0,53,12]]}
[{"$f":"muni&\" - \"&_ADJ6&\" - \"&Date","v":"NW375 Moses Kotane - Table B6 Adjustments Budget Financial Position - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,3,4,5,6,7,8,9,10]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["ASSETS"]
["Current assets"]
["Cash",null,10000000,10000000,0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":10000000},1000000,1202678]
["Call investment deposits",1,14377000,14377000,0,0,0,0,0,0,14377000,17712753,23648411]
["Consumer debtors",1,{"$f":"'SB2'!C14","v":475621000},{"$f":"'SB2'!D14","v":475621000},{"$f":"'SB2'!E14","v":0},{"$f":"'SB2'!F14","v":0},{"$f":"'SB2'!G14","v":0},{"$f":"'SB2'!H14","v":0},{"$f":"'SB2'!I14","v":0},0,475621000,{"$f":"'SB2'!L14","v":427384661},{"$f":"'SB2'!M14","v":727820042}]
["Other debtors",null,68100000,68100000,0,0,0,0,0,0,68100000,18000000,19734283]
["Current portion of long-term receivables",null,null,null,null,null,null,null,null,0,0]
["Inventory",null,4000000,4000000,0,0,0,0,0,0,4000000,5000000,5073498]
["Total current assets",null,{"$f":"SUM(C8:C13)","v":572098000},572098000,0,0,0,0,0,0,572098000,469097414,777478912]
[]
["Non current assets"]
["Long-term receivables",null,0,0,0,0,0,0,0,{"$f":"SUM(E17:I17)","v":0},{"$f":"IF(D17=0,C17+J17,D17+J17)","v":0},0,0]
["Investments",null,0,0,0,0,0,0,0,0,0,0,0]
["Investment property",null,0,0,0,0,0,0,0,0,0,155209867,17235257]
["Investment in Associate",null,null,null,null,null,null,null,null,0,0]
["Property, plant and equipment",1,{"$f":"'SB2'!C24","v":1785177147},{"$f":"'SB2'!D24","v":1786730362.1800001},{"$f":"'SB2'!E24","v":0},{"$f":"'SB2'!F24","v":0},{"$f":"'SB2'!G24","v":0},{"$f":"'SB2'!H24","v":0},{"$f":"'SB2'!I24","v":113975},113975,1786844337.1800001,{"$f":"'SB2'!L24","v":3530746542},{"$f":"'SB2'!M24","v":3928329513}]
[]
["Biological",null,null,null,null,null,null,null,null,0,0]
["Intangible",null,250000,0.01,0,0,0,0,0,0,0.01,0,0]
["Other non-current assets",null,0,0,0,0,0,0,0,0,0,14000,14000]
["Total non current assets",null,{"$f":"SUM(C17:C21)+SUM(C23:C25)","v":1785427147},{"$f":"SUM(D17:D21)+SUM(D23:D25)","v":1786730362.1900001},0,0,0,0,113975,113975,1786844337.1900001,3685970409,3945578770]
["TOTAL ASSETS",null,{"$f":"C14+C26","v":2357525147},2358828362.1900001,0,0,0,0,113975,113975,2358942337.1900001,4155067823,4723057682]
[]
["LIABILITIES"]
["Current liabilities"]
["Bank overdraft",null,null,null,null,null,null,null,null,{"$f":"SUM(E31:I31)","v":0},{"$f":"IF(D31=0,C31+J31,D31+J31)","v":0}]
["Borrowing",null,{"$f":"'SB2'!C30","v":132503000},{"$f":"'SB2'!D30","v":132503000},{"$f":"'SB2'!E30","v":0},{"$f":"'SB2'!F30","v":0},{"$f":"'SB2'!G30","v":0},{"$f":"'SB2'!H30","v":0},{"$f":"'SB2'!I30","v":0},{"$f":"SUM(E32:I32)","v":0},{"$f":"IF(D32=0,C32+J32,D32+J32)","v":132503000},{"$f":"'SB2'!L30","v":41362000},{"$f":"'SB2'!M30","v":43264652}]
["Consumer deposits",null,0,0,0,0,0,0,0,{"$f":"SUM(E33:I33)","v":0},{"$f":"IF(D33=0,C33+J33,D33+J33)","v":0},0,0]
["Trade and other payables",null,{"$f":"'SB2'!C36","v":40000000},{"$f":"'SB2'!D36","v":40000000},{"$f":"'SB2'!E36","v":0},{"$f":"'SB2'!F36","v":0},{"$f":"'SB2'!G36","v":0},{"$f":"'SB2'!H36","v":0},{"$f":"'SB2'!I36","v":0},{"$f":"SUM(E34:I34)","v":0},{"$f":"IF(D34=0,C34+J34,D34+J34)","v":40000000},{"$f":"'SB2'!L36","v":45000000},{"$f":"'SB2'!M36","v":45000000}]
["Provisions",null,0,0,0,0,0,0,0,{"$f":"SUM(E35:I35)","v":0},{"$f":"IF(D35=0,C35+J35,D35+J35)","v":0},0,0]
["Total current liabilities",null,{"$f":"SUM(C31:C35)","v":172503000},172503000,0,0,0,0,0,0,172503000,86362000,88264652]
[]
["Non current liabilities"]
["Borrowing",1,{"$f":"'SB2'!C40","v":0},{"$f":"'SB2'!D40","v":0},{"$f":"'SB2'!E40","v":0},{"$f":"'SB2'!F40","v":0},{"$f":"'SB2'!G40","v":0},{"$f":"'SB2'!H40","v":0},{"$f":"'SB2'!I40","v":0},{"$f":"SUM(E39:I39)","v":0},{"$f":"IF(D39=0,C39+J39,D39+J39)","v":0},{"$f":"'SB2'!L40","v":0},{"$f":"'SB2'!M40","v":0}]
["Provisions",1,{"$f":"'SB2'!C46","v":24600000},{"$f":"'SB2'!D46","v":24600000},{"$f":"'SB2'!E46","v":0},{"$f":"'SB2'!F46","v":0},{"$f":"'SB2'!G46","v":0},{"$f":"'SB2'!H46","v":0},{"$f":"'SB2'!I46","v":0},{"$f":"SUM(E40:I40)","v":0},{"$f":"IF(D40=0,C40+J40,D40+J40)","v":24600000},{"$f":"'SB2'!L46","v":29829314},{"$f":"'SB2'!M46","v":31171633}]
["Total non current liabilities",null,{"$f":"SUM(C39:C40)","v":24600000},24600000,0,0,0,0,0,0,24600000,29829314,31171633]
["TOTAL LIABILITIES",null,{"$f":"C36+C41","v":197103000},197103000,0,0,0,0,0,0,197103000,116191314,119436285]
[]
["NET ASSETS",2,{"$f":"C27-C42","v":2160422147},2161725362.1900001,0,0,0,0,113975,113975,2161839337.1900001,4038876509,4603621397]
[]
["COMMUNITY WEALTH/EQUITY"]
["Accumulated Surplus/(Deficit)",null,{"$f":"'SB2'!C57","v":2160422147},{"$f":"'SB2'!D57","v":2190922327.1199999},{"$f":"'SB2'!E57","v":0},{"$f":"'SB2'!F57","v":0},{"$f":"'SB2'!G57","v":0},{"$f":"'SB2'!H57","v":0},{"$f":"'SB2'!I57","v":290000},{"$f":"SUM(E47:I47)","v":290000},{"$f":"IF(D47=0,C47+J47,D47+J47)","v":2191212327.1199999},{"$f":"'SB2'!L57","v":4038876509},{"$f":"'SB2'!M57","v":4603621397}]
["Reserves",null,{"$f":"'SB2'!C64","v":0},{"$f":"'SB2'!D64","v":0},{"$f":"'SB2'!E64","v":0},{"$f":"'SB2'!F64","v":0},{"$f":"'SB2'!G64","v":0},{"$f":"'SB2'!H64","v":0},{"$f":"'SB2'!I64","v":0},{"$f":"SUM(E48:I48)","v":0},{"$f":"IF(D48=0,C48+J48,D48+J48)","v":0},{"$f":"'SB2'!L64","v":0},{"$f":"'SB2'!M64","v":0}]
[]
["TOTAL COMMUNITY WEALTH/EQUITY",null,{"$f":"SUM(C47:C48)","v":2160422147},{"$f":"SUM(D47:D48)","v":2190922327.1199999},0,0,0,0,290000,290000,2191212327.1199999,4038876509,4603621397]
[{"$f":"head27a","v":"References"}]
["1. Detail to be provided in Table SA3"]
["2. Net assets must balance with Total Community Wealth/Equity"]
["3. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["4. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["5. Increases of funds approved under MFMA section 31"]
["6. Adjustments approved in accordance with MFMA section 29 "]
["7. Adjustments to transfers from National or Provincial Government"]
["8. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["9. G = B + C + D + E + F"]
["10. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
["check balance",null,{"$f":"C44-C50","v":0},-29196964.929999828,0,0,0,0,-176025,-176025,-29372989.929999828,0,0]

{"sheet":"B7-CFlow","index":15,"n_rows":53,"n_cols":13,"rows_kept":53,"cut":false,"hidden":false,"merged":[[52,0,52,12],[46,0,46,12],[50,0,50,12],[1,0,3,0],[1,1,3,1],[1,2,1,10],[45,0,45,12],[47,0,47,12],[48,0,48,12]]}
[{"$f":"muni&\" - \"&_ADJ7&\" - \"&Date","v":"NW375 Moses Kotane - Table B7 Adjustments Budget Cash Flows - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,3,4,5,6,7,8,9,10]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["CASH FLOW FROM OPERATING ACTIVITIES"]
["Receipts"]
["Property rates",null,130327000,85298160,null,null,null,null,-7108180,{"$f":"SUM(E8:I8)","v":-7108180},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":78189980},{"$f":"K8*5%+K8","v":82099479},{"$f":"L8*5%+L8","v":86204452.950000003}]
["Service charges",null,113966000,77385420,null,null,null,null,-24572766,{"$f":"SUM(E9:I9)","v":-24572766},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":52812654},{"$f":"K9*5%+K9","v":55453286.700000003},58225951.035000004]
["Other revenue",null,2841000,2986154,null,null,null,null,290000,290000,3276154,{"$f":"K10*5%+K10","v":3439961.7},3611959.7850000001]
["Transfers and Subsidies - Operational",1,437830000,437830000,null,null,null,null,{"$f":"-63367513+89000","v":-63278513},-63278513,374551487,467331000,502264000]
["Transfers and Subsidies - Capital",1,199524000,206106000,null,null,null,null,null,0,206106000,0,0]
["Interest",null,17390000,4689317,null,null,null,null,1310683,1310683,6000000,{"$f":"K13*5%+K13","v":6300000},6615000]
["Dividends",null,null,null,null,null,null,null,null,0,0]
["Payments"]
["Suppliers and employees",null,-686837000,-599505000,0,0,0,0,32203000,{"$f":"SUM(E16:I16)","v":32203000},{"$f":"IF(D16=0,C16+J16,D16+J16)","v":-567302000},{"$f":"K16*5%+K16","v":-595667100},{"$f":"L16*5%+L16","v":-625450455}]
["Finance charges",null,0,-3689000,0,0,0,0,0,{"$f":"SUM(E17:I17)","v":0},{"$f":"IF(D17=0,C17+J17,D17+J17)","v":-3689000},{"$f":"K17*5%+K17","v":-3873450},{"$f":"L17*5%+L17","v":-4067122.5}]
["Transfers and Grants",1,null,null,0,0,0,0,null,{"$f":"SUM(E18:I18)","v":0},{"$f":"IF(D18=0,C18+J18,D18+J18)","v":0}]
["NET CASH FROM/(USED) OPERATING ACTIVITIES",null,{"$f":"SUM(C8:C14)+SUM(C16:C18)","v":215041000},{"$f":"SUM(D8:D14)+SUM(D16:D18)","v":211101051},0,0,0,0,-61155776,{"$f":"SUM(J8:J18)","v":-61155776},{"$f":"SUM(K8:K18)","v":149945275},{"$f":"SUM(L8:L14)+SUM(L16:L18)","v":15083177.399999976},{"$f":"SUM(M8:M14)+SUM(M16:M18)","v":27403786.269999981}]
[]
["CASH FLOWS FROM INVESTING ACTIVITIES"]
["Receipts"]
["Proceeds on disposal of PPE",null,null,null,null,null,null,null,null,{"$f":"SUM(E23:I23)","v":0},{"$f":"IF(D23=0,C23+J23,D23+J23)","v":0}]
[]
["Decrease (increase) in non-current receivables",null,null,null,null,null,null,null,null,{"$f":"SUM(E25:I25)","v":0},{"$f":"IF(D25=0,C25+J25,D25+J25)","v":0}]
["Decrease (increase) in non-current investments",null,null,null,0,0,0,0,null,{"$f":"SUM(E26:I26)","v":0},{"$f":"IF(D26=0,C26+J26,D26+J26)","v":0},0,0]
["Payments"]
["Capital assets",null,200374000,-206106150,null,null,null,null,-113975,{"$f":"SUM(E28:I28)","v":-113975},{"$f":"IF(D28=0,C28+J28,D28+J28)","v":-206220125},211771000,227138000]
["NET CASH FROM/(USED) INVESTING ACTIVITIES",null,{"$f":"+C23+C25+C26+C28","v":200374000},{"$f":"+D23+D25+D26+D28","v":-206106150},0,0,0,0,-113975,-113975,-206220125,211771000,227138000]
[]
["CASH FLOWS FROM FINANCING ACTIVITIES"]
["Receipts"]
["Short term loans",null,0,null,null,null,null,null,0,{"$f":"SUM(E33:I33)","v":0},{"$f":"IF(D33=0,C33+J33,D33+J33)","v":0}]
["Borrowing long term/refinancing",null,null,null,null,null,null,null,null,{"$f":"SUM(E34:I34)","v":0},{"$f":"IF(D34=0,C34+J34,D34+J34)","v":0}]
["Increase (decrease) in consumer deposits",null,null,null,0,0,0,0,null,{"$f":"SUM(E35:I35)","v":0},{"$f":"IF(D35=0,C35+J35,D35+J35)","v":0},0,0]
["Payments"]
["Repayment of borrowing",null,-7960000,null,0,0,0,0,0,{"$f":"SUM(E37:I37)","v":0},{"$f":"IF(D37=0,C37+J37,D37+J37)","v":-7960000},-8425000,-8722000]
["NET CASH FROM/(USED) FINANCING ACTIVITIES",null,{"$f":"SUM(C33:C35)+C37","v":-7960000},{"$f":"SUM(D33:D35)+D37","v":0},0,0,0,0,0,{"$f":"SUM(J33:J37)","v":0},{"$f":"SUM(K33:K37)","v":-7960000},{"$f":"SUM(L33:L35)+L37","v":-8425000},{"$f":"SUM(M33:M35)+M37","v":-8722000}]
[]
["NET INCREASE/ (DECREASE) IN CASH HELD",null,{"$f":"C19+C29+C38","v":407455000},{"$f":"D19+D29+D38","v":4994901},0,0,0,0,-61269751,-61269751,-64234850,218429177.39999998,245819786.26999998]
["Cash/cash equivalents at the year begin:",2,47399000,64693146,0,0,0,0,0,{"$f":"SUM(E41:I41)","v":0},{"$f":"IF(D41=0,C41+J41,D41+J41)","v":64693146},458296,644454296]
["Cash/cash equivalents at the year end:",2,{"$f":"C40+C41","v":454854000},{"$f":"D40+D41","v":69688047},0,0,0,0,-61269751,-61269751,{"$f":"K40+K41","v":458296},{"$f":"L40+L41","v":218887473.39999998},{"$f":"M40+M41","v":890274082.26999998}]
[{"$f":"head27a","v":"References"}]
["1. Local/District municipalities to include transfers from/to District/Local Municipalities"]
["2. Cash equivalents includes investments with maturities of 3 months or less"]
["3. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["4. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["5. Increases of funds approved under MFMA section 31"]
["6. Adjustments approved in accordance with MFMA section 29 "]
["7. Adjustments to transfers from National or Provincial Government"]
["8. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["9. G = B + C + D + E + F"]
["10. Adjusted Budget H = (A or A1/2 etc) + G"]

{"sheet":"B8-ResRecon","index":16,"n_rows":55,"n_cols":13,"rows_kept":55,"cut":false,"hidden":false,"merged":[[1,1,3,1],[1,0,3,0],[1,2,1,10]]}
[{"$f":"muni&\" - \"&_ADJ8&\" - \"&Date","v":"NW375 Moses Kotane - Table B8 Cash backed reserves/accumulated surplus reconciliation - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,3,4,5,6,7,8,9,10]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Cash and investments available"]
["Cash/cash equivalents at the year end",1,{"$f":"'B7-CFlow'!C42","v":454854000},{"$f":"'B7-CFlow'!D42","v":69688047},{"$f":"'B7-CFlow'!E42","v":0},{"$f":"'B7-CFlow'!F42","v":0},{"$f":"'B7-CFlow'!G42","v":0},{"$f":"'B7-CFlow'!H42","v":0},{"$f":"'B7-CFlow'!I42","v":-61269751},{"$f":"SUM(E7:I7)","v":-61269751},{"$f":"IF(D7=0,C7+J7,D7+J7)","v":8418296},{"$f":"'B7-CFlow'!L42","v":218887473.39999998},{"$f":"'B7-CFlow'!M42","v":890274082.26999998}]
["Other current investments  > 90 days",null,{"$f":"'B6-FinPos'!C8+'B6-FinPos'!C9-'B6-FinPos'!C31-'B8-ResRecon'!C7","v":-430477000},{"$f":"'B6-FinPos'!D8+'B6-FinPos'!D9-'B6-FinPos'!D31-'B8-ResRecon'!D7","v":-45311047},{"$f":"'B6-FinPos'!E8+'B6-FinPos'!E9-'B6-FinPos'!E31-'B8-ResRecon'!E7","v":0},{"$f":"'B6-FinPos'!F8+'B6-FinPos'!F9-'B6-FinPos'!F31-'B8-ResRecon'!F7","v":0},{"$f":"'B6-FinPos'!G8+'B6-FinPos'!G9-'B6-FinPos'!G31-'B8-ResRecon'!G7","v":0},{"$f":"'B6-FinPos'!H8+'B6-FinPos'!H9-'B6-FinPos'!H31-'B8-ResRecon'!H7","v":0},{"$f":"'B6-FinPos'!I8+'B6-FinPos'!I9-'B6-FinPos'!I31-'B8-ResRecon'!I7","v":61269751},{"$f":"SUM(E8:I8)","v":61269751},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":15958704},{"$f":"'B6-FinPos'!L8+'B6-FinPos'!L9-'B6-FinPos'!L31-'B8-ResRecon'!L7","v":-200174720.39999998},{"$f":"'B6-FinPos'!M8+'B6-FinPos'!M9-'B6-FinPos'!M31-'B8-ResRecon'!M7","v":-865422993.26999998}]
["Non current assets - Investments",1,{"$f":"'B6-FinPos'!C18","v":0},{"$f":"'B6-FinPos'!D18","v":0},{"$f":"'B6-FinPos'!E18","v":0},{"$f":"'B6-FinPos'!F18","v":0},{"$f":"'B6-FinPos'!G18","v":0},{"$f":"'B6-FinPos'!H18","v":0},{"$f":"'B6-FinPos'!I18","v":0},{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":0},{"$f":"'B6-FinPos'!L18","v":0},{"$f":"'B6-FinPos'!M18","v":0}]
["Cash and investments available:",null,{"$f":"SUM(C7:C9)","v":24377000},24377000,0,0,0,0,0,0,24377000,18712753,24851089]
[]
["Applications of cash and investments"]
["Unspent conditional transfers",null,{"$f":"'SB2'!C34","v":0},{"$f":"'SB2'!D34","v":0},{"$f":"'SB2'!E34","v":0},{"$f":"'SB2'!F34","v":0},{"$f":"'SB2'!G34","v":0},{"$f":"'SB2'!H34","v":0},{"$f":"'SB2'!I34","v":0},{"$f":"SUM(E13:I13)","v":0},{"$f":"IF(D13=0,C13+J13,D13+J13)","v":0},{"$f":"'SB2'!L34","v":0},{"$f":"'SB2'!M34","v":0}]
["Unspent borrowing",null,null,null,null,null,null,null,null,0,{"$f":"IF(D14=0,C14+J14,D14+J14)","v":0}]
["Statutory requirements",null,null,null,null,null,null,null,null,0,{"$f":"IF(D15=0,C15+J15,D15+J15)","v":0}]
["Other working capital requirements",2,{"$f":"-C40","v":-301620816},{"$f":"-D40","v":-189181134},null,null,null,null,{"$f":"IF(D16=0,(K16-C16)-SUM(E16:H16),(K16-D16)-SUM(E16:H16))","v":43561982},43561982,{"$f":"-K40","v":-145619152},{"$f":"-L40","v":-103415331},{"$f":"-M40","v":-209991299}]
["Other provisions",null,0,0,0,0,0,0,0,0,{"$f":"IF(D17=0,C17+J17,D17+J17)","v":0},25242000,25929000]
["Long term investments committed",null,{"$f":"C48","v":0},{"$f":"D48","v":0},0,0,0,0,{"$f":"IF(D18=0,(K18-C18)-SUM(E18:H18),(K18-D18)-SUM(E18:H18))","v":0},0,{"$f":"K48","v":0},{"$f":"L48","v":0},{"$f":"M48","v":0}]
["Reserves to be backed by cash/investments",null,{"$f":"C55","v":0},{"$f":"D55","v":0},null,null,null,null,{"$f":"IF(D19=0,(K19-C19)-SUM(E19:H19),(K19-D19)-SUM(E19:H19))","v":0},0,{"$f":"K55","v":0},{"$f":"L55","v":0},{"$f":"M55","v":0}]
["Total Application of cash and investments:",null,{"$f":"SUM(C13:C19)","v":-301620816},-189181134,0,0,0,0,43561982,43561982,-145619152,-78173331,-184062299]
["Surplus(shortfall)",null,{"$f":"C10-C20","v":325997816},213558134,0,0,0,0,-43561982,-43561982,169996152,96886084,208913388]
[{"$f":"head27a","v":"References"}]
["1. Must reconcile with the Adjustments Budget Cash Flow and Adjustements Budget Financial Position"]
["2. Council approval for policy required - include sufficient working capital (e.g. allowing for a % of current debtors > 90 days as uncollectable)"]
["3. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["4. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["5. Increases of funds approved under MFMA section 31"]
["6. Adjustments approved in accordance with MFMA section 29 "]
["7. Adjustments to transfers from National or Provincial Government"]
["8. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["9. G = B + C + D + E + F"]
["10. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
[]
[]
[]
[{"$f":"A16","v":"Other working capital requirements"}]
["Debtors",null,{"$f":"IF(ISERROR(ROUND(C43*C44,0)),0,(ROUND(C43*C44,0)))","v":341620816},{"$f":"IF(ISERROR(ROUND(D43*D44,0)),0,(ROUND(D43*D44,0)))","v":229181134},null,null,null,null,null,null,{"$f":"IF(ISERROR(ROUND(K43*K44,0)),0,(ROUND(K43*K44,0)))","v":185619152},{"$f":"IF(ISERROR(ROUND(L43*L44,0)),0,(ROUND(L43*L44,0)))","v":148415331},{"$f":"IF(ISERROR(ROUND(M43*M44,0)),0,(ROUND(M43*M44,0)))","v":254991299}]
["Creditors due",null,{"$f":"'SB2'!C32","v":40000000},{"$f":"'SB2'!D32","v":40000000},null,null,null,null,null,null,{"$f":"'SB2'!K32","v":40000000},{"$f":"'SB2'!L32","v":45000000},{"$f":"'SB2'!M32","v":45000000}]
["Total",null,{"$f":"C38-C39","v":301620816},{"$f":"D38-D39","v":189181134},null,null,null,null,null,null,{"$f":"K38-K39","v":145619152},{"$f":"L38-L39","v":103415331},{"$f":"M38-M39","v":209991299}]
[]
["Debtors collection assumptions:"]
["Balance outstanding - debtors",null,{"$f":"'B6-FinPos'!C10+'B6-FinPos'!C11+'B6-FinPos'!C17","v":543721000},{"$f":"'B6-FinPos'!D10+'B6-FinPos'!D11+'B6-FinPos'!D17","v":543721000},null,null,null,null,null,null,{"$f":"'B6-FinPos'!K10+'B6-FinPos'!K11+'B6-FinPos'!K17","v":543721000},{"$f":"'B6-FinPos'!L10+'B6-FinPos'!L11+'B6-FinPos'!L17","v":445384661},{"$f":"'B6-FinPos'!M10+'B6-FinPos'!M11+'B6-FinPos'!M17","v":747554325}]
["Estimate of debtors collection rate",null,{"$f":"IF(ISERROR('SB6'!G10),0,('SB6'!G10))","v":0.62830167657350144},{"$f":"IF(ISERROR('SB6'!H10),0,('SB6'!H10))","v":0.42150502606941659},null,null,null,null,null,null,{"$f":"IF(ISERROR('SB6'!I10),0,('SB6'!I10))","v":0.34138676246083988},{"$f":"IF(ISERROR('SB6'!J10),0,('SB6'!J10))","v":0.33322955115994013},{"$f":"IF(ISERROR('SB6'!K10),0,('SB6'!K10))","v":0.34110069337216964}]
[]
[{"$f":"A18","v":"Long term investments committed"}]
["(Insert description; eg sinking fund)"]
[null,null,{"$f":"SUM(C47:C47)","v":0},{"$f":"SUM(D47:D47)","v":0},null,null,null,null,null,null,{"$f":"SUM(K47:K47)","v":0},{"$f":"SUM(L47:L47)","v":0},{"$f":"SUM(M47:M47)","v":0}]
[]
[{"$f":"A19","v":"Reserves to be backed by cash/investments"}]
[{"$f":"'SB2'!A59","v":"Housing Development Fund"},null,{"$f":"'SB2'!C59","v":0},{"$f":"'SB2'!D59","v":0},null,null,null,null,null,null,{"$f":"'SB2'!K59","v":0},{"$f":"'SB2'!L59","v":0},{"$f":"'SB2'!M59","v":0}]
[{"$f":"'SB2'!A60","v":"Capital replacement"},null,{"$f":"'SB2'!C60","v":0},{"$f":"'SB2'!D60","v":0},null,null,null,null,null,null,{"$f":"'SB2'!K60","v":0},{"$f":"'SB2'!L60","v":0},{"$f":"'SB2'!M60","v":0}]
[{"$f":"'SB2'!A61","v":"Self-insurance"},null,{"$f":"'SB2'!C61","v":0},{"$f":"'SB2'!D61","v":0},null,null,null,null,null,null,{"$f":"'SB2'!K61","v":0},{"$f":"'SB2'!L61","v":0},{"$f":"'SB2'!M61","v":0}]
[{"$f":"'SB2'!A62","v":"Other reserves"},null,{"$f":"'SB2'!C62","v":0},{"$f":"'SB2'!D62","v":0},null,null,null,null,null,null,{"$f":"'SB2'!K62","v":0},{"$f":"'SB2'!L62","v":0},{"$f":"'SB2'!M62","v":0}]
[null,null,{"$f":"SUM(C51:C54)","v":0},{"$f":"SUM(D51:D54)","v":0},null,null,null,null,null,null,{"$f":"SUM(K51:K54)","v":0},{"$f":"SUM(L51:L54)","v":0},{"$f":"SUM(M51:M54)","v":0}]

{"sheet":"B9-Asset","index":17,"n_rows":227,"n_cols":13,"rows_kept":227,"cut":false,"hidden":false,"merged":[[223,0,223,12],[217,0,217,12],[221,0,221,12],[1,2,1,10],[1,0,3,0],[1,1,3,1],[216,0,216,12],[218,0,218,12],[219,0,219,12]]}
[{"$f":"muni&\" - \"&_ADJ9&\" - \"&Date","v":"NW375 Moses Kotane - Table B9 Asset Management - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,7,8,9,10,11,12,13,14]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["CAPITAL EXPENDITURE"]
["Total New Assets to be adjusted",1,{"$f":"C17+C20+C21+C24+C27+C28+SUM(C31:C37)","v":133961894},{"$f":"D17+D20+D21+D24+D27+D28+SUM(D31:D37)","v":103266698.17000002},0,0,0,0,113975,113975,103380673.17000002,131648975,150925369]
["Roads Infrastructure",null,{"$f":"SB18a!C9","v":0},{"$f":"SB18a!D9","v":0},{"$f":"SB18a!E9","v":0},{"$f":"SB18a!F9","v":0},{"$f":"SB18a!G9","v":0},{"$f":"SB18a!H9","v":0},{"$f":"SB18a!I9","v":0},{"$f":"SB18a!J9","v":0},{"$f":"SB18a!K9","v":0},{"$f":"SB18a!L9","v":0},{"$f":"SB18a!M9","v":0}]
["Storm water Infrastructure",null,{"$f":"SB18a!C14","v":6193238},{"$f":"SB18a!D14","v":0.01},{"$f":"SB18a!E14","v":0},{"$f":"SB18a!F14","v":0},{"$f":"SB18a!G14","v":0},{"$f":"SB18a!H14","v":0},{"$f":"SB18a!I14","v":0},{"$f":"SB18a!J14","v":0},{"$f":"SB18a!K14","v":0.01},{"$f":"SB18a!L14","v":0},{"$f":"SB18a!M14","v":0}]
["Electrical Infrastructure",null,{"$f":"SB18a!C18","v":22445688},{"$f":"SB18a!D18","v":20416973.030000001},{"$f":"SB18a!E18","v":0},{"$f":"SB18a!F18","v":0},{"$f":"SB18a!G18","v":0},{"$f":"SB18a!H18","v":0},{"$f":"SB18a!I18","v":0},{"$f":"SB18a!J18","v":0},{"$f":"SB18a!K18","v":20416973.030000001},{"$f":"SB18a!L18","v":11577740},{"$f":"SB18a!M18","v":12557370}]
["Water Supply Infrastructure",null,{"$f":"SB18a!C28","v":64814603},{"$f":"SB18a!D28","v":70357489.010000005},{"$f":"SB18a!E28","v":0},{"$f":"SB18a!F28","v":0},{"$f":"SB18a!G28","v":0},{"$f":"SB18a!H28","v":0},{"$f":"SB18a!I28","v":0},{"$f":"SB18a!J28","v":0},{"$f":"SB18a!K28","v":70357489.010000005},{"$f":"SB18a!L28","v":91183878},{"$f":"SB18a!M28","v":94263844}]
["Sanitation Infrastructure",null,{"$f":"SB18a!C39","v":24111456},{"$f":"SB18a!D39","v":12492236.07},{"$f":"SB18a!E39","v":0},{"$f":"SB18a!F39","v":0},{"$f":"SB18a!G39","v":0},{"$f":"SB18a!H39","v":0},{"$f":"SB18a!I39","v":0},{"$f":"SB18a!J39","v":0},{"$f":"SB18a!K39","v":12492236.07},{"$f":"SB18a!L39","v":25887357},{"$f":"SB18a!M39","v":25000000}]
["Solid Waste Infrastructure",null,{"$f":"SB18a!C46","v":15796909},{"$f":"SB18a!D46","v":0.01},{"$f":"SB18a!E46","v":0},{"$f":"SB18a!F46","v":0},{"$f":"SB18a!G46","v":0},{"$f":"SB18a!H46","v":0},{"$f":"SB18a!I46","v":0},{"$f":"SB18a!J46","v":0},{"$f":"SB18a!K46","v":0.01},{"$f":"SB18a!L46","v":3000000},{"$f":"SB18a!M46","v":19104155}]
["Rail Infrastructure",null,{"$f":"SB18a!C54","v":0},{"$f":"SB18a!D54","v":0},{"$f":"SB18a!E54","v":0},{"$f":"SB18a!F54","v":0},{"$f":"SB18a!G54","v":0},{"$f":"SB18a!H54","v":0},{"$f":"SB18a!I54","v":0},{"$f":"SB18a!J54","v":0},{"$f":"SB18a!K54","v":0},{"$f":"SB18a!L54","v":0},{"$f":"SB18a!M54","v":0}]
["Coastal Infrastructure",null,{"$f":"SB18a!C64","v":0},{"$f":"SB18a!D64","v":0},{"$f":"SB18a!E64","v":0},{"$f":"SB18a!F64","v":0},{"$f":"SB18a!G64","v":0},{"$f":"SB18a!H64","v":0},{"$f":"SB18a!I64","v":0},{"$f":"SB18a!J64","v":0},{"$f":"SB18a!K64","v":0},{"$f":"SB18a!L64","v":0},{"$f":"SB18a!M64","v":0}]
["Information and Communication Infrastructure",null,{"$f":"SB18a!C70","v":0},{"$f":"SB18a!D70","v":0},{"$f":"SB18a!E70","v":0},{"$f":"SB18a!F70","v":0},{"$f":"SB18a!G70","v":0},{"$f":"SB18a!H70","v":0},{"$f":"SB18a!I70","v":0},{"$f":"SB18a!J70","v":0},{"$f":"SB18a!K70","v":0},{"$f":"SB18a!L70","v":0},{"$f":"SB18a!M70","v":0}]
["Infrastructure",null,{"$f":"SUM(C8:C16)","v":133361894},{"$f":"SUM(D8:D16)","v":103266698.13000001},0,0,0,0,0,0,103266698.13000001,131648975,150925369]
["Community Facilities",null,{"$f":"SB18a!C77","v":0},{"$f":"SB18a!D77","v":0},{"$f":"SB18a!E77","v":0},{"$f":"SB18a!F77","v":0},{"$f":"SB18a!G77","v":0},{"$f":"SB18a!H77","v":0},{"$f":"SB18a!I77","v":0},{"$f":"SB18a!J77","v":0},{"$f":"SB18a!K77","v":0},{"$f":"SB18a!L77","v":0},{"$f":"SB18a!M77","v":0}]
["Sport and Recreation Facilities",null,{"$f":"SB18a!C100","v":0},{"$f":"SB18a!D100","v":0},{"$f":"SB18a!E100","v":0},{"$f":"SB18a!F100","v":0},{"$f":"SB18a!G100","v":0},{"$f":"SB18a!H100","v":0},{"$f":"SB18a!I100","v":0},{"$f":"SB18a!J100","v":0},{"$f":"SB18a!K100","v":0},{"$f":"SB18a!L100","v":0},{"$f":"SB18a!M100","v":0}]
["Community Assets",null,{"$f":"SUM(C18:C19)","v":0},{"$f":"SUM(D18:D19)","v":0},0,0,0,0,0,0,0,0,0]
["Heritage Assets",null,{"$f":"SB18a!C105","v":0},{"$f":"SB18a!D105","v":0},{"$f":"SB18a!E105","v":0},{"$f":"SB18a!F105","v":0},{"$f":"SB18a!G105","v":0},{"$f":"SB18a!H105","v":0},{"$f":"SB18a!I105","v":0},{"$f":"SB18a!J105","v":0},{"$f":"SB18a!K105","v":0},{"$f":"SB18a!L105","v":0},{"$f":"SB18a!M105","v":0}]
["Revenue Generating",null,{"$f":"SB18a!C113","v":0},{"$f":"SB18a!D113","v":0},{"$f":"SB18a!E113","v":0},{"$f":"SB18a!F113","v":0},{"$f":"SB18a!G113","v":0},{"$f":"SB18a!H113","v":0},{"$f":"SB18a!I113","v":0},{"$f":"SB18a!J113","v":0},{"$f":"SB18a!K113","v":0},{"$f":"SB18a!L113","v":0},{"$f":"SB18a!M113","v":0}]
["Non-revenue Generating",null,{"$f":"SB18a!C116","v":0},{"$f":"SB18a!D116","v":0},{"$f":"SB18a!E116","v":0},{"$f":"SB18a!F116","v":0},{"$f":"SB18a!G116","v":0},{"$f":"SB18a!H116","v":0},{"$f":"SB18a!I116","v":0},{"$f":"SB18a!J116","v":0},{"$f":"SB18a!K116","v":0},{"$f":"SB18a!L116","v":0},{"$f":"SB18a!M116","v":0}]
["Investment properties",null,{"$f":"SUM(C22:C23)","v":0},{"$f":"SUM(D22:D23)","v":0},0,0,0,0,0,0,0,0,0]
["Operational Buildings",null,{"$f":"SB18a!C121","v":0},{"$f":"SB18a!D121","v":0},{"$f":"SB18a!E121","v":0},{"$f":"SB18a!F121","v":0},{"$f":"SB18a!G121","v":0},{"$f":"SB18a!H121","v":0},{"$f":"SB18a!I121","v":0},{"$f":"SB18a!J121","v":0},{"$f":"SB18a!K121","v":0},{"$f":"SB18a!L121","v":0},{"$f":"SB18a!M121","v":0}]
["Housing",null,{"$f":"SB18a!C133","v":0},{"$f":"SB18a!D133","v":0},{"$f":"SB18a!E133","v":0},{"$f":"SB18a!F133","v":0},{"$f":"SB18a!G133","v":0},{"$f":"SB18a!H133","v":0},{"$f":"SB18a!I133","v":0},{"$f":"SB18a!J133","v":0},{"$f":"SB18a!K133","v":0},{"$f":"SB18a!L133","v":0},{"$f":"SB18a!M133","v":0}]
["Other Assets",6,{"$f":"SUM(C25:C26)","v":0},{"$f":"SUM(D25:D26)","v":0},0,0,0,0,0,0,0,0,0]
["Biological or Cultivated Assets",null,{"$f":"SB18a!C138","v":0},{"$f":"SB18a!D138","v":0},{"$f":"SB18a!E138","v":0},{"$f":"SB18a!F138","v":0},{"$f":"SB18a!G138","v":0},{"$f":"SB18a!H138","v":0},{"$f":"SB18a!I138","v":0},{"$f":"SB18a!J138","v":0},{"$f":"SB18a!K138","v":0},{"$f":"SB18a!L138","v":0},{"$f":"SB18a!M138","v":0}]
["Servitudes",null,{"$f":"SB18a!C142","v":0},{"$f":"SB18a!D142","v":0},{"$f":"SB18a!E142","v":0},{"$f":"SB18a!F142","v":0},{"$f":"SB18a!G142","v":0},{"$f":"SB18a!H142","v":0},{"$f":"SB18a!I142","v":0},{"$f":"SB18a!J142","v":0},{"$f":"SB18a!K142","v":0},{"$f":"SB18a!L142","v":0},{"$f":"SB18a!M142","v":0}]
["Licences and Rights",null,{"$f":"SB18a!C143","v":0},{"$f":"SB18a!D143","v":0},{"$f":"SB18a!E143","v":0},{"$f":"SB18a!F143","v":0},{"$f":"SB18a!G143","v":0},{"$f":"SB18a!H143","v":0},{"$f":"SB18a!I143","v":0},{"$f":"SB18a!J143","v":0},{"$f":"SB18a!K143","v":0},{"$f":"SB18a!L143","v":0},{"$f":"SB18a!M143","v":0}]
["Intangible Assets",null,{"$f":"SUM(C29:C30)","v":0},{"$f":"SUM(D29:D30)","v":0},0,0,0,0,0,0,0,0,0]
["Computer Equipment",null,{"$f":"SB18a!C151","v":0},{"$f":"SB18a!D151","v":0},{"$f":"SB18a!E151","v":0},{"$f":"SB18a!F151","v":0},{"$f":"SB18a!G151","v":0},{"$f":"SB18a!H151","v":0},{"$f":"SB18a!I151","v":0},{"$f":"SB18a!J151","v":0},{"$f":"SB18a!K151","v":0},{"$f":"SB18a!L151","v":0},{"$f":"SB18a!M151","v":0}]
["Furniture and Office Equipment",null,{"$f":"SB18a!C154","v":300000},{"$f":"SB18a!D154","v":0.02},{"$f":"SB18a!E154","v":0},{"$f":"SB18a!F154","v":0},{"$f":"SB18a!G154","v":0},{"$f":"SB18a!H154","v":0},{"$f":"SB18a!I154","v":113975},{"$f":"SB18a!J154","v":113975},{"$f":"SB18a!K154","v":113975.02},{"$f":"SB18a!L154","v":0},{"$f":"SB18a!M154","v":0}]
["Machinery and Equipment",null,{"$f":"SB18a!C157","v":300000},{"$f":"SB18a!D157","v":0.02},{"$f":"SB18a!E157","v":0},{"$f":"SB18a!F157","v":0},{"$f":"SB18a!G157","v":0},{"$f":"SB18a!H157","v":0},{"$f":"SB18a!I157","v":0},{"$f":"SB18a!J157","v":0},{"$f":"SB18a!K157","v":0.02},{"$f":"SB18a!L157","v":0},{"$f":"SB18a!M157","v":0}]
["Transport Assets",null,{"$f":"SB18a!C160","v":0},{"$f":"SB18a!D160","v":0},{"$f":"SB18a!E160","v":0},{"$f":"SB18a!F160","v":0},{"$f":"SB18a!G160","v":0},{"$f":"SB18a!H160","v":0},{"$f":"SB18a!I160","v":0},{"$f":"SB18a!J160","v":0},{"$f":"SB18a!K160","v":0},{"$f":"SB18a!L160","v":0},{"$f":"SB18a!M160","v":0}]
["Land",null,{"$f":"SB18a!C163","v":0},{"$f":"SB18a!D163","v":0},{"$f":"SB18a!E163","v":0},{"$f":"SB18a!F163","v":0},{"$f":"SB18a!G163","v":0},{"$f":"SB18a!H163","v":0},{"$f":"SB18a!I163","v":0},{"$f":"SB18a!J163","v":0},{"$f":"SB18a!K163","v":0},{"$f":"SB18a!L163","v":0},{"$f":"SB18a!M163","v":0}]
["Zoo's, Marine and Non-biological Animals",null,{"$f":"SB18a!C166","v":0},{"$f":"SB18a!D166","v":0},{"$f":"SB18a!E166","v":0},{"$f":"SB18a!F166","v":0},{"$f":"SB18a!G166","v":0},{"$f":"SB18a!H166","v":0},{"$f":"SB18a!I166","v":0},{"$f":"SB18a!J166","v":0},{"$f":"SB18a!K166","v":0},{"$f":"SB18a!L166","v":0},{"$f":"SB18a!M166","v":0}]
[]
["Total Renewal of Existing Assets to be adjusted",2,{"$f":"C49+C52+C53+C56+C59+C60+SUM(C63:C69)","v":14840253},{"$f":"D49+D52+D53+D56+D59+D60+SUM(D63:D69)","v":41650347.019999996},0,0,0,0,0,0,41650347.019999996,9864475,8000000]
["Roads Infrastructure",null,{"$f":"SB18b!C9","v":0},{"$f":"SB18b!D9","v":0},{"$f":"SB18b!E9","v":0},{"$f":"SB18b!F9","v":0},{"$f":"SB18b!G9","v":0},{"$f":"SB18b!H9","v":0},{"$f":"SB18b!I9","v":0},{"$f":"SB18b!J9","v":0},{"$f":"SB18b!K9","v":0},{"$f":"SB18b!L9","v":0},{"$f":"SB18b!M9","v":0}]
["Storm water Infrastructure",null,{"$f":"SB18b!C14","v":0},{"$f":"SB18b!D14","v":0},{"$f":"SB18b!E14","v":0},{"$f":"SB18b!F14","v":0},{"$f":"SB18b!G14","v":0},{"$f":"SB18b!H14","v":0},{"$f":"SB18b!I14","v":0},{"$f":"SB18b!J14","v":0},{"$f":"SB18b!K14","v":0},{"$f":"SB18b!L14","v":0},{"$f":"SB18b!M14","v":0}]
["Electrical Infrastructure",null,{"$f":"SB18b!C18","v":0},{"$f":"SB18b!D18","v":0},{"$f":"SB18b!E18","v":0},{"$f":"SB18b!F18","v":0},{"$f":"SB18b!G18","v":0},{"$f":"SB18b!H18","v":0},{"$f":"SB18b!I18","v":0},{"$f":"SB18b!J18","v":0},{"$f":"SB18b!K18","v":0},{"$f":"SB18b!L18","v":0},{"$f":"SB18b!M18","v":0}]
["Water Supply Infrastructure",null,{"$f":"SB18b!C28","v":0},{"$f":"SB18b!D28","v":10923593},{"$f":"SB18b!E28","v":0},{"$f":"SB18b!F28","v":0},{"$f":"SB18b!G28","v":0},{"$f":"SB18b!H28","v":0},{"$f":"SB18b!I28","v":0},{"$f":"SB18b!J28","v":0},{"$f":"SB18b!K28","v":10923593},{"$f":"SB18b!L28","v":0},{"$f":"SB18b!M28","v":0}]
["Sanitation Infrastructure",null,{"$f":"SB18b!C39","v":0},{"$f":"SB18b!D39","v":0},{"$f":"SB18b!E39","v":0},{"$f":"SB18b!F39","v":0},{"$f":"SB18b!G39","v":0},{"$f":"SB18b!H39","v":0},{"$f":"SB18b!I39","v":0},{"$f":"SB18b!J39","v":0},{"$f":"SB18b!K39","v":0},{"$f":"SB18b!L39","v":0},{"$f":"SB18b!M39","v":0}]
["Solid Waste Infrastructure",null,{"$f":"SB18b!C46","v":0},{"$f":"SB18b!D46","v":0},{"$f":"SB18b!E46","v":0},{"$f":"SB18b!F46","v":0},{"$f":"SB18b!G46","v":0},{"$f":"SB18b!H46","v":0},{"$f":"SB18b!I46","v":0},{"$f":"SB18b!J46","v":0},{"$f":"SB18b!K46","v":0},{"$f":"SB18b!L46","v":0},{"$f":"SB18b!M46","v":0}]
["Rail Infrastructure",null,{"$f":"SB18b!C54","v":0},{"$f":"SB18b!D54","v":0},{"$f":"SB18b!E54","v":0},{"$f":"SB18b!F54","v":0},{"$f":"SB18b!G54","v":0},{"$f":"SB18b!H54","v":0},{"$f":"SB18b!I54","v":0},{"$f":"SB18b!J54","v":0},{"$f":"SB18b!K54","v":0},{"$f":"SB18b!L54","v":0},{"$f":"SB18b!M54","v":0}]
["Coastal Infrastructure",null,{"$f":"SB18b!C64","v":0},{"$f":"SB18b!D64","v":0},{"$f":"SB18b!E64","v":0},{"$f":"SB18b!F64","v":0},{"$f":"SB18b!G64","v":0},{"$f":"SB18b!H64","v":0},{"$f":"SB18b!I64","v":0},{"$f":"SB18b!J64","v":0},{"$f":"SB18b!K64","v":0},{"$f":"SB18b!L64","v":0},{"$f":"SB18b!M64","v":0}]
["Information and Communication Infrastructure",null,{"$f":"SB18b!C70","v":0},{"$f":"SB18b!D70","v":0},{"$f":"SB18b!E70","v":0},{"$f":"SB18b!F70","v":0},{"$f":"SB18b!G70","v":0},{"$f":"SB18b!H70","v":0},{"$f":"SB18b!I70","v":0},{"$f":"SB18b!J70","v":0},{"$f":"SB18b!K70","v":0},{"$f":"SB18b!L70","v":0},{"$f":"SB18b!M70","v":0}]
["Infrastructure",null,{"$f":"SUM(C40:C48)","v":0},{"$f":"SUM(D40:D48)","v":10923593},0,0,0,0,0,0,10923593,0,0]
["Community Facilities",null,{"$f":"SB18b!C77","v":12000000},{"$f":"SB18b!D77","v":20106309},{"$f":"SB18b!E77","v":0},{"$f":"SB18b!F77","v":0},{"$f":"SB18b!G77","v":0},{"$f":"SB18b!H77","v":0},{"$f":"SB18b!I77","v":0},{"$f":"SB18b!J77","v":0},{"$f":"SB18b!K77","v":20106309},{"$f":"SB18b!L77","v":9864475},{"$f":"SB18b!M77","v":8000000}]
["Sport and Recreation Facilities",null,{"$f":"SB18b!C100","v":0},{"$f":"SB18b!D100","v":0},{"$f":"SB18b!E100","v":0},{"$f":"SB18b!F100","v":0},{"$f":"SB18b!G100","v":0},{"$f":"SB18b!H100","v":0},{"$f":"SB18b!I100","v":0},{"$f":"SB18b!J100","v":0},{"$f":"SB18b!K100","v":0},{"$f":"SB18b!L100","v":0},{"$f":"SB18b!M100","v":0}]
["Community Assets",null,{"$f":"SUM(C50:C51)","v":12000000},{"$f":"SUM(D50:D51)","v":20106309},0,0,0,0,0,0,20106309,9864475,8000000]
["Heritage Assets",null,{"$f":"SB18b!C105","v":0},{"$f":"SB18b!D105","v":0},{"$f":"SB18b!E105","v":0},{"$f":"SB18b!F105","v":0},{"$f":"SB18b!G105","v":0},{"$f":"SB18b!H105","v":0},{"$f":"SB18b!I105","v":0},{"$f":"SB18b!J105","v":0},{"$f":"SB18b!K105","v":0},{"$f":"SB18b!L105","v":0},{"$f":"SB18b!M105","v":0}]
["Revenue Generating",null,{"$f":"SB18b!C113","v":0},{"$f":"SB18b!D113","v":0},{"$f":"SB18b!E113","v":0},{"$f":"SB18b!F113","v":0},{"$f":"SB18b!G113","v":0},{"$f":"SB18b!H113","v":0},{"$f":"SB18b!I113","v":0},{"$f":"SB18b!J113","v":0},{"$f":"SB18b!K113","v":0},{"$f":"SB18b!L113","v":0},{"$f":"SB18b!M113","v":0}]
["Non-revenue Generating",null,{"$f":"SB18b!C116","v":0},{"$f":"SB18b!D116","v":0},{"$f":"SB18b!E116","v":0},{"$f":"SB18b!F116","v":0},{"$f":"SB18b!G116","v":0},{"$f":"SB18b!H116","v":0},{"$f":"SB18b!I116","v":0},{"$f":"SB18b!J116","v":0},{"$f":"SB18b!K116","v":0},{"$f":"SB18b!L116","v":0},{"$f":"SB18b!M116","v":0}]
["Investment properties",null,{"$f":"SUM(C54:C55)","v":0},{"$f":"SUM(D54:D55)","v":0},0,0,0,0,0,0,0,0,0]
["Operational Buildings",null,{"$f":"SB18b!C121","v":2590253},{"$f":"SB18b!D121","v":10620445.01},{"$f":"SB18b!E121","v":0},{"$f":"SB18b!F121","v":0},{"$f":"SB18b!G121","v":0},{"$f":"SB18b!H121","v":0},{"$f":"SB18b!I121","v":0},{"$f":"SB18b!J121","v":0},{"$f":"SB18b!K121","v":10620445.01},{"$f":"SB18b!L121","v":0},{"$f":"SB18b!M121","v":0}]
["Housing",null,{"$f":"SB18b!C133","v":0},{"$f":"SB18b!D133","v":0},{"$f":"SB18b!E133","v":0},{"$f":"SB18b!F133","v":0},{"$f":"SB18b!G133","v":0},{"$f":"SB18b!H133","v":0},{"$f":"SB18b!I133","v":0},{"$f":"SB18b!J133","v":0},{"$f":"SB18b!K133","v":0},{"$f":"SB18b!L133","v":0},{"$f":"SB18b!M133","v":0}]
["Other Assets",6,{"$f":"SUM(C57:C58)","v":2590253},{"$f":"SUM(D57:D58)","v":10620445.01},0,0,0,0,0,0,10620445.01,0,0]
["Biological or Cultivated Assets",null,{"$f":"SB18b!C138","v":0},{"$f":"SB18b!D138","v":0},{"$f":"SB18b!E138","v":0},{"$f":"SB18b!F138","v":0},{"$f":"SB18b!G138","v":0},{"$f":"SB18b!H138","v":0},{"$f":"SB18b!I138","v":0},{"$f":"SB18b!J138","v":0},{"$f":"SB18b!K138","v":0},{"$f":"SB18b!L138","v":0},{"$f":"SB18b!M138","v":0}]
["Servitudes",null,{"$f":"SB18b!C142","v":0},{"$f":"SB18b!D142","v":0},{"$f":"SB18b!E142","v":0},{"$f":"SB18b!F142","v":0},{"$f":"SB18b!G142","v":0},{"$f":"SB18b!H142","v":0},{"$f":"SB18b!I142","v":0},{"$f":"SB18b!J142","v":0},{"$f":"SB18b!K142","v":0},{"$f":"SB18b!L142","v":0},{"$f":"SB18b!M142","v":0}]
["Licences and Rights",null,{"$f":"SB18b!C143","v":250000},{"$f":"SB18b!D143","v":0.01},{"$f":"SB18b!E143","v":0},{"$f":"SB18b!F143","v":0},{"$f":"SB18b!G143","v":0},{"$f":"SB18b!H143","v":0},{"$f":"SB18b!I143","v":0},{"$f":"SB18b!J143","v":0},{"$f":"SB18b!K143","v":0.01},{"$f":"SB18b!L143","v":0},{"$f":"SB18b!M143","v":0}]
["Intangible Assets",null,{"$f":"SUM(C61:C62)","v":250000},{"$f":"SUM(D61:D62)","v":0.01},0,0,0,0,0,0,0.01,0,0]
["Computer Equipment",null,{"$f":"SB18b!C151","v":0},{"$f":"SB18b!D151","v":0},{"$f":"SB18b!E151","v":0},{"$f":"SB18b!F151","v":0},{"$f":"SB18b!G151","v":0},{"$f":"SB18b!H151","v":0},{"$f":"SB18b!I151","v":0},{"$f":"SB18b!J151","v":0},{"$f":"SB18b!K151","v":0},{"$f":"SB18b!L151","v":0},{"$f":"SB18b!M151","v":0}]
["Furniture and Office Equipment",null,{"$f":"SB18b!C154","v":0},{"$f":"SB18b!D154","v":0},{"$f":"SB18b!E154","v":0},{"$f":"SB18b!F154","v":0},{"$f":"SB18b!G154","v":0},{"$f":"SB18b!H154","v":0},{"$f":"SB18b!I154","v":0},{"$f":"SB18b!J154","v":0},{"$f":"SB18b!K154","v":0},{"$f":"SB18b!L154","v":0},{"$f":"SB18b!M154","v":0}]
["Machinery and Equipment",null,{"$f":"SB18b!C157","v":0},{"$f":"SB18b!D157","v":0},{"$f":"SB18b!E157","v":0},{"$f":"SB18b!F157","v":0},{"$f":"SB18b!G157","v":0},{"$f":"SB18b!H157","v":0},{"$f":"SB18b!I157","v":0},{"$f":"SB18b!J157","v":0},{"$f":"SB18b!K157","v":0},{"$f":"SB18b!L157","v":0},{"$f":"SB18b!M157","v":0}]
["Transport Assets",null,{"$f":"SB18b!C160","v":0},{"$f":"SB18b!D160","v":0},{"$f":"SB18b!E160","v":0},{"$f":"SB18b!F160","v":0},{"$f":"SB18b!G160","v":0},{"$f":"SB18b!H160","v":0},{"$f":"SB18b!I160","v":0},{"$f":"SB18b!J160","v":0},{"$f":"SB18b!K160","v":0},{"$f":"SB18b!L160","v":0},{"$f":"SB18b!M160","v":0}]
["Land",null,{"$f":"SB18b!C163","v":0},{"$f":"SB18b!D163","v":0},{"$f":"SB18b!E163","v":0},{"$f":"SB18b!F163","v":0},{"$f":"SB18b!G163","v":0},{"$f":"SB18b!H163","v":0},{"$f":"SB18b!I163","v":0},{"$f":"SB18b!J163","v":0},{"$f":"SB18b!K163","v":0},{"$f":"SB18b!L163","v":0},{"$f":"SB18b!M163","v":0}]
["Zoo's, Marine and Non-biological Animals",null,{"$f":"SB18b!C166","v":0},{"$f":"SB18b!D166","v":0},{"$f":"SB18b!E166","v":0},{"$f":"SB18b!F166","v":0},{"$f":"SB18b!G166","v":0},{"$f":"SB18b!H166","v":0},{"$f":"SB18b!I166","v":0},{"$f":"SB18b!J166","v":0},{"$f":"SB18b!K166","v":0},{"$f":"SB18b!L166","v":0},{"$f":"SB18b!M166","v":0}]
[]
["Total Upgrading of Existing Assets to be adjusted","2a",{"$f":"C81+C84+C85+C88+C91+C92+SUM(C95:C101)","v":56000000},{"$f":"D81+D84+D85+D88+D91+D92+SUM(D95:D101)","v":61188317},0,0,0,0,0,0,61188317,60981783,60000000]
["Roads Infrastructure",null,{"$f":"SB18e!C9","v":56000000},{"$f":"SB18e!D9","v":61188317},{"$f":"SB18e!E9","v":0},{"$f":"SB18e!F9","v":0},{"$f":"SB18e!G9","v":0},{"$f":"SB18e!H9","v":0},{"$f":"SB18e!I9","v":0},{"$f":"SB18e!J9","v":0},{"$f":"SB18e!K9","v":61188317},{"$f":"SB18e!L9","v":60981783},{"$f":"SB18e!M9","v":60000000}]
["Storm water Infrastructure",null,{"$f":"SB18e!C14","v":0},{"$f":"SB18e!D14","v":0},{"$f":"SB18e!E14","v":0},{"$f":"SB18e!F14","v":0},{"$f":"SB18e!G14","v":0},{"$f":"SB18e!H14","v":0},{"$f":"SB18e!I14","v":0},{"$f":"SB18e!J14","v":0},{"$f":"SB18e!K14","v":0},{"$f":"SB18e!L14","v":0},{"$f":"SB18e!M14","v":0}]
["Electrical Infrastructure",null,{"$f":"SB18e!C18","v":0},{"$f":"SB18e!D18","v":0},{"$f":"SB18e!E18","v":0},{"$f":"SB18e!F18","v":0},{"$f":"SB18e!G18","v":0},{"$f":"SB18e!H18","v":0},{"$f":"SB18e!I18","v":0},{"$f":"SB18e!J18","v":0},{"$f":"SB18e!K18","v":0},{"$f":"SB18e!L18","v":0},{"$f":"SB18e!M18","v":0}]
["Water Supply Infrastructure",null,{"$f":"SB18e!C28","v":0},{"$f":"SB18e!D28","v":0},{"$f":"SB18e!E28","v":0},{"$f":"SB18e!F28","v":0},{"$f":"SB18e!G28","v":0},{"$f":"SB18e!H28","v":0},{"$f":"SB18e!I28","v":0},{"$f":"SB18e!J28","v":0},{"$f":"SB18e!K28","v":0},{"$f":"SB18e!L28","v":0},{"$f":"SB18e!M28","v":0}]
["Sanitation Infrastructure",null,{"$f":"SB18e!C39","v":0},{"$f":"SB18e!D39","v":0},{"$f":"SB18e!E39","v":0},{"$f":"SB18e!F39","v":0},{"$f":"SB18e!G39","v":0},{"$f":"SB18e!H39","v":0},{"$f":"SB18e!I39","v":0},{"$f":"SB18e!J39","v":0},{"$f":"SB18e!K39","v":0},{"$f":"SB18e!L39","v":0},{"$f":"SB18e!M39","v":0}]
["Solid Waste Infrastructure",null,{"$f":"SB18e!C46","v":0},{"$f":"SB18e!D46","v":0},{"$f":"SB18e!E46","v":0},{"$f":"SB18e!F46","v":0},{"$f":"SB18e!G46","v":0},{"$f":"SB18e!H46","v":0},{"$f":"SB18e!I46","v":0},{"$f":"SB18e!J46","v":0},{"$f":"SB18e!K46","v":0},{"$f":"SB18e!L46","v":0},{"$f":"SB18e!M46","v":0}]
["Rail Infrastructure",null,{"$f":"SB18e!C54","v":0},{"$f":"SB18e!D54","v":0},{"$f":"SB18e!E54","v":0},{"$f":"SB18e!F54","v":0},{"$f":"SB18e!G54","v":0},{"$f":"SB18e!H54","v":0},{"$f":"SB18e!I54","v":0},{"$f":"SB18e!J54","v":0},{"$f":"SB18e!K54","v":0},{"$f":"SB18e!L54","v":0},{"$f":"SB18e!M54","v":0}]
["Coastal Infrastructure",null,{"$f":"SB18e!C64","v":0},{"$f":"SB18e!D64","v":0},{"$f":"SB18e!E64","v":0},{"$f":"SB18e!F64","v":0},{"$f":"SB18e!G64","v":0},{"$f":"SB18e!H64","v":0},{"$f":"SB18e!I64","v":0},{"$f":"SB18e!J64","v":0},{"$f":"SB18e!K64","v":0},{"$f":"SB18e!L64","v":0},{"$f":"SB18e!M64","v":0}]
["Information and Communication Infrastructure",null,{"$f":"SB18e!C70","v":0},{"$f":"SB18e!D70","v":0},{"$f":"SB18e!E70","v":0},{"$f":"SB18e!F70","v":0},{"$f":"SB18e!G70","v":0},{"$f":"SB18e!H70","v":0},{"$f":"SB18e!I70","v":0},{"$f":"SB18e!J70","v":0},{"$f":"SB18e!K70","v":0},{"$f":"SB18e!L70","v":0},{"$f":"SB18e!M70","v":0}]
["Infrastructure",null,{"$f":"SUM(C72:C80)","v":56000000},{"$f":"SUM(D72:D80)","v":61188317},0,0,0,0,0,0,61188317,60981783,60000000]
["Community Facilities",null,{"$f":"SB18e!C77","v":0},{"$f":"SB18e!D77","v":0},{"$f":"SB18e!E77","v":0},{"$f":"SB18e!F77","v":0},{"$f":"SB18e!G77","v":0},{"$f":"SB18e!H77","v":0},{"$f":"SB18e!I77","v":0},{"$f":"SB18e!J77","v":0},{"$f":"SB18e!K77","v":0},{"$f":"SB18e!L77","v":0},{"$f":"SB18e!M77","v":0}]
["Sport and Recreation Facilities",null,{"$f":"SB18e!C100","v":0},{"$f":"SB18e!D100","v":0},{"$f":"SB18e!E100","v":0},{"$f":"SB18e!F100","v":0},{"$f":"SB18e!G100","v":0},{"$f":"SB18e!H100","v":0},{"$f":"SB18e!I100","v":0},{"$f":"SB18e!J100","v":0},{"$f":"SB18e!K100","v":0},{"$f":"SB18e!L100","v":0},{"$f":"SB18e!M100","v":0}]
["Community Assets",null,{"$f":"SUM(C82:C83)","v":0},{"$f":"SUM(D82:D83)","v":0},0,0,0,0,0,0,0,0,0]
["Heritage Assets",null,{"$f":"SB18e!C105","v":0},{"$f":"SB18e!D105","v":0},{"$f":"SB18e!E105","v":0},{"$f":"SB18e!F105","v":0},{"$f":"SB18e!G105","v":0},{"$f":"SB18e!H105","v":0},{"$f":"SB18e!I105","v":0},{"$f":"SB18e!J105","v":0},{"$f":"SB18e!K105","v":0},{"$f":"SB18e!L105","v":0},{"$f":"SB18e!M105","v":0}]
["Revenue Generating",null,{"$f":"SB18e!C113","v":0},{"$f":"SB18e!D113","v":0},{"$f":"SB18e!E113","v":0},{"$f":"SB18e!F113","v":0},{"$f":"SB18e!G113","v":0},{"$f":"SB18e!H113","v":0},{"$f":"SB18e!I113","v":0},{"$f":"SB18e!J113","v":0},{"$f":"SB18e!K113","v":0},{"$f":"SB18e!L113","v":0},{"$f":"SB18e!M113","v":0}]
["Non-revenue Generating",null,{"$f":"SB18e!C116","v":0},{"$f":"SB18e!D116","v":0},{"$f":"SB18e!E116","v":0},{"$f":"SB18e!F116","v":0},{"$f":"SB18e!G116","v":0},{"$f":"SB18e!H116","v":0},{"$f":"SB18e!I116","v":0},{"$f":"SB18e!J116","v":0},{"$f":"SB18e!K116","v":0},{"$f":"SB18e!L116","v":0},{"$f":"SB18e!M116","v":0}]
["Investment properties",null,{"$f":"SUM(C86:C87)","v":0},{"$f":"SUM(D86:D87)","v":0},0,0,0,0,0,0,0,0,0]
["Operational Buildings",null,{"$f":"SB18e!C121","v":0},{"$f":"SB18e!D121","v":0},{"$f":"SB18e!E121","v":0},{"$f":"SB18e!F121","v":0},{"$f":"SB18e!G121","v":0},{"$f":"SB18e!H121","v":0},{"$f":"SB18e!I121","v":0},{"$f":"SB18e!J121","v":0},{"$f":"SB18e!K121","v":0},{"$f":"SB18e!L121","v":0},{"$f":"SB18e!M121","v":0}]
["Housing",null,{"$f":"SB18e!C133","v":0},{"$f":"SB18e!D133","v":0},{"$f":"SB18e!E133","v":0},{"$f":"SB18e!F133","v":0},{"$f":"SB18e!G133","v":0},{"$f":"SB18e!H133","v":0},{"$f":"SB18e!I133","v":0},{"$f":"SB18e!J133","v":0},{"$f":"SB18e!K133","v":0},{"$f":"SB18e!L133","v":0},{"$f":"SB18e!M133","v":0}]
["Other Assets",6,{"$f":"SUM(C89:C90)","v":0},{"$f":"SUM(D89:D90)","v":0},0,0,0,0,0,0,0,0,0]
["Biological or Cultivated Assets",null,{"$f":"SB18e!C138","v":0},{"$f":"SB18e!D138","v":0},{"$f":"SB18e!E138","v":0},{"$f":"SB18e!F138","v":0},{"$f":"SB18e!G138","v":0},{"$f":"SB18e!H138","v":0},{"$f":"SB18e!I138","v":0},{"$f":"SB18e!J138","v":0},{"$f":"SB18e!K138","v":0},{"$f":"SB18e!L138","v":0},{"$f":"SB18e!M138","v":0}]
["Servitudes",null,{"$f":"SB18e!C142","v":0},{"$f":"SB18e!D142","v":0},{"$f":"SB18e!E142","v":0},{"$f":"SB18e!F142","v":0},{"$f":"SB18e!G142","v":0},{"$f":"SB18e!H142","v":0},{"$f":"SB18e!I142","v":0},{"$f":"SB18e!J142","v":0},{"$f":"SB18e!K142","v":0},{"$f":"SB18e!L142","v":0},{"$f":"SB18e!M142","v":0}]
["Licences and Rights",null,{"$f":"SB18e!C143","v":0},{"$f":"SB18e!D143","v":0},{"$f":"SB18e!E143","v":0},{"$f":"SB18e!F143","v":0},{"$f":"SB18e!G143","v":0},{"$f":"SB18e!H143","v":0},{"$f":"SB18e!I143","v":0},{"$f":"SB18e!J143","v":0},{"$f":"SB18e!K143","v":0},{"$f":"SB18e!L143","v":0},{"$f":"SB18e!M143","v":0}]
["Intangible Assets",null,{"$f":"SUM(C93:C94)","v":0},{"$f":"SUM(D93:D94)","v":0},0,0,0,0,0,0,0,0,0]
["Computer Equipment",null,{"$f":"SB18e!C151","v":0},{"$f":"SB18e!D151","v":0},{"$f":"SB18e!E151","v":0},{"$f":"SB18e!F151","v":0},{"$f":"SB18e!G151","v":0},{"$f":"SB18e!H151","v":0},{"$f":"SB18e!I151","v":0},{"$f":"SB18e!J151","v":0},{"$f":"SB18e!K151","v":0},{"$f":"SB18e!L151","v":0},{"$f":"SB18e!M151","v":0}]
["Furniture and Office Equipment",null,{"$f":"SB18e!C154","v":0},{"$f":"SB18e!D154","v":0},{"$f":"SB18e!E154","v":0},{"$f":"SB18e!F154","v":0},{"$f":"SB18e!G154","v":0},{"$f":"SB18e!H154","v":0},{"$f":"SB18e!I154","v":0},{"$f":"SB18e!J154","v":0},{"$f":"SB18e!K154","v":0},{"$f":"SB18e!L154","v":0},{"$f":"SB18e!M154","v":0}]
["Machinery and Equipment",null,{"$f":"SB18e!C157","v":0},{"$f":"SB18e!D157","v":0},{"$f":"SB18e!E157","v":0},{"$f":"SB18e!F157","v":0},{"$f":"SB18e!G157","v":0},{"$f":"SB18e!H157","v":0},{"$f":"SB18e!I157","v":0},{"$f":"SB18e!J157","v":0},{"$f":"SB18e!K157","v":0},{"$f":"SB18e!L157","v":0},{"$f":"SB18e!M157","v":0}]
["Transport Assets",null,{"$f":"SB18e!C160","v":0},{"$f":"SB18e!D160","v":0},{"$f":"SB18e!E160","v":0},{"$f":"SB18e!F160","v":0},{"$f":"SB18e!G160","v":0},{"$f":"SB18e!H160","v":0},{"$f":"SB18e!I160","v":0},{"$f":"SB18e!J160","v":0},{"$f":"SB18e!K160","v":0},{"$f":"SB18e!L160","v":0},{"$f":"SB18e!M160","v":0}]
["Land",null,{"$f":"SB18e!C163","v":0},{"$f":"SB18e!D163","v":0},{"$f":"SB18e!E163","v":0},{"$f":"SB18e!F163","v":0},{"$f":"SB18e!G163","v":0},{"$f":"SB18e!H163","v":0},{"$f":"SB18e!I163","v":0},{"$f":"SB18e!J163","v":0},{"$f":"SB18e!K163","v":0},{"$f":"SB18e!L163","v":0},{"$f":"SB18e!M163","v":0}]
["Zoo's, Marine and Non-biological Animals",null,{"$f":"SB18e!C166","v":0},{"$f":"SB18e!D166","v":0},{"$f":"SB18e!E166","v":0},{"$f":"SB18e!F166","v":0},{"$f":"SB18e!G166","v":0},{"$f":"SB18e!H166","v":0},{"$f":"SB18e!I166","v":0},{"$f":"SB18e!J166","v":0},{"$f":"SB18e!K166","v":0},{"$f":"SB18e!L166","v":0},{"$f":"SB18e!M166","v":0}]
[]
["Total Capital Expenditure to be adjusted",4,{"$f":"C7+C39+C71","v":204802147},{"$f":"D7+D39+D71","v":206105362.19},0,0,0,0,113975,113975,206219337.19,202495233,218925369]
["Roads Infrastructure",null,{"$f":"C8+C40+C72","v":56000000},{"$f":"D8+D40+D72","v":61188317},0,0,0,0,0,0,61188317,60981783,60000000]
["Storm water Infrastructure",null,6193238,0.01,0,0,0,0,0,0,0.01,0,0]
["Electrical Infrastructure",null,22445688,20416973.030000001,0,0,0,0,0,0,20416973.030000001,11577740,12557370]
["Water Supply Infrastructure",null,64814603,{"$f":"D11+D43+D75","v":81281082.010000005},0,0,0,0,0,0,81281082.010000005,91183878,94263844]
["Sanitation Infrastructure",null,24111456,{"$f":"D12+D44+D76","v":12492236.07},0,0,0,0,0,0,12492236.07,25887357,25000000]
["Solid Waste Infrastructure",null,15796909,{"$f":"D13+D45+D77","v":0.01},0,0,0,0,0,0,0.01,3000000,19104155]
["Rail Infrastructure",null,0,{"$f":"D14+D46+D78","v":0},0,0,0,0,0,0,0,0,0]
["Coastal Infrastructure",null,0,{"$f":"D15+D47+D79","v":0},0,0,0,0,0,0,0,0,0]
["Information and Communication Infrastructure",null,0,{"$f":"D16+D48+D80","v":0},0,0,0,0,0,0,0,0,0]
["Infrastructure",null,189361894,{"$f":"D17+D49+D81","v":175378608.13},0,0,0,0,0,0,175378608.13,192630758,210925369]
["Community Facilities",null,12000000,{"$f":"D18+D50+D82","v":20106309},0,0,0,0,0,0,20106309,9864475,8000000]
["Sport and Recreation Facilities",null,0,{"$f":"D19+D51+D83","v":0},0,0,0,0,0,0,0,0,0]
["Community Assets",null,12000000,{"$f":"D20+D52+D84","v":20106309},0,0,0,0,0,0,20106309,9864475,8000000]
["Heritage Assets",null,0,{"$f":"D21+D53+D85","v":0},0,0,0,0,0,0,0,0,0]
["Revenue Generating",null,0,{"$f":"D22+D54+D86","v":0},0,0,0,0,0,0,0,0,0]
["Non-revenue Generating",null,0,{"$f":"D23+D55+D87","v":0},0,0,0,0,0,0,0,0,0]
["Investment properties",null,0,{"$f":"D24+D56+D88","v":0},0,0,0,0,0,0,0,0,0]
["Operational Buildings",null,2590253,{"$f":"D25+D57+D89","v":10620445.01},0,0,0,0,0,0,10620445.01,0,0]
["Housing",null,0,{"$f":"D26+D58+D90","v":0},0,0,0,0,0,0,0,0,0]
["Other Assets",null,2590253,{"$f":"D27+D59+D91","v":10620445.01},0,0,0,0,0,0,10620445.01,0,0]
["Biological or Cultivated Assets",null,0,{"$f":"D28+D60+D92","v":0},0,0,0,0,0,0,0,0,0]
["Servitudes",null,0,{"$f":"D29+D61+D93","v":0},0,0,0,0,0,0,0,0,0]
["Licences and Rights",null,250000,{"$f":"D30+D62+D94","v":0.01},0,0,0,0,0,0,0.01,0,0]
["Intangible Assets",null,250000,{"$f":"D31+D63+D95","v":0.01},0,0,0,0,0,0,0.01,0,0]
["Computer Equipment",null,0,{"$f":"D32+D64+D96","v":0},0,0,0,0,0,0,0,0,0]
["Furniture and Office Equipment",null,300000,{"$f":"D33+D65+D97","v":0.02},0,0,0,0,113975,113975,113975.02,0,0]
["Machinery and Equipment",null,300000,{"$f":"D34+D66+D98","v":0.02},0,0,0,0,0,0,0.02,0,0]
["Transport Assets",null,0,{"$f":"D35+D67+D99","v":0},0,0,0,0,0,0,0,0,0]
["Land",null,0,{"$f":"D36+D68+D100","v":0},0,0,0,0,0,0,0,0,0]
["Zoo's, Marine and Non-biological Animals",null,0,{"$f":"D37+D69+D101","v":0},0,0,0,0,0,0,0,0,0]
["TOTAL CAPITAL EXPENDITURE to be adjusted",4,{"$f":"C7+C39+C71","v":204802147},{"$f":"D7+D39+D71","v":206105362.19},0,0,0,0,113975,113975,206219337.19,202495233,218925369]
[]
["ASSET REGISTER SUMMARY - PPE (WDV)",5,{"$f":"C146+C149+C150+C153+C156+C157+SUM(C160:C166)","v":1785427147},{"$f":"D146+D149+D150+D153+D156+D157+SUM(D160:D166)","v":1786730362.1900001},0,0,0,0,113975,113975,1786844337.1900001,3685970409,3945578770]
[{"$f":"+A8","v":"Roads Infrastructure"},null,56000000,61188317,0,0,0,0,0,{"$f":"SUM(E137:I137)","v":0},{"$f":"IF(D137=0,C137+J137,D137+J137)","v":61188317},60981783,60000000]
[{"$f":"+A9","v":"Storm water Infrastructure"},null,6193238,0.01,0,0,0,0,0,0,{"$f":"IF(D138=0,C138+J138,D138+J138)","v":0.01},0,0]
["Electrical Infrastructure",null,22445688,20416973.030000001,0,0,0,0,0,0,{"$f":"IF(D139=0,C139+J139,D139+J139)","v":20416973.030000001},11577740,12557370]
["Water Supply Infrastructure",null,64814603,81281082.010000005,0,0,0,0,0,0,{"$f":"IF(D140=0,C140+J140,D140+J140)","v":81281082.010000005},91183878,94263844]
["Sanitation Infrastructure",null,24111456,12492236.07,0,0,0,0,0,0,{"$f":"IF(D141=0,C141+J141,D141+J141)","v":12492236.07},25887357,25000000]
["Solid Waste Infrastructure",null,15796909,0.01,0,0,0,0,0,0,0.01,3000000,19104155]
["Rail Infrastructure",null,null,null,null,null,null,null,null,0,0]
["Coastal Infrastructure",null,null,null,null,null,null,null,null,0,0]
["Information and Communication Infrastructure",null,0,0,0,0,0,0,0,0,0,0,0]
["Infrastructure",null,{"$f":"SUM(C137:C145)","v":189361894},175378608.13,0,0,0,0,0,0,175378608.13,{"$f":"SUM(L137:L145)","v":192630758},{"$f":"SUM(M137:M145)","v":210925369}]
[]
[]
["Community Assets",null,12000000,20106309,0,0,0,0,0,{"$f":"SUM(E149:I149)","v":0},{"$f":"IF(D149=0,C149+J149,D149+J149)","v":20106309},9864475,8000000]
["Heritage Assets",null,0,0,0,0,0,0,0,{"$f":"SUM(E150:I150)","v":0},0,14000,14000]
[]
[]
["Investment properties",null,0,0,0,0,0,0,0,{"$f":"SUM(E153:I153)","v":0},{"$f":"IF(D153=0,C153+J153,D153+J153)","v":0},155209867,17235257]
[]
[]
["Other Assets",null,2590253,10620445.01,0,0,0,0,0,{"$f":"SUM(E156:I156)","v":0},{"$f":"IF(D156=0,C156+J156,D156+J156)","v":10620445.01},0,0]
["Biological or Cultivated Assets",null,null,null,null,null,null,null,null,{"$f":"SUM(E157:I157)","v":0},{"$f":"IF(D157=0,C157+J157,D157+J157)","v":0}]
[]
[]
["Intangible Assets",null,250000,0.01,0,0,0,0,0,{"$f":"SUM(E160:I160)","v":0},{"$f":"IF(D160=0,C160+J160,D160+J160)","v":0.01},0,0]
["Computer Equipment",null,0,0,0,0,0,0,0,{"$f":"SUM(E161:I161)","v":0},{"$f":"IF(D161=0,C161+J161,D161+J161)","v":0},0,0]
["Furniture and Office Equipment",null,1580925000,1580625000.02,0,0,0,0,113975,113975,1580738975.02,3328251309,3709404144]
["Machinery and Equipment",null,300000,0.02,0,0,0,0,0,0,0.02,0,0]
["Transport Assets",null,0,0,0,0,0,0,0,0,0,0,0]
["Land",null,null,null,null,null,null,null,null,0,0]
["Zoo's, Marine and Non-biological Animals",null,null,null,null,null,null,null,null,0,0]
["TOTAL ASSET REGISTER SUMMARY - PPE (WDV)",5,{"$f":"C146+C149+C150+C153+C156+C157+SUM(C160:C166)","v":1785427147},{"$f":"D146+D149+D150+D153+D156+D157+SUM(D160:D166)","v":1786730362.1900001},0,0,0,0,113975,113975,1786844337.1900001,3685970409,3945578770]
[]
["EXPENDITURE OTHER ITEMS"]
["Depreciation & asset impairment",null,{"$f":"SB18d!C169","v":154536733},{"$f":"SB18d!D169","v":154536733},{"$f":"SB18d!E169","v":0},{"$f":"SB18d!F169","v":0},{"$f":"SB18d!G169","v":0},{"$f":"SB18d!H169","v":0},{"$f":"SB18d!I169","v":0},{"$f":"SB18d!J169","v":0},{"$f":"SB18d!K169","v":154536733},{"$f":"SB18d!L169","v":133503316},{"$f":"SB18d!M169","v":139644469}]
["Repairs and Maintenance by asset class",3,{"$f":"C181+C184+C185+C188+C191+C192+SUM(C195:C201)","v":65140000},{"$f":"D181+D184+D185+D188+D191+D192+SUM(D195:D201)","v":47038475.019999996},{"$f":"E181+E184+E185+E188+E191+E192+SUM(E195:E201)","v":0},{"$f":"F181+F184+F185+F188+F191+F192+SUM(F195:F201)","v":0},0,0,0,0,47038475.019999996,{"$f":"L181+L184+L185+L188+L191+L192+SUM(L195:L201)","v":42480000},{"$f":"M181+M184+M185+M188+M191+M192+SUM(M195:M201)","v":46588800}]
[{"$f":"+A8","v":"Roads Infrastructure"},null,{"$f":"SB18c!C9","v":9400000},{"$f":"SB18c!D9","v":1050000},{"$f":"SB18c!E9","v":0},{"$f":"SB18c!F9","v":0},{"$f":"SB18c!G9","v":0},{"$f":"SB18c!H9","v":0},{"$f":"SB18c!I9","v":0},{"$f":"SB18c!J9","v":0},{"$f":"SB18c!K9","v":1050000},{"$f":"SB18c!L9","v":1700000},{"$f":"SB18c!M9","v":1789000}]
[{"$f":"+A9","v":"Storm water Infrastructure"},null,{"$f":"SB18c!C14","v":2000000},{"$f":"SB18c!D14","v":450000},{"$f":"SB18c!E14","v":0},{"$f":"SB18c!F14","v":0},{"$f":"SB18c!G14","v":0},{"$f":"SB18c!H14","v":0},{"$f":"SB18c!I14","v":0},{"$f":"SB18c!J14","v":0},{"$f":"SB18c!K14","v":450000},{"$f":"SB18c!L14","v":760000},{"$f":"SB18c!M14","v":820000}]
["Electrical Infrastructure",null,{"$f":"SB18c!C18","v":6000000},{"$f":"SB18c!D18","v":1000000},{"$f":"SB18c!E18","v":0},{"$f":"SB18c!F18","v":0},{"$f":"SB18c!G18","v":0},{"$f":"SB18c!H18","v":0},{"$f":"SB18c!I18","v":0},{"$f":"SB18c!J18","v":0},{"$f":"SB18c!K18","v":1000000},{"$f":"SB18c!L18","v":2000000},{"$f":"SB18c!M18","v":2092000}]
["Water Supply Infrastructure",null,{"$f":"SB18c!C28","v":300000},{"$f":"SB18c!D28","v":150000},{"$f":"SB18c!E28","v":0},{"$f":"SB18c!F28","v":0},{"$f":"SB18c!G28","v":0},{"$f":"SB18c!H28","v":0},{"$f":"SB18c!I28","v":0},{"$f":"SB18c!J28","v":0},{"$f":"SB18c!K28","v":150000},{"$f":"SB18c!L28","v":300000},{"$f":"SB18c!M28","v":320000}]
["Sanitation Infrastructure",null,{"$f":"SB18c!C39","v":0},{"$f":"SB18c!D39","v":0},{"$f":"SB18c!E39","v":0},{"$f":"SB18c!F39","v":0},{"$f":"SB18c!G39","v":0},{"$f":"SB18c!H39","v":0},{"$f":"SB18c!I39","v":0},{"$f":"SB18c!J39","v":0},{"$f":"SB18c!K39","v":0},{"$f":"SB18c!L39","v":0},{"$f":"SB18c!M39","v":0}]
["Solid Waste Infrastructure",null,{"$f":"SB18c!C46","v":30210000},{"$f":"SB18c!D46","v":33688475},{"$f":"SB18c!E46","v":0},{"$f":"SB18c!F46","v":0},{"$f":"SB18c!G46","v":0},{"$f":"SB18c!H46","v":0},{"$f":"SB18c!I46","v":0},{"$f":"SB18c!J46","v":0},{"$f":"SB18c!K46","v":33688475},{"$f":"SB18c!L46","v":24310000},{"$f":"SB18c!M46","v":27106000}]
["Rail Infrastructure",null,{"$f":"SB18c!C54","v":0},{"$f":"SB18c!D54","v":0},{"$f":"SB18c!E54","v":0},{"$f":"SB18c!F54","v":0},{"$f":"SB18c!G54","v":0},{"$f":"SB18c!H54","v":0},{"$f":"SB18c!I54","v":0},{"$f":"SB18c!J54","v":0},{"$f":"SB18c!K54","v":0},{"$f":"SB18c!L54","v":0},{"$f":"SB18c!M54","v":0}]
["Coastal Infrastructure",null,{"$f":"SB18c!C64","v":0},{"$f":"SB18c!D64","v":0},{"$f":"SB18c!E64","v":0},{"$f":"SB18c!F64","v":0},{"$f":"SB18c!G64","v":0},{"$f":"SB18c!H64","v":0},{"$f":"SB18c!I64","v":0},{"$f":"SB18c!J64","v":0},{"$f":"SB18c!K64","v":0},{"$f":"SB18c!L64","v":0},{"$f":"SB18c!M64","v":0}]
["Information and Communication Infrastructure",null,{"$f":"SB18c!C70","v":0},{"$f":"SB18c!D70","v":0},{"$f":"SB18c!E70","v":0},{"$f":"SB18c!F70","v":0},{"$f":"SB18c!G70","v":0},{"$f":"SB18c!H70","v":0},{"$f":"SB18c!I70","v":0},{"$f":"SB18c!J70","v":0},{"$f":"SB18c!K70","v":0},{"$f":"SB18c!L70","v":0},{"$f":"SB18c!M70","v":0}]
["Infrastructure",null,{"$f":"SUM(C172:C180)","v":47910000},{"$f":"SUM(D172:D180)","v":36338475},0,0,0,0,0,0,36338475,29070000,32127000]
["Community Facilities",null,{"$f":"SB18c!C77","v":0},{"$f":"SB18c!D77","v":0},{"$f":"SB18c!E77","v":0},{"$f":"SB18c!F77","v":0},{"$f":"SB18c!G77","v":0},{"$f":"SB18c!H77","v":0},{"$f":"SB18c!I77","v":0},{"$f":"SB18c!J77","v":0},{"$f":"SB18c!K77","v":0},{"$f":"SB18c!L77","v":0},{"$f":"SB18c!M77","v":0}]
["Sport and Recreation Facilities",null,{"$f":"SB18c!C100","v":500000},{"$f":"SB18c!D100","v":200000},{"$f":"SB18c!E100","v":0},{"$f":"SB18c!F100","v":0},{"$f":"SB18c!G100","v":0},{"$f":"SB18c!H100","v":0},{"$f":"SB18c!I100","v":0},{"$f":"SB18c!J100","v":0},{"$f":"SB18c!K100","v":200000},{"$f":"SB18c!L100","v":400000},{"$f":"SB18c!M100","v":420000}]
["Community Assets",null,{"$f":"SUM(C182:C183)","v":500000},{"$f":"SUM(D182:D183)","v":200000},0,0,0,0,0,0,200000,400000,420000]
["Heritage Assets",null,{"$f":"SB18c!C105","v":0},{"$f":"SB18c!D105","v":0},{"$f":"SB18c!E105","v":0},{"$f":"SB18c!F105","v":0},{"$f":"SB18c!G105","v":0},{"$f":"SB18c!H105","v":0},{"$f":"SB18c!I105","v":0},{"$f":"SB18c!J105","v":0},{"$f":"SB18c!K105","v":0},{"$f":"SB18c!L105","v":0},{"$f":"SB18c!M105","v":0}]
["Revenue Generating",null,{"$f":"SB18c!C113","v":0},{"$f":"SB18c!D113","v":0},{"$f":"SB18c!E113","v":0},{"$f":"SB18c!F113","v":0},{"$f":"SB18c!G113","v":0},{"$f":"SB18c!H113","v":0},{"$f":"SB18c!I113","v":0},{"$f":"SB18c!J113","v":0},{"$f":"SB18c!K113","v":0},{"$f":"SB18c!L113","v":0},{"$f":"SB18c!M113","v":0}]
["Non-revenue Generating",null,{"$f":"SB18c!C116","v":0},{"$f":"SB18c!D116","v":0},{"$f":"SB18c!E116","v":0},{"$f":"SB18c!F116","v":0},{"$f":"SB18c!G116","v":0},{"$f":"SB18c!H116","v":0},{"$f":"SB18c!I116","v":0},{"$f":"SB18c!J116","v":0},{"$f":"SB18c!K116","v":0},{"$f":"SB18c!L116","v":0},{"$f":"SB18c!M116","v":0}]
["Investment properties",null,{"$f":"SUM(C186:C187)","v":0},{"$f":"SUM(D186:D187)","v":0},0,0,0,0,0,0,0,0,0]
["Operational Buildings",null,{"$f":"SB18c!C121","v":7800000},{"$f":"SB18c!D121","v":2500000},{"$f":"SB18c!E121","v":0},{"$f":"SB18c!F121","v":0},{"$f":"SB18c!G121","v":0},{"$f":"SB18c!H121","v":0},{"$f":"SB18c!I121","v":0},{"$f":"SB18c!J121","v":0},{"$f":"SB18c!K121","v":2500000},{"$f":"SB18c!L121","v":5800000},{"$f":"SB18c!M121","v":6066800}]
["Housing",null,{"$f":"SB18c!C133","v":0},{"$f":"SB18c!D133","v":0},{"$f":"SB18c!E133","v":0},{"$f":"SB18c!F133","v":0},{"$f":"SB18c!G133","v":0},{"$f":"SB18c!H133","v":0},{"$f":"SB18c!I133","v":0},{"$f":"SB18c!J133","v":0},{"$f":"SB18c!K133","v":0},{"$f":"SB18c!L133","v":0},{"$f":"SB18c!M133","v":0}]
["Other Assets",null,{"$f":"SUM(C189:C190)","v":7800000},{"$f":"SUM(D189:D190)","v":2500000},0,0,0,0,0,0,2500000,5800000,6066800]
["Biological or Cultivated Assets",null,{"$f":"SB18c!C138","v":0},{"$f":"SB18c!D138","v":0},{"$f":"SB18c!E138","v":0},{"$f":"SB18c!F138","v":0},{"$f":"SB18c!G138","v":0},{"$f":"SB18c!H138","v":0},{"$f":"SB18c!I138","v":0},{"$f":"SB18c!J138","v":0},{"$f":"SB18c!K138","v":0},{"$f":"SB18c!L138","v":0},{"$f":"SB18c!M138","v":0}]
["Servitudes",null,{"$f":"SB18c!C142","v":0},{"$f":"SB18c!D142","v":0},{"$f":"SB18c!E142","v":0},{"$f":"SB18c!F142","v":0},{"$f":"SB18c!G142","v":0},{"$f":"SB18c!H142","v":0},{"$f":"SB18c!I142","v":0},{"$f":"SB18c!J142","v":0},{"$f":"SB18c!K142","v":0},{"$f":"SB18c!L142","v":0},{"$f":"SB18c!M142","v":0}]
["Licences and Rights",null,{"$f":"SB18c!C143","v":3000000},{"$f":"SB18c!D143","v":2000000},{"$f":"SB18c!E143","v":0},{"$f":"SB18c!F143","v":0},{"$f":"SB18c!G143","v":0},{"$f":"SB18c!H143","v":0},{"$f":"SB18c!I143","v":0},{"$f":"SB18c!J143","v":0},{"$f":"SB18c!K143","v":2000000},{"$f":"SB18c!L143","v":0},{"$f":"SB18c!M143","v":0}]
["Intangible Assets",null,{"$f":"SUM(C193:C194)","v":3000000},{"$f":"SUM(D193:D194)","v":2000000},0,0,0,0,0,0,2000000,0,0]
["Computer Equipment",null,{"$f":"SB18c!C151","v":80000},{"$f":"SB18c!D151","v":50000.01},{"$f":"SB18c!E151","v":0},{"$f":"SB18c!F151","v":0},{"$f":"SB18c!G151","v":0},{"$f":"SB18c!H151","v":0},{"$f":"SB18c!I151","v":0},{"$f":"SB18c!J151","v":0},{"$f":"SB18c!K151","v":50000.01},{"$f":"SB18c!L151","v":50000},{"$f":"SB18c!M151","v":55000}]
["Furniture and Office Equipment",null,{"$f":"SB18c!C154","v":0},{"$f":"SB18c!D154","v":0},{"$f":"SB18c!E154","v":0},{"$f":"SB18c!F154","v":0},{"$f":"SB18c!G154","v":0},{"$f":"SB18c!H154","v":0},{"$f":"SB18c!I154","v":0},{"$f":"SB18c!J154","v":0},{"$f":"SB18c!K154","v":0},{"$f":"SB18c!L154","v":0},{"$f":"SB18c!M154","v":0}]
["Machinery and Equipment",null,{"$f":"SB18c!C157","v":0},{"$f":"SB18c!D157","v":0},{"$f":"SB18c!E157","v":0},{"$f":"SB18c!F157","v":0},{"$f":"SB18c!G157","v":0},{"$f":"SB18c!H157","v":0},{"$f":"SB18c!I157","v":0},{"$f":"SB18c!J157","v":0},{"$f":"SB18c!K157","v":0},{"$f":"SB18c!L157","v":0},{"$f":"SB18c!M157","v":0}]
["Transport Assets",null,{"$f":"SB18c!C160","v":5850000},{"$f":"SB18c!D160","v":5950000.0099999998},{"$f":"SB18c!E160","v":0},{"$f":"SB18c!F160","v":0},{"$f":"SB18c!G160","v":0},{"$f":"SB18c!H160","v":0},{"$f":"SB18c!I160","v":0},{"$f":"SB18c!J160","v":0},{"$f":"SB18c!K160","v":5950000.0099999998},{"$f":"SB18c!L160","v":7160000},{"$f":"SB18c!M160","v":7920000}]
["Land",null,{"$f":"SB18c!C163","v":0},{"$f":"SB18c!D163","v":0},{"$f":"SB18c!E163","v":0},{"$f":"SB18c!F163","v":0},{"$f":"SB18c!G163","v":0},{"$f":"SB18c!H163","v":0},{"$f":"SB18c!I163","v":0},{"$f":"SB18c!J163","v":0},{"$f":"SB18c!K163","v":0},{"$f":"SB18c!L163","v":0},{"$f":"SB18c!M163","v":0}]
["Zoo's, Marine and Non-biological Animals",6,{"$f":"SB18c!C166","v":0},{"$f":"SB18c!D166","v":0},{"$f":"SB18c!E166","v":0},{"$f":"SB18c!F166","v":0},{"$f":"SB18c!G166","v":0},{"$f":"SB18c!H166","v":0},{"$f":"SB18c!I166","v":0},{"$f":"SB18c!J166","v":0},{"$f":"SB18c!K166","v":0},{"$f":"SB18c!L166","v":0},{"$f":"SB18c!M166","v":0}]
["TOTAL EXPENDITURE OTHER ITEMS to be adjusted",null,{"$f":"+C170+C171","v":219676733},{"$f":"+D170+D171","v":201575208.01999998},0,0,0,0,0,0,201575208.01999998,175983316,186233269]
[]
["Renewal and upgrading of Existing Assets as % of total capex",null,{"$f":"IF(ISERROR((C39+C71)/C134),0,((C39+C71)/C134))","v":0.34589604668548712},{"$f":"IF(ISERROR((D39+D71)/D134),0,((D39+D71)/D134))","v":0.49896161326068406},null,null,null,null,null,null,{"$f":"IF(ISERROR((K39+K71)/K134),0,((K39+K71)/K134))","v":0.49868584305093411},{"$f":"IF(ISERROR((L39+L71)/L134),0,((L39+L71)/L134))","v":0.34986630030940036},{"$f":"IF(ISERROR((M39+M71)/M134),0,((M39+M71)/M134))","v":0.31060813239967633}]
["Renewal and upgrading of Existing Assets as % of deprecn\"",null,{"$f":"IF(ISERROR((C39+C71)/C170),0,((C39+C71)/C170))","v":0.45840397700137742},{"$f":"IF(ISERROR((D39+D71)/D170),0,((D39+D71)/D170))","v":0.66546420403490736},null,null,null,null,null,null,{"$f":"IF(ISERROR((K39+K71)/K170),0,((K39+K71)/K170))","v":0.66546420403490736},{"$f":"IF(ISERROR((L39+L71)/L170),0,((L39+L71)/L170))","v":0.53067039922813608},{"$f":"IF(ISERROR((M39+M71)/M170),0,((M39+M71)/M170))","v":0.48695090100561017}]
["R&M as a % of PPE",null,{"$f":"IF(ISERROR(C171/C167),0,(C171/C167))","v":3.648426658542344E-2},{"$f":"IF(ISERROR(D171/D167),0,(D171/D167))","v":2.632656612066793E-2},null,null,null,null,null,null,{"$f":"IF(ISERROR(K171/K167),0,(K171/K167))","v":2.6324886863940775E-2},{"$f":"IF(ISERROR(L171/L167),0,(L171/L167))","v":1.1524780528969244E-2},{"$f":"IF(ISERROR(M171/M167),0,(M171/M167))","v":1.1807849422304145E-2}]
["Renewal and upgrading and R&M as a % of PPE",null,{"$f":"IF(ISERROR((C39+C71+C171)/C167),0,((C39+C71+C171)/C167))","v":7.6161188222372195E-2},{"$f":"IF(ISERROR((D39+D71+D171)/D167),0,((D39+D71+D171)/D167))","v":8.388346793205842E-2},null,null,null,null,null,null,{"$f":"IF(ISERROR((K39+K71+K171)/K167),0,((K39+K71+K171)/K167))","v":8.3878117371822936E-2},{"$f":"IF(ISERROR((L39+L71+L171)/L167),0,((L39+L71+L171)/L167))","v":3.0745297825314148E-2},{"$f":"IF(ISERROR((M39+M71+M171)/M167),0,((M39+M71+M171)/M167))","v":2.9042329827823968E-2}]
[]
[{"$f":"head27a","v":"References"}]
["1. Detail of new assets provided in Table SB18a"]
["2. Detail of renewal of existing assets provided in Table SB18b"]
["2a. Detail of upgrading of existing assets provided in Table SB18e"]
["3. Detail of Repairs and Maintenance by Asset Class provided in Table SB18c"]
["4. Must reconcile to total capital expenditure on Budgeted Capital Expenditure"]
["5. Must reconcile to Adjustments Budget Financial Position (written down value)"]
["6. Donated/contributed and assets funded by finance leases to be allocated to the respective category"]
["7. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["8. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["9. Increases of funds approved under MFMA section 31"]
["10. Adjustments approved in accordance with MFMA section 29 "]
["11. Adjustments to transfers from National or Provincial Government"]
["12. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["13. G = B + C + D + E + F"]
["14. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
[]
[null,"Asset register balance check",{"$f":"SUM('B6-FinPos'!C21:C24)-'B9-Asset'!C167","v":0},{"$f":"SUM('B6-FinPos'!D21:D24)-'B9-Asset'!D167","v":0},{"$f":"SUM('B6-FinPos'!E21:E24)-'B9-Asset'!E167","v":0},{"$f":"SUM('B6-FinPos'!F21:F24)-'B9-Asset'!F167","v":0},{"$f":"SUM('B6-FinPos'!G21:G24)-'B9-Asset'!G167","v":0},{"$f":"SUM('B6-FinPos'!H21:H24)-'B9-Asset'!H167","v":0},{"$f":"SUM('B6-FinPos'!I21:I24)-'B9-Asset'!I167","v":0},{"$f":"SUM('B6-FinPos'!J21:J24)-'B9-Asset'!J167","v":0},{"$f":"SUM('B6-FinPos'!K21:K24)-'B9-Asset'!K167","v":0},{"$f":"SUM('B6-FinPos'!L21:L24)-'B9-Asset'!L167","v":-155223867},{"$f":"SUM('B6-FinPos'!M21:M24)-'B9-Asset'!M167","v":-17249257}]

{"sheet":"B10-SerDel","index":18,"n_rows":99,"n_cols":13,"rows_kept":99,"cut":false,"hidden":false,"merged":[[95,0,95,12],[93,0,93,12],[1,0,4,0],[1,1,4,1],[1,2,1,10],[89,0,89,12],[88,0,88,12],[90,0,90,12],[91,0,91,12]]}
[{"$f":"muni&\" - \"&_ADJ10&\" - \"&Date","v":"NW375 Moses Kotane - Table B10 Basic service delivery measurement - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,7,8,9,10,11,12,13,14]
[null,null,"A","A1","B","C","D","E","F","G","H"]
["Household service targets",1]
["Water:"]
["Piped water inside dwelling",null,5700,0,0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":5700},5700,5700]
["Piped water inside yard (but not in dwelling)",null,10000,0,0,0,0,0,0,0,10000,10000,10000]
["Using public tap (at least min.service level)",2,52000,0,0,0,0,0,0,0,52000,52000,52000]
["Other water supply (at least min.service level)",null,null,null,null,null,null,null,null,0,0]
["Minimum Service Level and Above sub-total",null,{"$f":"SUM(C8:C11)","v":67700},0,0,0,0,0,0,0,67700,67700,67700]
["Using public tap (< min.service level)",3,12000,0,0,0,0,0,0,0,12000,12000,12000]
["Other water supply (< min.service level)","3,4",null,null,null,null,null,null,null,0,0]
["No water supply",null,null,null,null,null,null,null,null,0,0]
["Below Minimum Servic Level sub-total",null,{"$f":"SUM(C13:C15)","v":12000},0,0,0,0,0,0,0,12000,12000,12000]
["Total number of households",5,{"$f":"C12+C16","v":79700},0,0,0,0,0,0,0,79700,79700,79700]
["Sanitation/sewerage:"]
["Flush toilet (connected to sewerage)",null,7000,0,0,0,0,0,0,{"$f":"SUM(E19:I19)","v":0},{"$f":"IF(D19=0,C19+J19,D19+J19)","v":7000},7000,7000]
["Flush toilet (with septic tank)",null,5000,0,0,0,0,0,0,0,5000,5000,5000]
["Chemical toilet",null,null,null,null,null,null,null,null,0,0]
["Pit toilet (ventilated)",null,null,null,null,null,null,null,null,0,0]
["Other toilet provisions (> min.service level)",null,null,null,null,null,null,null,null,0,0]
[{"$f":"$A$12","v":"Minimum Service Level and Above sub-total"},null,{"$f":"SUM(C19:C23)","v":12000},0,0,0,0,0,0,0,12000,12000,12000]
["Bucket toilet",null,null,null,null,null,null,null,null,0,0]
["Other toilet provisions (< min.service level)",null,null,null,null,null,null,null,null,0,0]
["No toilet provisions",null,39000,0,0,0,0,0,0,0,39000,39000,39000]
[{"$f":"$A$16","v":"Below Minimum Servic Level sub-total"},null,{"$f":"SUM(C25:C27)","v":39000},0,0,0,0,0,0,0,39000,39000,39000]
[{"$f":"$A$17","v":"Total number of households"},{"$f":"$B$17","v":5},{"$f":"C24+C28","v":51000},0,0,0,0,0,0,0,51000,51000,51000]
["Energy:"]
["Electricity (at least min. service level)",null,null,null,null,null,null,null,null,{"$f":"SUM(E31:I31)","v":0},{"$f":"IF(D31=0,C31+J31,D31+J31)","v":0}]
["Electricity - prepaid (> min.service level)",null,null,null,null,null,null,null,null,0,0]
[{"$f":"$A$12","v":"Minimum Service Level and Above sub-total"},null,{"$f":"SUM(C31:C32)","v":0},0,0,0,0,0,0,0,0,0,0]
["Electricity (< min.service level)",null,null,null,null,null,null,null,null,0,0]
["Electricity - prepaid (< min. service level)",null,null,null,null,null,null,null,null,0,0]
["Other energy sources",null,null,null,null,null,null,null,null,0,0]
[{"$f":"$A$16","v":"Below Minimum Servic Level sub-total"},null,{"$f":"SUM(C34:C36)","v":0},0,0,0,0,0,0,0,0,0,0]
[{"$f":"$A$17","v":"Total number of households"},{"$f":"$B$17","v":5},{"$f":"C33+C37","v":0},0,0,0,0,0,0,0,0,0,0]
["Refuse:"]
["Removed at least once a week (min.service)",null,75125,0,0,0,0,0,0,{"$f":"SUM(E40:I40)","v":0},{"$f":"IF(D40=0,C40+J40,D40+J40)","v":75125},75125,75125]
[{"$f":"$A$12","v":"Minimum Service Level and Above sub-total"},null,{"$f":"SUM(C40)","v":75125},0,0,0,0,0,0,{"$f":"SUM(E41:I41)","v":0},75125,{"$f":"SUM(L40)","v":75125},{"$f":"SUM(M40)","v":75125}]
["Removed less frequently than once a week",null,null,null,null,null,null,null,null,0,0]
["Using communal refuse dump",null,null,null,null,null,null,null,null,0,0]
["Using own refuse dump",null,null,null,null,null,null,null,null,0,0]
["Other rubbish disposal",null,null,null,null,null,null,null,null,0,0]
["No rubbish disposal",null,null,null,null,null,null,null,null,0,0]
[{"$f":"$A$16","v":"Below Minimum Servic Level sub-total"},null,{"$f":"SUM(C42:C46)","v":0},0,0,0,0,0,0,0,0,0,0]
[{"$f":"$A$17","v":"Total number of households"},{"$f":"$B$17","v":5},{"$f":"C41+C47","v":75125},0,0,0,0,0,0,{"$f":"J40+J47","v":0},{"$f":"K40+K47","v":75125},{"$f":"L41+L47","v":75125},{"$f":"M41+M47","v":75125}]
[]
["Households receiving Free Basic Service",15]
["Water (6 kilolitres per household per month)",null,19000,0,0,0,0,0,0,{"$f":"SUM(E51:I51)","v":0},{"$f":"IF(D51=0,C51+J51,D51+J51)","v":19000},19000,0]
["Sanitation (free minimum level service)",null,{"$f":"'SB5'!E274","v":330},{"$f":"'SB5'!F274","v":0},{"$f":"'SB5'!G274","v":0},{"$f":"'SB5'!H274","v":0},{"$f":"'SB5'!I274","v":0},{"$f":"'SB5'!J274","v":0},{"$f":"'SB5'!K274","v":0},{"$f":"SUM(E52:I52)","v":0},{"$f":"IF(D52=0,C52+J52,D52+J52)","v":330},{"$f":"'SB5'!N274","v":330},{"$f":"'SB5'!O274","v":0}]
["Electricity/other energy (50kwh per household per month)",null,{"$f":"'SB5'!E250","v":0},{"$f":"'SB5'!F250","v":0},{"$f":"'SB5'!G250","v":0},{"$f":"'SB5'!H250","v":0},{"$f":"'SB5'!I250","v":0},{"$f":"'SB5'!J250","v":0},{"$f":"'SB5'!K250","v":0},{"$f":"SUM(E53:I53)","v":0},{"$f":"IF(D53=0,C53+J53,D53+J53)","v":0},{"$f":"'SB5'!N250","v":0},{"$f":"'SB5'!O250","v":0}]
["Refuse (removed at least once a week)",null,{"$f":"'SB5'!E286","v":58114},{"$f":"'SB5'!F286","v":0},{"$f":"'SB5'!G286","v":0},{"$f":"'SB5'!H286","v":0},{"$f":"'SB5'!I286","v":0},{"$f":"'SB5'!J286","v":0},{"$f":"'SB5'!K286","v":0},{"$f":"SUM(E54:I54)","v":0},{"$f":"IF(D54=0,C54+J54,D54+J54)","v":58114},{"$f":"'SB5'!N286","v":58114},{"$f":"'SB5'!O286","v":0}]
[]
["Cost of Free Basic Services provided (R'000)",16," "]
["Water (6 kilolitres per indigent household per month)",null,{"$f":"'SB1'!C21","v":10653000},{"$f":"'SB1'!D21","v":10653000},{"$f":"'SB1'!E21","v":0},{"$f":"'SB1'!F21","v":0},{"$f":"'SB1'!G21","v":0},{"$f":"'SB1'!H21","v":0},{"$f":"'SB1'!I21","v":0},{"$f":"SUM(E57:I57)","v":0},{"$f":"IF(D57=0,C57+J57,D57+J57)","v":10653000},{"$f":"'SB1'!L21","v":10682385},{"$f":"'SB1'!M21","v":11173775}]
["Sanitation (free sanitation service to indigent households)",null,{"$f":"'SB1'!C27","v":350000},{"$f":"'SB1'!D27","v":350000},{"$f":"'SB1'!E27","v":0},{"$f":"'SB1'!F27","v":0},{"$f":"'SB1'!G27","v":0},{"$f":"'SB1'!H27","v":0},{"$f":"'SB1'!I27","v":0},{"$f":"SUM(E58:I58)","v":0},{"$f":"IF(D58=0,C58+J58,D58+J58)","v":350000},{"$f":"'SB1'!L27","v":374500},{"$f":"'SB1'!M27","v":400715}]
["Electricity/other energy (50kwh per indigent household per month)",null,{"$f":"'SB1'!C15","v":4000000},{"$f":"'SB1'!D15","v":4000000},{"$f":"'SB1'!E15","v":0},{"$f":"'SB1'!F15","v":0},{"$f":"'SB1'!G15","v":0},{"$f":"'SB1'!H15","v":0},{"$f":"'SB1'!I15","v":0},{"$f":"SUM(E59:I59)","v":0},{"$f":"IF(D59=0,C59+J59,D59+J59)","v":4000000},{"$f":"'SB1'!L15","v":4000000},{"$f":"'SB1'!M15","v":4000000}]
["Refuse (removed once a week for indigent households)",null,{"$f":"'SB1'!C34","v":20530000},{"$f":"'SB1'!D34","v":20530000},{"$f":"'SB1'!E34","v":0},{"$f":"'SB1'!F34","v":0},{"$f":"'SB1'!G34","v":0},{"$f":"'SB1'!H34","v":0},{"$f":"'SB1'!I34","v":0},{"$f":"SUM(E60:I60)","v":0},{"$f":"IF(D60=0,C60+J60,D60+J60)","v":20530000},{"$f":"'SB1'!L34","v":21453850},{"$f":"'SB1'!M34","v":22440727}]
["Cost of Free Basic Services provided - Informal Formal Settlements (R'000)",null,{"$f":"'SB5'!E259+'SB5'!E271+'SB5'!E283+'SB5'!E295","v":30500000},{"$f":"'SB5'!F259+'SB5'!F271+'SB5'!F283+'SB5'!F295","v":0},{"$f":"'SB5'!G259+'SB5'!G271+'SB5'!G283+'SB5'!G295","v":0},{"$f":"'SB5'!H259+'SB5'!H271+'SB5'!H283+'SB5'!H295","v":0},{"$f":"'SB5'!I259+'SB5'!I271+'SB5'!I283+'SB5'!I295","v":0},{"$f":"'SB5'!J259+'SB5'!J271+'SB5'!J283+'SB5'!J295","v":0},{"$f":"'SB5'!K259+'SB5'!K271+'SB5'!K283+'SB5'!K295","v":0},{"$f":"SUM(E61:I61)","v":0},{"$f":"IF(D61=0,C61+J61,D61+J61)","v":30500000},{"$f":"'SB5'!N259+'SB5'!N271+'SB5'!N283+'SB5'!N295","v":30500000},{"$f":"'SB5'!O259+'SB5'!O271+'SB5'!O283+'SB5'!O295","v":0}]
["Total cost of FBS provided  ",null,{"$f":"SUM(C57:C61)","v":66033000},{"$f":"SUM(D57:D61)","v":35533000},0,0,0,0,0,0,66033000,67010735,38015217]
[]
["Highest level of free service provided"]
["Property rates (R'000 value threshold)",null,null,null,null,null,null,null,null,{"$f":"SUM(E65:I65)","v":0},{"$f":"IF(D65=0,C65+J65,D65+J65)","v":0}]
["Water (kilolitres per household per month)",null,null,null,null,null,null,null,null,0,0]
["Sanitation (kilolitres per household per month)",null,null,null,null,null,null,null,null,0,0]
["Sanitation (Rand per household per month)",null,null,null,null,null,null,null,null,0,0]
["Electricity (kw per household per month)",null,null,null,null,null,null,null,null,0,0]
["Refuse (average litres per week)",null,null,null,null,null,null,null,null,0,0]
["Revenue cost of free services provided (R'000)",17]
["Property rates (tariff adjustment) ( impermissable values per section 17 of MPRA)",null,1593000,0,0,0,0,0,0,{"$f":"SUM(E72:I72)","v":0},{"$f":"IF(D72=0,C72+J72,D72+J72)","v":1593000},1593000,1593000]
["Property rates  exemptions, reductions and rebates and impermissable values in excess of section 17 of MPRA)",null,{"$f":"'SB1'!C9","v":2668000},{"$f":"'SB1'!D9","v":2668000},{"$f":"'SB1'!E9","v":0},{"$f":"'SB1'!F9","v":0},{"$f":"'SB1'!G9","v":0},{"$f":"'SB1'!H9","v":0},{"$f":"'SB1'!I9","v":0},0,2668000,{"$f":"'SB1'!L9","v":2746947},{"$f":"'SB1'!M9","v":2856879}]
["Water (in excess of 6 kilolitres per indigent household per month)",null,{"$f":"'SB1'!C20","v":0},{"$f":"'SB1'!D20","v":0},{"$f":"'SB1'!E20","v":0},{"$f":"'SB1'!F20","v":0},{"$f":"'SB1'!G20","v":0},{"$f":"'SB1'!H20","v":0},{"$f":"'SB1'!I20","v":0},0,0,{"$f":"'SB1'!L20","v":0},{"$f":"'SB1'!M20","v":0}]
["Sanitation (in excess of free sanitation service to indigent households)",null,{"$f":"'SB1'!C26","v":0},{"$f":"'SB1'!D26","v":0},{"$f":"'SB1'!E26","v":0},{"$f":"'SB1'!F26","v":0},{"$f":"'SB1'!G26","v":0},{"$f":"'SB1'!H26","v":0},{"$f":"'SB1'!I26","v":0},0,0,{"$f":"'SB1'!L26","v":0},{"$f":"'SB1'!M26","v":0}]
["Electricity/other energy (in excess of 50 kwh per indigent household per month)",null,{"$f":"'SB1'!C14","v":0},{"$f":"'SB1'!D14","v":0},{"$f":"'SB1'!E14","v":0},{"$f":"'SB1'!F14","v":0},{"$f":"'SB1'!G14","v":0},{"$f":"'SB1'!H14","v":0},{"$f":"'SB1'!I14","v":0},0,0,{"$f":"'SB1'!L14","v":0},{"$f":"'SB1'!M14","v":0}]
["Refuse (in excess of one removal a week for indigent households)",null,{"$f":"'SB1'!C33","v":0},{"$f":"'SB1'!D33","v":0},{"$f":"'SB1'!E33","v":0},{"$f":"'SB1'!F33","v":0},{"$f":"'SB1'!G33","v":0},{"$f":"'SB1'!H33","v":0},{"$f":"'SB1'!I33","v":0},0,0,{"$f":"'SB1'!L33","v":0},{"$f":"'SB1'!M33","v":0}]
["Municipal Housing - rental rebates",null,null,null,null,null,null,null,null,0,0]
["Housing - top structure subsidies",6,null,null,null,null,null,null,null,0,0]
["Other",null,null,null,null,null,null,null,null,0,0]
["Total revenue cost of subsidised services provided ",null,{"$f":"SUM(C72:C80)","v":4261000},2668000,0,0,0,0,0,0,4261000,4339947,4449879]
[{"$f":"head27a","v":"References"}]
["1. Include services provided by another entity; e.g. Eskom"]
["2. Stand distance > 200m from dwelling"]
["3. Stand distance <= 200m from dwelling"]
["4. Borehole, spring, rain-water tank etc."]
["5. Must agree to total number of households in municipal area"]
["6. Include value of subsidy provided by municipality above provincial subsidy level"]
["7. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["8. Additional cash-backed accumulated funds/unspent funds (MFMA section 18(1)(b) and section 28(2)(e)) identified after the Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably have been foreseen)"]
["9. Increases of funds approved under MFMA section 31"]
["10. Adjustments approved in accordance with MFMA section 29 "]
["11. Adjustments to transfers from National or Provincial Government"]
["12. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (section 28(2)(f))"]
["13. G = B + C + D + E + F"]
["14. Adjusted Budget H = (A or A1/2 etc) + G"]
["15. Show number of households receiving at least these levels of services completely free"]
["16. Must reflect the cost to the municipality of providing the Free Basic Service"]
["17. Reflect the cost to the municipality in terms of 'revenue foregone' of providing free services (note this will not equal 'Revenue Foregone' on SA1)"]

{"sheet":"SB1","index":19,"n_rows":181,"n_cols":13,"rows_kept":181,"cut":false,"hidden":false,"merged":[[176,0,176,12],[172,0,172,12],[1,0,3,0],[1,1,3,1],[1,2,1,10]]}
[{"$f":"muni&\" - \"&ADJB1&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB1 Supporting detail to 'Budgeted Financial Performance' - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,6,7,8,9,10,11,12,13]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["REVENUE ITEMS"]
["Property rates"]
["Total Property Rates",null,144831600,144831600,0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":144831600},171773093,179674656]
["less Revenue Foregone (exemptions, reductions and rebates and impermissable values in excess of section 17 of MPRA)",null,2668000,2668000,0,0,0,0,0,{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":2668000},2746947,2856879]
["Net Property Rates",null,{"$f":"C8-C9","v":142163600},{"$f":"D8-D9","v":142163600},0,0,0,0,0,0,142163600,169026146,176817777]
[]
["Service charges - electricity revenue"]
["Total Service charges - electricity revenue",null,4000000,4000000,0,0,0,0,0,{"$f":"SUM(E13:I13)","v":0},{"$f":"IF(D13=0,C13+J13,D13+J13)","v":4000000},4000000,4000000]
["less Revenue Foregone (in excess of 50 kwh per indigent household per month)",null,null,null,null,null,null,null,null,{"$f":"SUM(E14:I14)","v":0},{"$f":"IF(D14=0,C14+J14,D14+J14)","v":0}]
["less Cost of Free Basis Services (50 kwh per indigent household per month)",null,{"$f":"'SB5'!E249","v":4000000},{"$f":"'SB5'!F249","v":4000000},{"$f":"'SB5'!G249","v":0},{"$f":"'SB5'!H249","v":0},{"$f":"'SB5'!I249","v":0},{"$f":"'SB5'!J249","v":0},{"$f":"'SB5'!K249","v":0},{"$f":"SUM(E15:I15)","v":0},{"$f":"IF(D15=0,C15+J15,D15+J15)","v":4000000},{"$f":"'SB5'!N249","v":4000000},{"$f":"'SB5'!O249","v":4000000}]
["Net Service charges - electricity revenue",null,{"$f":"C13-C14-C15","v":0},{"$f":"D13-D14-D15","v":0},0,0,0,0,0,0,0,0,0]
[]
["Service charges - water revenue"]
["Total Service charges - water revenue",null,182210000,182210000,0,0,0,0,0,{"$f":"SUM(E19:I19)","v":0},{"$f":"IF(D19=0,C19+J19,D19+J19)","v":182210000},182210000,182210000]
["less Revenue Foregone (in excess of 6 kilolitres per indigent household per month)",null,null,null,null,null,null,null,null,{"$f":"SUM(E20:I20)","v":0},{"$f":"IF(D20=0,C20+J20,D20+J20)","v":0}]
["less Cost of Free Basis Services (6 kilolitres per indigent household per month)",null,{"$f":"'SB5'!E261","v":10653000},{"$f":"'SB5'!F261","v":10653000},{"$f":"'SB5'!G261","v":0},{"$f":"'SB5'!H261","v":0},{"$f":"'SB5'!I261","v":0},{"$f":"'SB5'!J261","v":0},{"$f":"'SB5'!K261","v":0},{"$f":"SUM(E21:I21)","v":0},{"$f":"IF(D21=0,C21+J21,D21+J21)","v":10653000},{"$f":"'SB5'!N261","v":10682385},{"$f":"'SB5'!O261","v":11173775}]
["Net Service charges - water revenue",null,{"$f":"C19-C20-C21","v":171557000},{"$f":"D19-D20-D21","v":171557000},0,0,0,0,0,{"$f":"J19-J20-J21","v":0},171557000,171527615,171036225]
[]
["Service charges - sanitation revenue"]
["Total Service charges - sanitation revenue",null,3100000,3100000,0,0,0,0,0,{"$f":"SUM(E25:I25)","v":0},{"$f":"IF(D25=0,C25+J25,D25+J25)","v":3100000},2864898,2996684]
["less Revenue Foregone (in excess of free sanitation service to indigent households)",null,null,null,null,null,null,null,null,{"$f":"SUM(E26:I26)","v":0},{"$f":"IF(D26=0,C26+J26,D26+J26)","v":0}]
["less Cost of Free Basis Services (free sanitation service to indigent households)",null,{"$f":"'SB5'!E273","v":350000},{"$f":"'SB5'!F273","v":350000},{"$f":"'SB5'!G273","v":0},{"$f":"'SB5'!H273","v":0},{"$f":"'SB5'!I273","v":0},{"$f":"'SB5'!J273","v":0},{"$f":"'SB5'!K273","v":0},{"$f":"SUM(E27:I27)","v":0},{"$f":"IF(D27=0,C27+J27,D27+J27)","v":350000},{"$f":"'SB5'!N273","v":374500},{"$f":"'SB5'!O273","v":400715}]
["Net Service charges - sanitation revenue",null,{"$f":"C25-C26-C27","v":2750000},{"$f":"D25-D26-D27","v":2750000},0,0,0,0,0,0,2750000,2490398,2595969]
[null,null,"."]
["Service charges - refuse revenue"]
["Total refuse removal revenue",null,30474428,30474428,0,0,0,0,0,{"$f":"SUM(E31:I31)","v":0},{"$f":"IF(D31=0,C31+J31,D31+J31)","v":30474428},33928557,35489270]
["Total landfill revenue",null,null,null,null,null,null,null,null,{"$f":"SUM(E32:I32)","v":0},{"$f":"IF(D32=0,C32+J32,D32+J32)","v":0}]
["less Revenue Foregone (in excess of one removal a week to indigent households)",null,null,null,null,null,null,null,null,{"$f":"SUM(E33:I33)","v":0},{"$f":"IF(D33=0,C33+J33,D33+J33)","v":0}]
["less Cost of Free Basis Services  (removed once a week to indigent households)",null,{"$f":"'SB5'!E285","v":20530000},{"$f":"'SB5'!F285","v":20530000},{"$f":"'SB5'!G285","v":0},{"$f":"'SB5'!H285","v":0},{"$f":"'SB5'!I285","v":0},{"$f":"'SB5'!J285","v":0},{"$f":"'SB5'!K285","v":0},{"$f":"SUM(E34:I34)","v":0},{"$f":"IF(D34=0,C34+J34,D34+J34)","v":20530000},{"$f":"'SB5'!N285","v":21453850},{"$f":"'SB5'!O285","v":22440727}]
["Net Service charges - refuse revenue",null,{"$f":"SUM(C31:C32)-SUM(C33:C34)","v":9944428},{"$f":"SUM(D31:D32)-SUM(D33:D34)","v":9944428},0,0,0,0,0,0,9944428,12474707,13048543]
[]
["Other Revenue By Source"]
["Fuel Levy",null,null,null,null,null,null,null,null,{"$f":"SUM(E38:I38)","v":0},{"$f":"IF(D38=0,C38+J38,D38+J38)","v":0}]
["Other Revenue",null,2530500,3430500,0,0,0,0,290000,{"$f":"SUM(E39:I39)","v":290000},{"$f":"IF(D39=0,C39+J39,D39+J39)","v":3720500},2030500,2080500]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Total 'Other' Revenue",1,{"$f":"SUM(C38:C39)","v":2530500},{"$f":"SUM(D38:D39)","v":3430500},0,0,0,0,290000,290000,3720500,2030500,2080500]
[]
["EXPENDITURE ITEMS"]
["Employee related costs"]
["Basic Salaries and Wages",null,199962898,180149934.06999999,0,0,0,0,-2300000,{"$f":"SUM(E54:I54)","v":-2300000},{"$f":"IF(D54=0,C54+J54,D54+J54)","v":177849934.06999999},197604328,208745595]
["Pension and UIF Contributions",null,35891909,33872074.079999998,0,0,0,0,0,0,33872074.079999998,37438314,39310235]
["Medical Aid Contributions",null,11863754,11992043.039999999,0,0,0,0,0,0,11992043.039999999,26476382,27800198]
["Overtime",null,5346000,6623759.0199999996,0,0,0,0,0,0,6623759.0199999996,0,0]
["Performance Bonus",null,11132112,10771228.039999999,0,0,0,0,0,0,10771228.039999999,13531993,14208592]
["Motor Vehicle Allowance",null,1345593,1105593.02,0,0,0,0,0,{"$f":"SUM(E59:I59)","v":0},{"$f":"IF(D59=0,C59+J59,D59+J59)","v":1105593.02},2358593,2476523]
["Cellphone Allowance",null,0,0,0,0,0,0,0,{"$f":"SUM(E60:I60)","v":0},{"$f":"IF(D60=0,C60+J60,D60+J60)","v":0},0,0]
["Housing Allowances",null,655601,512517.05,0,0,0,0,0,{"$f":"SUM(E61:I61)","v":0},{"$f":"IF(D61=0,C61+J61,D61+J61)","v":512517.05},518739,544679]
["Other benefits and allowances",null,4076793,3825211.06,0,0,0,0,0,0,3825211.06,403058,423210]
["Payments in lieu of leave",null,0,0,0,0,0,0,0,0,0,0,0]
["Long service awards",null,0,0,0,0,0,0,0,0,0,0,0]
["Post-retirement benefit obligations",4,0,0,0,0,0,0,0,0,0,0,0]
["sub-total",null,{"$f":"SUM(C54:C65)","v":270274660},{"$f":"SUM(D54:D65)","v":248852359.38},0,0,0,0,-2300000,-2300000,246552359.38,278331407,293509032]
["Less: Employees costs capitalised to PPE",null,0,0,0,0,0,0,0,{"$f":"SUM(E67:I67)","v":0},{"$f":"IF(D67=0,C67+J67,D67+J67)","v":0},0,0]
[{"$f":"\"Total \"&A53","v":"Total Employee related costs"},1,{"$f":"C66-C67","v":270274660},{"$f":"D66-D67","v":248852359.38},0,0,0,0,-2300000,{"$f":"SUM(J66:J67)","v":-2300000},{"$f":"SUM(K66:K67)","v":246552359.38},{"$f":"L66-L67","v":278331407},{"$f":"M66-M67","v":293509032}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Depreciation & asset impairment"]
["Depreciation of Property, Plant & Equipment",null,154536733,154536733,0,0,0,0,0,{"$f":"SUM(E80:I80)","v":0},{"$f":"IF(D80=0,C80+J80,D80+J80)","v":154536733},133503316,139644469]
["Lease amortisation",null,0,0,0,0,0,0,0,{"$f":"SUM(E81:I81)","v":0},{"$f":"IF(D81=0,C81+J81,D81+J81)","v":0},0,0]
["Capital asset impairment",null,null,null,null,null,null,null,null,{"$f":"SUM(E82:I82)","v":0},{"$f":"IF(D82=0,C82+J82,D82+J82)","v":0}]
[]
[{"$f":"\"Total \"&LEFT(A79,35)","v":"Total Depreciation & asset impairment"},1,{"$f":"SUM(C80:C82)","v":154536733},{"$f":"SUM(D80:D82)","v":154536733},0,0,0,0,0,0,154536733,133503316,139644469]
[]
["Bulk purchases"]
["Electricity Bulk Purchases",null,12700000,18145038,0,0,0,0,0,{"$f":"SUM(E87:I87)","v":0},{"$f":"IF(D87=0,C87+J87,D87+J87)","v":18145038},11000000,11506000]
["Water Bulk Purchases",null,91000000,71000000,0,0,0,0,0,{"$f":"SUM(E88:I88)","v":0},{"$f":"IF(D88=0,C88+J88,D88+J88)","v":71000000},100000000,104600000]
["Total bulk purchases",1,{"$f":"SUM(C87:C88)","v":103700000},89145038,0,0,0,0,0,0,89145038,111000000,116106000]
[]
["Transfers and grants"]
["Cash transfers and grants",null,0,0,0,0,0,0,0,{"$f":"SUM(E92:I92)","v":0},{"$f":"IF(D92=0,C92+J92,D92+J92)","v":0},0,0]
["Non-cash transfers and grants",null,null,null,null,null,null,null,null,{"$f":"SUM(E93:I93)","v":0},{"$f":"IF(D93=0,C93+J93,D93+J93)","v":0}]
["Total transfers and grants",null,{"$f":"SUM(C92:C93)","v":0},0,0,0,0,0,0,{"$f":"SUM(J92:J93)","v":0},{"$f":"SUM(K92:K93)","v":0},{"$f":"SUM(L92:L93)","v":0},{"$f":"SUM(M92:M93)","v":0}]
[]
["Contracted services"]
["Outsourced Services",null,64951500,46338475.020000003,0,0,0,0,0,{"$f":"SUM(E97:I97)","v":0},{"$f":"IF(D97=0,C97+J97,D97+J97)","v":46338475.020000003},43969200,48333934]
["Consultants and Professional Services",null,72140000,51936917.079999998,0,0,0,0,0,{"$f":"SUM(E98:I98)","v":0},{"$f":"IF(D98=0,C98+J98,D98+J98)","v":51936917.079999998},65633000,70369000]
["Contractors",null,14745000,12766627.02,0,0,0,0,0,{"$f":"SUM(E99:I99)","v":0},{"$f":"IF(D99=0,C99+J99,D99+J99)","v":12766627.02},11587000,12585800]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Total contracted services",null,{"$f":"SUM(C97:C99)","v":151836500},{"$f":"SUM(D97:D99)","v":111042019.11999999},0,0,0,0,0,0,111042019.11999999,121189200,131288734]
[]
["Other Expenditure By Type"]
["Collection costs",null,null,null,null,null,null,null,null,{"$f":"SUM(E131:I131)","v":0},{"$f":"IF(D131=0,C131+J131,D131+J131)","v":0}]
["Contributions to 'other' provisions",null,null,null,null,null,null,null,null,{"$f":"SUM(E132:I132)","v":0},{"$f":"IF(D132=0,C132+J132,D132+J132)","v":0}]
[]
["Audit fees",null,null,null,null,null,null,null,null,{"$f":"SUM(E134:I134)","v":0},{"$f":"IF(D134=0,C134+J134,D134+J134)","v":0}]
[]
[]
["Other Expenditure",null,129714800,89643355.349999994,0,0,0,0,-179487,{"$f":"SUM(E137:I137)","v":-179487},{"$f":"IF(D137=0,C137+J137,D137+J137)","v":89463868.349999994},66888300,70314784]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Total Other Expenditure",1,{"$f":"+C131+C132+C134+C137","v":129714800},{"$f":"+D131+D132+D134+D137","v":89643355.349999994},0,0,0,0,-179487,-179487,89463868.349999994,66888300,70314784]
[]
["Repairs and Maintenance \nby Expenditure Item",14]
["Employee related costs",null,null,null,null,null,null,null,null,{"$f":"SUM(E161:I161)","v":0},{"$f":"IF(D161=0,C161+J161,D161+J161)","v":0}]
["Other materials",null,500000,150000,0,0,0,0,0,{"$f":"SUM(E162:I162)","v":0},{"$f":"IF(D162=0,C162+J162,D162+J162)","v":150000},260000,270000]
["Contracted Services",null,61160000,44788475.009999998,0,0,0,0,0,{"$f":"SUM(E163:I163)","v":0},{"$f":"IF(D163=0,C163+J163,D163+J163)","v":44788475.009999998},41970000,46043800]
["Other Expenditure",null,3480000,2100000.0099999998,0,0,0,0,0,{"$f":"SUM(E164:I164)","v":0},{"$f":"IF(D164=0,C164+J164,D164+J164)","v":2100000.0099999998},250000,275000]
["Total Repairs and Maintenance Expenditure",15,{"$f":"SUM(C161:C164)","v":65140000},{"$f":"SUM(D161:D164)","v":47038475.019999996},0,0,0,0,0,0,47038475.019999996,42480000,46588800]
[{"$f":"head27a","v":"References"}]
["1. Must reconcile with relevant line on the 'Financial Performance' budget"]
["2. Must reconcile to supporting documentation on staff salaries"]
["3. Insert other categories where revenue or expenditure is of a material nature"]
["4. Expenditure to meet any unfunded obligations"]
["5. Special consideration may have to be given to including 'goodwill arising' or 'joint venture' budgets where circumstances require this (include separately under relevant notes)"]
["6. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["7. Additional cash-backed accumulated funds/unspent funds (section 18(1)(b) and section 28(2)(e) MFMA) identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have for"]
["8. Increases of funds approved under section 31 MFMA"]
["9. Adjustments approved in accordance with section 29 MFMA"]
["10. Adjustments to funding allocations from National or Provincial Government"]
["11. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sec"]
["12. G = B + C + D + E + F"]
["13. Adjusted Budget H = (A or A1/2 etc) + G"]
["14. Repairs and Maintenance is not a GRAP item. However to facilitate transparency, municipalities must provide a breakdown of the amounts included in the relevant GRAP items that will be spent on Repairs and Maintenance."]
["15. Must reconcile with Repairs and Maintenance by Asset Class (Total Repairs and Maintenance) on Table SA34c."]

{"sheet":"SB2","index":20,"n_rows":83,"n_cols":13,"rows_kept":83,"cut":false,"hidden":false,"merged":[[79,0,79,12],[75,0,75,12],[1,1,3,1],[1,0,3,0],[1,2,1,10]]}
[{"$f":"muni&\" - \"&ADJB2&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB2 Supporting detail to 'Financial Position Budget' - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,4,5,6,7,8,9,10,11]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["ASSETS"]
[]
[]
[]
[]
["Consumer debtors"]
[{"$f":"A11","v":"Consumer debtors"},null,475621000,475621000,0,0,0,0,0,{"$f":"SUM(E12:I12)","v":0},{"$f":"IF(D12=0,C12+J12,D12+J12)","v":475621000},675396619,595697919]
["Less: provision for debt impairment",null,{"$f":"C19","v":0},0,0,0,0,0,0,{"$f":"SUM(E13:I13)","v":0},{"$f":"IF(D13=0,C13+J13,D13+J13)","v":0},{"$f":"L19","v":-248011958},{"$f":"M19","v":132122123}]
[{"$f":"\"Total \"&A11","v":"Total Consumer debtors"},1,{"$f":"C12+C13","v":475621000},475621000,0,0,0,0,0,0,475621000,427384661,727820042]
["Debt impairment provision"]
["Balance at the beginning of the year",null,0,0,0,0,0,0,0,{"$f":"SUM(E16:I16)","v":0},{"$f":"IF(D16=0,C16+J16,D16+J16)","v":0},-248011958,132122123]
["Contributions to the provision",null,0,0,0,0,0,0,0,{"$f":"SUM(E17:I17)","v":0},{"$f":"IF(D17=0,C17+J17,D17+J17)","v":0},0,0]
["Bad debts written off",null,0,0,0,0,0,0,0,{"$f":"SUM(E18:I18)","v":0},{"$f":"IF(D18=0,C18+J18,D18+J18)","v":0},0,0]
["Balance at end of year",null,{"$f":"SUM(C16:C18)","v":0},0,0,0,0,0,0,{"$f":"J13","v":0},{"$f":"K13","v":0},{"$f":"SUM(L16:L18)","v":-248011958},{"$f":"SUM(M16:M18)","v":132122123}]
["Property, plant & equipment"]
["PPE at cost/valuation (excl. finance leases)",null,1785177147,1786730362.1800001,0,0,0,0,113975,{"$f":"SUM(E21:I21)","v":113975},{"$f":"IF(D21=0,C21+J21,D21+J21)","v":1786844337.1800001},3530746542,3928329513]
["Leases recognised as PPE",2,null,null,null,null,null,null,null,{"$f":"SUM(E22:I22)","v":0},{"$f":"IF(D22=0,C22+J22,D22+J22)","v":0}]
["Less: Accumulated depreciation",null,0,0,0,0,0,0,0,{"$f":"SUM(E23:I23)","v":0},{"$f":"IF(D23=0,C23+J23,D23+J23)","v":0},0,0]
[{"$f":"\"Total \"&A20","v":"Total Property, plant & equipment"},1,{"$f":"SUM(C21:C22)-C23","v":1785177147},{"$f":"SUM(D21:D22)-D23","v":1786730362.1800001},0,0,0,0,113975,113975,1786844337.1800001,{"$f":"SUM(L21:L22)-L23","v":3530746542},{"$f":"SUM(M21:M22)-M23","v":3928329513}]
[]
["LIABILITIES"]
["Current liabilities - Borrowing"]
["Short term loans (other than bank overdraft)",null,0,0,0,0,0,0,0,{"$f":"SUM(E28:I28)","v":0},{"$f":"IF(D28=0,C28+J28,D28+J28)","v":0},0,0]
["Current portion of long-term liabilities",null,132503000,132503000,0,0,0,0,0,{"$f":"SUM(E29:I29)","v":0},{"$f":"IF(D29=0,C29+J29,D29+J29)","v":132503000},41362000,43264652]
[{"$f":"\"Total \"&A27","v":"Total Current liabilities - Borrowing"},null,{"$f":"SUM(C28:C29)","v":132503000},132503000,0,0,0,0,0,0,132503000,41362000,43264652]
["Trade and other payables"]
["Trade Payables",null,40000000,40000000,0,0,0,0,0,{"$f":"SUM(E32:I32)","v":0},{"$f":"IF(D32=0,C32+J32,D32+J32)","v":40000000},45000000,45000000]
[" Other creditors",null,0,0,0,0,0,0,0,{"$f":"SUM(E33:I33)","v":0},{"$f":"IF(D33=0,C33+J33,D33+J33)","v":0},0,0]
["Unspent conditional transfers",null,0,0,0,0,0,0,0,{"$f":"SUM(E34:I34)","v":0},{"$f":"IF(D34=0,C34+J34,D34+J34)","v":0},0,0]
["VAT",null,0,0,0,0,0,0,0,{"$f":"SUM(E35:I35)","v":0},{"$f":"IF(D35=0,C35+J35,D35+J35)","v":0},0,0]
[{"$f":"\"Total \"&A31","v":"Total Trade and other payables"},1,{"$f":"SUM(C32:C35)","v":40000000},40000000,0,0,0,0,0,0,40000000,45000000,45000000]
["Non current liabilities - Borrowing"]
["Borrowing",3,0,0,0,0,0,0,0,{"$f":"SUM(E38:I38)","v":0},{"$f":"IF(D38=0,C38+J38,D38+J38)","v":0},0,0]
["Finance leases (including PPP asset element)",null,0,0,0,0,0,0,0,{"$f":"SUM(E39:I39)","v":0},{"$f":"IF(D39=0,C39+J39,D39+J39)","v":0},0,0]
[{"$f":"\"Total \"&A37","v":"Total Non current liabilities - Borrowing"},null,{"$f":"SUM(C38:C39)","v":0},0,0,0,0,0,0,0,0,0,0]
["Provisions - non current"]
["Retirement benefits",null,null,null,null,null,null,null,null,{"$f":"SUM(E42:I42)","v":0},{"$f":"IF(D42=0,C42+J42,D42+J42)","v":0}]
[]
["Refuse landfill site rehabilitation",null,24600000,24600000,0,0,0,0,0,{"$f":"SUM(E44:I44)","v":0},{"$f":"IF(D44=0,C44+J44,D44+J44)","v":24600000},29829314,31171633]
["Other",null,0,0,0,0,0,0,0,{"$f":"SUM(E45:I45)","v":0},{"$f":"IF(D45=0,C45+J45,D45+J45)","v":0},0,0]
[{"$f":"\"Total \"&A41","v":"Total Provisions - non current"},null,{"$f":"+C42+C44+C45","v":24600000},{"$f":"+D42+D44+D45","v":24600000},0,0,0,0,0,0,24600000,29829314,31171633]
[]
["CHANGES IN NET ASSETS"]
["Accumulated surplus/(Deficit)"]
[{"$f":"A49&\" - opening balance\"","v":"Accumulated surplus/(Deficit) - opening balance"},null,2091571941,2091571941,0,0,0,0,0,{"$f":"SUM(E50:I50)","v":0},{"$f":"IF(D50=0,C50+J50,D50+J50)","v":2091571941},1609020655,1632058260]
["GRAP adjustments",null,0,0,0,0,0,0,0,{"$f":"SUM(E51:I51)","v":0},{"$f":"IF(D51=0,C51+J51,D51+J51)","v":0},0,0]
["Restated balance",null,{"$f":"+C50+C51","v":2091571941},{"$f":"+D50+D51","v":2091571941},0,0,0,0,0,0,2091571941,1609020655,1632058260]
["Surplus/(Deficit)",null,{"$f":"'B4-FinPerf RE'!C47","v":68850206},{"$f":"'B4-FinPerf RE'!D47","v":74423570.11999999},{"$f":"'B4-FinPerf RE'!E47","v":0},{"$f":"'B4-FinPerf RE'!F47","v":0},{"$f":"'B4-FinPerf RE'!G47","v":0},{"$f":"'B4-FinPerf RE'!H47","v":0},{"$f":"'B4-FinPerf RE'!I47","v":290000},{"$f":"'B4-FinPerf RE'!J47","v":290000},{"$f":"'B4-FinPerf RE'!K47","v":74713570.11999999},{"$f":"'B4-FinPerf RE'!L47","v":160194654},{"$f":"'B4-FinPerf RE'!M47","v":178403878}]
["Transfers to/from Reserves",null,0,24926816,0,0,0,0,0,{"$f":"SUM(E54:I54)","v":0},{"$f":"IF(D54=0,C54+J54,D54+J54)","v":24926816},2269661200,2793159259]
["Depreciation offsets",null,0,0,0,0,0,0,0,{"$f":"SUM(E55:I55)","v":0},{"$f":"IF(D55=0,C55+J55,D55+J55)","v":0},0,0]
["Other adjustments",null,0,0,0,0,0,0,0,{"$f":"SUM(E56:I56)","v":0},{"$f":"IF(D56=0,C56+J56,D56+J56)","v":0},0,0]
["Accumulated Surplus/(Deficit)",1,{"$f":"SUM(C52:C56)","v":2160422147},{"$f":"SUM(D52:D56)","v":2190922327.1199999},0,0,0,0,290000,290000,2191212327.1199999,4038876509,4603621397]
["Reserves"]
["Housing Development Fund",null,null,null,null,null,null,null,null,{"$f":"SUM(E59:I59)","v":0},{"$f":"IF(D59=0,C59+J59,D59+J59)","v":0}]
["Capital replacement",null,null,null,null,null,null,null,null,{"$f":"SUM(E60:I60)","v":0},{"$f":"IF(D60=0,C60+J60,D60+J60)","v":0}]
["Self-insurance",null,null,null,null,null,null,null,null,{"$f":"SUM(E61:I61)","v":0},{"$f":"IF(D61=0,C61+J61,D61+J61)","v":0}]
["Other reserves",null,null,null,null,null,null,null,null,{"$f":"SUM(E62:I62)","v":0},{"$f":"IF(D62=0,C62+J62,D62+J62)","v":0}]
["Revaluation",null,null,null,null,null,null,null,null,{"$f":"SUM(E63:I63)","v":0},{"$f":"IF(D63=0,C63+J63,D63+J63)","v":0}]
["Total Reserves",2,{"$f":"SUM(C59:C63)","v":0},0,0,0,0,0,0,0,0,0,0]
["TOTAL COMMUNITY WEALTH/EQUITY",2,{"$f":"C57+C64","v":2160422147},2190922327.1199999,0,0,0,0,290000,290000,2191212327.1199999,4038876509,4603621397]
[]
[]
[]
[]
[]
[{"$f":"head27a","v":"References"}]
["1. Must reconcile with 'Financial Position' budget"]
["2. Leases treated as assets to be depreciated as the same as purchased/constructed assets.  Includes PPP asset element accounted for as finance leases"]
["3. Borrowing (original budget) must reconcile to Budget Table A16"]
["4. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["5. Additional cash-backed accumulated funds/unspent funds (section 18(1)(b) and section 28(2)(e) MFMA) identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have for"]
["6. Increases of funds approved under section 31 MFMA"]
["7. Adjustments approved in accordance with section 29 MFMA"]
["8. Adjustments to funding allocations from National or Provincial Government"]
["9. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sect"]
["10. G = B + C + D + E + F"]
["11. Adjusted Budget H = (A or A1/2 etc) + G"]
["check",null,{"$f":"C65-'B6-FinPos'!C50","v":0},null,null,null,null,null,null,null,null,null,{"$f":"K65-'B6-FinPos'!K50","v":0}]

{"sheet":"SB3","index":21,"n_rows":28,"n_cols":13,"rows_kept":28,"cut":false,"hidden":false,"merged":[[27,0,27,12],[22,0,22,12],[1,0,3,0],[1,1,3,1],[1,2,1,10],[26,0,26,12]]}
[{"$f":"muni&\" - \"&ADJB3&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB3 Adjustments to the SDBIP - performance objectives - 44171"}]
[{"$f":"desc","v":"Description"},"Unit of measurement",{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,"A","A1","B","C","D","E","F","G","H"]
["07 - Infrastructure & Technical Services"]
["Waste Water Management"]
["Sewerage"]
["Flush Toilet (Connected To Sewerage)","Households",7000,0,0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":7000},7000,0]
["Flush Toilet (With Septic Tank)","Households",5000,0,0,0,0,0,0,{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":5000},5000,0]
["Formal Settlement Households Receiving Sanitation","Households",330,0,0,0,0,0,0,{"$f":"SUM(E10:I10)","v":0},{"$f":"IF(D10=0,C10+J10,D10+J10)","v":330},330,0]
["Informal Settlements (R000)","Rand Value",500000,0,0,0,0,0,0,{"$f":"SUM(E11:I11)","v":0},{"$f":"IF(D11=0,C11+J11,D11+J11)","v":500000},500000,0]
["No Toilet Provisions","Households",39000,0,0,0,0,0,0,{"$f":"SUM(E12:I12)","v":0},{"$f":"IF(D12=0,C12+J12,D12+J12)","v":39000},39000,0]
["Water Management"]
["Water Distribution"]
["Formal Settlement Households Receiving Water","Households",19000,0,0,0,0,0,0,{"$f":"SUM(E15:I15)","v":0},{"$f":"IF(D15=0,C15+J15,D15+J15)","v":19000},19000,0]
["Informal Settlements (R000)","Rand Value",10000000,0,0,0,0,0,0,0,10000000,10000000,0]
["Piped Water Inside Dwelling","Households",5700,0,0,0,0,0,0,0,5700,5700,0]
["Piped Water Inside Yard (But Not In Dwelling)","Households",10000,0,0,0,0,0,0,0,10000,10000,0]
["Using Public Tap (< Min.Service Level)","Households",12000,0,0,0,0,0,0,0,12000,12000,0]
["Using Public Tap (At Least Min.Service Level)","Households",52000,0,0,0,0,0,0,0,52000,52000,0]
[null,null,null,null,null,null,null,null,null,0,0,{"$f":"IF(E21=0,D21+K21,E21+K21)","v":0},{"$f":"IF(F21=0,E21+L21,F21+L21)","v":0}]
[{"$f":"head27a","v":"References"}]
["1. Include a measurable performance objective for each revenue source (within a relevant function) and each vote (MFMA s17(3)(b))"]
["2. Include the estimated effect on the target of each component of an adjustment budget (B to G)"]
["3. Include all Basic Services performance targets from Table A10 to ensure Table SA7 represents all strategic responsibilities"]
["4. Total target adjustments G = B + C + D + E + F"]
["5. Total Adjusted Budget targets H = (A or A1/2 etc) + G"]
["6. NOTE - include adjustsment by 'exception' (only where amended)"]

{"sheet":"SB4","index":22,"n_rows":49,"n_cols":11,"rows_kept":49,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,1,2,1],[1,5,1,7],[28,0,29,0],[25,0,26,0]]}
[{"$f":"muni&\" - \"&ADJB4&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB4 Adjustments to budgeted performance indicators and benchmarks - 44171"}]
[{"$f":"desc&\" of financial indicator\"","v":"Description of financial indicator"},"Basis of calculation",{"$f":"Head1B","v":"2016/17"},{"$f":"Head1A","v":"2017/18"},{"$f":"Head1","v":"2018/19"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head5","v":"Audited Outcome"},{"$f":"Head5","v":"Audited Outcome"},{"$f":"Head5","v":"Audited Outcome"},{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["Borrowing Management"]
[]
["Credit Rating","Short term/long term rating"]
["Capital Charges to Operating Expenditure","Interest & Principal Paid /Operating Expenditure",null,null,null,{"$f":"IF(ISERROR(('B4-FinPerf RE'!C30-'B7-CFlow'!C37)/'B4-FinPerf RE'!C37),0,(('B4-FinPerf RE'!C30-'B7-CFlow'!C37)/'B4-FinPerf RE'!C37))","v":1.2043500188156961E-2},{"$f":"IF(ISERROR(('B4-FinPerf RE'!D30-'B7-CFlow'!D37)/'B4-FinPerf RE'!D37),0,(('B4-FinPerf RE'!D30-'B7-CFlow'!D37)/'B4-FinPerf RE'!D37))","v":4.073554548866363E-3},{"$f":"IF(ISERROR(('B4-FinPerf RE'!K30-'B7-CFlow'!K37)/'B4-FinPerf RE'!K37),0,(('B4-FinPerf RE'!K30-'B7-CFlow'!K37)/'B4-FinPerf RE'!K37))","v":1.2862173937412402E-2},{"$f":"IF(ISERROR(('B4-FinPerf RE'!L30-'B7-CFlow'!L37)/'B4-FinPerf RE'!L37),0,(('B4-FinPerf RE'!L30-'B7-CFlow'!L37)/'B4-FinPerf RE'!L37))","v":1.2220291632206106E-2},{"$f":"IF(ISERROR(('B4-FinPerf RE'!M30-'B7-CFlow'!M37)/'B4-FinPerf RE'!M37),0,(('B4-FinPerf RE'!M30-'B7-CFlow'!M37)/'B4-FinPerf RE'!M37))","v":1.1681473963031905E-2}]
["Capital Charges to Own Revenue","Finance charges & Repayment of borrowing /Own Revenue",null,null,null,{"$f":"IF(ISERROR(('B4-FinPerf RE'!C31-'B7-CFlow'!C38)/'B4-FinPerf RE'!C38),0,(('B4-FinPerf RE'!C31-'B7-CFlow'!C38)/'B4-FinPerf RE'!C38))","v":0},{"$f":"IF(ISERROR(('B4-FinPerf RE'!D31-'B7-CFlow'!D38)/'B4-FinPerf RE'!D38),0,(('B4-FinPerf RE'!D31-'B7-CFlow'!D38)/'B4-FinPerf RE'!D38))","v":0},{"$f":"IF(ISERROR(('B4-FinPerf RE'!K31-'B7-CFlow'!K38)/'B4-FinPerf RE'!K38),0,(('B4-FinPerf RE'!K31-'B7-CFlow'!K38)/'B4-FinPerf RE'!K38))","v":0},{"$f":"IF(ISERROR(('B4-FinPerf RE'!L31-'B7-CFlow'!L38)/'B4-FinPerf RE'!L38),0,(('B4-FinPerf RE'!L31-'B7-CFlow'!L38)/'B4-FinPerf RE'!L38))","v":0},{"$f":"IF(ISERROR(('B4-FinPerf RE'!M31-'B7-CFlow'!M38)/'B4-FinPerf RE'!M38),0,(('B4-FinPerf RE'!M31-'B7-CFlow'!M38)/'B4-FinPerf RE'!M38))","v":0}]
["Borrowed funding of 'own' capital expenditure","Borrowing/Capital expenditure excl. transfers and grants",null,null,null,{"$f":"IF(ISERROR('B5-Capex'!C74/('B5-Capex'!C65-'B5-Capex'!C72)),0,('B5-Capex'!C74/('B5-Capex'!C65-'B5-Capex'!C72)))","v":0},{"$f":"IF(ISERROR('B5-Capex'!D74/('B5-Capex'!D65-'B5-Capex'!D72)),0,('B5-Capex'!D74/('B5-Capex'!D65-'B5-Capex'!D72)))","v":0},{"$f":"IF(ISERROR('B5-Capex'!K74/('B5-Capex'!K65-'B5-Capex'!L72)),0,('B5-Capex'!K74/('B5-Capex'!K65-'B5-Capex'!L72)))","v":0},{"$f":"IF(ISERROR('B5-Capex'!L74/('B5-Capex'!L65-'B5-Capex'!M72)),0,('B5-Capex'!L74/('B5-Capex'!L65-'B5-Capex'!M72)))","v":0},{"$f":"IF(ISERROR('B5-Capex'!M74/('B5-Capex'!M65-'B5-Capex'!N72)),0,('B5-Capex'!M74/('B5-Capex'!M65-'B5-Capex'!N72)))","v":0}]
["Safety of Capital"]
["Gearing","Long Term Borrowing/ Funds & Reserves",null,null,null,{"$f":"IF(ISERROR('B6-FinPos'!C39/'B6-FinPos'!C48),0,('B6-FinPos'!C39/'B6-FinPos'!C48))","v":0},{"$f":"IF(ISERROR('B6-FinPos'!D39/'B6-FinPos'!D48),0,('B6-FinPos'!D39/'B6-FinPos'!D48))","v":0},{"$f":"IF(ISERROR('B6-FinPos'!K39/'B6-FinPos'!K48),0,('B6-FinPos'!K39/'B6-FinPos'!K48))","v":0},{"$f":"IF(ISERROR('B6-FinPos'!L39/'B6-FinPos'!L48),0,('B6-FinPos'!L39/'B6-FinPos'!L48))","v":0},{"$f":"IF(ISERROR('B6-FinPos'!M39/'B6-FinPos'!M48),0,('B6-FinPos'!M39/'B6-FinPos'!M48))","v":0}]
["Liquidity"]
["Current Ratio","Current assets/current liabilities",null,null,null,{"$f":"IF(ISERROR('B6-FinPos'!C14/'B6-FinPos'!C36),0,('B6-FinPos'!C14/'B6-FinPos'!C36))","v":3.3164524674933191},{"$f":"IF(ISERROR('B6-FinPos'!D14/'B6-FinPos'!D36),0,('B6-FinPos'!D14/'B6-FinPos'!D36))","v":3.3164524674933191},{"$f":"IF(ISERROR('B6-FinPos'!K14/'B6-FinPos'!K36),0,('B6-FinPos'!K14/'B6-FinPos'!K36))","v":3.3164524674933191},{"$f":"IF(ISERROR('B6-FinPos'!L14/'B6-FinPos'!L36),0,('B6-FinPos'!L14/'B6-FinPos'!L36))","v":5.4317571848729767},{"$f":"IF(ISERROR('B6-FinPos'!M14/'B6-FinPos'!M36),0,('B6-FinPos'!M14/'B6-FinPos'!M36))","v":8.808496882761176}]
["Current Ratio adjusted for aged debtors","Current assets/current liabilities less debtors > 90 days/current liabilities",null,null,null,{"$f":"IF(ISERROR(('B6-FinPos'!C14-'SB4'!F44)/'B6-FinPos'!C36),0,(('B6-FinPos'!C14-'SB4'!F44)/'B6-FinPos'!C36))","v":3.3164524674933191},{"$f":"IF(ISERROR(('B6-FinPos'!D14-'SB4'!G44)/'B6-FinPos'!D36),0,(('B6-FinPos'!D14-'SB4'!G44)/'B6-FinPos'!D36))","v":3.3164524674933191},{"$f":"IF(ISERROR(('B6-FinPos'!E14-'SB4'!H44)/'B6-FinPos'!E36),0,(('B6-FinPos'!E14-'SB4'!H44)/'B6-FinPos'!E36))","v":0},{"$f":"IF(ISERROR(('B6-FinPos'!F14-'SB4'!I44)/'B6-FinPos'!F36),0,(('B6-FinPos'!F14-'SB4'!I44)/'B6-FinPos'!F36))","v":0},{"$f":"IF(ISERROR(('B6-FinPos'!G14-'SB4'!J44)/'B6-FinPos'!G36),0,(('B6-FinPos'!G14-'SB4'!J44)/'B6-FinPos'!G36))","v":0}]
["Liquidity Ratio","Monetary Assets/Current Liabilities",null,null,null,{"$f":"IF(ISERROR(('B6-FinPos'!C8+'B6-FinPos'!C9)/'B6-FinPos'!C36),0,(('B6-FinPos'!C8+'B6-FinPos'!C9)/'B6-FinPos'!C36))","v":0.14131348440316979},{"$f":"IF(ISERROR(('B6-FinPos'!D8+'B6-FinPos'!D9)/'B6-FinPos'!D36),0,(('B6-FinPos'!D8+'B6-FinPos'!D9)/'B6-FinPos'!D36))","v":0.14131348440316979},{"$f":"IF(ISERROR(('B6-FinPos'!K8+'B6-FinPos'!K9)/'B6-FinPos'!K36),0,(('B6-FinPos'!K8+'B6-FinPos'!K9)/'B6-FinPos'!K36))","v":0.14131348440316979},{"$f":"IF(ISERROR(('B6-FinPos'!L8+'B6-FinPos'!L9)/'B6-FinPos'!L36),0,(('B6-FinPos'!L8+'B6-FinPos'!L9)/'B6-FinPos'!L36))","v":0.21667808758481741},{"$f":"IF(ISERROR(('B6-FinPos'!M8+'B6-FinPos'!M9)/'B6-FinPos'!M36),0,(('B6-FinPos'!M8+'B6-FinPos'!M9)/'B6-FinPos'!M36))","v":0.28155199660221852}]
["Revenue Management"]
["Annual Debtors Collection Rate (Payment Level %)","Last 12 Mths Receipts/ Last 12 Mths Billing"]
["Current Debtors Collection Rate (Cash receipts % of Ratepayer & Other revenue)"]
["Outstanding Debtors to Revenue","Total Outstanding Debtors to Annual Revenue",null,null,null,{"$f":"IF(ISERROR((SUM('B6-FinPos'!C10:C12)+'B6-FinPos'!C17)/'B4-FinPerf RE'!C23),0,((SUM('B6-FinPos'!C10:C12)+'B6-FinPos'!C17)/'B4-FinPerf RE'!C23))","v":0.64994380928614293},{"$f":"IF(ISERROR((SUM('B6-FinPos'!D10:D12)+'B6-FinPos'!D17)/'B4-FinPerf RE'!D23),0,((SUM('B6-FinPos'!D10:D12)+'B6-FinPos'!D17)/'B4-FinPerf RE'!D23))","v":0.70256774341173323},{"$f":"IF(ISERROR((SUM('B6-FinPos'!K10:K12)+'B6-FinPos'!K17)/'B4-FinPerf RE'!K23),0,((SUM('B6-FinPos'!K10:K12)+'B6-FinPos'!K17)/'B4-FinPerf RE'!K23))","v":0.70222428927898939},{"$f":"IF(ISERROR((SUM('B6-FinPos'!L10:L12)+'B6-FinPos'!L17)/'B4-FinPerf RE'!L23),0,((SUM('B6-FinPos'!L10:L12)+'B6-FinPos'!L17)/'B4-FinPerf RE'!L23))","v":0.49696756717349133},{"$f":"IF(ISERROR((SUM('B6-FinPos'!M10:M12)+'B6-FinPos'!M17)/'B4-FinPerf RE'!M23),0,((SUM('B6-FinPos'!M10:M12)+'B6-FinPos'!M17)/'B4-FinPerf RE'!M23))","v":0.79546747902379666}]
["Longstanding Debtors Recovered","Debtors > 12 Mths Recovered/Total Debtors > 12 Months Old",null,null,null,{"$f":"IF(ISERROR(F45/'B6-FinPos'!C17),0,(F45/'B6-FinPos'!C17))","v":0},{"$f":"IF(ISERROR(G45/'B6-FinPos'!D17),0,(G45/'B6-FinPos'!D17))","v":0},{"$f":"IF(ISERROR(H45/'B6-FinPos'!K17),0,(H45/'B6-FinPos'!K17))","v":0},{"$f":"IF(ISERROR(I45/'B6-FinPos'!L17),0,(I45/'B6-FinPos'!L17))","v":0},{"$f":"IF(ISERROR(J45/'B6-FinPos'!M17),0,(J45/'B6-FinPos'!M17))","v":0}]
["Creditors Management"]
["Creditors System Efficiency","% of Creditors Paid Within Terms (within MFMA s 65(e))"]
["Creditors to Cash and Investments",null,null,null,null,{"$f":"IF(ISERROR('SB2'!C36/'B7-CFlow'!C42), 0, ('SB2'!C36/'B7-CFlow'!C42))","v":8.7940306120205605E-2},{"$f":"IF(ISERROR('SB2'!D36/'B7-CFlow'!D42), 0, ('SB2'!D36/'B7-CFlow'!D42))","v":0.57398652598199518},{"$f":"IF(ISERROR('SB2'!K36/'B7-CFlow'!K42), 0, ('SB2'!K36/'B7-CFlow'!K42))","v":87.279836612145857},{"$f":"IF(ISERROR('SB2'!L36/'B7-CFlow'!L42), 0, ('SB2'!L36/'B7-CFlow'!L42))","v":0.2055850858023564},{"$f":"IF(ISERROR('SB2'!M36/'B7-CFlow'!M42), 0, ('SB2'!M36/'B7-CFlow'!M42))","v":5.054623165627832E-2}]
[]
["Other Indicators"]
["Electricity Distribution Losses (2)","Total Volume Losses (kW)"]
[null,"Total Cost of Losses (Rand '000)"]
[null,"% Volume (units purchased and generated less units sold)/units purchased and generated"]
["Water Distribution Losses (2)","Total Volume Losses (kℓ)"]
[null,"Total Cost of Losses (Rand '000)"]
[null,"% Volume (units purchased and generated less units sold)/units purchased and generated"]
["Employee costs","Employee costs/(Total Revenue - capital revenue)",null,null,null,{"$f":"IF(ISERROR('B4-FinPerf RE'!C26/'B4-FinPerf RE'!C23),0,('B4-FinPerf RE'!C26/'B4-FinPerf RE'!C23))","v":0.32307625063942191},{"$f":"IF(ISERROR('B4-FinPerf RE'!D26/'B4-FinPerf RE'!D23),0,('B4-FinPerf RE'!D26/'B4-FinPerf RE'!D23))","v":0.32155395979241608},{"$f":"IF(ISERROR('B4-FinPerf RE'!K26/'B4-FinPerf RE'!K23),0,('B4-FinPerf RE'!K26/'B4-FinPerf RE'!K23))","v":0.31842627990399208},{"$f":"IF(ISERROR('B4-FinPerf RE'!L26/'B4-FinPerf RE'!L23),0,('B4-FinPerf RE'!L26/'B4-FinPerf RE'!L23))","v":0.31056678488701894},{"$f":"IF(ISERROR('B4-FinPerf RE'!M26/'B4-FinPerf RE'!M23),0,('B4-FinPerf RE'!M26/'B4-FinPerf RE'!M23))","v":0.31232096711600837}]
["Remuneration","Total remuneration/(Total Revenue - capital revenue)"]
["Repairs & Maintenance","R&M/(Total Revenue excluding capital revenue)",null,null,null,{"$f":"IF(ISERROR('B9-Asset'!C171/'B4-FinPerf RE'!C23),0,('B9-Asset'!C171/'B4-FinPerf RE'!C23))","v":7.7865927078224595E-2},{"$f":"IF(ISERROR('B9-Asset'!D171/'B4-FinPerf RE'!D23),0,('B9-Asset'!D171/'B4-FinPerf RE'!D23))","v":6.0780648987864332E-2},{"$f":"IF(ISERROR('B9-Asset'!K171/'B4-FinPerf RE'!K23),0,('B9-Asset'!K171/'B4-FinPerf RE'!K23))","v":6.0750936030955202E-2},{"$f":"IF(ISERROR('B9-Asset'!L171/'B4-FinPerf RE'!L23),0,('B9-Asset'!L171/'B4-FinPerf RE'!L23))","v":4.7399886215501959E-2},{"$f":"IF(ISERROR('B9-Asset'!M171/'B4-FinPerf RE'!M23),0,('B9-Asset'!M171/'B4-FinPerf RE'!M23))","v":4.9574825597783624E-2}]
["Finance charges & Depreciation","FC&D/(Total Revenue - capital revenue)",null,null,null,{"$f":"IF(ISERROR(('B4-FinPerf RE'!C29+'B4-FinPerf RE'!C30)/'B4-FinPerf RE'!C23),0,(('B4-FinPerf RE'!C29+'B4-FinPerf RE'!C30)/'B4-FinPerf RE'!C23))","v":0.18913709234224169},{"$f":"IF(ISERROR(('B4-FinPerf RE'!D29+'B4-FinPerf RE'!D30)/'B4-FinPerf RE'!D23),0,(('B4-FinPerf RE'!D29+'B4-FinPerf RE'!D30)/'B4-FinPerf RE'!D23))","v":0.20445093600982844},{"$f":"IF(ISERROR(('B4-FinPerf RE'!K29+'B4-FinPerf RE'!K30)/'B4-FinPerf RE'!K23),0,(('B4-FinPerf RE'!K29+'B4-FinPerf RE'!K30)/'B4-FinPerf RE'!K23))","v":0.20435098903734872},{"$f":"IF(ISERROR(('B4-FinPerf RE'!L29+'B4-FinPerf RE'!L30)/'B4-FinPerf RE'!L23),0,(('B4-FinPerf RE'!L29+'B4-FinPerf RE'!L30)/'B4-FinPerf RE'!L23))","v":0.15236153815098955},{"$f":"IF(ISERROR(('B4-FinPerf RE'!M29+'B4-FinPerf RE'!M30)/'B4-FinPerf RE'!M23),0,(('B4-FinPerf RE'!M29+'B4-FinPerf RE'!M30)/'B4-FinPerf RE'!M23))","v":0.15149887317849856}]
["IDP regulation financial viability indicators"]
["i. Debt coverage","(Total Operating Revenue - Operating Grants)/Debt service payments due within financial year)",null,null,null,{"$f":"IF(ISERROR(('B4-FinPerf RE'!C23-'B4-FinPerf RE'!C20)/('B4-FinPerf RE'!L30-'B7-CFlow'!L37)),0,(('B4-FinPerf RE'!C23-'B4-FinPerf RE'!C20)/('B4-FinPerf RE'!L30-'B7-CFlow'!L37)))","v":34.767041875668333},{"$f":"IF(ISERROR(('B4-FinPerf RE'!D23-'B4-FinPerf RE'!D20)/('B4-FinPerf RE'!L30-'B7-CFlow'!L37)),0,(('B4-FinPerf RE'!D23-'B4-FinPerf RE'!D20)/('B4-FinPerf RE'!L30-'B7-CFlow'!L37)))","v":34.828669029946269},{"$f":"IF(ISERROR(('B4-FinPerf RE'!K23-'B4-FinPerf RE'!K20)/('B4-FinPerf RE'!L30-'B7-CFlow'!L37)),0,(('B4-FinPerf RE'!K23-'B4-FinPerf RE'!K20)/('B4-FinPerf RE'!L30-'B7-CFlow'!L37)))","v":34.853955005611745},{"$f":"IF(ISERROR(('B4-FinPerf RE'!L23-'B4-FinPerf RE'!L20)/('B4-FinPerf RE'!M30-'B7-CFlow'!M37)),0,(('B4-FinPerf RE'!L23-'B4-FinPerf RE'!L20)/('B4-FinPerf RE'!M30-'B7-CFlow'!M37)))","v":37.420466189710126},{"$f":"IF(ISERROR(('B4-FinPerf RE'!M23-'B4-FinPerf RE'!M20)/('B4-FinPerf RE'!M30-'B7-CFlow'!M37)),0,(('B4-FinPerf RE'!M23-'B4-FinPerf RE'!M20)/('B4-FinPerf RE'!M30-'B7-CFlow'!M37)))","v":38.355192434551505}]
["ii. O/S Service Debtors to Revenue","Total outstanding service debtors/annual revenue received for services",null,null,null,{"$f":"IF(ISERROR('B6-FinPos'!C10/'B4-FinPerf RE'!C23),0,('B6-FinPos'!C10/'B4-FinPerf RE'!C23))","v":0.56853960857955566},{"$f":"IF(ISERROR('B6-FinPos'!D10/'B4-FinPerf RE'!D23),0,('B6-FinPos'!D10/'B4-FinPerf RE'!D23))","v":0.61457249708808737},{"$f":"IF(ISERROR('B6-FinPos'!K10/'B4-FinPerf RE'!K23),0,('B6-FinPos'!K10/'B4-FinPerf RE'!K23))","v":0.61427205991889633},{"$f":"IF(ISERROR('B6-FinPos'!L10/'B4-FinPerf RE'!L23),0,('B6-FinPos'!L10/'B4-FinPerf RE'!L23))","v":0.47688286962454984},{"$f":"IF(ISERROR('B6-FinPos'!M10/'B4-FinPerf RE'!M23),0,('B6-FinPos'!M10/'B4-FinPerf RE'!M23))","v":0.77446836254038631}]
["iii. Cost coverage","(Available cash + Investments)/monthly fixed operational expenditure",null,null,null,{"$f":"IF(ISERROR('B7-CFlow'!C42/'SB4'!F46),0,('B7-CFlow'!C42/'SB4'!F46))","v":0},{"$f":"IF(ISERROR('B7-CFlow'!D42/'SB4'!G46),0,('B7-CFlow'!D42/'SB4'!G46))","v":0},{"$f":"IF(ISERROR('B7-CFlow'!K42/'SB4'!H46),0,('B7-CFlow'!K42/'SB4'!H46))","v":0},{"$f":"IF(ISERROR('B7-CFlow'!L42/'SB4'!I46),0,('B7-CFlow'!L42/'SB4'!I46))","v":0},{"$f":"IF(ISERROR('B7-CFlow'!M42/'SB4'!J46),0,('B7-CFlow'!M42/'SB4'!J46))","v":0}]
[{"$f":"head27a","v":"References"}]
["1.  Consumer debtors > 12 months old are excluded from current assets"]
["2. Only include if services provided by the municipality"]
["Calculation data"]
["Debtors > 90 days"]
["Debtors > 12 months recovered"]
["Monthly fixed operational expenditure"]
["Fixed operational expenditure % assumption",null,null,null,null,0.4,{"$f":"$F$47","v":0.4},{"$f":"$F$47","v":0.4},{"$f":"$F$47","v":0.4},{"$f":"$F$47","v":0.4},"develop own assumption as appropriate"]
["Own capex",null,null,null,null,{"$f":"'B5-Capex'!C42-'B5-Capex'!C72","v":3440253},{"$f":"'B5-Capex'!D42-'B5-Capex'!D72","v":6.0000002384185791E-2},{"$f":"'B5-Capex'!K42-'B5-Capex'!K72","v":113975.06000000238},{"$f":"'B5-Capex'!L42-'B5-Capex'!L72","v":0},{"$f":"'B5-Capex'!M42-'B5-Capex'!M72","v":0}]
["Borrowing",null,null,null,null,{"$f":"'B5-Capex'!C42-'B5-Capex'!C72","v":3440253},{"$f":"'B5-Capex'!D42-'B5-Capex'!D72","v":6.0000002384185791E-2},{"$f":"'B5-Capex'!K42-'B5-Capex'!K72","v":113975.06000000238},{"$f":"'B5-Capex'!L42-'B5-Capex'!L72","v":0},{"$f":"'B5-Capex'!M42-'B5-Capex'!M72","v":0}]

{"sheet":"SB5","index":23,"n_rows":310,"n_cols":15,"rows_kept":310,"cut":false,"hidden":false,"merged":[[1,0,2,0],[199,0,200,0],[1,2,2,2],[199,10,199,12],[153,10,153,12],[61,7,61,9],[1,1,2,1],[107,0,108,0],[1,4,2,4],[1,5,2,5],[61,10,61,12],[199,7,199,9],[107,7,107,9],[61,0,62,0],[1,3,2,3],[1,10,1,12],[245,0,246,0],[245,4,245,12],[153,0,154,0],[107,10,107,12],[153,7,153,9]]}
[{"$f":"muni&\" - \"&ADJB5&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB5 Adjustments Budget - social, economic and demographic statistics and assumptions - 44171"}]
["Description of economic indicator","Ref.","Basis of calculation",{"$f":"Head44","v":"2001 Census"},"2007 Survey",{"$f":"Head45","v":"2011 Census"},{"$f":"Head1B","v":"2016/17"},{"$f":"Head1A","v":"2017/18"},{"$f":"Head1","v":"2018/19"},{"$f":"Head2","v":"Budget Year 2019/20"},{"$f":"Head3","v":"2019/20 Medium Term Revenue & Expenditure Framework"}]
[null,null,null,null,null,null,{"$f":"Head5A","v":"Outcome"},"Outcome","Outcome",{"$f":"Head6","v":"Original Budget"},"Outcome","Outcome","Outcome"]
["Demographics"]
["Population",null,null,0,0,237000000,0,0,0,242553000,242553000]
["Females aged 5 - 14",null,null,0,0,24000000,0,242553000,0,35099000,35099000]
["Males aged 5 - 14",null,null,0,0,23000000,0,35099000,0,35696000,35696000]
["Females aged 15 - 34",null,null,0,0,41000000,0,75483000,0,75483000,75483000]
["Males aged 15 - 34",null,null,0,0,41000000,0,77489000,0,77489000,77489000]
["Unemployment",null,null,0,0,142000000,0,18786000,0,18786000,18786000]
[]
["Monthly Household income ( no. of households)","1, 12"]
["None",null,null,0,0,32821,0,0,0,33758,33758]
["R1 - R1 600",null,null,0,0,12532,0,0,0,12532,12532]
["R1 601 - R3 200"]
["R3 201 - R6 400"]
["R6 401 - R12 800"]
["R12 801 - R25 600"]
["R25 601 - R51 200"]
["R52 201 - R102 400"]
["R102 401 - R204 800"]
["R204 801 - R409 600"]
["R409 601 - R819 200"]
[" > R819 200"]
[]
[]
["Poverty profiles (no. of households)"]
["< R2 060 per household per month",13]
[]
["Household/demographics (000)"]
["Number of people in municipal area",null,null,0,0,227000000,0,0,0,242553000,242553000]
["Number of poor people in municipal area",null,null,0,0,84000,0,0,0,0,0]
["Number of households in municipal area",null,null,0,0,60000,0,0,0,61759,61759]
["Number of poor households in municipal area",null,null,0,0,33000,0,0,0,33000,33000]
["Definition of poor household (R per month)"]
[]
["Housing statistics",3]
["Formal"]
["Informal"]
["Total number of households",null,{"$f":"SUM(C38:C39)","v":0},0,0,0,0,0,0,0,0]
["Dwellings provided by municipality",4,null,0,0,52571,0,0,0,54162,54162]
["Dwellings provided by province/s",null,null,0,0,7596,0,0,0,80.59,80.59]
["Dwellings provided by private sector",5]
["Total new housing dwellings",null,{"$f":"SUM(C41:C43)","v":0},0,0,60167,0,0,0,54242.59,54242.59]
[]
["Economic",6]
["Inflation/inflation outlook (CPIX)"]
["Interest rate - borrowing",null,null,null,null,null,0,0,4.7E-2,5.1999999999999998E-2,5.3999999999999999E-2]
["Interest rate - investment",null,null,null,null,null,0,0,0,0.12,0.12]
["Remuneration increases",null,null,null,null,null,0,0,0,7.4999999999999997E-2,7.4999999999999997E-2]
["Consumption growth (electricity)",null,null,null,null,null,0,0,0,7.4999999999999997E-2,7.4999999999999997E-2]
["Consumption growth (water)"]
[null,null,null,null,null,null,0,0,0.03,0.02,0.02]
["Collection rates",7]
["Property tax/service charges",null,null,null,null,"%","%","%","%","%","%"]
["Rental of facilities & equipment",null,null,null,null,"%",0,0,0.65,1.03,1.02]
["Interest - external investments",null,null,null,null,"%","%","%","%","%","%"]
["Interest - debtors",null,null,null,null,"%","%","%","%","%","%"]
["Revenue from agency services",null,null,null,null,"%","%","%","%","%","%"]
[]
["Detail on the provision of municipal services for B10"]
["Total municipal services",null,null,null,{"$f":"Head1B","v":"2016/17"},{"$f":"Head1A","v":"2017/18"},{"$f":"Head1","v":"2018/19"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,{"$f":"Head3","v":"2019/20 Medium Term Revenue & Expenditure Framework"}]
[null,"Ref.",null,null,{"$f":"Head5A","v":"Outcome"},{"$f":"Head5A","v":"Outcome"},{"$f":"Head5A","v":"Outcome"},{"$f":"Head6","v":"Original Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head8","v":"Full Year Forecast"},{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,"Household service targets (000)"]
[null,null,"Water:"]
[null,null,"Piped water inside dwelling",null,5700,5700,0,5700,5700,5700,5700,5700,5700]
[null,null,"Piped water inside yard (but not in dwelling)",null,10000,10000,0,10000,10000,10000,10000,10000,10000]
[null,8,"Using public tap (at least min.service level)",null,52000,52000,0,52000,52000,52000,52000,52000,52000]
[null,10,"Other water supply (at least min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E66:E69)","v":67700},{"$f":"SUM(F66:F69)","v":67700},0,67700,67700,67700,67700,67700,67700]
[null,9,"Using public tap (< min.service level)",null,12000000,12000,0,12000,12000,12000,12000,12000,12000]
[null,10,"Other water supply (< min.service level)"]
[null,null,"No water supply"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E71:E73)","v":12000000},{"$f":"SUM(F71:F73)","v":12000},0,12000,12000,12000,12000,12000,12000]
[null,null,"Total number of households",null,{"$f":"E70+E74","v":12067700},{"$f":"F70+F74","v":79700},0,79700,79700,79700,79700,79700,79700]
[null,null,"Sanitation/sewerage:"]
[null,null,"Flush toilet (connected to sewerage)",null,7000,7000,0,7000,7000,7000,7000,7000,7000]
[null,null,"Flush toilet (with septic tank)",null,5000,5000,0,5000,5000,5000,5000,5000,5000]
[null,null,"Chemical toilet"]
[null,null,"Pit toilet (ventilated)"]
[null,null,"Other toilet provisions (> min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E77:E81)","v":12000},{"$f":"SUM(F77:F81)","v":12000},0,12000,12000,12000,12000,12000,12000]
[null,null,"Bucket toilet"]
[null,null,"Other toilet provisions (< min.service level)"]
[null,null,"No toilet provisions",null,39000000,39000,0,39000,39000,39000,39000,39000,39000]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E83:E85)","v":39000000},{"$f":"SUM(F83:F85)","v":39000},0,39000,39000,39000,39000,39000,39000]
[null,null,"Total number of households",null,{"$f":"E82+E86","v":39012000},{"$f":"F82+F86","v":51000},0,51000,51000,51000,51000,51000,51000]
[null,null,"Energy:"]
[null,null,"Electricity (at least min.service level)"]
[null,null,"Electricity - prepaid (min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E89:E90)","v":0},{"$f":"SUM(F89:F90)","v":0},0,0,0,0,0,0,0]
[null,null,"Electricity (< min.service level)"]
[null,null,"Electricity - prepaid (< min. service level)"]
[null,null,"Other energy sources"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E92:E94)","v":0},{"$f":"SUM(F92:F94)","v":0},0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E91+E95","v":0},{"$f":"F91+F95","v":0},0,0,0,0,0,0,0]
[null,null,"Refuse:"]
[null,null,"Removed at least once a week",null,64000,128000,0,75125,75125,75125,75125,75125,75125]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E98)","v":64000},{"$f":"SUM(F98)","v":128000},0,75125,75125,75125,75125,75125,75125]
[null,null,"Removed less frequently than once a week"]
[null,null,"Using communal refuse dump"]
[null,null,"Using own refuse dump"]
[null,null,"Other rubbish disposal"]
[null,null,"No rubbish disposal"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E100:E104)","v":0},0,0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E99+E105","v":64000},{"$f":"F99+F105","v":128000},0,75125,75125,75125,75125,75125,75125]
[]
["Municipal in-house services",null,null,null,{"$f":"Head1B","v":"2016/17"},{"$f":"Head1A","v":"2017/18"},{"$f":"Head1","v":"2018/19"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,{"$f":"Head3","v":"2019/20 Medium Term Revenue & Expenditure Framework"}]
[null,"Ref.",null,null,{"$f":"Head5A","v":"Outcome"},{"$f":"Head5A","v":"Outcome"},{"$f":"Head5A","v":"Outcome"},{"$f":"Head6","v":"Original Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head8","v":"Full Year Forecast"},{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,"Household service targets (000)"]
[null,null,"Water:"]
[null,null,"Piped water inside dwelling",null,5700,5700,0,5700,5700,5700,5700,5700,5700]
[null,null,"Piped water inside yard (but not in dwelling)",null,10000,10000,0,10000,10000,10000,10000,10000,10000]
[null,8,"Using public tap (at least min.service level)",null,52000,52000,0,52000,52000,52000,52000,52000,52000]
[null,10,"Other water supply (at least min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E112:E115)","v":67700},{"$f":"SUM(F112:F115)","v":67700},0,67700,67700,67700,67700,67700,67700]
[null,9,"Using public tap (< min.service level)",null,12000000,12000,0,12000,12000,12000,12000,12000,12000]
[null,10,"Other water supply (< min.service level)"]
[null,null,"No water supply"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E117:E119)","v":12000000},{"$f":"SUM(F117:F119)","v":12000},0,12000,12000,12000,12000,12000,12000]
[null,null,"Total number of households",null,{"$f":"E116+E120","v":12067700},{"$f":"F116+F120","v":79700},0,79700,79700,79700,79700,79700,79700]
[null,null,"Sanitation/sewerage:"]
[null,null,"Flush toilet (connected to sewerage)",null,7000,7000,0,7000,7000,7000,7000,7000,7000]
[null,null,"Flush toilet (with septic tank)",null,5000,5000,0,5000,5000,5000,5000,5000,5000]
[null,null,"Chemical toilet"]
[null,null,"Pit toilet (ventilated)"]
[null,null,"Other toilet provisions (> min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E123:E127)","v":12000},{"$f":"SUM(F123:F127)","v":12000},0,12000,12000,12000,12000,12000,12000]
[null,null,"Bucket toilet"]
[null,null,"Other toilet provisions (< min.service level)"]
[null,null,"No toilet provisions",null,39000000,39000,0,39000,39000,39000,39000,39000,39000]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E129:E131)","v":39000000},{"$f":"SUM(F129:F131)","v":39000},0,39000,39000,39000,39000,39000,39000]
[null,null,"Total number of households",null,{"$f":"E128+E132","v":39012000},{"$f":"F128+F132","v":51000},0,51000,51000,51000,51000,51000,51000]
[null,null,"Energy:"]
[null,null,"Electricity (at least min.service level)"]
[null,null,"Electricity - prepaid (min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E135:E136)","v":0},{"$f":"SUM(F135:F136)","v":0},0,0,0,0,0,0,0]
[null,null,"Electricity (< min.service level)"]
[null,null,"Electricity - prepaid (< min. service level)"]
[null,null,"Other energy sources"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E138:E140)","v":0},{"$f":"SUM(F138:F140)","v":0},0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E137+E141","v":0},{"$f":"F137+F141","v":0},0,0,0,0,0,0,0]
[null,null,"Refuse:"]
[null,null,"Removed at least once a week",null,64000,128000,0,75125,75125,75125,75125,75125,75125]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E144)","v":64000},{"$f":"SUM(F144)","v":128000},0,75125,75125,75125,75125,75125,75125]
[null,null,"Removed less frequently than once a week"]
[null,null,"Using communal refuse dump"]
[null,null,"Using own refuse dump"]
[null,null,"Other rubbish disposal"]
[null,null,"No rubbish disposal"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E146:E150)","v":0},0,0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E145+E151","v":64000},{"$f":"F145+F151","v":128000},0,75125,75125,75125,75125,75125,75125]
[]
["Municipal entity services",null,null,null,{"$f":"Head1B","v":"2016/17"},{"$f":"Head1A","v":"2017/18"},{"$f":"Head1","v":"2018/19"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,{"$f":"Head3","v":"2019/20 Medium Term Revenue & Expenditure Framework"}]
[null,"Ref.",null,null,{"$f":"Head5A","v":"Outcome"},{"$f":"Head5A","v":"Outcome"},{"$f":"Head5A","v":"Outcome"},{"$f":"Head6","v":"Original Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head8","v":"Full Year Forecast"},{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,"Household service targets (000)"]
["Name of municipal entity",null,"Water:"]
[null,null,"Piped water inside dwelling"]
[null,null,"Piped water inside yard (but not in dwelling)"]
[null,8,"Using public tap (at least min.service level)"]
[null,10,"Other water supply (at least min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E158:E161)","v":0},{"$f":"SUM(F158:F161)","v":0},0,0,0,0,0,0,0]
[null,9,"Using public tap (< min.service level)"]
[null,10,"Other water supply (< min.service level)"]
[null,null,"No water supply"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E163:E165)","v":0},{"$f":"SUM(F163:F165)","v":0},0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E162+E166","v":0},{"$f":"F162+F166","v":0},0,0,0,0,0,0,0]
["Name of municipal entity",null,"Sanitation/sewerage:"]
[null,null,"Flush toilet (connected to sewerage)"]
[null,null,"Flush toilet (with septic tank)"]
[null,null,"Chemical toilet"]
[null,null,"Pit toilet (ventilated)"]
[null,null,"Other toilet provisions (> min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E169:E173)","v":0},{"$f":"SUM(F169:F173)","v":0},0,0,0,0,0,0,0]
[null,null,"Bucket toilet"]
[null,null,"Other toilet provisions (< min.service level)"]
[null,null,"No toilet provisions"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E175:E177)","v":0},{"$f":"SUM(F175:F177)","v":0},0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E174+E178","v":0},{"$f":"F174+F178","v":0},0,0,0,0,0,0,0]
["Name of municipal entity",null,"Energy:"]
[null,null,"Electricity (at least min.service level)"]
[null,null,"Electricity - prepaid (min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E181:E182)","v":0},{"$f":"SUM(F181:F182)","v":0},0,0,0,0,0,0,0]
[null,null,"Electricity (< min.service level)"]
[null,null,"Electricity - prepaid (< min. service level)"]
[null,null,"Other energy sources"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E184:E186)","v":0},{"$f":"SUM(F184:F186)","v":0},0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E183+E187","v":0},{"$f":"F183+F187","v":0},0,0,0,0,0,0,0]
["Name of municipal entity",null,"Refuse:"]
[null,null,"Removed at least once a week"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E190)","v":0},{"$f":"SUM(F190)","v":0},0,0,0,0,0,0,0]
[null,null,"Removed less frequently than once a week"]
[null,null,"Using communal refuse dump"]
[null,null,"Using own refuse dump"]
[null,null,"Other rubbish disposal"]
[null,null,"No rubbish disposal"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E192:E196)","v":0},0,0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E191+E197","v":0},{"$f":"F191+F197","v":0},0,0,0,0,0,0,0]
[]
["Services provided by 'external mechanisms'",null,null,null,{"$f":"Head1B","v":"2016/17"},{"$f":"Head1A","v":"2017/18"},{"$f":"Head1","v":"2018/19"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,{"$f":"Head3","v":"2019/20 Medium Term Revenue & Expenditure Framework"}]
[null,"Ref.",null,null,{"$f":"Head5A","v":"Outcome"},{"$f":"Head5A","v":"Outcome"},{"$f":"Head5A","v":"Outcome"},{"$f":"Head6","v":"Original Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head8","v":"Full Year Forecast"},{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
["Names of service providers",null,"Household service targets (000)"]
[null,null,"Water:"]
[null,null,"Piped water inside dwelling"]
[null,null,"Piped water inside yard (but not in dwelling)"]
[null,8,"Using public tap (at least min.service level)"]
[null,10,"Other water supply (at least min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E204:E207)","v":0},{"$f":"SUM(F204:F207)","v":0},0,0,0,0,0,0,0]
[null,9,"Using public tap (< min.service level)"]
[null,10,"Other water supply (< min.service level)"]
[null,null,"No water supply"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E209:E211)","v":0},{"$f":"SUM(F209:F211)","v":0},0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E208+E212","v":0},{"$f":"F208+F212","v":0},0,0,0,0,0,0,0]
["Names of service providers",null,"Sanitation/sewerage:"]
[null,null,"Flush toilet (connected to sewerage)"]
[null,null,"Flush toilet (with septic tank)"]
[null,null,"Chemical toilet"]
[null,null,"Pit toilet (ventilated)"]
[null,null,"Other toilet provisions (> min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E215:E219)","v":0},{"$f":"SUM(F215:F219)","v":0},0,0,0,0,0,0,0]
[null,null,"Bucket toilet"]
[null,null,"Other toilet provisions (< min.service level)"]
[null,null,"No toilet provisions"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E221:E223)","v":0},{"$f":"SUM(F221:F223)","v":0},0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E220+E224","v":0},{"$f":"F220+F224","v":0},0,0,0,0,0,0,0]
["Names of service providers",null,"Energy:"]
[null,null,"Electricity (at least min.service level)"]
[null,null,"Electricity - prepaid (min.service level)"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E227:E228)","v":0},{"$f":"SUM(F227:F228)","v":0},0,0,0,0,0,0,0]
[null,null,"Electricity (< min.service level)"]
[null,null,"Electricity - prepaid (< min. service level)"]
[null,null,"Other energy sources"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E230:E232)","v":0},{"$f":"SUM(F230:F232)","v":0},0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E229+E233","v":0},{"$f":"F229+F233","v":0},0,0,0,0,0,0,0]
["Names of service providers",null,"Refuse:"]
[null,null,"Removed at least once a week"]
[null,null,"Minimum Service Level and Above sub-total",null,{"$f":"SUM(E236)","v":0},{"$f":"SUM(F236)","v":0},0,0,0,0,0,0,0]
[null,null,"Removed less frequently than once a week"]
[null,null,"Using communal refuse dump"]
[null,null,"Using own refuse dump"]
[null,null,"Other rubbish disposal"]
[null,null,"No rubbish disposal"]
[null,null,"Below Minimum Service Level sub-total",null,{"$f":"SUM(E238:E242)","v":0},0,0,0,0,0,0,0,0]
[null,null,"Total number of households",null,{"$f":"E237+E243","v":0},{"$f":"F237+F243","v":0},0,0,0,0,0,0,0]
[]
["Detail of Free Basic Services (FBS) provided",null,null,null,{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["Electricity","Ref.","Location of households for each type of FBS"]
["List type of FBS service",null,"Formal settlements -  (50 kwh per indigent household per month R '000)",null,4000000,4000000,0,0,0,0,0,{"$f":"SUM(G249:K249)","v":0},{"$f":"IF(F249=0,E249+L249,F249+L249)","v":4000000},4000000,4000000]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,{"$f":"SUM(G250:K250)","v":0},0]
[null,null,"Informal settlements (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Informal settlements targeted for upgrading (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Living in informal backyard rental agreement (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Other (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Total cost of FBS - Electricity for informal settlements",null,{"$f":"E251+E253+E255+E257","v":0},{"$f":"F251+F253+F255+F257","v":0},0,0,0,0,0,{"$f":"L251+L253+L255+L257","v":0},0,{"$f":"N251+N253+N255+N257","v":0},0]
["Water","Ref.","Location of households for each type of FBS"]
["List type of FBS service",null,"Formal settlements -  (6 kilolitre per indigent household per month R '000)",null,10653000,10653000,0,0,0,0,0,{"$f":"SUM(G261:K261)","v":0},{"$f":"IF(F261=0,E261+L261,F261+L261)","v":10653000},10682385,11173775]
[null,null,"Number of HH receiving this type of FBS",null,19000,0,0,0,0,0,0,0,19000,19000,0]
[null,null,"Informal settlements (R '000)",null,10000000,0,0,0,0,0,0,0,10000000,10000000,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Informal settlements targeted for upgrading (R '000)",null,null,null,null,null,null,null,null,{"$f":"SUM(G265:K265)","v":0},0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Living in informal backyard rental agreement (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Other (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Total cost of FBS - Water  for informal settlements",null,{"$f":"E263+E265+E267+E269","v":10000000},{"$f":"F263+F265+F267+F269","v":0},0,0,0,0,0,0,10000000,{"$f":"N263+N265+N267+N269","v":10000000},{"$f":"O263+O265+O267+O269","v":0}]
["Sanitation","Ref.","Location of households for each type of FBS"]
["List type of FBS service",null,"Formal settlements -  (free sanitation service to indigent households R '000)",null,350000,350000,0,0,0,0,0,{"$f":"SUM(G273:K273)","v":0},{"$f":"IF(F273=0,E273+L273,F273+L273)","v":350000},374500,400715]
[null,null,"Number of HH receiving this type of FBS",null,330,0,0,0,0,0,0,0,330,330,0]
[null,null,"Informal settlements (R '000)",null,500000,0,0,0,0,0,0,0,500000,500000,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Informal settlements targeted for upgrading (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Living in informal backyard rental agreement (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Other (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Total cost of FBS - Sanitation for informal settlements",null,{"$f":"E275+E277+E279+E281","v":500000},{"$f":"F275+F277+F279+F281","v":0},0,0,0,0,0,0,500000,{"$f":"N275+N277+N279+N281","v":500000},{"$f":"O275+O277+O279+O281","v":0}]
["Refuse Removal","Ref.","Location of households for each type of FBS"]
["List type of FBS service",null,"Formal settlements -  (removed once a week to indigent households R '000)",null,20530000,20530000,0,0,0,0,0,{"$f":"SUM(G285:K285)","v":0},{"$f":"IF(F285=0,E285+L285,F285+L285)","v":20530000},21453850,22440727]
[null,null,"Number of HH receiving this type of FBS",null,58114,0,0,0,0,0,0,0,58114,58114,0]
[null,null,"Informal settlements (R '000)",null,20000000,0,0,0,0,0,0,0,20000000,20000000,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Informal settlements targeted for upgrading (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Living in informal backyard rental agreement (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Other (R '000)",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of HH receiving this type of FBS",null,null,null,null,null,null,null,null,0,0]
[null,null,"Total cost of FBS - Refuse Removal for informal settlements",null,{"$f":"E287+E289+E291+E293","v":20000000},{"$f":"F287+F289+F291+F293","v":0},0,0,0,0,0,0,20000000,{"$f":"N287+N289+N291+N293","v":20000000},{"$f":"O287+O289+O291+O293","v":0}]
[]
[{"$f":"head27a","v":"References"}]
["1. Monthly household income threshold. Should include all sources of income."]
["2. Show the poverty analysis the municipality uses to determine its indigents policy and the provision of services"]
["3. Include total of all housing units within the municipality"]
["4. Number of subsidised dwellings to be constructed by the municipality under agency agreement with province"]
["5. Provide estimate based on building approval information. Include any non-subsidised dwellings constructed by the municipality"]
["6. Insert actual or estimated % increases assumed as a basis for budget calculations"]
["7. Insert actual or estimated % collection rate assumed as a basis for budget calculations for each revenue group"]
["8. Stand distance <= 200m from dwelling"]
["9. Stand distance > 200m from dwelling"]
["10. Borehole, spring, rain-water tank etc."]
["11. Must agree to total number of households in municipal area"]
["12. Household income categories assume an average 4 person household. Stats SA - Census 2011 Questionnaire"]
["13. Based on National poverty line of R515 per capita per month (2008 prices), assuming an average household size of 4 persons"]

{"sheet":"SB6","index":24,"n_rows":71,"n_cols":11,"rows_kept":71,"cut":false,"hidden":false,"merged":[[1,1,2,1],[1,2,2,2]]}
[{"$f":"muni &\" - \"&ADJB6&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB6 Adjustments Budget - funding measurement - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},"MFMA section",{"$f":"Head1B","v":"2016/17"},{"$f":"Head1A","v":"2017/18"},{"$f":"Head1","v":"2018/19"},{"$f":"Head3a","v":"Medium Term Revenue and Expenditure Framework"}]
["R thousands",null,null,{"$f":"Head5","v":"Audited Outcome"},{"$f":"Head5","v":"Audited Outcome"},{"$f":"Head5","v":"Audited Outcome"},{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
["Funding measures"]
["Cash/cash equivalents at the year end - R'000",1,"18(1)b",null,null,null,{"$f":"'B7-CFlow'!C42","v":454854000},{"$f":"'B7-CFlow'!D42","v":69688047},{"$f":"'B7-CFlow'!K42","v":458296},{"$f":"'B7-CFlow'!L42","v":218887473.39999998},{"$f":"'B7-CFlow'!M42","v":890274082.26999998}]
["Cash + investments at the yr end less applications - R'000",2,"18(1)b",null,null,null,{"$f":"'B8-ResRecon'!C21","v":325997816},{"$f":"'B8-ResRecon'!D21","v":213558134},{"$f":"'B8-ResRecon'!K21","v":169996152},{"$f":"'B8-ResRecon'!L21","v":96886084},{"$f":"'B8-ResRecon'!M21","v":208913388}]
["Cash year end/monthly employee/supplier payments",3,"18(1)b",null,null,null,{"$f":"'SB4'!F39","v":0},{"$f":"'SB4'!G39","v":0},{"$f":"'SB4'!H39","v":0},{"$f":"'SB4'!I39","v":0},{"$f":"'SB4'!J39","v":0}]
["Surplus/(Deficit) excluding depreciation offsets: R'000",4,"18(1)",null,null,null,{"$f":"'B4-FinPerf RE'!C43+'SB2'!C54","v":68850206},{"$f":"'B4-FinPerf RE'!D43+'SB2'!D54","v":99350386.11999999},{"$f":"'B4-FinPerf RE'!K43+'SB2'!K54","v":99640386.11999999},{"$f":"'B4-FinPerf RE'!L43+'SB2'!L54","v":2429855854},{"$f":"'B4-FinPerf RE'!M43+'SB2'!M54","v":2971563137}]
["Service charge rev % change - macro CPIX target exclusive",5,"18(1)a,(2)",null,null,null,{"$f":"IF(ISERROR(((G36/G37)-1)-G35),0,(((G36/G37)-1)-G35))","v":0},{"$f":"IF(ISERROR(((H36/H37)-1)-H35),0,(((H36/H37)-1)-H35))","v":0},{"$f":"IF(ISERROR(((I36/I37)-1)-I35),0,(((I36/I37)-1)-I35))","v":0},{"$f":"IF(ISERROR(((J36/J37)-1)-J35),0,(((J36/J37)-1)-J35))","v":2.9162065173053142E-2},{"$f":"IF(ISERROR(((K36/K37)-1)-K35),0,(((K36/K37)-1)-K35))","v":-3.7554923906626125E-2}]
["Cash receipts % of Ratepayer & Other revenue",6,"18(1)a,(2)",{"$f":"IF(ISERROR(D40/D41),0,(D40/D41))","v":0},{"$f":"IF(ISERROR(E40/E41),0,(E40/E41))","v":0},0,0.62830167657350144,0.42150502606941659,0.34138676246083988,0.33322955115994013,0.34110069337216964]
["Debt impairment expense as a % of total billable revenue",7,"18(1)a,(2)",null,null,null,{"$f":"IF(ISERROR('B4-FinPerf RE'!C28/(SUM('B4-FinPerf RE'!C7:C13))),0,('B4-FinPerf RE'!C28/(SUM('B4-FinPerf RE'!C7:C13))))","v":0.37535299078653295},{"$f":"IF(ISERROR('B4-FinPerf RE'!D28/(SUM('B4-FinPerf RE'!D7:D13))),0,('B4-FinPerf RE'!D28/(SUM('B4-FinPerf RE'!D7:D13))))","v":0.55177920201840924},{"$f":"IF(ISERROR('B4-FinPerf RE'!K28/(SUM('B4-FinPerf RE'!K7:K13))),0,('B4-FinPerf RE'!K28/(SUM('B4-FinPerf RE'!K7:K13))))","v":0.55177920201840924},{"$f":"IF(ISERROR('B4-FinPerf RE'!L28/(SUM('B4-FinPerf RE'!L7:L13))),0,('B4-FinPerf RE'!L28/(SUM('B4-FinPerf RE'!L7:L13))))","v":0.54733072049792442},{"$f":"IF(ISERROR('B4-FinPerf RE'!M28/(SUM('B4-FinPerf RE'!M7:M13))),0,('B4-FinPerf RE'!M28/(SUM('B4-FinPerf RE'!M7:M13))))","v":0.53716552204210311}]
["Capital payments % of capital expenditure",8,"18(1)c;19",null,null,null,{"$f":"IF(ISERROR(-'B7-CFlow'!C28/'B5-Capex'!C65),0,(-'B7-CFlow'!C28/'B5-Capex'!C65))","v":-0.97837841514425139},{"$f":"IF(ISERROR(-'B7-CFlow'!D28/'B5-Capex'!D65),0,(-'B7-CFlow'!D28/'B5-Capex'!D65))","v":1.0000038223653749},{"$f":"IF(ISERROR(-'B7-CFlow'!E28/'B5-Capex'!E65),0,(-'B7-CFlow'!E28/'B5-Capex'!E65))","v":0},{"$f":"IF(ISERROR(-'B7-CFlow'!F28/'B5-Capex'!F65),0,(-'B7-CFlow'!F28/'B5-Capex'!F65))","v":0},{"$f":"IF(ISERROR(-'B7-CFlow'!G28/'B5-Capex'!G65),0,(-'B7-CFlow'!G28/'B5-Capex'!G65))","v":0}]
["Borrowing receipts % of capital expenditure (excl. transfers)",9,"18(1)c",null,null,null,{"$f":"IF(ISERROR('SB4'!F9),0,('SB4'!F9))","v":0},{"$f":"IF(ISERROR('SB4'!G9),0,('SB4'!G9))","v":0},{"$f":"IF(ISERROR('SB4'!H9),0,('SB4'!H9))","v":0},{"$f":"IF(ISERROR('SB4'!I9),0,('SB4'!I9))","v":0},{"$f":"IF(ISERROR('SB4'!J9),0,('SB4'!J9))","v":0}]
["Grants % of Govt. legislated/gazetted allocations",10,"18(1)a",null,null,null,{"$f":"IF(ISERROR(('B4-FinPerf RE'!C20+'B4-FinPerf RE'!C40)/('SB6'!G38+'SB6'!G39)),0,(('B4-FinPerf RE'!C20+'B4-FinPerf RE'!C40)/('SB6'!G38+'SB6'!G39)))","v":0},{"$f":"IF(ISERROR(('B4-FinPerf RE'!D20+'B4-FinPerf RE'!D40)/('SB6'!H38+'SB6'!H39)),0,(('B4-FinPerf RE'!D20+'B4-FinPerf RE'!D40)/('SB6'!H38+'SB6'!H39)))","v":0},{"$f":"IF(ISERROR(('B4-FinPerf RE'!K20+'B4-FinPerf RE'!K40)/('SB6'!I38+'SB6'!I39)),0,(('B4-FinPerf RE'!K20+'B4-FinPerf RE'!K40)/('SB6'!I38+'SB6'!I39)))","v":0},{"$f":"IF(ISERROR(('B4-FinPerf RE'!L20+'B4-FinPerf RE'!L40)/('SB6'!J38+'SB6'!J39)),0,(('B4-FinPerf RE'!L20+'B4-FinPerf RE'!L40)/('SB6'!J38+'SB6'!J39)))","v":0},{"$f":"IF(ISERROR(('B4-FinPerf RE'!M20+'B4-FinPerf RE'!M40)/('SB6'!K38+'SB6'!K39)),0,(('B4-FinPerf RE'!M20+'B4-FinPerf RE'!M40)/('SB6'!K38+'SB6'!K39)))","v":0}]
["Current consumer debtors % change - incr(decr)",11,"18(1)a",null,null,null,null,null,null,{"$f":"IF(ISERROR((SUM('B6-FinPos'!L10:L12)-SUM('B6-FinPos'!K10:K12))/SUM('B6-FinPos'!K10:K12)), 0, (SUM('B6-FinPos'!L10:L12)-SUM('B6-FinPos'!K10:K12))/SUM('B6-FinPos'!K10:K12))","v":-0.18085808530477948},{"$f":"IF(ISERROR((SUM('B6-FinPos'!M10:M12)-SUM('B6-FinPos'!L10:L12))/SUM('B6-FinPos'!L10:L12)), 0, (SUM('B6-FinPos'!M10:M12)-SUM('B6-FinPos'!L10:L12))/SUM('B6-FinPos'!L10:L12))","v":0.67844649908138621}]
["Long term receivables % change - incr(decr)",12,"18(1)a",null,null,null,null,null,null,{"$f":"IF(ISERROR(('B6-FinPos'!L17-'B6-FinPos'!K17)/'B6-FinPos'!K17),0,(('B6-FinPos'!L17-'B6-FinPos'!K17)/'B6-FinPos'!K17))","v":0},{"$f":"IF(ISERROR(('B6-FinPos'!M17-'B6-FinPos'!L17)/'B6-FinPos'!L17),0,(('B6-FinPos'!M17-'B6-FinPos'!L17)/'B6-FinPos'!L17))","v":0}]
["R&M % of Property Plant & Equipment",13,"20(1)(vi)",null,null,null,{"$f":"IF(ISERROR('B9-Asset'!C171/'B9-Asset'!C167),0,('B9-Asset'!C171/'B9-Asset'!C167))","v":3.648426658542344E-2},{"$f":"IF(ISERROR('B9-Asset'!D171/'B9-Asset'!D167),0,('B9-Asset'!D171/'B9-Asset'!D167))","v":2.632656612066793E-2},{"$f":"IF(ISERROR('B9-Asset'!K171/'B9-Asset'!K167),0,('B9-Asset'!K171/'B9-Asset'!K167))","v":2.6324886863940775E-2},{"$f":"IF(ISERROR('B9-Asset'!L171/'B9-Asset'!L167),0,('B9-Asset'!L171/'B9-Asset'!L167))","v":1.1524780528969244E-2},{"$f":"IF(ISERROR('B9-Asset'!M171/'B9-Asset'!M167),0,('B9-Asset'!M171/'B9-Asset'!M167))","v":1.1807849422304145E-2}]
["Asset renewal % of capital budget",14,{"$f":"C17","v":"20(1)(vi)"},null,null,null,{"$f":"IF(ISERROR('B9-Asset'!C39/'B9-Asset'!C134),0,('B9-Asset'!C39/'B9-Asset'!C134))","v":7.2461413209696485E-2},{"$f":"IF(ISERROR('B9-Asset'!D39/'B9-Asset'!D134),0,('B9-Asset'!D39/'B9-Asset'!D134))","v":0.2020827919149637},{"$f":"IF(ISERROR('B9-Asset'!K39/'B9-Asset'!K134),0,('B9-Asset'!K39/'B9-Asset'!K134))","v":0.20197110313484079},{"$f":"IF(ISERROR('B9-Asset'!L39/'B9-Asset'!L134),0,('B9-Asset'!L39/'B9-Asset'!L134))","v":4.8714603567976342E-2},{"$f":"IF(ISERROR('B9-Asset'!M39/'B9-Asset'!M134),0,('B9-Asset'!M39/'B9-Asset'!M134))","v":3.6542133223491334E-2}]
[{"$f":"head27a","v":"References"}]
["1. Positive cash balances indicative of minimum compliance - subject to 2"]
["2. Deduct applications (defined) from cash balances"]
["3. Indicative of sufficient liquidity to meet average monthly operating payments"]
["4. Indicative of funded operational requirements"]
["5. Indicative of adherence to macro-economic targets (prior to 2003/04 revenue not available for high capacity municipalities and later for other capacity classifications)"]
["6. Realistic average cash collection forecasts as % of annual billed revenue"]
["7. Realistic average increase in doubtful debt provision"]
["8. Indicative of planned capital expenditure level & cash payment timing"]
["9. Indicative of compliance with borrowing 'only' for the capital budget - should not exceed 100% unless refinancing"]
["10. Substantiation of National/Province allocations included in budget"]
["11. Indicative of realistic current arrear debtor collection targets (prior to 2003/04 revenue not available for high cap municipalities and later for other capacity classifications)"]
["12. Indicative of realistic long term arrear debtor collection targets (prior to 2003/04 revenue not available for high cap municipalities and later for other capacity classifications)"]
["13. Indicative of a credible allowance for repairs & maintenance of assets"]
["14. Indicative of a credible allowance for asset renewal (requires analysis of asset renewal projects as % of total capital projects - detailed capital plan)"]
[]
["Macro CPIX target",null,null,null,null,null,0.06,0.06,0.06,0.06,0.06]
["Total service charge revenue",null,null,null,null,null,{"$f":"IF(ISERROR(SUM('B4-FinPerf RE'!C7:C12)),0,(SUM('B4-FinPerf RE'!C7:C12)))","v":326415028},{"$f":"IF(ISERROR(SUM('B4-FinPerf RE'!D7:D12)),0,(SUM('B4-FinPerf RE'!D7:D12)))","v":326415028},{"$f":"IF(ISERROR(SUM('B4-FinPerf RE'!K7:K12)),0,(SUM('B4-FinPerf RE'!K7:K12)))","v":326415028},{"$f":"IF(ISERROR(SUM('B4-FinPerf RE'!L7:L12)),0,(SUM('B4-FinPerf RE'!L7:L12)))","v":355518866},{"$f":"IF(ISERROR(SUM('B4-FinPerf RE'!M7:M12)),0,(SUM('B4-FinPerf RE'!M7:M12)))","v":363498514}]
["Total service charge revenue - previous year",null,null,null,null,null,null,null,{"$f":"G37","v":0},{"$f":"I36","v":326415028},{"$f":"J36","v":355518866}]
["Provincial government gazetted allocations"]
["National government DoRA allocations"]
["Cash receipts from ratepayers",null,null,null,null,null,{"$f":"'B7-CFlow'!C8+'B7-CFlow'!C9+'B7-CFlow'!C10","v":247134000},{"$f":"'B7-CFlow'!D8+'B7-CFlow'!D9+'B7-CFlow'!D10","v":165669734},{"$f":"'B7-CFlow'!K8+'B7-CFlow'!K9+'B7-CFlow'!K10","v":134278788},{"$f":"'B7-CFlow'!L8+'B7-CFlow'!L9+'B7-CFlow'!L10","v":140992727.39999998},{"$f":"'B7-CFlow'!M8+'B7-CFlow'!M9+'B7-CFlow'!M10","v":148042363.77000001}]
["Ratepayer & Other revenue",null,null,null,null,null,{"$f":"SUM('B4-FinPerf RE'!C7:C13)+'B4-FinPerf RE'!C15+SUM('B4-FinPerf RE'!C17:C19)+'B4-FinPerf RE'!C21","v":393336528},{"$f":"SUM('B4-FinPerf RE'!D7:D13)+'B4-FinPerf RE'!D15+SUM('B4-FinPerf RE'!D17:D19)+'B4-FinPerf RE'!D21","v":393043318},{"$f":"SUM('B4-FinPerf RE'!K7:K13)+'B4-FinPerf RE'!K15+SUM('B4-FinPerf RE'!K17:K19)+'B4-FinPerf RE'!K21","v":393333318},{"$f":"SUM('B4-FinPerf RE'!L7:L13)+'B4-FinPerf RE'!L15+SUM('B4-FinPerf RE'!L17:L19)+'B4-FinPerf RE'!L21","v":423109916},{"$f":"SUM('B4-FinPerf RE'!M7:M13)+'B4-FinPerf RE'!M15+SUM('B4-FinPerf RE'!M17:M19)+'B4-FinPerf RE'!M21","v":434013670}]
["Change in debtors",null,null,null,null,null,null,null,null,{"$f":"(SUM('B6-FinPos'!L10:L12)+'B6-FinPos'!L17)-(SUM('B6-FinPos'!K10:K12)+'B6-FinPos'!K17)","v":-98336339},{"$f":"(SUM('B6-FinPos'!M10:M12)+'B6-FinPos'!M17)-(SUM('B6-FinPos'!L10:L12)+'B6-FinPos'!L17)","v":302169664}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["Average annual collection rate (arrears inclusive)"]

{"sheet":"SB7","index":25,"n_rows":58,"n_cols":11,"rows_kept":58,"cut":false,"hidden":false,"merged":[[55,0,55,10],[52,0,52,10],[1,0,3,0],[1,1,3,1],[1,2,1,8]]}
[{"$f":"muni&\" - \"&ADJB7&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB7 Adjustments Budget - transfers and grant receipts - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,7,8,9,10,11,12]
["R thousands",null,"A","A1","B","C","D","E","F"]
["RECEIPTS:","1, 2"]
[]
["Operating Transfers and Grants"]
["National Government:",null,{"$f":"SUM(C10:C17)","v":437829637},373297637,0,0,268000,268000,373565637,467694767,500553630]
["Local Government Equitable Share",null,null,null,null,null,null,{"$f":"SUM(E10:G10)","v":0},{"$f":"IF(D10=0,C10+H10,D10+H10)","v":0}]
["Equitable Share",3,429267000,366320000,0,0,0,0,366320000,459989000,494249000]
["Expanded Public Works Programme Integrated Grant",null,1695000,1695000,0,0,0,0,1695000,1827000,0]
["Local Government Financial Management Grant",null,1700000,1700000,0,0,0,0,1700000,1700000,1900000]
["Municipal Disaster Relief Grant",null,0,0,0,0,268000,268000,268000,0,0]
["Municipal Infrastructure Grant",null,5167637,3582637,0,0,0,0,3582637,4178767,4404630]
["Water Services Infrastructure Grant",null,0,0,0,0,0,{"$f":"SUM(E16:G16)","v":0},{"$f":"IF(D16=0,C16+H16,D16+H16)","v":0},0,0]
["Water Services Operating Subsidy Grant [Schedule 5B]",null,0,0,0,0,0,{"$f":"SUM(E17:G17)","v":0},{"$f":"IF(D17=0,C17+H17,D17+H17)","v":0},0,0]
[" ",null,null,null,null,null,null,0,0]
["Provincial Government:",null,{"$f":"SUM(C20:C21)","v":0},0,0,0,0,0,0,0,0]
["Libraries; Archives and Museums",null,0,0,0,0,0,{"$f":"SUM(E20:G20)","v":0},{"$f":"IF(D20=0,C20+H20,D20+H20)","v":0},0,0]
["Specify (Add grant description)",null,0,0,0,0,0,{"$f":"SUM(E21:G21)","v":0},{"$f":"IF(D21=0,C21+H21,D21+H21)","v":0},0,0]
[" ",5,null,null,null,null,null,{"$f":"SUM(E22:G22)","v":0},{"$f":"IF(D22=0,C22+H22,D22+H22)","v":0}]
["District Municipality:",null,{"$f":"SUM(C24:C24)","v":0},0,0,0,0,0,0,0,0]
[" ",null,null,null,null,null,null,{"$f":"SUM(E24:G24)","v":0},{"$f":"IF(D24=0,C24+H24,D24+H24)","v":0}]
["Other grant providers:",null,{"$f":"SUM(C26:C26)","v":0},1164487,0,0,-179487,-179487,985000,0,0]
["National Library South Africa",null,0,1164487,0,0,-179487,{"$f":"SUM(E26:G26)","v":-179487},{"$f":"IF(D26=0,C26+H26,D26+H26)","v":985000},0,0]
["Total Operating Transfers and Grants",6,{"$f":"C9+C19+C23+C25","v":437829637},374462124,0,0,88513,88513,374550637,467694767,500553630]
[]
["Capital Transfers and Grants"]
[{"$f":"A9","v":"National Government:"},null,{"$f":"SUM(C31:C33)","v":87086153},93773318,0,0,0,0,93773318,202495233,218925370]
["Municipal Infrastructure Grant",null,32086153,38773318,0,0,0,{"$f":"SUM(E31:G31)","v":0},{"$f":"IF(D31=0,C31+H31,D31+H31)","v":38773318},144470233,157709370]
["Municipal Water Infrastructure Grant  ",null,0,0,0,0,0,{"$f":"SUM(E32:G32)","v":0},{"$f":"IF(D32=0,C32+H32,D32+H32)","v":0},0,0]
["Water Services Infrastructure Grant  ",null,55000000,55000000,0,0,0,{"$f":"SUM(E33:G33)","v":0},{"$f":"IF(D33=0,C33+H33,D33+H33)","v":55000000},58025000,61216000]
[" ",null,null,null,null,null,null,{"$f":"SUM(E34:G34)","v":0},{"$f":"IF(D34=0,C34+H34,D34+H34)","v":0}]
[{"$f":"A19","v":"Provincial Government:"},null,{"$f":"SUM(C36:C36)","v":0},0,0,0,0,0,0,0,0]
["Waste Water Infrastructure",null,0,0,0,0,0,{"$f":"SUM(E36:G36)","v":0},{"$f":"IF(D36=0,C36+H36,D36+H36)","v":0},0,0]
[" ",null,null,null,null,null,null,{"$f":"SUM(E37:G37)","v":0},{"$f":"IF(D37=0,C37+H37,D37+H37)","v":0}]
[{"$f":"A23","v":"District Municipality:"},null,{"$f":"SUM(C39:C39)","v":0},0,0,0,0,0,0,0,0]
["[insert description]",null,null,null,null,null,null,{"$f":"SUM(E39:G39)","v":0},{"$f":"IF(D39=0,C39+H39,D39+H39)","v":0}]
[{"$f":"A25","v":"Other grant providers:"},null,{"$f":"SUM(C41:C43)","v":112438210},112332044.98999999,0,0,0,0,112332044.98999999,0,0]
["[insert description]",null,null,null,null,null,null,{"$f":"SUM(E41:G41)","v":0},{"$f":"IF(D41=0,C41+H41,D41+H41)","v":0}]
["Municipal Infrastructure Investment Unit",null,112438210,112332044.98999999,0,0,0,{"$f":"SUM(E42:G42)","v":0},{"$f":"IF(D42=0,C42+H42,D42+H42)","v":112332044.98999999},0,0]
["Registration of Deeds Trade Account",null,0,0,0,0,0,{"$f":"SUM(E43:G43)","v":0},{"$f":"IF(D43=0,C43+H43,D43+H43)","v":0},0,0]
["Total Capital Transfers and Grants",6,{"$f":"C30+C35+C38+C40","v":199524363},206105362.99000001,0,0,0,0,206105362.99000001,202495233,218925370]
["TOTAL RECEIPTS OF TRANSFERS & GRANTS",null,{"$f":"C27+C44","v":637354000},580567486.99000001,0,0,88513,88513,580655999.99000001,670190000,719479000]
[{"$f":"head27a","v":"References"}]
["1. Each grant is listed by name as gazetted together with the name of the transferring department or municipality, donor or other organisation"]
["2. Amounts actually RECEIVED; not revenue earned (the objective is to confirm grants allocated)"]
["3. Replacement of RSC levies"]
["4. Housing subsidies for housing where ownership transferred to organisations or persons outside the control of the municipality"]
["5. Motor vehicle licensing refunds to be included under 'agency' services (Not shown here as Receipts)"]
["6. Total Grant Receipts original budget must reconcile to budget supporting table A18"]
["7. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["8. Increases of funds approved under section 31 MFMA"]
["9. Adjustments to funding allocations from National or Provincial Government"]
["10. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); error correction (section 28(2)(f)); functional shifts and any adjustments made under delegation by the AO since the budget was approve"]
["11. E = B + C + D"]
["12. Adjusted Budget F = (A or A1/2 etc) + E"]

{"sheet":"SB8","index":26,"n_rows":58,"n_cols":11,"rows_kept":58,"cut":false,"hidden":false,"merged":[[55,0,55,10],[1,0,3,0],[1,1,3,1],[1,2,1,8]]}
[{"$f":"muni&\" - \"&ADJB8&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB8 Adjustments Budget - expenditure on transfers and grant programme - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,2,3,4,5,6,7]
["R thousands",null,"A","A1","B","C","D","E","F"]
["EXPENDITURE ON TRANSFERS AND GRANT PROGRAM:",1]
[]
["Operating expenditure of Transfers and Grants"]
["National Government:",null,{"$f":"SUM(C10:C13)","v":114558916},75395000.030000001,0,0,268000,268000,75663000.030000001,100539000,106427000]
["Equitable Share",null,91000000,71000000,0,0,0,{"$f":"SUM(E10:G10)","v":0},{"$f":"IF(D10=0,C10+H10,D10+H10)","v":71000000},100000000,104600000]
["Expanded Public Works Programme Integrated Grant",null,4470131,1695000.01,0,0,0,{"$f":"SUM(E11:G11)","v":0},{"$f":"IF(D11=0,C11+H11,D11+H11)","v":1695000.01},539000,1827000]
["Local Government Financial Management Grant",null,19088785,2700000.02,0,0,0,{"$f":"SUM(E12:G12)","v":0},{"$f":"IF(D12=0,C12+H12,D12+H12)","v":2700000.02},0,0]
["Municipal Disaster Relief Grant",null,0,0,0,0,268000,{"$f":"SUM(E13:G13)","v":268000},{"$f":"IF(D13=0,C13+H13,D13+H13)","v":268000},0,0]
[" ",null,null,null,null,null,null,{"$f":"SUM(E14:G14)","v":0},{"$f":"IF(D14=0,C14+H14,D14+H14)","v":0}]
[" ",null,null,null,null,null,null,0,0]
[" ",null,null,null,null,null,null,0,0]
["Provincial Government:",null,{"$f":"SUM(C18:C22)","v":0},0,0,0,0,0,0,0,0]
[" ",null,null,null,null,null,null,{"$f":"SUM(E18:G18)","v":0},{"$f":"IF(D18=0,C18+H18,D18+H18)","v":0}]
[" ",null,null,null,null,null,null,{"$f":"SUM(E19:G19)","v":0},{"$f":"IF(D19=0,C19+H19,D19+H19)","v":0}]
[" ",null,null,null,null,null,null,{"$f":"SUM(E20:G20)","v":0},{"$f":"IF(D20=0,C20+H20,D20+H20)","v":0}]
[" ",null,null,null,null,null,null,{"$f":"SUM(E21:G21)","v":0},{"$f":"IF(D21=0,C21+H21,D21+H21)","v":0}]
[" ",null,null,null,null,null,null,{"$f":"SUM(E22:G22)","v":0},{"$f":"IF(D22=0,C22+H22,D22+H22)","v":0}]
["District Municipality:",null,{"$f":"SUM(C24:C25)","v":0},0,0,0,0,0,0,0,0]
[" ",null,null,null,null,null,null,{"$f":"SUM(E24:G24)","v":0},{"$f":"IF(D24=0,C24+H24,D24+H24)","v":0}]
[" ",null,null,null,null,null,null,{"$f":"SUM(E25:G25)","v":0},{"$f":"IF(D25=0,C25+H25,D25+H25)","v":0}]
["Other grant providers:",null,{"$f":"SUM(C27:C28)","v":0},0,0,0,0,0,0,0,0]
[" ",null,null,null,null,null,null,{"$f":"SUM(E27:G27)","v":0},{"$f":"IF(D27=0,C27+H27,D27+H27)","v":0}]
[" ",null,null,null,null,null,null,{"$f":"SUM(E28:G28)","v":0},{"$f":"IF(D28=0,C28+H28,D28+H28)","v":0}]
["Total operating expenditure of Transfers and Grants:",null,{"$f":"C9+C17+C23+C26","v":114558916},75395000.030000001,0,0,268000,268000,{"$f":"I9+I17+I23+I26","v":75663000.030000001},100539000,106427000]
[]
["Capital expenditure of Transfers and Grants"]
["National Government:",null,{"$f":"SUM(C33:C34)","v":201361894},206105362.13,0,0,0,0,206105362.13,202495233,218925369]
["Municipal Infrastructure Grant",null,146361894,163108574.13,0,0,0,{"$f":"SUM(E33:G33)","v":0},{"$f":"IF(D33=0,C33+H33,D33+H33)","v":163108574.13},144470233,157709369]
["Water Services Infrastructure Grant  ",null,55000000,42996788,0,0,0,{"$f":"SUM(E34:G34)","v":0},{"$f":"IF(D34=0,C34+H34,D34+H34)","v":42996788},58025000,61216000]
[" ",null,null,null,null,null,null,{"$f":"SUM(E35:G35)","v":0},{"$f":"IF(D35=0,C35+H35,D35+H35)","v":0}]
[" ",null,null,null,null,null,null,0,0]
[" ",null,null,null,null,null,null,0,0]
[" ",null,null,null,null,null,null,0,0]
["Provincial Government:",null,{"$f":"SUM(C40:C41)","v":0},0,0,0,0,0,0,0,0]
[" ",null,null,null,null,null,null,{"$f":"SUM(E40:G40)","v":0},{"$f":"IF(D40=0,C40+H40,D40+H40)","v":0}]
[" ",null,null,null,null,null,null,{"$f":"SUM(E41:G41)","v":0},{"$f":"IF(D41=0,C41+H41,D41+H41)","v":0}]
["District Municipality:",null,{"$f":"SUM(C43:C44)","v":0},0,0,0,0,0,0,0,0]
[" ",null,null,null,null,null,null,{"$f":"SUM(E43:G43)","v":0},{"$f":"IF(D43=0,C43+H43,D43+H43)","v":0}]
[" ",null,null,null,null,null,null,{"$f":"SUM(E44:G44)","v":0},{"$f":"IF(D44=0,C44+H44,D44+H44)","v":0}]
["Other grant providers:",null,{"$f":"SUM(C46:C46)","v":0},0,0,0,0,0,0,0,0]
["Municipal Infrastructure Investment Unit",null,0,0,0,0,0,{"$f":"SUM(E46:G46)","v":0},{"$f":"IF(D46=0,C46+H46,D46+H46)","v":0},0,0]
[" ",null,null,null,null,null,null,{"$f":"SUM(E47:G47)","v":0},{"$f":"IF(D47=0,C47+H47,D47+H47)","v":0}]
["Total capital expenditure of Transfers and Grants",null,{"$f":"C32+C39+C42+C45","v":201361894},206105362.13,0,0,0,0,206105362.13,202495233,218925369]
[]
["Total capital expenditure of Transfers and Grants",null,{"$f":"C29+C48","v":315920810},281500362.15999997,0,0,268000,268000,281768362.15999997,303034233,325352369]
[{"$f":"head27a","v":"References"}]
["1. Transfers/Grant expenditure must be separately listed for each allocation received"]
["2. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["3. Increases of funds approved under section 31 MFMA"]
["4. Adjustments to funding allocations from National or Provincial Government"]
["5. Adjusts. = 'Other' Adjustments proposed to be approved; error correction (section 28(2)(f)); functional shifts and any adjustments made under delegation by the AO since the budget was approved or since a previously 'approved' Adjustments Budget in the "]
["6. E = B + C + D"]
["7. Adjusted Budget F = (A or A1/2 etc) + E"]

{"sheet":"SB9","index":27,"n_rows":65,"n_cols":11,"rows_kept":65,"cut":false,"hidden":false,"merged":[[59,0,59,10],[62,0,62,10],[1,2,1,8],[1,0,3,0],[1,1,3,1]]}
[{"$f":"muni&\" - \"&ADJB9&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB9 Adjustments Budget - reconciliation of transfers, grant receipts, and unspent funds - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,2,3,4,5,6,7]
["R thousands",null,"A","A1","B","C","D","E","F"]
["Operating transfers and grants:"]
["National Government:",null,0,0,0,0,0,null,null,0,0]
["Balance unspent at beginning of the year",null,0,0,0,0,0,{"$f":"SUM(E8:G8)","v":0},{"$f":"IF(D8=0,C8+H8,D8+H8)","v":0},0,0]
["Current year receipts",null,0,0,0,0,0,{"$f":"SUM(E9:G9)","v":0},{"$f":"IF(D9=0,C9+H9,D9+H9)","v":0},0,0]
["Conditions met - transferred to revenue",null,0,0,0,0,0,{"$f":"H8+H9-H11","v":0},0,0,0]
["Conditions still to be met - transferred to liabilities",null,0,0,0,0,0,{"$f":"SUM(E11:G11)","v":0},{"$f":"IF(D11=0,C11+H11,D11+H11)","v":0},0,0]
["Provincial Government:"]
["Balance unspent at beginning of the year",null,null,null,null,null,null,{"$f":"SUM(E13:G13)","v":0},{"$f":"IF(D13=0,C13+H13,D13+H13)","v":0}]
[{"$f":"A9","v":"Current year receipts"},null,null,null,null,null,null,{"$f":"SUM(E14:G14)","v":0},{"$f":"IF(D14=0,C14+H14,D14+H14)","v":0}]
[{"$f":"A10","v":"Conditions met - transferred to revenue"},null,{"$f":"C13+C14-C16","v":0},0,0,0,0,0,0,0,0]
[{"$f":"A11","v":"Conditions still to be met - transferred to liabilities"},null,null,null,null,null,null,{"$f":"SUM(E16:G16)","v":0},{"$f":"IF(D16=0,C16+H16,D16+H16)","v":0}]
["District Municipality:"]
[{"$f":"A13","v":"Balance unspent at beginning of the year"},null,null,null,null,null,null,{"$f":"SUM(E18:G18)","v":0},{"$f":"IF(D18=0,C18+H18,D18+H18)","v":0}]
[{"$f":"A14","v":"Current year receipts"},null,null,null,null,null,null,{"$f":"SUM(E19:G19)","v":0},{"$f":"IF(D19=0,C19+H19,D19+H19)","v":0}]
[{"$f":"A15","v":"Conditions met - transferred to revenue"},null,{"$f":"C18+C19-C21","v":0},0,0,0,0,0,0,0,0]
[{"$f":"A16","v":"Conditions still to be met - transferred to liabilities"},null,null,null,null,null,null,{"$f":"SUM(E21:G21)","v":0},{"$f":"IF(D21=0,C21+H21,D21+H21)","v":0}]
["Other grant providers:"]
[{"$f":"A13","v":"Balance unspent at beginning of the year"},null,null,null,null,null,null,{"$f":"SUM(E23:G23)","v":0},{"$f":"IF(D23=0,C23+H23,D23+H23)","v":0}]
[{"$f":"A14","v":"Current year receipts"},null,null,null,null,null,null,{"$f":"SUM(E24:G24)","v":0},{"$f":"IF(D24=0,C24+H24,D24+H24)","v":0}]
[{"$f":"A15","v":"Conditions met - transferred to revenue"},null,{"$f":"C23+C24-C26","v":0},0,0,0,0,0,0,0,0]
[{"$f":"A16","v":"Conditions still to be met - transferred to liabilities"},null,null,null,null,null,null,{"$f":"SUM(E26:G26)","v":0},{"$f":"IF(D26=0,C26+H26,D26+H26)","v":0}]
["Total operating transfers and grants revenue",null,{"$f":"C10+C15+C20+C25","v":0},0,0,0,0,0,0,0,0]
["Total operating transfers and grants - CTBM",2,{"$f":"C11+C16+C21+C26","v":0},0,0,0,0,0,0,0,0]
[]
["Capital transfers and grants:"]
[{"$f":"A7","v":"National Government:"}]
["Balance unspent at beginning of the year",null,0,0,0,0,0,{"$f":"SUM(E32:G32)","v":0},{"$f":"IF(D32=0,C32+H32,D32+H32)","v":0},0,0]
["Current year receipts",null,0,0,0,0,0,{"$f":"SUM(E33:G33)","v":0},{"$f":"IF(D33=0,C33+H33,D33+H33)","v":0},0,0]
["Conditions met - transferred to revenue",null,0,0,0,0,0,{"$f":"H32+H33-H35","v":10133273.539999999},10133273.539999999,0,0]
["Conditions still to be met - transferred to liabilities",null,0,0,-10133273.539999999,0,0,{"$f":"SUM(E35:G35)","v":-10133273.539999999},{"$f":"IF(D35=0,C35+H35,D35+H35)","v":-10133273.539999999},0,0]
["Provincial Government:"]
["Balance unspent at beginning of the year",null,null,null,null,null,null,{"$f":"SUM(E37:G37)","v":0},{"$f":"IF(D37=0,C37+H37,D37+H37)","v":0}]
[{"$f":"A33","v":"Current year receipts"},null,null,null,null,null,null,{"$f":"SUM(E38:G38)","v":0},{"$f":"IF(D38=0,C38+H38,D38+H38)","v":0}]
[{"$f":"A34","v":"Conditions met - transferred to revenue"},null,{"$f":"C37+C38-C40","v":0},0,0,0,0,0,0,0,0]
[{"$f":"A35","v":"Conditions still to be met - transferred to liabilities"},null,null,null,null,null,null,{"$f":"SUM(E40:G40)","v":0},{"$f":"IF(D40=0,C40+H40,D40+H40)","v":0}]
["District Municipality:"]
[{"$f":"A37","v":"Balance unspent at beginning of the year"},null,null,null,null,null,null,{"$f":"SUM(E42:G42)","v":0},{"$f":"IF(D42=0,C42+H42,D42+H42)","v":0}]
[{"$f":"A38","v":"Current year receipts"},null,null,null,null,null,null,{"$f":"SUM(E43:G43)","v":0},{"$f":"IF(D43=0,C43+H43,D43+H43)","v":0}]
[{"$f":"A39","v":"Conditions met - transferred to revenue"},null,{"$f":"C42+C43-C45","v":0},0,0,0,0,0,0,0,0]
[{"$f":"A40","v":"Conditions still to be met - transferred to liabilities"},null,null,null,null,null,null,{"$f":"SUM(E45:G45)","v":0},{"$f":"IF(D45=0,C45+H45,D45+H45)","v":0}]
["Other grant providers:"]
[{"$f":"A37","v":"Balance unspent at beginning of the year"},null,0,0,0,0,0,{"$f":"SUM(E47:G47)","v":0},{"$f":"IF(D47=0,C47+H47,D47+H47)","v":0},0,0]
[{"$f":"A38","v":"Current year receipts"},null,0,0,0,0,0,{"$f":"SUM(E48:G48)","v":0},{"$f":"IF(D48=0,C48+H48,D48+H48)","v":0},0,0]
[{"$f":"A39","v":"Conditions met - transferred to revenue"},null,0,0,0,0,0,{"$f":"H47+H48-H50","v":0},0,0,0]
[{"$f":"A40","v":"Conditions still to be met - transferred to liabilities"},null,0,0,0,0,0,{"$f":"SUM(E50:G50)","v":0},{"$f":"IF(D50=0,C50+H50,D50+H50)","v":0},0,0]
["Total capital transfers and grants revenue",null,{"$f":"C34+C39+C44+C49","v":0},0,0,0,0,10133273.539999999,10133273.539999999,0,0]
["Total capital transfers and grants - CTBM",null,{"$f":"C35+C40+C45+C50","v":0},0,-10133273.539999999,0,0,-10133273.539999999,-10133273.539999999,0,0]
[]
["TOTAL TRANSFERS AND GRANTS REVENUE",null,{"$f":"C27+C51","v":0},0,0,0,0,10133273.539999999,10133273.539999999,0,0]
["TOTAL TRANSFERS AND GRANTS -  CTBM",null,{"$f":"C28+C52","v":0},0,-10133273.539999999,0,0,-10133273.539999999,-10133273.539999999,0,0]
[]
[{"$f":"head27a","v":"References"}]
["1. Total capital grants revenue budget must reconcile to budget tables A4 and A5; total operating grants revenue must reconcile to budget table A4"]
["2. CTBM = conditions to be met"]
["3. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["4. Increases of funds approved under section 31 MFMA"]
["5. Adjustments to funding allocations from National or Provincial Government"]
["5. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sect"]
["6. E = B + C + D"]
["7. Adjusted Budget F = (A or A1/2 etc) + E"]

{"sheet":"SB10","index":28,"n_rows":71,"n_cols":13,"rows_kept":71,"cut":false,"hidden":false,"merged":[[1,0,3,0],[1,1,3,1],[1,2,1,10]]}
[{"$f":"muni&\" - \"&ADJB10&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB10 Adjustments Budget - transfers and grants made by the municipality - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,6,7,8,9,10,11,12,13]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Cash transfers to other municipalities"]
[null,1,null,null,null,null,null,null,null,{"$f":"SUM(E7:I7)","v":0},{"$f":"IF(D7=0,C7+J7,D7+J7)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":0}]
["TOTAL ALLOCATIONS TO MUNICIPALITIES:",null,{"$f":"SUM(C7:C9)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Cash transfers to Entities/Other External Mechanisms"]
[null,2,null,null,null,null,null,null,null,{"$f":"SUM(E13:I13)","v":0},{"$f":"IF(D13=0,C13+J13,D13+J13)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E14:I14)","v":0},{"$f":"IF(D14=0,C14+J14,D14+J14)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E15:I15)","v":0},{"$f":"IF(D15=0,C15+J15,D15+J15)","v":0}]
["TOTAL ALLOCATIONS TO ENTITIES/EMs'",null,{"$f":"SUM(C13:C15)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Cash transfers to other Organs of State"]
[null,3,null,null,null,null,null,null,null,{"$f":"SUM(E19:I19)","v":0},{"$f":"IF(D19=0,C19+J19,D19+J19)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E20:I20)","v":0},{"$f":"IF(D20=0,C20+J20,D20+J20)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E21:I21)","v":0},{"$f":"IF(D21=0,C21+J21,D21+J21)","v":0}]
["TOTAL ALLOCATIONS TO OTHER ORGANS OF STATE:",null,{"$f":"SUM(C19:C21)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Cash transfers to other Organisations"]
[null,4,null,null,null,null,null,null,null,{"$f":"SUM(E25:I25)","v":0},{"$f":"IF(D25=0,C25+J25,D25+J25)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E26:I26)","v":0},{"$f":"IF(D26=0,C26+J26,D26+J26)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E27:I27)","v":0},{"$f":"IF(D27=0,C27+J27,D27+J27)","v":0}]
["TOTAL CASH TRANSFERS TO OTHER ORGANISATIONS:",null,{"$f":"SUM(C25:C27)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["TOTAL CASH TRANSFERS",5,{"$f":"C10+C16+C22+C28","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Non-cash transfers to other municipalities"]
[null,1,null,null,null,null,null,null,null,{"$f":"SUM(E33:I33)","v":0},{"$f":"IF(D33=0,C33+J33,D33+J33)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E34:I34)","v":0},{"$f":"IF(D34=0,C34+J34,D34+J34)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E35:I35)","v":0},{"$f":"IF(D35=0,C35+J35,D35+J35)","v":0}]
["TOTAL ALLOCATIONS TO MUNICIPALITIES:",null,{"$f":"SUM(C33:C35)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Non-cash transfers to Entities/Other External Mechanisms"]
[null,2,null,null,null,null,null,null,null,{"$f":"SUM(E39:I39)","v":0},{"$f":"IF(D39=0,C39+J39,D39+J39)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E40:I40)","v":0},{"$f":"IF(D40=0,C40+J40,D40+J40)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E41:I41)","v":0},{"$f":"IF(D41=0,C41+J41,D41+J41)","v":0}]
["TOTAL ALLOCATIONS TO ENTITIES/EMs'",null,{"$f":"SUM(C39:C41)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Non-cash transfers to other Organs of State"]
[null,3,null,null,null,null,null,null,null,{"$f":"SUM(E45:I45)","v":0},{"$f":"IF(D45=0,C45+J45,D45+J45)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E46:I46)","v":0},{"$f":"IF(D46=0,C46+J46,D46+J46)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E47:I47)","v":0},{"$f":"IF(D47=0,C47+J47,D47+J47)","v":0}]
["TOTAL ALLOCATIONS TO OTHER ORGANS OF STATE:",null,{"$f":"SUM(C45:C47)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Non-cash transfers to other Organisations"]
[null,4,null,null,null,null,null,null,null,{"$f":"SUM(E51:I51)","v":0},{"$f":"IF(D51=0,C51+J51,D51+J51)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E52:I52)","v":0},{"$f":"IF(D52=0,C52+J52,D52+J52)","v":0}]
[null,null,null,null,null,null,null,null,null,{"$f":"SUM(E53:I53)","v":0},{"$f":"IF(D53=0,C53+J53,D53+J53)","v":0}]
["TOTAL NON-CASH TRANSFERS TO OTHER ORGANISATIONS:",null,{"$f":"SUM(C51:C53)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["TOTAL NON-CASH TRANSFERS",5,{"$f":"C36+C42+C48+C54","v":0},0,0,0,0,0,0,0,0,0,0]
["TOTAL TRANSFERS",null,{"$f":"C30+C56","v":0},{"$f":"D30+D56","v":0},0,0,0,0,0,0,0,0,0]
[{"$f":"head27a","v":"References"}]
["1. Insert description listed by municipal name and demarcation code of recipient"]
["2. Insert description of each entity or external mechanism (an external mechanism may be provided with resources to ensure a minimum level of service)"]
["3. Insert description of each Organ of State; e.g. Eskom"]
["4. Insert description of each 'other' organisation"]
["5. All descriptions should separate allocations for 'capital purposes' and 'operating purposes'"]
["6. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["7. Additional cash-backed accumulated funds/unspent funds (section 18(1)(b) and section 28(2)(e) MFMA) identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have for"]
["8. Increases of funds approved under section 31 MFMA"]
["9. Adjustments approved in accordance with section 29 MFMA"]
["10. Adjustments to funding allocations from National or Provincial Government"]
["11. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sec"]
["12. G = B + C + D + E +  F"]
["13. Adjusted Budget H = (A or A1/2 etc) + G"]

{"sheet":"SB11","index":29,"n_rows":120,"n_cols":12,"rows_kept":120,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,1,2,1],[117,0,117,11],[119,0,119,11],[112,0,112,11],[114,0,114,9],[115,0,115,11],[113,0,113,11],[1,2,1,10]]}
[{"$f":"muni&\" - \"&ADJB11&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB11 Adjustments Budget - councillor and staff benefits - 44171"}]
["Summary of remuneration",{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},"% change"]
[null,null,null,5,6,7,8,9,10,11,12]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Councillors (Political Office Bearers plus Other)"]
["Basic Salaries and Wages",null,16499368,16499368,null,null,0,null,1614473,{"$f":"G7+I7","v":1614473},{"$f":"IF(D7=0,C7+J7,D7+J7)","v":18113841},{"$f":"IF(K7=0,\"\",(K7/C7)-1)","v":9.7850596459209793E-2}]
["Pension and UIF Contributions",null,0,0,null,null,0,null,0,0,0,{"$f":"IF(K8=0,\"\",(K8/C8)-1)","v":""}]
["Medical Aid Contributions",null,0,0,null,null,0,null,0,0,0,{"$f":"IF(K9=0,\"\",(K9/C9)-1)","v":""}]
["Motor Vehicle Allowance",null,null,null,null,null,null,null,null,0,0,{"$f":"IF(K10=0,\"\",(K10/C10)-1)","v":""}]
["Cellphone Allowance",null,3186888,3186888,null,null,0,null,248200,248200,3435088]
["Housing Allowances",null,0,0,null,null,0,null,0,0,0]
["Other benefits and allowances",null,5685164,5685164,null,null,0,null,437327,437327,6122491]
["Sub Total - Councillors",null,{"$f":"SUM(C7:C13)","v":25371420},{"$f":"SUM(D7:D13)","v":25371420},null,null,{"$f":"SUM(G7:G13)","v":0},null,{"$f":"SUM(I7:I13)","v":2300000},{"$f":"SUM(J7:J13)","v":2300000},{"$f":"SUM(K7:K13)","v":27671420},{"$f":"IF(K14=0,\"\",(K14/C14)-1)","v":9.0653183779228819E-2}]
["% increase",null,null,{"$f":"IF(ISERROR((D14/C14)-1),0,((D14/C14)-1))","v":0},null,null,null,null,null,null,{"$f":"IF(ISERROR((K14/J14)-1),0,((K14/J14)-1))","v":11.031052173913043}]
[]
["Senior Managers of the Municipality"]
["Basic Salaries and Wages",null,8984087,8984087,0,null,0,null,0,{"$f":"E18+G18+I18","v":0},{"$f":"IF(D18=0,C18+J18,D18+J18)","v":8984087},{"$f":"IF(K18=0,\"\",(K18/C18)-1)","v":0}]
["Pension and UIF Contributions",null,193379,193379,0,null,0,null,0,0,193379,0]
["Medical Aid Contributions",null,101236,101236,0,null,0,null,0,0,101236,0]
["Overtime",null,0,0,0,null,0,null,0,{"$f":"E21+G21+I21","v":0},0,""]
["Performance Bonus",null,192304,193167,0,null,0,null,0,{"$f":"E22+G22+I22","v":0},{"$f":"IF(D22=0,C22+J22,D22+J22)","v":193167}]
["Motor Vehicle Allowance",null,582593,582593,0,null,0,null,0,0,582593,0]
["Cellphone Allowance",null,0,0,0,null,0,null,0,0,0,""]
["Housing Allowances",null,0,0,0,null,0,null,0,{"$f":"E25+G25+I25","v":0},{"$f":"IF(D25=0,C25+J25,D25+J25)","v":0}]
["Other benefits and allowances",null,791,791,0,null,0,null,0,{"$f":"E26+G26+I26","v":0},{"$f":"IF(D26=0,C26+J26,D26+J26)","v":791}]
["Payments in lieu of leave",null,0,0,0,null,0,null,0,{"$f":"E27+G27+I27","v":0},{"$f":"IF(D27=0,C27+J27,D27+J27)","v":0}]
["Long service awards",null,0,0,0,null,0,null,0,0,0,""]
["Post-retirement benefit obligations",5,0,0,0,null,0,null,0,0,0,""]
["Sub Total - Senior Managers of Municipality",null,{"$f":"SUM(C18:C29)","v":10054390},{"$f":"SUM(D18:D29)","v":10055253},{"$f":"SUM(E18:E29)","v":0},null,{"$f":"SUM(G18:G29)","v":0},null,{"$f":"SUM(I18:I29)","v":0},{"$f":"SUM(J18:J29)","v":0},{"$f":"SUM(K18:K29)","v":10055253},8.5833153478320767E-5]
[{"$f":"$A$15","v":"% increase"},null,null,{"$f":"IF(ISERROR((D30/C30)-1),0,((D30/C30)-1))","v":8.5833153478320767E-5},null,null,null,null,null,null,{"$f":"IF(ISERROR((K30/J30)-1),0,((K30/J30)-1))","v":0}]
[]
["Other Municipal Staff"]
["Basic Salaries and Wages",null,190978811,171165847.06999999,0,0,0,0,-2300000,{"$f":"SUM(E34:I34)","v":-2300000},{"$f":"IF(D34=0,C34+J34,D34+J34)","v":168865847.06999999},{"$f":"IF(K34=0,\"\",(K34/C34)-1)","v":-0.11578752540249093}]
["Pension and UIF Contributions",null,35698530,33678695.079999998,0,0,0,0,0,0,33678695.079999998,-5.6580338742239555E-2]
["Medical Aid Contributions",null,11762518,11890807.039999999,0,0,0,0,0,0,11890807.039999999,1.0906596699788107E-2]
["Overtime",null,5346000,6623759.0199999996,0,0,0,0,0,0,6623759.0199999996,0.23901216236438461]
["Performance Bonus",null,10939808,10578061.039999999,0,0,0,0,0,{"$f":"SUM(E38:I38)","v":0},{"$f":"IF(D38=0,C38+J38,D38+J38)","v":10578061.039999999}]
["Motor Vehicle Allowance",null,763000,523000.02,0,0,0,0,0,0,523000.02,-0.31454781127129749]
["Cellphone Allowance",null,null,null,null,null,null,null,null,0,0,""]
["Housing Allowances",null,655601,512517.05,0,0,0,0,0,{"$f":"SUM(E41:I41)","v":0},{"$f":"IF(D41=0,C41+J41,D41+J41)","v":512517.05}]
["Other benefits and allowances",null,4076002,3824420.06,0,0,0,0,0,{"$f":"SUM(E42:I42)","v":0},{"$f":"IF(D42=0,C42+J42,D42+J42)","v":3824420.06}]
["Payments in lieu of leave",null,0,0,0,0,0,0,0,0,0,""]
["Long service awards",null,null,null,null,null,null,null,null,0,0,""]
["Post-retirement benefit obligations",5,0,0,0,0,0,0,0,0,0,""]
["Sub Total - Other Municipal Staff",null,{"$f":"SUM(C34:C45)","v":260220270},238797106.38,0,0,0,0,-2300000,-2300000,236497106.38,-9.1165702118439884E-2]
[{"$f":"$A$15","v":"% increase"}]
["Total Parent Municipality",null,{"$f":"C14+C30+C46","v":295646080},274223779.38,0,0,0,0,0,0,274223779.38,{"$f":"IF(K48=0,\"\",(K48/C48)-1)","v":-7.2459275022351055E-2}]
[]
[]
["Board Members of Entities"]
["Basic Salaries and Wages",null,null,null,null,null,null,null,null,{"$f":"SUM(E52:I52)","v":0},{"$f":"IF(D52=0,C52+J52,D52+J52)","v":0},{"$f":"IF(K52=0,\"\",(K52/C52)-1)","v":""}]
["Pension and UIF Contributions",null,null,null,null,null,null,null,null,0,0,{"$f":"IF(K53=0,\"\",(K53/C53)-1)","v":""}]
["Medical Aid Contributions",null,null,null,null,null,null,null,null,0,0,{"$f":"IF(K54=0,\"\",(K54/C54)-1)","v":""}]
["Overtime",null,null,null,null,null,null,null,null,0,{"$f":"IF(D55=0,C55+J55,D55+J55)","v":0}]
["Performance Bonus",null,null,null,null,null,null,null,null,0,{"$f":"IF(D56=0,C56+J56,D56+J56)","v":0}]
["Motor Vehicle Allowance",null,null,null,null,null,null,null,null,0,{"$f":"IF(D57=0,C57+J57,D57+J57)","v":0}]
["Cellphone Allowance",null,null,null,null,null,null,null,null,0,{"$f":"IF(D58=0,C58+J58,D58+J58)","v":0}]
["Housing Allowances",null,null,null,null,null,null,null,null,{"$f":"G59+I59","v":0},0,{"$f":"IF(K59=0,\"\",(K59/C59)-1)","v":""}]
["Other benefits and allowances",null,null,null,null,null,null,null,null,{"$f":"G60+I60","v":0},0]
["Board Fees",null,null,null,null,null,null,null,null,{"$f":"SUM(E61:I61)","v":0},0,{"$f":"IF(K61=0,\"\",(K61/C61)-1)","v":""}]
["Payments in lieu of leave",null,null,null,null,null,null,null,null,{"$f":"SUM(E62:I62)","v":0},0,{"$f":"IF(K62=0,\"\",(K62/C62)-1)","v":""}]
["Long service awards",null,null,null,null,null,null,null,null,{"$f":"SUM(E63:I63)","v":0},{"$f":"IF(D63=0,C63+J63,D63+J63)","v":0}]
["Post-retirement benefit obligations",5,null,null,null,null,null,null,null,{"$f":"SUM(E64:I64)","v":0},0,{"$f":"IF(K64=0,\"\",(K64/C64)-1)","v":""}]
["Sub Total - Board Members of Entities",null,{"$f":"SUM(C52:C64)","v":0},0,0,0,0,0,0,0,0,{"$f":"IF(K65=0,\"\",(K65/C65)-1)","v":""}]
[{"$f":"$A$15","v":"% increase"}]
[]
["Senior Managers of Entities"]
["Basic Salaries and Wages",null,null,null,null,null,null,null,null,{"$f":"SUM(E69:I69)","v":0},{"$f":"IF(D69=0,C69+J69,D69+J69)","v":0},{"$f":"IF(K69=0,\"\",(K69/C69)-1)","v":""}]
["Pension and UIF Contributions",null,null,null,null,null,null,null,null,0,0,""]
["Medical Aid Contributions",null,null,null,null,null,null,null,null,0,0,""]
["Overtime",null,null,null,null,null,null,null,null,{"$f":"SUM(E72:I72)","v":0},{"$f":"IF(D72=0,C72+J72,D72+J72)","v":0}]
["Performance Bonus",null,null,null,null,null,null,null,null,{"$f":"SUM(E73:I73)","v":0},{"$f":"IF(D73=0,C73+J73,D73+J73)","v":0}]
["Motor Vehicle Allowance",null,null,null,null,null,null,null,null,{"$f":"SUM(E74:I74)","v":0},{"$f":"IF(D74=0,C74+J74,D74+J74)","v":0}]
["Cellphone Allowance",null,null,null,null,null,null,null,null,{"$f":"SUM(E75:I75)","v":0},{"$f":"IF(D75=0,C75+J75,D75+J75)","v":0}]
["Housing Allowances",null,null,null,null,null,null,null,null,0,0,""]
["Other benefits and allowances",null,null,null,null,null,null,null,null,{"$f":"SUM(E77:I77)","v":0},{"$f":"IF(D77=0,C77+J77,D77+J77)","v":0}]
["Payments in lieu of leave",null,null,null,null,null,null,null,null,0,0,""]
["Long service awards",null,null,null,null,null,null,null,null,0,0,""]
["Post-retirement benefit obligations",5,null,null,null,null,null,null,null,0,0,""]
["Sub Total - Senior Managers of Entities",null,{"$f":"SUM(C69:C80)","v":0},0,0,0,0,0,0,0,0,""]
[{"$f":"$A$15","v":"% increase"}]
[]
["Other Staff of Entities"]
["Basic Salaries and Wages",null,null,null,null,null,null,null,null,{"$f":"SUM(E85:I85)","v":0},{"$f":"IF(D85=0,C85+J85,D85+J85)","v":0},{"$f":"IF(K85=0,\"\",(K85/C85)-1)","v":""}]
["Pension and UIF Contributions",null,null,null,null,null,null,null,null,0,0,""]
["Medical Aid Contributions",null,null,null,null,null,null,null,null,0,0,""]
["Overtime",null,null,null,null,null,null,null,null,0,0,""]
["Performance Bonus",null,null,null,null,null,null,null,null,{"$f":"SUM(E89:I89)","v":0},{"$f":"IF(D89=0,C89+J89,D89+J89)","v":0}]
["Motor Vehicle Allowance",null,null,null,null,null,null,null,null,0,0,""]
["Cellphone Allowance",null,null,null,null,null,null,null,null,0,0,""]
["Housing Allowances",null,null,null,null,null,null,null,null,{"$f":"SUM(E92:I92)","v":0},{"$f":"IF(D92=0,C92+J92,D92+J92)","v":0}]
["Other benefits and allowances",null,null,null,null,null,null,null,null,{"$f":"SUM(E93:I93)","v":0},{"$f":"IF(D93=0,C93+J93,D93+J93)","v":0}]
["Payments in lieu of leave",null,null,null,null,null,null,null,null,0,0,""]
["Long service awards",null,null,null,null,null,null,null,null,0,0,""]
["Post-retirement benefit obligations",5,null,null,null,null,null,null,null,0,0,""]
["Sub Total - Other Staff of Entities",null,{"$f":"SUM(C85:C96)","v":0},0,0,0,0,0,0,0,0,""]
[{"$f":"$A$15","v":"% increase"}]
["Total Municipal Entities",null,{"$f":"C65+C81+C97","v":0},0,0,0,0,0,0,0,0,{"$f":"IF(K99=0,\"\",(K99/C99)-1)","v":""}]
[]
["TOTAL SALARY, ALLOWANCES & BENEFITS",null,{"$f":"C48+C99","v":295646080},274223779.38,0,0,0,0,0,0,274223779.38,{"$f":"IF(K101=0,\"\",(K101/C101)-1)","v":-7.2459275022351055E-2}]
[{"$f":"$A$15","v":"% increase"}]
["TOTAL MANAGERS AND STAFF",null,{"$f":"C30+C46+C81+C97","v":270274660},248852359.38,0,0,0,0,-2300000,-2300000,246552359.38,{"$f":"IF(K103=0,\"\",(K103/C103)-1)","v":-8.7771086716009528E-2}]
[{"$f":"head27a","v":"References"}]
["1. Include 'Loans and advances' where applicable if any reportable amounts only until phased compliance with s164 of MFMA achieved"]
["2. If benefits in kind are provided (e.g. provision of living quarters) the full market value must be shown as the cost to the municipality"]
["3. s57 of the Systems Act"]
["4. Must agree to the sub-total appearing on Table C1 (Employee costs)"]
["5. Includes pension payments and employer contributions to medical aid"]
[]
["Column Definitions:"]
["A. The original budget approved by council for the current year"]
["5. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["6. Additional cash-backed accumulated funds/unspent funds (section 18(1)(b) and section 28(2)(e) MFMA) identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have for"]
["7. Increases of funds approved under section 31 MFMA"]
["8. Adjustments approved in accordance with section 29 MFMA"]
["9. Adjustments caused by changes in funding allocations from National or Provincial Government"]
["10. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sec"]
["11. G = B + C + D + E +  F"]
["12. Adjusted Budget H = (A or A1/2 etc) + G"]

{"sheet":"SB12","index":30,"n_rows":43,"n_cols":18,"rows_kept":43,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,2,1,13],[1,1,2,1]]}
[{"$f":"muni&\" - \"&ADJB12&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB12 Adjustments Budget - monthly revenue and expenditure (municipal vote) - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,null,null,null,null,"Medium Term Revenue and Expenditure Framework"]
[null,null,"July","August","Sept.","October","November","December","January","February","March","April","May","June","Full year budget",{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
["R thousands",null,"Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Adjusted Budget",null,{"$f":"Head7","v":"Adjusted Budget"},"Adjusted Budget","Adjusted Budget"]
[{"$f":"'B3-FinPerf V'!A6","v":"Revenue by Vote"}]
[{"$f":"'B3-FinPerf V'!A7","v":"Vote 01 - Municipal Council"},null,0,-895132.84,0,47761.89,0,-199584,0,0,0,1831274.49,0,{"$f":"P6-SUM(C6:M6)","v":910680.46},{"$f":"SUM(C6:N6)","v":1695000},{"$f":"'B3-FinPerf V'!K7","v":1695000},{"$f":"'B3-FinPerf V'!L7","v":1827000},{"$f":"'B3-FinPerf V'!M7","v":940}]
[{"$f":"'B3-FinPerf V'!A8","v":"Vote 02 - Office Of The Accounting Officer"},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K8","v":0},{"$f":"'B3-FinPerf V'!L8","v":0},{"$f":"'B3-FinPerf V'!M8","v":0}]
[{"$f":"'B3-FinPerf V'!A9","v":"Vote 03 - Budget And Treasury Office"},null,194739154.72999999,17981913.670000002,17666975.940000001,17370407.449999999,17839521.530000001,97309038.299999997,17812250.789999999,17477217.530000001,-32992746.5,15141965.09,80341184.670000002,-42489993.199999928,418196890,{"$f":"'B3-FinPerf V'!K9","v":418196890},{"$f":"'B3-FinPerf V'!L9","v":526235196},{"$f":"'B3-FinPerf V'!M9","v":556112493}]
[{"$f":"'B3-FinPerf V'!A10","v":"Vote 04 - Corporate Services"},null,0,0,0,0,157061.54,0,90997.56,0,0,-1550797.74,395783.82,1674954.8199999998,768000,{"$f":"'B3-FinPerf V'!K10","v":768000},{"$f":"'B3-FinPerf V'!L10","v":500000},{"$f":"'B3-FinPerf V'!M10","v":500000}]
[{"$f":"'B3-FinPerf V'!A11","v":"Vote 05 - Community Services"},null,872373.13,852777.45,19082342.32,1358302.97,832721.72,829735.89,831489,829453.52,55842658.710000001,19095586.210000001,1329847.8500000001,-1446106.7799999714,100311181.99000001,{"$f":"'B3-FinPerf V'!K11","v":100311181.99000001},{"$f":"'B3-FinPerf V'!L11","v":87323182},{"$f":"'B3-FinPerf V'!M11","v":106256198}]
[{"$f":"'B3-FinPerf V'!A12","v":"Vote 06 - Planning & Development"},null,9949.25,15232.27,0,434.78,11691.28,64220.82,1713.05,2878.41,8770.44,0,0,35109.699999999997,150000,{"$f":"'B3-FinPerf V'!K12","v":150000},{"$f":"'B3-FinPerf V'!L12","v":100000},{"$f":"'B3-FinPerf V'!M12","v":100000}]
[{"$f":"'B3-FinPerf V'!A13","v":"Vote 07 - Infrastructure & Technical Services"},null,12166717.66,12145902.1,25335704.09,9776223.7599999998,15575016.85,15837273.24,15090573.17,14766990,121337044.55,70719347.359999999,28970029.420000002,117547423.80000001,459268246,{"$f":"'B3-FinPerf V'!K13","v":459268246},{"$f":"'B3-FinPerf V'!L13","v":482714538},{"$f":"'B3-FinPerf V'!M13","v":495723039}]
[{"$f":"'B3-FinPerf V'!A14","v":"Vote 08 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K14","v":0},{"$f":"'B3-FinPerf V'!L14","v":0},{"$f":"'B3-FinPerf V'!M14","v":0}]
[{"$f":"'B3-FinPerf V'!A15","v":"Vote 09 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K15","v":0},{"$f":"'B3-FinPerf V'!L15","v":0},{"$f":"'B3-FinPerf V'!M15","v":0}]
[{"$f":"'B3-FinPerf V'!A16","v":"Vote 10 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B3-FinPerf V'!K16","v":0},{"$f":"'B3-FinPerf V'!L16","v":0},{"$f":"'B3-FinPerf V'!M16","v":0}]
[{"$f":"'B3-FinPerf V'!A17","v":"Vote 11 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B3-FinPerf V'!K17","v":0},{"$f":"'B3-FinPerf V'!L17","v":0},{"$f":"'B3-FinPerf V'!M17","v":0}]
[{"$f":"'B3-FinPerf V'!A18","v":"Vote 12 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B3-FinPerf V'!K18","v":0},{"$f":"'B3-FinPerf V'!L18","v":0},{"$f":"'B3-FinPerf V'!M18","v":0}]
[{"$f":"'B3-FinPerf V'!A19","v":"Vote 13 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B3-FinPerf V'!K19","v":0},{"$f":"'B3-FinPerf V'!L19","v":0},{"$f":"'B3-FinPerf V'!M19","v":0}]
[{"$f":"'B3-FinPerf V'!A20","v":"Vote 14 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B3-FinPerf V'!K20","v":0},{"$f":"'B3-FinPerf V'!L20","v":0},{"$f":"'B3-FinPerf V'!M20","v":0}]
[{"$f":"'B3-FinPerf V'!A21","v":"Vote 15 - Other"},null,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"SUM(C20:N20)","v":0},{"$f":"'B3-FinPerf V'!K21","v":0},{"$f":"'B3-FinPerf V'!L21","v":0},{"$f":"'B3-FinPerf V'!M21","v":0}]
[{"$f":"'B3-FinPerf V'!A22","v":"Total Revenue by Vote"},null,{"$f":"SUM(C6:C20)","v":207788194.76999998},30100692.649999999,62085022.350000009,28553130.850000001,34416012.920000002,113840684.24999999,33827023.57,33076539.460000001,144195727.19999999,105237375.41,111036845.75999999,76232068.800000116,980389317.99000001,980389317.99000001,1098699916,1158692670]
[]
[{"$f":"'B3-FinPerf V'!A24","v":"Expenditure by Vote"}]
[{"$f":"'B3-FinPerf V'!A25","v":"Vote 01 - Municipal Council"},null,6044072.0499999998,4032347.03,4292081.82,5070436.95,4550824.78,5074353.3,2183735.48,6375798.8600000003,8381291.3799999999,4337368.8899999997,4297140.3,{"$f":"P24-SUM(C24:M24)","v":14837801.379999995},{"$f":"SUM(C24:N24)","v":69477252.219999999},{"$f":"'B3-FinPerf V'!K25","v":69477252.219999999},{"$f":"'B3-FinPerf V'!L25","v":70271020},{"$f":"'B3-FinPerf V'!M25","v":75483033}]
[{"$f":"'B3-FinPerf V'!A26","v":"Vote 02 - Office Of The Accounting Officer"},null,994838.16,1071476.99,1055666.8899999999,2298699.66,1613122.46,2943547.53,1072743.8500000001,1209976.21,2557727.02,1112719.98,1072400.3500000001,2784853.9299999997,19787773.030000001,{"$f":"'B3-FinPerf V'!K26","v":19787773.030000001},{"$f":"'B3-FinPerf V'!L26","v":25008311},{"$f":"'B3-FinPerf V'!M26","v":26427215}]
[{"$f":"'B3-FinPerf V'!A27","v":"Vote 03 - Budget And Treasury Office"},null,5663142.4400000004,3063137.22,4256284.76,3090063.56,4005615.27,8709892.3000000007,4130979.25,4911322.5199999996,6781814.6399999997,23704274.73,9612672.0099999998,42529068.379999995,120458267.08,{"$f":"'B3-FinPerf V'!K27","v":120458267.08},{"$f":"'B3-FinPerf V'!L27","v":145208027},{"$f":"'B3-FinPerf V'!M27","v":152100815}]
[{"$f":"'B3-FinPerf V'!A28","v":"Vote 04 - Corporate Services"},null,4087993.86,18202342.539999999,8872900.4000000004,9088636.4199999999,5185808.2699999996,15510037.119999999,13287956.5,4294291.88,9557743.5199999996,12967566.210000001,8656024.4000000004,-4493022.0299999714,105218279.09,{"$f":"'B3-FinPerf V'!K28","v":105218279.09},{"$f":"'B3-FinPerf V'!L28","v":90642312},{"$f":"'B3-FinPerf V'!M28","v":94844362}]
[{"$f":"'B3-FinPerf V'!A29","v":"Vote 05 - Community Services"},null,9439127.2799999993,6408655.0999999996,10785818.77,17346516.129999999,7168597.9900000002,18810301.920000002,9771995.3300000001,7022883.2300000004,14279961.82,22061820.129999999,7286029.2800000003,15597612.110000014,145979319.09,{"$f":"'B3-FinPerf V'!K29","v":145979319.09},{"$f":"'B3-FinPerf V'!L29","v":166499408},{"$f":"'B3-FinPerf V'!M29","v":175379400}]
[{"$f":"'B3-FinPerf V'!A30","v":"Vote 06 - Planning & Development"},null,1358671.92,1404467.56,1465242.48,1491796.54,1427289.9,1411205.69,1430951.91,1345573.53,1444755.03,1343070.02,1402498.42,6346445.0200000014,21871968.02,{"$f":"'B3-FinPerf V'!K30","v":21871968.02},{"$f":"'B3-FinPerf V'!L30","v":25289438},{"$f":"'B3-FinPerf V'!M30","v":27330875}]
[{"$f":"'B3-FinPerf V'!A31","v":"Vote 07 - Infrastructure & Technical Services"},null,23195056.370000001,20015801.460000001,24875965.829999998,22722015.550000001,21804876.16,48961800.950000003,20614050.52,28963701.120000001,38448046.789999999,116979047.3,16913654.77,39388872.519999981,422882889.33999997,{"$f":"'B3-FinPerf V'!K31","v":422882889.33999997},{"$f":"'B3-FinPerf V'!L31","v":415586746},{"$f":"'B3-FinPerf V'!M31","v":428723092}]
[{"$f":"'B3-FinPerf V'!A32","v":"Vote 08 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K32","v":0},{"$f":"'B3-FinPerf V'!L32","v":0},{"$f":"'B3-FinPerf V'!M32","v":0}]
[{"$f":"'B3-FinPerf V'!A33","v":"Vote 09 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K33","v":0},{"$f":"'B3-FinPerf V'!L33","v":0},{"$f":"'B3-FinPerf V'!M33","v":0}]
[{"$f":"'B3-FinPerf V'!A34","v":"Vote 10 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K34","v":0},{"$f":"'B3-FinPerf V'!L34","v":0},{"$f":"'B3-FinPerf V'!M34","v":0}]
[{"$f":"'B3-FinPerf V'!A35","v":"Vote 11 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K35","v":0},{"$f":"'B3-FinPerf V'!L35","v":0},{"$f":"'B3-FinPerf V'!M35","v":0}]
[{"$f":"'B3-FinPerf V'!A36","v":"Vote 12 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K36","v":0},{"$f":"'B3-FinPerf V'!L36","v":0},{"$f":"'B3-FinPerf V'!M36","v":0}]
[{"$f":"'B3-FinPerf V'!A37","v":"Vote 13 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K37","v":0},{"$f":"'B3-FinPerf V'!L37","v":0},{"$f":"'B3-FinPerf V'!M37","v":0}]
[{"$f":"'B3-FinPerf V'!A38","v":"Vote 14 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K38","v":0},{"$f":"'B3-FinPerf V'!L38","v":0},{"$f":"'B3-FinPerf V'!M38","v":0}]
[{"$f":"'B3-FinPerf V'!A39","v":"Vote 15 - Other"},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B3-FinPerf V'!K39","v":0},{"$f":"'B3-FinPerf V'!L39","v":0},{"$f":"'B3-FinPerf V'!M39","v":0}]
["Total Expenditure by Vote",null,{"$f":"SUM(C24:C38)","v":50782902.079999998},54198227.900000006,55603960.949999996,61108164.810000002,45756134.829999998,101421138.81,52492412.839999996,54123547.350000001,81451340.199999988,182505867.25999999,49240419.530000001,116991631.31000002,905675747.86999989,905675747.86999989,938505262,980288792]
[]
["Surplus/ (Deficit)",null,{"$f":"C21-C39","v":157005292.69},-24097535.250000007,6481061.4000000134,-32555033.960000001,-11340121.909999996,12419545.439999983,-18665389.269999996,-21047007.890000001,62744387,-77268491.849999994,61796426.229999989,-40759562.509999901,74713570.120000124,74713570.120000124,160194654,178403878]
[{"$f":"head27a","v":"References"}]
["1. Surplus (Deficit) must reconcile with budget table A2 and monthly budget statement table C2"]

{"sheet":"SB13","index":31,"n_rows":53,"n_cols":18,"rows_kept":53,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,1,2,1],[1,2,1,13]]}
[{"$f":"muni&\" - \"&ADJB13&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB13 Adjustments Budget - monthly revenue and expenditure (functional classification) - 44171"}]
[{"$f":"desc&\" - Standard classification\"","v":"Description - Standard classification"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,null,null,null,null,"Medium Term Revenue and Expenditure Framework"]
[null,null,"July","August","Sept.","October","November","December","January","February","March","April","May","June","Full year budget",{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
["R thousands",null,"Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Adjusted Budget",null,{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["Revenue - Functional"]
[{"$f":"'B2-FinPerf SC'!A7","v":"Governance and administration"},null,{"$f":"SUM(C7:C9)","v":194739154.72999999},17086780.830000002,17666975.940000001,17418169.34,17996583.07,97109454.299999997,17903248.350000001,17477217.530000001,-32992746.5,15422441.84,80736968.489999995,{"$f":"P6-SUM(C6:M6)","v":-39904357.920000017},{"$f":"SUM(C6:N6)","v":420659890},{"$f":"'B2-FinPerf SC'!K7","v":420659890},{"$f":"'B2-FinPerf SC'!L7","v":528562196},{"$f":"'B2-FinPerf SC'!M7","v":556613433}]
[{"$f":"'B2-FinPerf SC'!A8","v":"Executive and council"},null,0,-895132.84,0,47761.89,0,-199584,0,0,0,1831274.49,0,910680.46,1695000,{"$f":"'B2-FinPerf SC'!K8","v":1695000},{"$f":"'B2-FinPerf SC'!L8","v":1827000},{"$f":"'B2-FinPerf SC'!M8","v":940}]
[{"$f":"'B2-FinPerf SC'!A9","v":"Finance and administration"},null,194739154.72999999,17981913.670000002,17666975.940000001,17370407.449999999,17996583.07,97309038.299999997,17903248.350000001,17477217.530000001,-32992746.5,13591167.35,80736968.489999995,-40815038.379999995,418964890,{"$f":"'B2-FinPerf SC'!K9","v":418964890},{"$f":"'B2-FinPerf SC'!L9","v":526735196},{"$f":"'B2-FinPerf SC'!M9","v":556612493}]
[{"$f":"'B2-FinPerf SC'!A10","v":"Internal audit"},null,null,null,null,null,null,null,null,null,null,null,null,0,0,{"$f":"'B2-FinPerf SC'!K10","v":0},{"$f":"'B2-FinPerf SC'!L10","v":0},{"$f":"'B2-FinPerf SC'!M10","v":0}]
[{"$f":"'B2-FinPerf SC'!A11","v":"Community and public safety"},null,{"$f":"SUM(C11:C15)","v":0},6525.49,16842121.720000003,526768.71,1108.7,3436.49,1608.7,2132.92,15771.29,18784850.41,502881.67,-1320452.1000000015,35366754,{"$f":"'B2-FinPerf SC'!K11","v":35366754},{"$f":"'B2-FinPerf SC'!L11","v":12998475},{"$f":"'B2-FinPerf SC'!M11","v":11134000}]
[{"$f":"'B2-FinPerf SC'!A12","v":"Community and social services"},null,0,5486.95,16841856.050000001,526768.71,1108.7,3436.49,1608.7,1601.57,15505.62,13603850.41,465881.67,294649.12999999896,31761754,{"$f":"'B2-FinPerf SC'!K12","v":31761754},{"$f":"'B2-FinPerf SC'!L12","v":50000},{"$f":"'B2-FinPerf SC'!M12","v":8050000}]
[{"$f":"'B2-FinPerf SC'!A13","v":"Sport and recreation"},null,0,1038.54,265.67,0,0,0,0,531.35,265.67,0,0,52898.77,55000,{"$f":"'B2-FinPerf SC'!K13","v":55000},{"$f":"'B2-FinPerf SC'!L13","v":9898475},{"$f":"'B2-FinPerf SC'!M13","v":34000}]
[{"$f":"'B2-FinPerf SC'!A14","v":"Public safety"},null,0,0,0,0,0,0,0,0,0,5181000,37000,-1668000,3550000,{"$f":"'B2-FinPerf SC'!K14","v":3550000},{"$f":"'B2-FinPerf SC'!L14","v":3050000},{"$f":"'B2-FinPerf SC'!M14","v":3050000}]
[{"$f":"'B2-FinPerf SC'!A15","v":"Housing"},null,null,null,null,null,null,null,null,null,null,null,null,0,0,{"$f":"'B2-FinPerf SC'!K15","v":0},{"$f":"'B2-FinPerf SC'!L15","v":0},{"$f":"'B2-FinPerf SC'!M15","v":0}]
[{"$f":"'B2-FinPerf SC'!A16","v":"Health"},null,null,null,null,null,null,null,null,null,null,null,null,0,0,{"$f":"'B2-FinPerf SC'!K16","v":0},{"$f":"'B2-FinPerf SC'!L16","v":0},{"$f":"'B2-FinPerf SC'!M16","v":0}]
[{"$f":"'B2-FinPerf SC'!A17","v":"Economic and environmental services"},null,{"$f":"SUM(C17:C19)","v":9949.25},15232.27,1926658.7,434.78,11691.28,64220.82,1713.05,2878.41,8770.44,29326866.780000001,2615175.46,30937363.759999998,64920955,{"$f":"'B2-FinPerf SC'!K17","v":64920955},{"$f":"'B2-FinPerf SC'!L17","v":65260549},{"$f":"'B2-FinPerf SC'!M17","v":64504631}]
[{"$f":"'B2-FinPerf SC'!A18","v":"Planning and development"},null,9949.25,15232.27,0,434.78,11691.28,64220.82,1713.05,2878.41,8770.44,0,2615175.46,1002571.2400000002,3732637,{"$f":"'B2-FinPerf SC'!K18","v":3732637},{"$f":"'B2-FinPerf SC'!L18","v":4278767},{"$f":"'B2-FinPerf SC'!M18","v":4504630}]
[{"$f":"'B2-FinPerf SC'!A19","v":"Road transport"},null,0,0,1926658.7,0,0,0,0,0,0,29326866.780000001,0,29934792.52,61188318,{"$f":"'B2-FinPerf SC'!K19","v":61188318},{"$f":"'B2-FinPerf SC'!L19","v":60981782},{"$f":"'B2-FinPerf SC'!M19","v":60000001}]
[{"$f":"'B2-FinPerf SC'!A20","v":"Environmental protection"},null,null,null,null,null,null,null,null,null,null,null,null,0,0,{"$f":"'B2-FinPerf SC'!K20","v":0},{"$f":"'B2-FinPerf SC'!L20","v":0},{"$f":"'B2-FinPerf SC'!M20","v":0}]
[{"$f":"'B2-FinPerf SC'!A21","v":"Trading services"},null,{"$f":"SUM(C21:C24)","v":13039090.790000001},{"$f":"SUM(D21:D24)","v":12992154.059999999},25649265.990000002,10607758.02,16406629.869999999,16663572.640000001,15920453.470000001,15594310.6,177163931.97,41703216.379999995,27181820.140000001,{"$f":"P20-SUM(C20:M20)","v":86519515.060000062},459441718.99000001,{"$f":"'B2-FinPerf SC'!K21","v":459441718.99000001},{"$f":"'B2-FinPerf SC'!L21","v":491878696},{"$f":"'B2-FinPerf SC'!M21","v":526440606}]
[{"$f":"'B2-FinPerf SC'!A22","v":"Energy sources"},null,0,0,1951083.15,0,0,0,0,0,0,7733146.7800000003,0,10732743.07,20416973,{"$f":"'B2-FinPerf SC'!K22","v":20416973},{"$f":"'B2-FinPerf SC'!L22","v":11577741},{"$f":"'B2-FinPerf SC'!M22","v":12557370}]
[{"$f":"'B2-FinPerf SC'!A23","v":"Water management"},null,11829888.189999999,11866982.560000001,20627982.98,9513471.1899999995,15330387.859999999,15626320.34,14888085.26,14599044.609999999,103123534.14,27871973.440000001,26169336.550000001,69391074.879999995,340838082,{"$f":"'B2-FinPerf SC'!K23","v":340838082},{"$f":"'B2-FinPerf SC'!L23","v":358598493},{"$f":"'B2-FinPerf SC'!M23","v":371165069}]
[{"$f":"'B2-FinPerf SC'!A24","v":"Waste water management"},null,336829.47,278919.53999999998,829979.26,262752.57,244628.99,210952.9,202487.91,167945.39,18213510.41,5787360.3600000003,185517.41,6521351.7899999991,33242236,{"$f":"'B2-FinPerf SC'!K24","v":33242236},{"$f":"'B2-FinPerf SC'!L24","v":47377755},{"$f":"'B2-FinPerf SC'!M24","v":47595969}]
[{"$f":"'B2-FinPerf SC'!A25","v":"Waste management"},null,872373.13,846251.96,2240220.6,831534.26,831613.02,826299.4,829880.3,827320.6,55826887.420000002,310735.8,826966.18,-125654.6799999997,64944427.990000002,{"$f":"'B2-FinPerf SC'!K25","v":64944427.990000002},{"$f":"'B2-FinPerf SC'!L25","v":74324707},{"$f":"'B2-FinPerf SC'!M25","v":95122198}]
[{"$f":"'B2-FinPerf SC'!A26","v":"Other"},null,null,null,null,null,null,null,null,null,null,null,null,0,0,{"$f":"'B2-FinPerf SC'!K26","v":0},{"$f":"'B2-FinPerf SC'!L26","v":0},{"$f":"'B2-FinPerf SC'!M26","v":0}]
["Total Revenue - Functional",null,{"$f":"C6+C10+C16+C20+C25","v":207788194.76999998},{"$f":"D6+D10+D16+D20+D25","v":30100692.649999999},{"$f":"E6+E10+E16+E20+E25","v":62085022.350000009},{"$f":"F6+F10+F16+F20+F25","v":28553130.850000001},34416012.920000002,113840684.24999999,33827023.57,33076539.460000001,144195727.19999999,105237375.41,111036845.75999999,76232068.800000042,980389317.99000001,980389317.99000001,1098699916,1158692670]
[]
["Expenditure - Functional"]
[{"$f":"A6","v":"Governance and administration"},null,{"$f":"SUM(C30:C32)","v":17780543.109999999},28474017.009999998,19630250.309999999,20985827.930000003,16679312.720000001,33434534.199999999,21607980.170000002,17892934.27,28536005.430000003,42605510.469999999,24414105.219999999,{"$f":"P29-SUM(C29:M29)","v":60570503.619999945},{"$f":"SUM(C29:N29)","v":332611524.45999998},{"$f":"'B2-FinPerf SC'!K30","v":332611524.45999998},{"$f":"'B2-FinPerf SC'!L30","v":349715191},{"$f":"'B2-FinPerf SC'!M30","v":368351423}]
["Executive and council",null,6772456.8899999997,4762986.95,5074951.7699999996,7096339.6699999999,5891150.2999999998,7700756.7000000002,2980653.51,7248348.2999999998,10660522.310000001,5130655.37,5091044.5599999996,17393147.909999996,85803014.239999995,{"$f":"'B2-FinPerf SC'!K31","v":85803014.239999995},{"$f":"'B2-FinPerf SC'!L31","v":87162222},{"$f":"'B2-FinPerf SC'!M31","v":93378791}]
["Finance and administration",null,10741632.9,23370192.989999998,14282501.6,13616691.32,10515365.48,25416633.370000001,18351500.84,10307159.199999999,17596987.030000001,37155421.600000001,19044564.57,42947848.310000002,243346499.21000001,{"$f":"'B2-FinPerf SC'!K32","v":243346499.21000001},{"$f":"'B2-FinPerf SC'!L32","v":258527601},{"$f":"'B2-FinPerf SC'!M32","v":270737504}]
["Internal audit",null,266453.32,340837.07,272796.94,272796.94,272796.94,317144.13,275825.82,337426.77,278496.09000000003,319433.5,278496.09000000003,229507.40000000037,3462011.01,{"$f":"'B2-FinPerf SC'!K33","v":3462011.01},{"$f":"'B2-FinPerf SC'!L33","v":4025368},{"$f":"'B2-FinPerf SC'!M33","v":4235128}]
["Community and public safety",null,{"$f":"SUM(C34:C38)","v":4712555.18},3450703.4099999997,6626262.3399999999,10208147.310000001,3734435.95,10816881.919999998,5985618.5299999993,4773306.2300000004,6396862.04,11433573.789999999,5655351.9299999997,7130720.4100000113,80924419.040000007,{"$f":"'B2-FinPerf SC'!K34","v":80924419.040000007},{"$f":"'B2-FinPerf SC'!L34","v":103872294},{"$f":"'B2-FinPerf SC'!M34","v":108711163}]
["Community and social services",null,2009947.99,1416186.2,725058.1,1480161.18,1451187.66,2131186.5299999998,1517705.57,1372082.18,1562750.9,-634935.13,1595463.89,8299133.9299999997,22925929,{"$f":"'B2-FinPerf SC'!K35","v":22925929},{"$f":"'B2-FinPerf SC'!L35","v":26180426},{"$f":"'B2-FinPerf SC'!M35","v":27495935}]
["Sport and recreation",null,2177143.44,1417952.94,3498428.3,2773453.77,1679880.76,4465670.75,1966327.85,2684046.23,2423140.54,9874024.0399999991,1947769.09,-9192334.6999999993,25715503.010000002,{"$f":"'B2-FinPerf SC'!K36","v":25715503.010000002},{"$f":"'B2-FinPerf SC'!L36","v":42725232},{"$f":"'B2-FinPerf SC'!M36","v":44784178}]
["Public safety",null,525463.75,616564.27,2402775.94,5954532.3600000003,603367.53,4220024.6399999997,2501585.11,717177.82,2410970.6,2194484.88,2112118.9500000002,8023921.1800000034,32282987.030000001,{"$f":"'B2-FinPerf SC'!K37","v":32282987.030000001},{"$f":"'B2-FinPerf SC'!L37","v":34966636},{"$f":"'B2-FinPerf SC'!M37","v":36431050}]
["Housing",null,null,null,null,null,null,null,null,null,null,null,null,0,0,{"$f":"'B2-FinPerf SC'!K38","v":0},{"$f":"'B2-FinPerf SC'!L38","v":0},{"$f":"'B2-FinPerf SC'!M38","v":0}]
["Health",null,null,null,null,null,null,null,null,null,null,null,null,0,null,{"$f":"'B2-FinPerf SC'!K39","v":0},{"$f":"'B2-FinPerf SC'!L39","v":0},{"$f":"'B2-FinPerf SC'!M39","v":0}]
["Economic and environmental services",null,{"$f":"SUM(C40:C42)","v":7395902},7181318.9700000007,7156028.4299999997,7446258.8600000003,8324225.6999999993,7671033.9500000002,7465197.4100000001,7980314.1799999997,8061705.0800000001,-6440698.7300000004,7277547.8300000001,27718020.38000001,null,{"$f":"'B2-FinPerf SC'!K40","v":97236854.060000002},{"$f":"'B2-FinPerf SC'!L40","v":86089149},{"$f":"'B2-FinPerf SC'!M40","v":90942754}]
["Planning and development",null,1517330.72,1561936.56,1722837.26,1749391.32,1706745.35,1671417.07,1691732.09,1638154.91,1735261.71,1604425.6,1687704.9,7167667.5300000012,null,{"$f":"'B2-FinPerf SC'!K41","v":25454605.020000003},{"$f":"'B2-FinPerf SC'!L41","v":24460808},{"$f":"'B2-FinPerf SC'!M41","v":26477739}]
["Road transport",null,5878571.2800000003,5619382.4100000001,5433191.1699999999,5696867.54,6617480.3499999996,5999616.8799999999,5773465.3200000003,6342159.2699999996,6326443.3700000001,-8045124.3300000001,5589842.9299999997,20550352.850000009,null,{"$f":"'B2-FinPerf SC'!K42","v":71782249.040000007},{"$f":"'B2-FinPerf SC'!L42","v":61628341},{"$f":"'B2-FinPerf SC'!M42","v":64465015}]
["Environmental protection",null,null,null,null,null,null,null,null,null,null,null,null,0,null,{"$f":"'B2-FinPerf SC'!K43","v":0},{"$f":"'B2-FinPerf SC'!L43","v":0},{"$f":"'B2-FinPerf SC'!M43","v":0}]
["Trading services",null,{"$f":"SUM(C44:C47)","v":20893901.790000003},{"$f":"SUM(D44:D47)","v":15092188.51},22191419.870000001,22467930.710000001,17018160.459999997,49498688.739999995,17433616.73,23476992.670000002,38456767.649999999,134907481.72999999,11893414.549999999,{"$f":"P43-SUM(C43:M43)","v":21572386.899999976},{"$f":"SUM(C43:N43)","v":394902950.30999994},{"$f":"'B2-FinPerf SC'!K44","v":394902950.30999994},{"$f":"'B2-FinPerf SC'!L44","v":398828628},{"$f":"'B2-FinPerf SC'!M44","v":412283452}]
["Energy sources",null,3685022.01,1828704.56,3098231.16,3250481.5,3158460.01,2949145.39,2795816.58,2670761.1,2728031.19,-513237.68,2910595.35,3191746.8299999945,{"$f":"SUM(C44:N44)","v":31753758},{"$f":"'B2-FinPerf SC'!K45","v":31753758},{"$f":"'B2-FinPerf SC'!L45","v":19598588},{"$f":"'B2-FinPerf SC'!M45","v":20384798}]
["Water management",null,10948867.390000001,10482542.76,14175603.369999999,11435473.1,9608449.2899999991,37604662.939999998,9898030.4299999997,17742980.129999999,27466696.649999999,126743631.97,6532521.5999999996,5959117.6299999952,null,{"$f":"'B2-FinPerf SC'!K46","v":288598577.25999999},{"$f":"'B2-FinPerf SC'!L46","v":306488832},{"$f":"'B2-FinPerf SC'!M46","v":314139435}]
["Waste water management",null,2338996.02,1722698.59,1698898.46,1896385.85,1955818.28,2076074.07,1813476.52,1842737.75,1563887.41,-1432559.73,1523006.92,7790144.8900000006,null,{"$f":"'B2-FinPerf SC'!K47","v":24789565.030000001},{"$f":"'B2-FinPerf SC'!L47","v":21228371},{"$f":"'B2-FinPerf SC'!M47","v":22743337}]
["Waste management",null,3921016.37,1058242.6000000001,3218686.88,5885590.2599999998,2295432.88,6868806.3399999999,2926293.2,1220513.69,6698152.4000000004,10109647.17,927290.68,4631377.5500000045,null,{"$f":"'B2-FinPerf SC'!K48","v":49761050.020000003},{"$f":"'B2-FinPerf SC'!L48","v":51512837},{"$f":"'B2-FinPerf SC'!M48","v":55015882}]
["Other",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B2-FinPerf SC'!K49","v":0},{"$f":"'B2-FinPerf SC'!L49","v":0},{"$f":"'B2-FinPerf SC'!M49","v":0}]
["Total Expenditure - Functional",null,{"$f":"C29+C33+C39+C43+C48","v":50782902.079999998},{"$f":"D29+D33+D39+D43+D48","v":54198227.899999999},{"$f":"E29+E33+E39+E43+E48","v":55603960.950000003},{"$f":"F29+F33+F39+F43+F48","v":61108164.810000002},45756134.829999998,101421138.81,52492412.840000004,54123547.350000001,81451340.200000003,182505867.25999999,{"$f":"M29+M33+M39+M43+M48","v":49240419.529999994},116991631.30999994,808438893.80999994,905675747.86999989,938505262,980288792]
[]
["Surplus/ (Deficit) 1.",null,{"$f":"C26-C49","v":157005292.69},-24097535.25,6481061.400000006,-32555033.960000001,-11340121.909999996,12419545.439999983,-18665389.270000003,-21047007.890000001,62744386.999999985,-77268491.849999994,61796426.229999997,-40759562.509999901,171950424.18000007,74713570.120000124,160194654,178403878]
[{"$f":"head27a","v":"References"}]
["1. Surplus (Deficit) must reconcile with budget table A3 and monthly budget statement table C3"]

{"sheet":"SB14","index":32,"n_rows":45,"n_cols":18,"rows_kept":45,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,1,2,1],[1,2,1,13]]}
[{"$f":"muni&\" - \"&ADJB14&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB14 Adjustments Budget - monthly revenue and expenditure - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,null,null,null,null,"Medium Term Revenue and Expenditure Framework"]
[null,null,"July","August","Sept.","October","November","December","January","February","March","April","May","June","Full year budget",{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
["R thousands",null,"Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Budget",null,{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["Revenue By Source"]
[{"$f":"'B4-FinPerf RE'!A7","v":"Property rates"},null,11735433.390000001,11867426.189999999,11815199.27,11699857.060000001,11752961.939999999,11782873.550000001,11761079.07,11760700.279999999,11746532.810000001,11903539.68,11706734.84,{"$f":"P6-SUM(C6:M6)","v":12631261.919999987},{"$f":"SUM(C6:N6)","v":142163600},{"$f":"'B4-FinPerf RE'!K7","v":142163600},{"$f":"'B4-FinPerf RE'!L7","v":169026146},{"$f":"'B4-FinPerf RE'!M7","v":176817777}]
[{"$f":"'B4-FinPerf RE'!A8","v":"Service charges - electricity revenue"},null,0,-895132.84,0,0,0,-199584,0,0,0,1094716.8400000001,0,-2.3283064365386963E-10,0,{"$f":"'B4-FinPerf RE'!K8","v":0},{"$f":"'B4-FinPerf RE'!L8","v":0},{"$f":"'B4-FinPerf RE'!M8","v":0}]
[{"$f":"'B4-FinPerf RE'!A9","v":"Service charges - water revenue"},null,11829888.189999999,11866982.560000001,14205707.9,14488072.050000001,15330387.859999999,15626320.34,14888085.26,14599044.609999999,15123534.140000001,6644810.0599999996,10354810.460000001,26599356.569999993,171557000,{"$f":"'B4-FinPerf RE'!K9","v":171557000},{"$f":"'B4-FinPerf RE'!L9","v":171527615},{"$f":"'B4-FinPerf RE'!M9","v":171036225}]
[{"$f":"'B4-FinPerf RE'!A10","v":"Service charges - sanitation revenue"},null,336829.47,278919.53999999998,167698.1,262752.57,244628.99,210952.9,202487.91,167945.39,213510.41,193571.21,185517.41,285186.10000000009,2750000,{"$f":"'B4-FinPerf RE'!K10","v":2750000},{"$f":"'B4-FinPerf RE'!L10","v":2490398},{"$f":"'B4-FinPerf RE'!M10","v":2595969}]
[{"$f":"'B4-FinPerf RE'!A11","v":"Service charges - refuse revenue"},null,872373.13,846251.96,831494.88,831534.26,831613.02,826299.4,829880.3,827320.6,826887.42,826926.8,826966.18,766880.05000000075,9944428,{"$f":"'B4-FinPerf RE'!K11","v":9944428},{"$f":"'B4-FinPerf RE'!L11","v":12474707},{"$f":"'B4-FinPerf RE'!M11","v":13048543}]
[{"$f":"'B4-FinPerf RE'!A12","v":0}]
[{"$f":"'B4-FinPerf RE'!A13","v":"Rental of facilities and equipment"},null,0,6733.89,5961.02,11960.24,4347.83,6264.89,6264.89,6796.24,6530.56,6264.89,6264.89,3610.6600000000035,71000,{"$f":"'B4-FinPerf RE'!K13","v":71000},{"$f":"'B4-FinPerf RE'!L13","v":30000},{"$f":"'B4-FinPerf RE'!M13","v":30000}]
[{"$f":"'B4-FinPerf RE'!A14","v":"Interest earned - external investments"},null,808971.23,888382.53,790016.65,615183.29,473649.02,275193.40999999997,308763.67,191194.23,242781.29,465732.7,4248.0600000000004,1335883.92,6400000,{"$f":"'B4-FinPerf RE'!K14","v":6400000},{"$f":"'B4-FinPerf RE'!L14","v":5400000},{"$f":"'B4-FinPerf RE'!M14","v":5200000}]
[{"$f":"'B4-FinPerf RE'!A15","v":"Interest earned - outstanding debtors"},null,3266140.38,4940732.6500000004,4905912.41,4995257.37,5109808.6399999997,5047745.75,5368175.97,5484528.7400000002,5615294.1799999997,5752875,5938676.3799999999,3151642.5299999937,59576790,{"$f":"'B4-FinPerf RE'!K15","v":59576790},{"$f":"'B4-FinPerf RE'!L15","v":62480550},{"$f":"'B4-FinPerf RE'!M15","v":65354656}]
[{"$f":"'B4-FinPerf RE'!A16","v":"Dividends received"},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B4-FinPerf RE'!K16","v":0},{"$f":"'B4-FinPerf RE'!L16","v":0},{"$f":"'B4-FinPerf RE'!M16","v":0}]
[{"$f":"'B4-FinPerf RE'!A17","v":"Fines, penalties and forfeits"},null,0,0,0,0,0,0,0,0,0,5181000,37000,-1718000,3500000,{"$f":"'B4-FinPerf RE'!K17","v":3500000},{"$f":"'B4-FinPerf RE'!L17","v":3000000},{"$f":"'B4-FinPerf RE'!M17","v":3000000}]
[{"$f":"'B4-FinPerf RE'!A18","v":"Licences and permits"},null,0,0,0,0,0,0,0,0,0,0,0,50000,50000,{"$f":"'B4-FinPerf RE'!K18","v":50000},{"$f":"'B4-FinPerf RE'!L18","v":50000},{"$f":"'B4-FinPerf RE'!M18","v":50000}]
[{"$f":"'B4-FinPerf RE'!A19","v":"Agency services"},null,null,null,null,null,null,null,null,null,null,null,null,0,0,{"$f":"'B4-FinPerf RE'!K19","v":0},{"$f":"'B4-FinPerf RE'!L19","v":0},{"$f":"'B4-FinPerf RE'!M19","v":0}]
[{"$f":"'B4-FinPerf RE'!A20","v":"Transfers and subsidies"},null,178861000,0,0,47761.89,0,80142000,0,0,110321485.8,-2267928.15,65600085.770000003,-58153768.310000002,374550637,{"$f":"'B4-FinPerf RE'!K20","v":374550637},{"$f":"'B4-FinPerf RE'!L20","v":467694767},{"$f":"'B4-FinPerf RE'!M20","v":500553630}]
[{"$f":"'B4-FinPerf RE'!A21","v":"Other revenue"},null,77558.98,300396.17,81010.63,49953.84,668615.62,122618.01,462286.5,39009.370000000003,99170.59,-1532363.24,562015.68000000005,2790227.8499999996,3720500,{"$f":"'B4-FinPerf RE'!K21","v":3720500},{"$f":"'B4-FinPerf RE'!L21","v":2030500},{"$f":"'B4-FinPerf RE'!M21","v":2080500}]
[{"$f":"'B4-FinPerf RE'!A22","v":"Gains"},null,0,0,72776.42,0,0,0,0,0,0,0,0,-72776.42,0,{"$f":"'B4-FinPerf RE'!K22","v":0},{"$f":"'B4-FinPerf RE'!L22","v":0},{"$f":"'B4-FinPerf RE'!M22","v":0}]
["Total Revenue",null,{"$f":"SUM(C6:C10)+SUM(C12:C21)","v":207788194.77000001},{"$f":"SUM(D6:D10)+SUM(D12:D21)","v":30100692.649999999},32875777.280000001,33002332.57,34416012.919999994,113840684.25,33827023.57,33076539.460000001,144195727.20000002,28269145.789999999,95222319.670000017,-12330495.130000025,774283955,774283955,896204683,939767300]
[]
["Expenditure By Type"]
[{"$f":"'B4-FinPerf RE'!A26","v":"Employee related costs"},null,18021255.77,17056466.07,17503042.059999999,17949507.219999999,17970591.780000001,19519560.190000001,18792316.390000001,19929668.829999998,17022437.559999999,18538051.920000002,16269525.720000001,{"$f":"P25-SUM(C25:M25)","v":47979935.869999975},{"$f":"SUM(C25:N25)","v":246552359.38},{"$f":"'B4-FinPerf RE'!K26","v":246552359.38},{"$f":"'B4-FinPerf RE'!L26","v":278331407},{"$f":"'B4-FinPerf RE'!M26","v":293509032}]
[{"$f":"'B4-FinPerf RE'!A27","v":"Remuneration of councillors"},null,1678235.09,1697864.68,1771559.98,1946220.6,1946220.6,1948668.42,0,3928346.39,3940270.6,1968883.11,1968883.12,4876267.41,27671420,{"$f":"'B4-FinPerf RE'!K27","v":27671420},{"$f":"'B4-FinPerf RE'!L27","v":24819114},{"$f":"'B4-FinPerf RE'!M27","v":26060071}]
[{"$f":"'B4-FinPerf RE'!A28","v":"Debt impairment"},null,2898491.39,0,58488.99,43792.92,247219.35,325646.3,50916.4,397205.38,3827.86,143741628.22999999,0,32380983.180000007,180148200,{"$f":"'B4-FinPerf RE'!K28","v":180148200},{"$f":"'B4-FinPerf RE'!L28","v":194602817},{"$f":"'B4-FinPerf RE'!M28","v":195274984}]
[{"$f":"'B4-FinPerf RE'!A29","v":"Depreciation & asset impairment"},null,12878072,12878072,12878072,12878072,12992046.439999999,12878072,12878072,12878072,12878072,-4620515.5199999996,12878072,30262554.079999998,154536733,{"$f":"'B4-FinPerf RE'!K29","v":154536733},{"$f":"'B4-FinPerf RE'!L29","v":133503316},{"$f":"'B4-FinPerf RE'!M29","v":139644469}]
[{"$f":"'B4-FinPerf RE'!A30","v":"Finance charges"},null,1761333.32,0,-1677236.3,118965.11,55473.120000000003,1660719.75,-271618.45,290758.77,245851.9,7944.82,116641.59,1380125.37,3688959,{"$f":"'B4-FinPerf RE'!K30","v":3688959},{"$f":"'B4-FinPerf RE'!L30","v":3043808},{"$f":"'B4-FinPerf RE'!M30","v":2729218}]
[{"$f":"'B4-FinPerf RE'!A31","v":"Bulk purchases"},null,2496852.2200000002,876405.85,8507578.3699999992,2290618,1789733.95,27170865.300000001,1763259.66,10711049.76,20362099.370000001,3220080.56,1989144.55,7967350.4100000113,89145038,{"$f":"'B4-FinPerf RE'!K31","v":89145038},{"$f":"'B4-FinPerf RE'!L31","v":111000000},{"$f":"'B4-FinPerf RE'!M31","v":116106000}]
[{"$f":"'B4-FinPerf RE'!A32","v":"Other materials"},null,15912.17,611277.24,4050.35,3958,185478,81514,14219.28,186082.65,181160.7,3681,125989.8,2013827.83,3427151.02,{"$f":"'B4-FinPerf RE'!K32","v":3427151.02},{"$f":"'B4-FinPerf RE'!L32","v":5127300},{"$f":"'B4-FinPerf RE'!M32","v":5361500}]
[{"$f":"'B4-FinPerf RE'!A33","v":"Contracted services"},null,6096264.2199999997,6745326.0800000001,6955351.6399999997,16758762.859999999,7873047.3799999999,21683735.149999999,7959410.9199999999,3527482.41,16724906.859999999,13268367.689999999,9616518.0199999996,-6167154.1099999994,111042019.11999999,{"$f":"'B4-FinPerf RE'!K33","v":111042019.11999999},{"$f":"'B4-FinPerf RE'!L33","v":121189200},{"$f":"'B4-FinPerf RE'!M33","v":131288734}]
[{"$f":"'B4-FinPerf RE'!A34","v":"Transfers and subsidies"},null,0,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B4-FinPerf RE'!K34","v":0},{"$f":"'B4-FinPerf RE'!L34","v":0},{"$f":"'B4-FinPerf RE'!M34","v":0}]
[{"$f":"'B4-FinPerf RE'!A35","v":"Other expenditure"},null,4936485.9000000004,14332815.98,9059522.7699999996,9118268.0999999996,2696324.21,16152357.699999999,10604420.369999999,2274881.16,10092713.35,6377745.4500000002,6275644.7300000004,-2457311.3700000048,89463868.349999994,{"$f":"'B4-FinPerf RE'!K35","v":89463868.349999994},{"$f":"'B4-FinPerf RE'!L35","v":66888300},{"$f":"'B4-FinPerf RE'!M35","v":70314784}]
[{"$f":"'B4-FinPerf RE'!A36","v":"Losses"},null,0,0,543531.09,0,0,0,701416.27,0,0,0,0,-1244947.3599999999,0,{"$f":"'B4-FinPerf RE'!K36","v":0},{"$f":"'B4-FinPerf RE'!L36","v":0},{"$f":"'B4-FinPerf RE'!M36","v":0}]
["Total Expenditure",null,{"$f":"SUM(C25:C35)","v":50782902.079999998},{"$f":"SUM(D25:D35)","v":54198227.900000006},55603960.950000003,61108164.810000002,45756134.830000006,101421138.80999999,52492412.840000004,54123547.349999994,81451340.199999988,182505867.25999996,49240419.530000001,116991631.30999999,905675747.87,905675747.87,938505262,980288792]
[]
["Surplus/(Deficit)",null,{"$f":"C22-C36","v":157005292.69},-24097535.250000007,-22728183.670000002,-28105832.240000002,-11340121.910000011,12419545.440000013,-18665389.270000003,-21047007.889999993,62744387.00000003,-154236721.46999997,45981900.140000015,-129322126.44000001,-131391792.87,-131391792.87,-42300579,-40521492]
[{"$f":"'B4-FinPerf RE'!A40","v":"Transfers and subsidies - capital (monetary allocations) (National / Provincial and District)"},null,0,0,7084556.2400000002,-4974600.8600000003,0,0,0,0,0,26820952.530000001,15814526.09,{"$f":"P39-SUM(C39:M39)","v":49027884},null,{"$f":"'B4-FinPerf RE'!K40","v":93773318},{"$f":"'B4-FinPerf RE'!L40","v":202495233},{"$f":"'B4-FinPerf RE'!M40","v":218925370}]
[{"$f":"'B4-FinPerf RE'!A41","v":"Transfers and subsidies - capital (monetary allocations) (National / Provincial Departmental Agencies, Households, Non-profit Institutions, Private Enterprises, Public Corporatons, Higher Educational Institutions)"},null,0,0,0,0,0,0,0,0,0,0,0,{"$f":"P40-SUM(C40:M40)","v":112332044.98999999},null,{"$f":"'B4-FinPerf RE'!K41","v":112332044.98999999},{"$f":"'B4-FinPerf RE'!L41","v":0},{"$f":"'B4-FinPerf RE'!M41","v":0}]
[{"$f":"'B4-FinPerf RE'!A42","v":"Transfers and subsidies - capital (in-kind - all) "},null,0,0,22124688.829999998,525399.14,0,0,0,0,0,50147277.090000004,0,{"$f":"P41-SUM(C41:M41)","v":-72797365.060000002},null,{"$f":"'B4-FinPerf RE'!K42","v":0},{"$f":"'B4-FinPerf RE'!L42","v":0},{"$f":"'B4-FinPerf RE'!M42","v":0}]
["Surplus/(Deficit) after capital transfers & contributions",null,{"$f":"C38+SUM(C39:C41)","v":157005292.69},{"$f":"D38+SUM(D39:D41)","v":-24097535.250000007},6481061.3999999985,-32555033.960000001,-11340121.910000011,12419545.440000013,-18665389.270000003,-21047007.889999993,62744387.00000003,-77268491.849999964,61796426.230000019,-40759562.510000005,-131391792.87,{"$f":"P38+SUM(P39:P41)","v":74713570.120000005},160194654,178403878]
[{"$f":"head27a","v":"References"}]
["1. Surplus (Deficit) must reconcile with budget table A4 and monthly budget statement table C4"]
["check",null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"P42-'B4-FinPerf RE'!K43","v":0},{"$f":"Q42-'B4-FinPerf RE'!L43","v":0},{"$f":"R42-'B4-FinPerf RE'!M43","v":0}]

{"sheet":"SB15","index":33,"n_rows":64,"n_cols":18,"rows_kept":64,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,15,1,17],[1,1,2,1],[1,2,1,13]]}
[{"$f":"muni&\" - \"&ADJB15&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB15 Adjustments Budget - monthly cash flow - 44171"}]
["Monthly cash flows",{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Head3a","v":"Medium Term Revenue and Expenditure Framework"}]
[null,null,"July","August","Sept.","October","November","December","January","February","March","April","May","June","Full year budget",{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
["R thousands",null,"Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Budget",null,{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["Cash Receipts By Source",1]
["Property rates",null,3273904.34,2443951,27420215,4928898.8499999996,2741124.07,2755115,2758238,3167004,3142036,2175696,2175696,{"$f":"P6-SUM(C6:M6)","v":21208101.740000002},{"$f":"SUM(C6:N6)","v":78189980},78189980,{"$f":"P6*5%+P6","v":82099479},{"$f":"Q6*5%+Q6","v":86204452.950000003}]
["Service charges - electricity revenue",null,0,0,0,0,0,0,0,0,0,null,null,0,0,0]
["Service charges - water revenue",null,4974330.2300000004,4346819,2115580,10268405.23,7095235.2199999997,6624913,4220093,8539976,5190118,2858936,761372,-12390977.68,44604800,44604800,{"$f":"P8*5%+P8","v":46835040},49176792]
["Service charges - sanitation revenue",null,43073.05,20190,23243,61719.72,112432.42,130573,33921,371477,16276,32566,9017,3273011.81,4127500,{"$f":"75500+4052000","v":4127500},{"$f":"P9*5%+P9","v":4333875},4550568.75]
["Service charges - refuse",null,48775.75,20336,28609,37063.15,55535.77,37328,35062,42703,19068,17602,9809,3728428.33,4080320,{"$f":"28320+4052000","v":4080320},{"$f":"P10*5%+P10","v":4284336},4498552.8]
[]
["Rental of facilities and equipment",null,0,7000,0,11960.24,4347.83,0,6265,6796,6531,6265,6265,-55430.07,0,0]
["Interest earned - external investments",null,461609,888383,23922,615183.29,473649.02,275193,308764,191194,242781,458616,4248,1456457.69,5400000,5400000,{"$f":"P13*5%+P13","v":5670000},5953500]
["Interest earned - outstanding debtors",null,15000,15000,15000,15000,15000,15000,15000,371477,16276,32566,9017,65664,600000,600000,{"$f":"P14*5%+P14","v":630000},661500]
["Dividends received",null,null,null,null,null,null,null,null,null,null,null,null,0,0]
["Fines, penalties and forfeits",null,0,0,0,0,0,0,0,0,0,null,null,0,0,0]
["Licences and permits",null,0,0,0,0,0,0,0,0,0,null,null,0,0,0]
["Agency services",null,null,null,null,null,null,null,null,null,null,null,null,0,0]
["Transfers and Subsidies - Operational",null,178861000,2124000,0,1483761.89,4355480,80142000,null,0,107317000,0,268000,245.11000001430511,374551487,374551487,467331000,502264000]
["Other revenue",null,405568,null,0,2339243,null,0,462287,0,0,null,null,69056,3276154,3276154,{"$f":"P20*5%+P20","v":3439961.7},3611959.7850000001]
["Cash Receipts by Source",null,{"$f":"SUM(C6:C10)+SUM(C12:C20)","v":188083260.37},{"$f":"SUM(D6:D10)+SUM(D12:D20)","v":9865679},29626569,19761235.370000001,14852804.329999998,89980122,7839630,12690627,115950086,5582247,3243424,17354556.930000018,514830241,514830241,614623691.70000005,656921326.28500009]
[]
["Other Cash Flows by Source"]
[{"$f":"'B4-FinPerf RE'!A40","v":"Transfers and subsidies - capital (monetary allocations) (National / Provincial and District)"},null,66506000,11000000,0,0,0,27500000,0,0,101099000,0,0,{"$f":"P24-SUM(C24:M24)","v":0},{"$f":"SUM(C24:N24)","v":206105000},206105000,211771000,227138000]
[{"$f":"'B4-FinPerf RE'!A41","v":"Transfers and subsidies - capital (monetary allocations) (National / Provincial Departmental Agencies, Households, Non-profit Institutions, Private Enterprises, Public Corporatons, Higher Educational Institutions)"},null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"SUM(C25:N25)","v":0}]
["Proceeds on Disposal of Fixed and Intangible Assets",null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"SUM(C26:N26)","v":0}]
["Short term loans",null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"SUM(C27:N27)","v":0}]
["Borrowing long term/refinancing",null,null,null,null,null,null,null,null,null,null,null,null,0]
["Increase (decrease) in consumer deposits",null,0,0,0,0,0,0,0,0,0,0,0,0,null,0,0,0]
[]
["Decrease (increase) in non-current receivables",null,null,null,null,null,null,null,null,null,null,null,null,0]
["Decrease (increase) in non-current investments",null,0,0,0,0,0,0,0,0,0,0,0,0,null,0,0,0]
["Total Cash Receipts by Source",null,{"$f":"SUM(C21:C29)+SUM(C31:C32)","v":254589260.37},{"$f":"SUM(D21:D29)+SUM(D31:D32)","v":20865679},29626569,19761235.370000001,14852804.329999998,117480122,7839630,12690627,217049086,5582247,3243424,17354556.930000018,720935241,720935241,826394691.70000005,884059326.28500009]
[]
["Cash Payments by Type"]
["Employee related costs",null,18021255.77,17056466.07,17503042.059999999,17949507.219999999,17970591.780000001,19519560.190000001,18792316.390000001,19929668.829999998,17022437.559999999,18538051.920000002,16269525.720000001,{"$f":"P36-SUM(C36:M36)","v":47979935.48999998},{"$f":"SUM(C36:N36)","v":246552359},246552359,278331407,293509032]
["Remuneration of councillors",null,1678235.09,1697864.68,1771559.98,1946220.6,1946220.6,1948668.42,0,3928346.39,3940270.6,1968883.11,1968883.12,4876267.41,27671420,27671420,24819114,26060071]
["Finance charges",null,1761333.32,0,-1677236.3,118965.11,55473.120000000003,1660719.75,-271618.45,290758.77,245851.9,7944.82,116641.59,1380125.37,3688959,3688959,3043808,2729218]
["Bulk purchases - Electricity",null,2496852.2200000002,876405.85,2446529.56,2290618,1789733.95,1781638.64,1763259.66,1645905.11,1806623.62,3220080.56,1989144.55,-3961753.7199999988,18145038,18145038,11000000,11506000]
["Bulk purchases - Water & Sewer",null,0,0,6061048.8099999996,0,0,25389226.66,0,9065144.6500000004,18555475.75,0,0,11929104.130000003,71000000,71000000,100000000,104600000]
["Other materials",null,15912.17,611277.24,4050.35,3958,185478,81514,14219.28,186082.65,181160.7,3681,125989.8,2013827.81,3427151,3427151,5127300,5361500]
["Contracted services",null,6096264.2199999997,6745326.0800000001,6955351.6399999997,16758762.859999999,7873047.3799999999,21683735.149999999,7959410.9199999999,3527482.41,16724906.859999999,13268367.689999999,9616518.0199999996,-6167154.2299999893,null,111042019,121189200,131288734]
["Transfers and grants - other municipalities",null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"SUM(C43:N43)","v":0}]
["Transfers and grants - other",null,0,0,0,0,0,0,0,0,0,0,0,0,null,0,0,0]
["Other expenditure",null,4936485.9000000004,14332815.98,9059522.7699999996,9118268.0999999996,2696324.21,16152357.699999999,10604420.369999999,2274881.16,10092713.35,6377745.4500000002,6275644.7300000004,-2457311.7199999988,{"$f":"SUM(C45:N45)","v":89463868},89463868,66888300,70314784]
["Cash Payments by Type",null,{"$f":"SUM(C36:C45)","v":35006338.689999998},41320155.900000006,42123868.869999997,48186299.890000001,32516869.040000003,88217420.510000005,38862008.170000002,40848269.969999999,68569440.340000004,43384754.550000004,36362347.530000001,55593040.539999992,459948795,570990814,610399129,645369339]
[]
["Other Cash Flows/Payments by Type"]
["Capital assets",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"P49-SUM(C49:M49)","v":0},{"$f":"SUM(C49:N49)","v":0}]
["Repayment of borrowing",null,2813354.93,15970.52,2691838.59,137703.43,-39502.6,-1644749.23,4847994.07,-275008.67,768529.97,7305.2,138838.20000000001,{"$f":"P50-SUM(C50:M50)","v":-17422274.41},{"$f":"SUM(C50:N50)","v":-7960000},-7960000,-8425000,-8722000]
["Other Cash Flows/Payments",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"P51-SUM(C51:M51)","v":0},{"$f":"SUM(C51:N51)","v":0}]
["Total Cash Payments by Type",null,{"$f":"SUM(C46:C51)","v":37819693.619999997},41336126.420000009,44815707.459999993,48324003.32,32477366.440000001,86572671.280000001,43710002.240000002,40573261.299999997,69337970.310000002,43392059.750000007,36501185.730000004,38170766.129999995,451988795,563030814,601974129,636647339]
[]
["NET INCREASE/(DECREASE) IN CASH HELD",null,{"$f":"C33-C52","v":216769566.75},-20470447.420000009,-15189138.459999993,-28562767.949999999,-17624562.110000003,30907450.719999999,-35870372.240000002,-27882634.299999997,147711115.69,-37809812.750000007,-33257761.730000004,-20816209.199999977,268946446,157904427,224420562.70000005,247411987.28500009]
["Cash/cash equivalents at the month/year beginning:",null,0,0,0,0,0,0,0,0,0,0,0,{"$f":"M56","v":-33257761.730000004},null,24377000,18712753,24851089]
["Cash/cash equivalents at the month/year end:",null,{"$f":"C54+C55","v":216769566.75},-20470447.420000009,-15189138.459999993,-28562767.949999999,-17624562.110000003,30907450.719999999,-35870372.240000002,-27882634.299999997,147711115.69,-37809812.750000007,-33257761.730000004,-54073970.929999977,null,{"$f":"P54+P55","v":182281427},{"$f":"Q54+Q55","v":243133315.70000005},{"$f":"R54+R55","v":272263076.28500009}]
["References"]
["1. Note that this section of Table SB15 is deliberately not linked to Table B4 because timing differences between the invoicing of clients and receiving the cash means that the cashflow will differ from budgeted revenue, and similarly for budgeted expenditure. "]
[]
[]
[]
[]
[null,null,null,null,null,{"$f":"F46+F62","v":48186299.890000001},32516869.040000003,88217420.510000005,38862008.170000002,40848269.969999999,68569440.340000004,43384754.550000004,36362347.530000001,55593040.539999992,459948795,570990814,610399129,645369339]
[null,null,null,null,null,{"$f":"F54-F62","v":-28562767.949999999},-17624562.110000003,30907450.719999999,-35870372.240000002,-27882634.299999997,147711115.69,-37809812.750000007,-33257761.730000004,-20816209.199999977,268946446,157904427,224420562.70000005,247411987.28500009]

{"sheet":"SB16","index":34,"n_rows":45,"n_cols":18,"rows_kept":45,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,1,2,1]]}
[{"$f":"muni&\" - \"&ADJB16&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB16 Adjustments Budget - monthly capital expenditure (municipal vote) - 44171"}]
[{"$f":"desc&\" - Municipal Vote\"","v":"Description - Municipal Vote"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,null,null,null,null,"Medium Term Revenue and Expenditure Framework"]
[null,null,"July","August","Sept.","October","November","December","January","February","March","April","May","June","Full year budget",{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
["R thousands",null,"Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Adjusted Budget",null,{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["Multi-year expenditure appropriation",1]
[{"$f":"'B5-Capex'!A8","v":"Vote 01 - Municipal Council"},null,0,0,0,0,0,0,0,0,0,0,0,{"$f":"P6-SUM(C6:M6)","v":0},null,{"$f":"'B5-Capex'!K8","v":0},{"$f":"'B5-Capex'!L8","v":0},{"$f":"'B5-Capex'!M8","v":0}]
[{"$f":"'B5-Capex'!A9","v":"Vote 02 - Office Of The Accounting Officer"},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K9","v":0},{"$f":"'B5-Capex'!L9","v":0},{"$f":"'B5-Capex'!M9","v":0}]
[{"$f":"'B5-Capex'!A10","v":"Vote 03 - Budget And Treasury Office"},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K10","v":0},{"$f":"'B5-Capex'!L10","v":0},{"$f":"'B5-Capex'!M10","v":0}]
[{"$f":"'B5-Capex'!A11","v":"Vote 04 - Corporate Services"},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K11","v":0},{"$f":"'B5-Capex'!L11","v":0},{"$f":"'B5-Capex'!M11","v":0}]
[{"$f":"'B5-Capex'!A12","v":"Vote 05 - Community Services"},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K12","v":0},{"$f":"'B5-Capex'!L12","v":0},{"$f":"'B5-Capex'!M12","v":0}]
[{"$f":"'B5-Capex'!A13","v":"Vote 06 - Planning & Development"},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K13","v":0},{"$f":"'B5-Capex'!L13","v":0},{"$f":"'B5-Capex'!M13","v":0}]
[{"$f":"'B5-Capex'!A14","v":"Vote 07 - Infrastructure & Technical Services"},null,456868.82,9014292.5800000001,5920539.3899999997,8552451.4900000002,3552017.91,8531454.0800000001,5825218.2599999998,1833798.51,7099300.2199999997,-5202217.78,2165930.23,30040848.310000002,null,{"$f":"'B5-Capex'!K14","v":77790502.019999996},{"$f":"'B5-Capex'!L14","v":11375458},{"$f":"'B5-Capex'!M14","v":17503825}]
[{"$f":"'B5-Capex'!A15","v":"Vote 08 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K15","v":0},{"$f":"'B5-Capex'!L15","v":0},{"$f":"'B5-Capex'!M15","v":0}]
[{"$f":"'B5-Capex'!A16","v":"Vote 09 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K16","v":0},{"$f":"'B5-Capex'!L16","v":0},{"$f":"'B5-Capex'!M16","v":0}]
[{"$f":"'B5-Capex'!A17","v":"Vote 10 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K17","v":0},{"$f":"'B5-Capex'!L17","v":0},{"$f":"'B5-Capex'!M17","v":0}]
[{"$f":"'B5-Capex'!A18","v":"Vote 11 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K18","v":0},{"$f":"'B5-Capex'!L18","v":0},{"$f":"'B5-Capex'!M18","v":0}]
[{"$f":"'B5-Capex'!A19","v":"Vote 12 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K19","v":0},{"$f":"'B5-Capex'!L19","v":0},{"$f":"'B5-Capex'!M19","v":0}]
[{"$f":"'B5-Capex'!A20","v":"Vote 13 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K20","v":0},{"$f":"'B5-Capex'!L20","v":0},{"$f":"'B5-Capex'!M20","v":0}]
[{"$f":"'B5-Capex'!A21","v":"Vote 14 - "},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K21","v":0},{"$f":"'B5-Capex'!L21","v":0},{"$f":"'B5-Capex'!M21","v":0}]
[{"$f":"'B5-Capex'!A22","v":"Vote 15 - Other"},null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K22","v":0},{"$f":"'B5-Capex'!L22","v":0},{"$f":"'B5-Capex'!M22","v":0}]
["Capital Multi-year expenditure sub-total",3,{"$f":"SUM(C6:C20)","v":456868.82},9014292.5800000001,5920539.3899999997,8552451.4900000002,3552017.91,8531454.0800000001,5825218.2599999998,1833798.51,7099300.2199999997,-5202217.78,2165930.23,30040848.310000002,0,77790502.019999996,11375458,17503825]
[null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"SUM(N7:N21)","v":60081696.620000005},{"$f":"SUM(O7:O21)","v":0},{"$f":"SUM(P7:P21)","v":155581004.03999999},{"$f":"SUM(Q7:Q21)","v":22750916},{"$f":"SUM(R7:R21)","v":35007650}]
["Single-year expenditure appropriation"]
[{"$f":"A6","v":"Vote 01 - Municipal Council"},null,0,0,0,0,0,0,0,0,0,0,0,{"$f":"P24-SUM(C24:M24)","v":0},null,{"$f":"'B5-Capex'!K26","v":0},{"$f":"'B5-Capex'!L26","v":0},{"$f":"'B5-Capex'!M26","v":0}]
["Vote 02 - Office Of The Accounting Officer",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K27","v":0},{"$f":"'B5-Capex'!L27","v":0},{"$f":"'B5-Capex'!M27","v":0}]
["Vote 03 - Budget And Treasury Office",null,0,0,0,25850,0,0,0,0,0,0,0,-25849.99,null,{"$f":"'B5-Capex'!K28","v":0.01},{"$f":"'B5-Capex'!L28","v":0},{"$f":"'B5-Capex'!M28","v":0}]
["Vote 04 - Corporate Services",null,0,0,0,0,0,0,0,0,0,113974.44,0,0.58999999999650754,null,{"$f":"'B5-Capex'!K29","v":113975.03},{"$f":"'B5-Capex'!L29","v":0},{"$f":"'B5-Capex'!M29","v":0}]
["Vote 05 - Community Services",null,0,3337610.81,1735134.19,1305556.7,3601458.83,4022570.62,2265453.85,2266405,1219126.72,-1341046.44,1296771.51,11017712.240000006,null,{"$f":"'B5-Capex'!K30","v":30726754.030000005},{"$f":"'B5-Capex'!L30","v":12864475},{"$f":"'B5-Capex'!M30","v":27104155}]
["Vote 06 - Planning & Development",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K31","v":0},{"$f":"'B5-Capex'!L31","v":0},{"$f":"'B5-Capex'!M31","v":0}]
["Vote 07 - Infrastructure & Technical Services",null,0,3030062.57,0,0,5183333.33,7432748.3600000003,4089569.34,5030408.91,3184890.78,10335281.58,3884376.53,55417434.699999988,null,{"$f":"'B5-Capex'!K32","v":97588106.099999994},{"$f":"'B5-Capex'!L32","v":178255300},{"$f":"'B5-Capex'!M32","v":174317389}]
["Vote 08 - ",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K33","v":0},{"$f":"'B5-Capex'!L33","v":0},{"$f":"'B5-Capex'!M33","v":0}]
["Vote 09 - ",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K34","v":0},{"$f":"'B5-Capex'!L34","v":0},{"$f":"'B5-Capex'!M34","v":0}]
["Vote 10 - ",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K35","v":0},{"$f":"'B5-Capex'!L35","v":0},{"$f":"'B5-Capex'!M35","v":0}]
["Vote 11 - ",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K36","v":0},{"$f":"'B5-Capex'!L36","v":0},{"$f":"'B5-Capex'!M36","v":0}]
["Vote 12 - ",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K37","v":0},{"$f":"'B5-Capex'!L37","v":0},{"$f":"'B5-Capex'!M37","v":0}]
["Vote 13 - ",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K38","v":0},{"$f":"'B5-Capex'!L38","v":0},{"$f":"'B5-Capex'!M38","v":0}]
["Vote 14 - ",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K39","v":0},{"$f":"'B5-Capex'!L39","v":0},{"$f":"'B5-Capex'!M39","v":0}]
["Vote 15 - Other",null,0,0,0,0,0,0,0,0,0,0,0,0,null,{"$f":"'B5-Capex'!K40","v":0},{"$f":"'B5-Capex'!L40","v":0},{"$f":"'B5-Capex'!M40","v":0}]
["Capital single-year expenditure sub-total",3,{"$f":"SUM(C24:C38)","v":0},{"$f":"SUM(D24:D38)","v":6367673.3799999999},1735134.19,1331406.7,8784792.1600000001,11455318.98,6355023.1899999995,7296813.9100000001,4404017.5,9108209.5800000001,5181148.04,66409297.539999992,0,128428835.17,191119775,201421544]
["Total Capital Expenditure",2,{"$f":"C21+C39","v":456868.82},{"$f":"D21+D39","v":15381965.960000001},7655673.5800000001,9883858.1899999995,12336810.07,19986773.060000002,12180241.449999999,9130612.4199999999,11503317.719999999,3905991.8,7347078.2699999996,96450145.849999994,0,206219337.19,202495233,218925369]
[{"$f":"head27a","v":"References"}]
["1. Table should be completed as either Multi-Year expenditure appropriation or Budget Year and Forward Year estimates"]
["2. Total Capital Expenditure must reconcile to budget table A5 and monthly budget statement table C5"]
[]
["check",null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"O40-'B5-Capex'!J42","v":-113975},{"$f":"P40-'B5-Capex'!K42","v":0},{"$f":"Q40-'B5-Capex'!L42","v":0},{"$f":"R40-'B5-Capex'!M42","v":0}]

{"sheet":"SB17","index":35,"n_rows":31,"n_cols":17,"rows_kept":31,"cut":false,"hidden":false,"merged":[[1,0,2,0],[1,1,2,1],[1,2,1,13]]}
[{"$f":"muni&\" - \"&ADJB17&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB17 Adjustments Budget - monthly capital expenditure (functional classification) - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,null,null,null,{"$f":"Head3a","v":"Medium Term Revenue and Expenditure Framework"}]
[null,null,"July","August","Sept.","October","November","December","January","February","March","April","May","June",{"$f":"Head9","v":"Budget Year 2019/20"},{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
["R thousands",null,"Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Outcome","Budget",{"$f":"Head7","v":"Adjusted Budget"},"Adjusted Budget","Adjusted Budget"]
["Capital Expenditure - Functional"]
[{"$f":"'B2-FinPerf SC'!A7","v":"Governance and administration"},null,{"$f":"SUM(C7:C9)","v":0},0,0,25850,0,0,0,0,0,113974.44,0,{"$f":"O6-SUM(C6:M6)","v":-25849.400000000009},{"$f":"'B5-Capex'!K45","v":113975.03999999999},{"$f":"'B5-Capex'!L45","v":0},{"$f":"'B5-Capex'!M45","v":0}]
[{"$f":"'B2-FinPerf SC'!A8","v":"Executive and council"},null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"'B5-Capex'!K46","v":0},{"$f":"'B5-Capex'!L46","v":0},{"$f":"'B5-Capex'!M46","v":0}]
[{"$f":"'B2-FinPerf SC'!A9","v":"Finance and administration"},null,0,0,0,25850,0,0,0,0,0,113974.44,0,-25849.400000000009,{"$f":"'B5-Capex'!K47","v":113975.03999999999},{"$f":"'B5-Capex'!L47","v":0},{"$f":"'B5-Capex'!M47","v":0}]
[{"$f":"'B2-FinPerf SC'!A10","v":"Internal audit"},null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"'B5-Capex'!K48","v":0},{"$f":"'B5-Capex'!L48","v":0},{"$f":"'B5-Capex'!M48","v":0}]
[{"$f":"'B2-FinPerf SC'!A11","v":"Community and public safety"},null,{"$f":"SUM(C11:C15)","v":0},2888749.07,1735134.19,1305556.7,2483756.27,2745683.45,2265453.85,1069906,1219126.72,2941874.2,1296771.51,10774742.060000002,{"$f":"'B5-Capex'!K49","v":30726754.020000003},{"$f":"'B5-Capex'!L49","v":9864475},{"$f":"'B5-Capex'!M49","v":8000000}]
[{"$f":"'B2-FinPerf SC'!A12","v":"Community and social services"},null,0,2888749.07,1735134.19,1305556.7,2483756.27,2745683.45,2265453.85,1069906,1219126.72,2941874.2,1296771.51,10774742.050000001,{"$f":"'B5-Capex'!K50","v":30726754.010000002},{"$f":"'B5-Capex'!L50","v":0},{"$f":"'B5-Capex'!M50","v":8000000}]
[{"$f":"'B2-FinPerf SC'!A13","v":"Sport and recreation"},null,0,0,0,0,0,0,0,0,0,0,0,0.01,{"$f":"'B5-Capex'!K51","v":0.01},{"$f":"'B5-Capex'!L51","v":9864475},{"$f":"'B5-Capex'!M51","v":0}]
[{"$f":"'B2-FinPerf SC'!A14","v":"Public safety"},null,0,0,0,0,0,0,0,0,0,0,0,0,{"$f":"'B5-Capex'!K52","v":0},{"$f":"'B5-Capex'!L52","v":0},{"$f":"'B5-Capex'!M52","v":0}]
[{"$f":"'B2-FinPerf SC'!A15","v":"Housing"},null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"'B5-Capex'!K53","v":0},{"$f":"'B5-Capex'!L53","v":0},{"$f":"'B5-Capex'!M53","v":0}]
[{"$f":"'B2-FinPerf SC'!A16","v":"Health"},null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"'B5-Capex'!K54","v":0},{"$f":"'B5-Capex'!L54","v":0},{"$f":"'B5-Capex'!M54","v":0}]
[{"$f":"'B2-FinPerf SC'!A17","v":"Economic and environmental services"},null,{"$f":"SUM(C17:C19)","v":0},2451472.54,0,4524256.3,2343798.92,5637406.1200000001,5825218.2599999998,1833798.51,5718363.4500000002,2890651.01,2031106.7,27932245.199999999,{"$f":"'B5-Capex'!K55","v":61188317.009999998},{"$f":"'B5-Capex'!L55","v":60981783},{"$f":"'B5-Capex'!M55","v":60000000}]
[{"$f":"'B2-FinPerf SC'!A18","v":"Planning and development"},null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"'B5-Capex'!K56","v":0},{"$f":"'B5-Capex'!L56","v":0},{"$f":"'B5-Capex'!M56","v":0}]
[{"$f":"'B2-FinPerf SC'!A19","v":"Road transport"},null,0,2451472.54,0,4524256.3,2343798.92,5637406.1200000001,5825218.2599999998,1833798.51,5718363.4500000002,2890651.01,2031106.7,27932245.199999999,{"$f":"'B5-Capex'!K57","v":61188317.009999998},{"$f":"'B5-Capex'!L57","v":60981783},{"$f":"'B5-Capex'!M57","v":60000000}]
[{"$f":"'B2-FinPerf SC'!A20","v":"Environmental protection"},null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"'B5-Capex'!K58","v":0},{"$f":"'B5-Capex'!L58","v":0},{"$f":"'B5-Capex'!M58","v":0}]
[{"$f":"'B2-FinPerf SC'!A21","v":"Trading services"},null,{"$f":"SUM(C21:C24)","v":456868.82},{"$f":"SUM(D21:D24)","v":10041744.35},5920539.3899999997,4028195.19,7509254.8800000008,11603683.49,4089569.34,6226907.9100000001,4565827.5500000007,-2040507.8499999996,4019200.06,57769007.990000017,{"$f":"'B5-Capex'!K59","v":114190291.12000002},{"$f":"'B5-Capex'!L59","v":131648975},{"$f":"'B5-Capex'!M59","v":150925369}]
[{"$f":"'B2-FinPerf SC'!A22","v":"Energy sources"},null,0,1696594.03,0,0,0,3386232.18,1027200,794832.3,1322512.74,275947.32,1898325.87,10015328.59,{"$f":"'B5-Capex'!K60","v":20416973.030000001},{"$f":"'B5-Capex'!L60","v":11577740},{"$f":"'B5-Capex'!M60","v":12557370}]
[{"$f":"'B2-FinPerf SC'!A23","v":"Water management"},null,456868.82,7320391.9100000001,5920539.3899999997,4028195.19,3540501.28,6045397.71,2865654.6,3678659.75,2878999.45,1510345.9,1695330.3,41340197.710000001,{"$f":"'B5-Capex'!K61","v":81281082.010000005},{"$f":"'B5-Capex'!L61","v":91183878},{"$f":"'B5-Capex'!M61","v":94263844}]
[{"$f":"'B2-FinPerf SC'!A24","v":"Waste water management"},null,0,575896.67000000004,0,0,2851051.04,895166.43,196714.74,556916.86,364315.36,456119.57,425543.89,6170511.5099999998,{"$f":"'B5-Capex'!K62","v":12492236.07},{"$f":"'B5-Capex'!L62","v":25887357},{"$f":"'B5-Capex'!M62","v":25000000}]
[{"$f":"'B2-FinPerf SC'!A25","v":"Waste management"},null,0,448861.74,0,0,1117702.56,1276887.17,0,1196499,0,-4282920.6399999997,0,242970.17999999993,{"$f":"'B5-Capex'!K63","v":0.01},{"$f":"'B5-Capex'!L63","v":3000000},{"$f":"'B5-Capex'!M63","v":19104155}]
[{"$f":"'B2-FinPerf SC'!A26","v":"Other"},null,null,null,null,null,null,null,null,null,null,null,null,0,{"$f":"'B5-Capex'!K64","v":0},{"$f":"'B5-Capex'!L64","v":0},{"$f":"'B5-Capex'!M64","v":0}]
["Total Capital Expenditure - Functional",null,{"$f":"C6+C10+C16+C20+C25","v":456868.82},{"$f":"D6+D10+D16+D20+D25","v":15381965.959999999},7655673.5800000001,9883858.1899999995,12336810.07,19986773.060000002,12180241.449999999,9130612.4199999999,11503317.720000001,3905991.8000000007,7347078.2699999996,96450145.850000024,{"$f":"O6+O10+O16+O20+O25","v":206219337.19},{"$f":"P6+P10+P16+P20+P25","v":202495233},{"$f":"Q6+Q10+Q16+Q20+Q25","v":218925369}]
[{"$f":"head27a","v":"References"}]
["1. Table should be completed as either Multi-Year expenditure appropriation or Budget Year and Forward Year estimates"]
["2. Total Capital Expenditure must reconcile to the 'Financial Position' budget and monthly budget statement"]
[]
["check",null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"O26-'B5-Capex'!K65","v":0},{"$f":"P26-'B5-Capex'!L65","v":0},{"$f":"Q26-'B5-Capex'!M65","v":0}]

{"sheet":"SB18a","index":36,"n_rows":183,"n_cols":13,"rows_kept":183,"cut":false,"hidden":false,"merged":[[1,0,3,0],[177,0,177,12],[179,0,179,12],[172,0,172,12],[173,0,173,9],[174,0,174,9],[175,0,175,12],[1,2,1,10],[1,1,3,1]]}
[{"$f":"muni&\" - \"&ADJB18a&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB18a Adjustments Budget - capital expenditure on new assets by asset class - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,7,8,9,10,11,12,13,14]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Capital expenditure on new assets by Asset Class/Sub-class"]
[]
["Infrastructure",null,{"$f":"C9+C14+C18+C28+C39+C46+C54+C64+C70","v":133361894},{"$f":"D9+D14+D18+D28+D39+D46+D54+D64+D70","v":103266698.13000001},0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":103266698.13000001},{"$f":"L9+L14+L18+L28+L39+L46+L54+L64+L70","v":131648975},{"$f":"M9+M14+M18+M28+M39+M46+M54+M64+M70","v":150925369}]
["Roads Infrastructure",null,{"$f":"SUM(C10:C13)","v":0},{"$f":"SUM(D10:D13)","v":0},0,0,0,0,0,{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":0},0,0]
["Roads",null,0,0,0,0,0,0,0,0,0,0,0]
["Road Structures",null,null,null,null,null,null,null,null,0,0]
["Road Furniture",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Storm water Infrastructure",null,{"$f":"SUM(C15:C17)","v":6193238},0.01,0,0,0,0,0,0,0.01,{"$f":"SUM(L15:L17)","v":0},{"$f":"SUM(M15:M17)","v":0}]
["Drainage Collection",null,6193238,0.01,0,0,0,0,0,0,0.01,0,0]
["Storm water Conveyance",null,null,null,null,null,null,null,null,0,0]
["Attenuation",null,null,null,null,null,null,null,null,0,0]
["Electrical Infrastructure",null,{"$f":"SUM(C19:C27)","v":22445688},20416973.030000001,0,0,0,0,0,0,20416973.030000001,11577740,12557370]
["Power Plants",null,null,null,null,null,null,null,null,0,0]
["HV Substations",null,null,null,null,null,null,null,null,0,0]
["HV Switching Station",null,null,null,null,null,null,null,null,0,0]
["HV Transmission Conductors",null,null,null,null,null,null,null,null,0,0]
["MV Substations",null,null,null,null,null,null,null,null,0,0]
["MV Switching Stations",null,null,null,null,null,null,null,null,0,0]
["MV Networks",null,null,null,null,null,null,null,null,0,0]
["LV Networks",null,22445688,20416973.030000001,0,0,0,0,0,0,20416973.030000001,11577740,12557370]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Water Supply Infrastructure",null,{"$f":"SUM(C29:C38)","v":64814603},70357489.010000005,0,0,0,0,0,0,70357489.010000005,91183878,94263844]
["Dams and Weirs",null,null,null,null,null,null,null,null,0,0]
["Boreholes",null,null,null,null,null,null,null,null,0,0]
["Reservoirs",null,0,0,0,0,0,0,0,0,0,0,0]
["Pump Stations",null,null,null,null,null,null,null,null,0,0]
["Water Treatment Works",null,null,null,null,null,null,null,null,0,0]
["Bulk Mains",null,0,0,0,0,0,0,0,0,0,0,0]
["Distribution",null,64814603,70357489.010000005,0,0,0,0,0,0,70357489.010000005,91183878,94263844]
["Distribution Points",null,null,null,null,null,null,null,null,0,0]
["PRV Stations",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Sanitation Infrastructure",null,{"$f":"SUM(C40:C45)","v":24111456},12492236.07,0,0,0,0,0,0,12492236.07,25887357,25000000]
["Pump Station",null,null,null,null,null,null,null,null,0,0]
["Reticulation",null,null,null,null,null,null,null,null,0,0]
["Waste Water Treatment Works",null,null,null,null,null,null,null,null,0,0]
["Outfall Sewers",null,null,null,null,null,null,null,null,0,0]
["Toilet Facilities",null,24111456,12492236.07,0,0,0,0,0,0,12492236.07,25887357,25000000]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Infrastructure",null,{"$f":"SUM(C47:C53)","v":15796909},0.01,0,0,0,0,0,0,0.01,3000000,19104155]
["Landfill Sites",null,15796909,0.01,0,0,0,0,0,0,0.01,3000000,19104155]
["Waste Transfer Stations",null,null,null,null,null,null,null,null,0,0]
["Waste Processing Facilities",null,null,null,null,null,null,null,null,0,0]
["Waste Drop-off Points",null,null,null,null,null,null,null,null,0,0]
["Waste Separation Facilities",null,null,null,null,null,null,null,null,0,0]
["Electricity Generation Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Rail Infrastructure",null,{"$f":"SUM(C55:C63)","v":0},0,0,0,0,0,0,0,0,0,0]
["Rail Lines",null,null,null,null,null,null,null,null,0,0]
["Rail Structures",null,null,null,null,null,null,null,null,0,0]
["Rail Furniture",null,null,null,null,null,null,null,null,0,0]
["Drainage Collection",null,null,null,null,null,null,null,null,0,0]
["Storm water Conveyance",null,null,null,null,null,null,null,null,0,0]
["Attenuation",null,null,null,null,null,null,null,null,0,0]
["MV Substations",null,null,null,null,null,null,null,null,0,0]
["LV Networks",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Coastal Infrastructure",null,{"$f":"SUM(C65:C69)","v":0},0,0,0,0,0,0,0,0,0,0]
["Sand Pumps",null,null,null,null,null,null,null,null,0,0]
["Piers",null,null,null,null,null,null,null,null,0,0]
["Revetments",null,null,null,null,null,null,null,null,0,0]
["Promenades",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Information and Communication Infrastructure",null,{"$f":"SUM(C71:C74)","v":0},0,0,0,0,0,0,0,0,0,0]
["Data Centres",null,null,null,null,null,null,null,null,0,0]
["Core Layers",null,null,null,null,null,null,null,null,0,0]
["Distribution Layers",null,null,null,null,null,null,null,null,{"$f":"SUM(E73:I73)","v":0},{"$f":"IF(D73=0,C73+J73,D73+J73)","v":0}]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Community Assets",null,{"$f":"+C77+C100","v":0},{"$f":"+D77+D100","v":0},{"$f":"+E77+E100","v":0},0,0,0,0,0,0,0,0]
["Community Facilities",null,{"$f":"SUM(C78:C99)","v":0},{"$f":"SUM(D78:D99)","v":0},{"$f":"SUM(E78:E99)","v":0},0,0,0,0,0,0,0,0]
["Halls",null,null,null,null,null,null,null,null,0,0]
["Centres",null,null,null,null,null,null,null,null,0,0]
["Crèches",null,null,null,null,null,null,null,null,0,0]
["Clinics/Care Centres",null,null,null,null,null,null,null,null,0,0]
["Fire/Ambulance Stations",null,null,null,null,null,null,null,null,0,0]
["Testing Stations",null,null,null,null,null,null,null,null,0,0]
["Museums",null,null,null,null,null,null,null,null,0,0]
["Galleries",null,null,null,null,null,null,null,null,0,0]
["Theatres",null,null,null,null,null,null,null,null,0,0]
["Libraries",null,null,null,null,null,null,null,null,0,0]
["Cemeteries/Crematoria",null,null,null,null,null,null,null,null,0,0]
["Police",null,null,null,null,null,null,null,null,0,0]
["Purls",null,null,null,null,null,null,null,null,0,0]
["Public Open Space",null,null,null,null,null,null,null,null,0,0]
["Nature Reserves",null,null,null,null,null,null,null,null,0,0]
["Public Ablution Facilities",null,null,null,null,null,null,null,null,0,0]
["Markets",null,null,null,null,null,null,null,null,0,0]
["Stalls",null,null,null,null,null,null,null,null,0,0]
["Abattoirs",null,null,null,null,null,null,null,null,0,0]
["Airports",null,null,null,null,null,null,null,null,0,0]
["Taxi Ranks/Bus Terminals",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Sport and Recreation Facilities",null,{"$f":"SUM(C101:C103)","v":0},{"$f":"SUM(D101:D103)","v":0},0,0,0,0,0,0,0,0,0]
["Indoor Facilities",null,null,null,null,null,null,null,null,0,0]
["Outdoor Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Heritage assets",null,{"$f":"SUM(C106:C110)","v":0},0,0,0,0,0,0,0,0,0,0]
["Monuments",null,null,null,null,null,null,null,null,0,0]
["Historic Buildings",null,null,null,null,null,null,null,null,0,0]
["Works of Art",null,null,null,null,null,null,null,null,0,0]
["Conservation Areas",null,null,null,null,null,null,null,null,0,0]
["Other Heritage",null,null,null,null,null,null,null,null,0,0]
[]
["Investment properties",null,{"$f":"+C113+C116","v":0},0,0,0,0,0,0,0,0,{"$f":"+L113+L116","v":0},{"$f":"+M113+M116","v":0}]
["Revenue Generating",null,{"$f":"SUM(C114:C115)","v":0},{"$f":"SUM(D114:D115)","v":0},{"$f":"SUM(E114:E115)","v":0},0,0,0,0,0,0,0,0]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
["Non-revenue Generating",null,{"$f":"SUM(C117:C118)","v":0},{"$f":"SUM(D117:D118)","v":0},{"$f":"SUM(E117:E118)","v":0},0,0,0,0,0,0,0,0]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
[]
["Other assets",null,{"$f":"+C121+C133","v":0},{"$f":"+D121+D133","v":0},0,0,0,0,0,0,0,{"$f":"+L121+L133","v":0},{"$f":"+M121+M133","v":0}]
["Operational Buildings",null,{"$f":"SUM(C122:C132)","v":0},{"$f":"SUM(D122:D132)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(L122:L132)","v":0},{"$f":"SUM(M122:M132)","v":0}]
["Municipal Offices",null,0,0,0,0,0,0,0,0,0,0,0]
["Pay/Enquiry Points",null,null,null,null,null,null,null,null,0,0]
["Building Plan Offices",null,null,null,null,null,null,null,null,0,0]
["Workshops",null,null,null,null,null,null,null,null,0,0]
["Yards",null,null,null,null,null,null,null,null,0,0]
["Stores",null,null,null,null,null,null,null,null,0,0]
["Laboratories",null,null,null,null,null,null,null,null,0,0]
["Training Centres",null,null,null,null,null,null,null,null,0,0]
["Manufacturing Plant",null,null,null,null,null,null,null,null,0,0]
["Depots",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Housing",null,{"$f":"SUM(C134:C136)","v":0},{"$f":"SUM(D134:D136)","v":0},{"$f":"SUM(E134:E136)","v":0},0,0,0,0,0,0,0,0]
["Staff Housing",null,null,null,null,null,null,null,null,0,0]
["Social Housing",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Biological or Cultivated Assets",null,{"$f":"SUM(C139:C139)","v":0},0,0,0,0,0,0,{"$f":"SUM(E138:I138)","v":0},{"$f":"IF(D138=0,C138+J138,D138+J138)","v":0},0,0]
["Biological or Cultivated Assets",null,null,null,null,null,null,null,null,0,0]
[]
["Intangible Assets",null,{"$f":"SUM(C142:C143)","v":0},{"$f":"SUM(D142:D143)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(L142:L143)","v":0},{"$f":"SUM(M142:M143)","v":0}]
["Servitudes",null,null,null,null,null,null,null,null,0,0]
["Licences and Rights",null,{"$f":"SUM(C144:C149)","v":0},{"$f":"SUM(D144:D149)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(L144:L149)","v":0},{"$f":"SUM(M144:M149)","v":0}]
["Water Rights",null,null,null,null,null,null,null,null,0,0]
["Effluent Licenses",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Licenses",null,null,null,null,null,null,null,null,0,0]
["Computer Software and Applications",null,0,0,0,0,0,0,0,0,0,0,0]
["Load Settlement Software Applications",null,null,null,null,null,null,null,null,0,0]
["Unspecified",null,null,null,null,null,null,null,null,0,0]
[]
["Computer Equipment",null,{"$f":"SUM(C152:C152)","v":0},0,0,0,0,0,0,0,0,0,0]
["Computer Equipment",null,null,null,null,null,null,null,null,0,0]
[]
["Furniture and Office Equipment",null,{"$f":"SUM(C155:C155)","v":300000},0.02,0,0,0,0,113975,113975,113975.02,0,0]
["Furniture and Office Equipment",null,300000,0.02,0,0,0,0,113975,113975,113975.02,0,0]
[]
["Machinery and Equipment",null,{"$f":"SUM(C158:C158)","v":300000},0.02,0,0,0,0,0,0,0.02,0,0]
["Machinery and Equipment",null,300000,0.02,0,0,0,0,0,0,0.02,0,0]
[]
["Transport Assets",null,{"$f":"SUM(C161:C161)","v":0},0,0,0,0,0,0,0,0,0,0]
["Transport Assets",null,null,null,null,null,null,null,null,0,0]
[]
["Land",null,{"$f":"SUM(C164:C164)","v":0},0,0,0,0,0,0,0,0,0,0]
["Land",null,null,null,null,null,null,null,null,0,0]
[]
["Zoo's, Marine and Non-biological Animals",null,{"$f":"SUM(C167:C167)","v":0},0,0,0,0,0,0,0,0,0,0]
["Zoo's, Marine and Non-biological Animals",null,null,null,null,null,null,null,null,0,0]
[]
["Total Capital Expenditure on new assets to be adjusted",1,{"$f":"C8+C76+C105+C112+C120+C151+C138+C141+C154+C157+C160+C163+C166","v":133961894},{"$f":"D8+D76+D105+D112+D120+D151+D138+D141+D154+D157+D160+D163+D166","v":103266698.17},0,0,0,0,113975,113975,103380673.17,131648975,150925369]
[]
[{"$f":"head27a","v":"References"}]
["1. Total Capital Expenditure on new assets (SB18a) plus Total Capital Expenditure on renewal of existing assets (SB18b) plus Total Capital Expenditure on upgrading of existing assets (SB18e) must reconcile to total capital expenditure in Budgeted Capital Expenditure"]
["7. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["8. Additional cash-backed accumulated funds/unspent funds (section 18(1)(b) and section 28(2)(e) MFMA) identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have for"]
["9. Increases of funds approved under section 31 MFMA"]
["10. Adjustments approved in accordance with section 29 MFMA"]
["11. Adjustments to funding allocations from National or Provincial Government"]
["12. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sec"]
["13. G = B + C + D + E + F"]
["14. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
[]
["check balance",null,{"$f":"(C169+SB18b!C169+SB18e!C169)-'B5-Capex'!C65","v":0},null,null,null,null,null,null,null,null,{"$f":"(L169+SB18b!L169+SB18e!L169)-'B5-Capex'!L65","v":0},{"$f":"(M169+SB18b!M169+SB18e!M169)-'B5-Capex'!M65","v":0}]

{"sheet":"SB18b","index":37,"n_rows":183,"n_cols":13,"rows_kept":183,"cut":false,"hidden":false,"merged":[[1,0,3,0],[1,1,3,1],[1,2,1,10],[172,0,172,12],[179,0,179,12],[173,0,173,9],[174,0,174,9],[175,0,175,12],[177,0,177,12]]}
[{"$f":"muni&\" - \"&ADJB18b&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB18b Adjustments Budget - capital expenditure on renewal of existing assets by asset class - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,7,8,9,10,11,12,13,14]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Capital expenditure on renewal of existing assets by Asset Class/Sub-class"]
[]
["Infrastructure",null,{"$f":"C9+C14+C18+C28+C70+C39+C46+C54+C64","v":0},{"$f":"D9+D14+D18+D28+D70+D39+D46+D54+D64","v":10923593},0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":10923593},{"$f":"L9+L14+L18+L28+L70+L39+L46+L54+L64","v":0},{"$f":"M9+M14+M18+M28+M70+M39+M46+M54+M64","v":0}]
["Roads Infrastructure",null,{"$f":"SUM(C10:C13)","v":0},{"$f":"SUM(D10:D13)","v":0},0,0,0,0,0,{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":0},0,0]
["Roads",null,null,null,null,null,null,null,null,0,0]
["Road Structures",null,null,null,null,null,null,null,null,0,0]
["Road Furniture",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Storm water Infrastructure",null,{"$f":"SUM(C15:C17)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L15:L17)","v":0},{"$f":"SUM(M15:M17)","v":0}]
["Drainage Collection",null,null,null,null,null,null,null,null,0,0]
["Storm water Conveyance",null,null,null,null,null,null,null,null,0,0]
["Attenuation",null,null,null,null,null,null,null,null,0,0]
["Electrical Infrastructure",null,{"$f":"SUM(C19:C27)","v":0},0,0,0,0,0,0,0,0,0,0]
["Power Plants",null,null,null,null,null,null,null,null,0,0]
["HV Substations",null,null,null,null,null,null,null,null,0,0]
["HV Switching Station",null,null,null,null,null,null,null,null,0,0]
["HV Transmission Conductors",null,null,null,null,null,null,null,null,0,0]
["MV Substations",null,null,null,null,null,null,null,null,0,0]
["MV Switching Stations",null,null,null,null,null,null,null,null,0,0]
["MV Networks",null,null,null,null,null,null,null,null,0,0]
["LV Networks",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Water Supply Infrastructure",null,{"$f":"SUM(C29:C38)","v":0},10923593,0,0,0,0,0,0,10923593,0,0]
["Dams and Weirs",null,null,null,null,null,null,null,null,0,0]
["Boreholes",null,0,10923593,0,0,0,0,0,0,10923593,0,0]
["Reservoirs",null,null,null,null,null,null,null,null,0,0]
["Pump Stations",null,null,null,null,null,null,null,null,0,0]
["Water Treatment Works",null,null,null,null,null,null,null,null,0,0]
["Bulk Mains",null,null,null,null,null,null,null,null,0,0]
["Distribution",null,null,null,null,null,null,null,null,0,0]
["Distribution Points",null,null,null,null,null,null,null,null,0,0]
["PRV Stations",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Sanitation Infrastructure",null,{"$f":"SUM(C40:C45)","v":0},{"$f":"SUM(D40:D45)","v":0},0,0,0,0,0,0,0,0,0]
["Pump Station",null,null,null,null,null,null,null,null,0,0]
["Reticulation",null,null,null,null,null,null,null,null,0,0]
["Waste Water Treatment Works",null,null,null,null,null,null,null,null,0,0]
["Outfall Sewers",null,null,null,null,null,null,null,null,0,0]
["Toilet Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Infrastructure",null,{"$f":"SUM(C47:C53)","v":0},{"$f":"SUM(D47:D53)","v":0},0,0,0,0,0,0,0,0,0]
["Landfill Sites",null,null,null,null,null,null,null,null,0,0]
["Waste Transfer Stations",null,null,null,null,null,null,null,null,0,0]
["Waste Processing Facilities",null,null,null,null,null,null,null,null,0,0]
["Waste Drop-off Points",null,null,null,null,null,null,null,null,0,0]
["Waste Separation Facilities",null,null,null,null,null,null,null,null,0,0]
["Electricity Generation Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Rail Infrastructure",null,{"$f":"SUM(C55:C63)","v":0},{"$f":"SUM(D55:D63)","v":0},0,0,0,0,0,0,0,0,0]
["Rail Lines",null,null,null,null,null,null,null,null,0,0]
["Rail Structures",null,null,null,null,null,null,null,null,0,0]
["Rail Furniture",null,null,null,null,null,null,null,null,0,0]
["Drainage Collection",null,null,null,null,null,null,null,null,0,0]
["Storm water Conveyance",null,null,null,null,null,null,null,null,0,0]
["Attenuation",null,null,null,null,null,null,null,null,0,0]
["MV Substations",null,null,null,null,null,null,null,null,0,0]
["LV Networks",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Coastal Infrastructure",null,{"$f":"SUM(C65:C69)","v":0},0,0,0,0,0,0,0,0,0,0]
["Sand Pumps",null,null,null,null,null,null,null,null,0,0]
["Piers",null,null,null,null,null,null,null,null,0,0]
["Revetments",null,null,null,null,null,null,null,null,0,0]
["Promenades",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Information and Communication Infrastructure",null,{"$f":"SUM(C71:C74)","v":0},0,0,0,0,0,0,0,0,0,0]
["Data Centres",null,null,null,null,null,null,null,null,0,0]
["Core Layers",null,null,null,null,null,null,null,null,0,0]
["Distribution Layers",null,null,null,null,null,null,null,null,{"$f":"SUM(E73:I73)","v":0},{"$f":"IF(D73=0,C73+J73,D73+J73)","v":0}]
["Capital Spares",null,null,null,null,null,null,null,null,{"$f":"SUM(E74:I74)","v":0},{"$f":"IF(D74=0,C74+J74,D74+J74)","v":0}]
[]
["Community Assets",null,{"$f":"+C77+C100","v":12000000},{"$f":"+D77+D100","v":20106309},{"$f":"+E77+E100","v":0},0,0,0,0,{"$f":"SUM(E76:I76)","v":0},{"$f":"IF(D76=0,C76+J76,D76+J76)","v":20106309},9864475,8000000]
["Community Facilities",null,{"$f":"SUM(C78:C99)","v":12000000},{"$f":"SUM(D78:D99)","v":20106309},0,0,0,0,0,0,20106309,{"$f":"SUM(L78:L99)","v":9864475},{"$f":"SUM(M78:M99)","v":8000000}]
["Halls",null,12000000,20106309,0,0,0,0,0,0,20106309,9864475,8000000]
["Centres",null,null,null,null,null,null,null,null,0,0]
["Crèches",null,null,null,null,null,null,null,null,0,0]
["Clinics/Care Centres",null,null,null,null,null,null,null,null,0,0]
["Fire/Ambulance Stations",null,null,null,null,null,null,null,null,0,0]
["Testing Stations",null,0,0,0,0,0,0,0,0,0,0,0]
["Museums",null,null,null,null,null,null,null,null,0,0]
["Galleries",null,null,null,null,null,null,null,null,0,0]
["Theatres",null,null,null,null,null,null,null,null,0,0]
["Libraries",null,null,null,null,null,null,null,null,0,0]
["Cemeteries/Crematoria",null,null,null,null,null,null,null,null,0,0]
["Police",null,null,null,null,null,null,null,null,0,0]
["Purls",null,null,null,null,null,null,null,null,0,0]
["Public Open Space",null,0,0,0,0,0,0,0,0,0,0,0]
["Nature Reserves",null,null,null,null,null,null,null,null,0,0]
["Public Ablution Facilities",null,null,null,null,null,null,null,null,0,0]
["Markets",null,null,null,null,null,null,null,null,0,0]
["Stalls",null,null,null,null,null,null,null,null,0,0]
["Abattoirs",null,null,null,null,null,null,null,null,0,0]
["Airports",null,null,null,null,null,null,null,null,0,0]
["Taxi Ranks/Bus Terminals",null,0,0,0,0,0,0,0,0,0,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Sport and Recreation Facilities",null,{"$f":"SUM(C101:C103)","v":0},{"$f":"SUM(D101:D103)","v":0},0,0,0,0,0,0,0,0,0]
["Indoor Facilities",null,null,null,null,null,null,null,null,0,0]
["Outdoor Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Heritage assets",null,{"$f":"SUM(C106:C110)","v":0},0,0,0,0,0,0,0,0,0,0]
["Monuments",null,null,null,null,null,null,null,null,0,0]
["Historic Buildings",null,null,null,null,null,null,null,null,0,0]
["Works of Art",null,null,null,null,null,null,null,null,0,0]
["Conservation Areas",null,null,null,null,null,null,null,null,0,0]
["Other Heritage",null,null,null,null,null,null,null,null,0,0]
[]
["Investment properties",null,{"$f":"+C113+C116","v":0},{"$f":"+D113+D116","v":0},0,0,0,0,0,0,0,{"$f":"+L113+L116","v":0},{"$f":"+M113+M116","v":0}]
["Revenue Generating",null,{"$f":"SUM(C114:C115)","v":0},{"$f":"SUM(D114:D115)","v":0},{"$f":"SUM(E114:E115)","v":0},0,0,0,0,0,0,0,0]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
["Non-revenue Generating",null,{"$f":"SUM(C117:C118)","v":0},{"$f":"SUM(D117:D118)","v":0},{"$f":"SUM(E117:E118)","v":0},0,0,0,0,0,0,0,0]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
[]
["Other assets",null,{"$f":"+C121+C133","v":2590253},{"$f":"+D121+D133","v":10620445.01},0,0,0,0,0,0,10620445.01,{"$f":"+L121+L133","v":0},{"$f":"+M121+M133","v":0}]
["Operational Buildings",null,{"$f":"SUM(C122:C132)","v":2590253},{"$f":"SUM(D122:D132)","v":10620445.01},0,0,0,0,0,0,10620445.01,{"$f":"SUM(L122:L132)","v":0},{"$f":"SUM(M122:M132)","v":0}]
["Municipal Offices",null,0,0,0,0,0,0,0,0,0,0,0]
["Pay/Enquiry Points",null,null,null,null,null,null,null,null,0,0]
["Building Plan Offices",null,null,null,null,null,null,null,null,0,0]
["Workshops",null,null,null,null,null,null,null,null,0,0]
["Yards",null,null,null,null,null,null,null,null,0,0]
["Stores",null,2590253,10620445.01,0,0,0,0,0,0,10620445.01,0,0]
["Laboratories",null,null,null,null,null,null,null,null,0,0]
["Training Centres",null,null,null,null,null,null,null,null,0,0]
["Manufacturing Plant",null,null,null,null,null,null,null,null,0,0]
["Depots",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Housing",null,{"$f":"SUM(C134:C136)","v":0},{"$f":"SUM(D134:D136)","v":0},{"$f":"SUM(E134:E136)","v":0},0,0,0,0,0,0,0,0]
["Staff Housing",null,null,null,null,null,null,null,null,0,0]
["Social Housing",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Biological or Cultivated Assets",null,{"$f":"SUM(C139:C139)","v":0},0,0,0,0,0,0,0,0,0,0]
["Biological or Cultivated Assets",null,null,null,null,null,null,null,null,0,0]
[]
["Intangible Assets",null,{"$f":"SUM(C142:C143)","v":250000},{"$f":"SUM(D142:D143)","v":0.01},0,0,0,0,0,{"$f":"SUM(E141:I141)","v":0},{"$f":"IF(D141=0,C141+J141,D141+J141)","v":0.01},{"$f":"SUM(L142:L143)","v":0},{"$f":"SUM(M142:M143)","v":0}]
["Servitudes",null,null,null,null,null,null,null,null,0,0]
["Licences and Rights",null,{"$f":"SUM(C144:C149)","v":250000},{"$f":"SUM(D144:D149)","v":0.01},0,0,0,0,0,0,0.01,{"$f":"SUM(L144:L149)","v":0},{"$f":"SUM(M144:M149)","v":0}]
["Water Rights",null,null,null,null,null,null,null,null,0,0]
["Effluent Licenses",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Licenses",null,null,null,null,null,null,null,null,0,0]
["Computer Software and Applications",null,250000,0.01,0,0,0,0,0,0,0.01,0,0]
["Load Settlement Software Applications",null,null,null,null,null,null,null,null,0,0]
["Unspecified",null,null,null,null,null,null,null,null,0,0]
[]
["Computer Equipment",null,{"$f":"SUM(C152:C152)","v":0},0,0,0,0,0,0,0,0,0,0]
["Computer Equipment",null,null,null,null,null,null,null,null,{"$f":"SUM(E152:I152)","v":0},{"$f":"IF(D152=0,C152+J152,D152+J152)","v":0}]
[]
["Furniture and Office Equipment",null,{"$f":"SUM(C155:C155)","v":0},0,0,0,0,0,0,{"$f":"SUM(E154:I154)","v":0},{"$f":"IF(D154=0,C154+J154,D154+J154)","v":0},0,0]
["Furniture and Office Equipment",null,null,null,null,null,null,null,null,{"$f":"SUM(E155:I155)","v":0},{"$f":"IF(D155=0,C155+J155,D155+J155)","v":0}]
[]
["Machinery and Equipment",null,{"$f":"SUM(C158:C158)","v":0},0,0,0,0,0,0,{"$f":"SUM(E157:I157)","v":0},{"$f":"IF(D157=0,C157+J157,D157+J157)","v":0},0,0]
["Machinery and Equipment",null,null,null,null,null,null,null,null,{"$f":"SUM(E158:I158)","v":0},{"$f":"IF(D158=0,C158+J158,D158+J158)","v":0}]
[]
["Transport Assets",null,{"$f":"SUM(C161:C161)","v":0},0,0,0,0,0,0,{"$f":"SUM(E160:I160)","v":0},{"$f":"IF(D160=0,C160+J160,D160+J160)","v":0},0,0]
["Transport Assets",null,null,null,null,null,null,null,null,{"$f":"SUM(E161:I161)","v":0},{"$f":"IF(D161=0,C161+J161,D161+J161)","v":0}]
[]
["Land",null,{"$f":"SUM(C164:C164)","v":0},0,0,0,0,0,0,{"$f":"SUM(E163:I163)","v":0},{"$f":"IF(D163=0,C163+J163,D163+J163)","v":0},0,0]
["Land",null,null,null,null,null,null,null,null,{"$f":"SUM(E164:I164)","v":0},{"$f":"IF(D164=0,C164+J164,D164+J164)","v":0}]
[]
["Zoo's, Marine and Non-biological Animals",null,{"$f":"SUM(C167:C167)","v":0},0,0,0,0,0,0,{"$f":"SUM(E166:I166)","v":0},{"$f":"IF(D166=0,C166+J166,D166+J166)","v":0},0,0]
["Zoo's, Marine and Non-biological Animals",null,null,null,null,null,null,null,null,{"$f":"SUM(E167:I167)","v":0},{"$f":"IF(D167=0,C167+J167,D167+J167)","v":0}]
[]
["Total Capital Expenditure on renewal of existing assets to be adjusted",1,{"$f":"C8+C76+C105+C112+C120+C151+C138+C141+C154+C157+C160+C163+C166","v":14840253},{"$f":"D8+D76+D105+D112+D120+D151+D138+D141+D154+D157+D160+D163+D166","v":41650347.019999996},0,0,0,0,0,{"$f":"SUM(E169:I169)","v":0},{"$f":"IF(D169=0,C169+J169,D169+J169)","v":41650347.019999996},9864475,8000000]
[]
[{"$f":"head27a","v":"References"}]
["1. Total Capital Expenditure  on renewal of existing assets (SB18b) plus Total Capital Expenditure on new assets (SB18a) plus Total Capital Expenditure  on upgrading of existing assets (SB18e) must reconcile to total capital expenditure in Budgeted Capital Expenditure"]
["7. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["8. Additional cash-backed accumulated funds/unspent funds (section 18(1)(b) and section 28(2)(e) MFMA) identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have for"]
["9. Increases of funds approved under section 31 MFMA"]
["10. Adjustments approved in accordance with section 29 MFMA"]
["11. Adjustments to funding allocations from National or Provincial Government"]
["12. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sec"]
["13. G = B + C + D + E + F"]
["14. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
[]
["check balance",null,{"$f":"(C169+SB18a!C169+SB18e!C169)-'B5-Capex'!C65","v":0},null,null,null,null,null,null,null,null,{"$f":"(L169+SB18a!L169+SB18e!L169)-'B5-Capex'!L65","v":0},{"$f":"(M169+SB18a!M169+SB18e!M169)-'B5-Capex'!M65","v":0}]

{"sheet":"SB18c","index":38,"n_rows":182,"n_cols":13,"rows_kept":182,"cut":false,"hidden":false,"merged":[[1,0,3,0],[1,1,3,1],[1,2,1,10],[171,0,171,12],[178,0,178,12],[172,0,172,9],[173,0,173,9],[174,0,174,12],[176,0,176,12]]}
[{"$f":"muni&\" - \"&ADJB18c&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB18c Adjustments Budget - expenditure on repairs and maintenance by asset class - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,7,8,9,10,11,12,13,14]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Repairs and maintenance expenditure by Asset Class/Sub-class"]
[]
["Infrastructure",null,{"$f":"C9+C14+C18+C28+C70+C39+C46+C54+C64","v":47910000},{"$f":"D9+D14+D18+D28+D70+D39+D46+D54+D64","v":36338475},0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":36338475},{"$f":"L9+L14+L18+L28+L70+L39+L46+L54+L64","v":29070000},{"$f":"M9+M14+M18+M28+M70+M39+M46+M54+M64","v":32127000}]
["Roads Infrastructure",null,{"$f":"SUM(C10:C13)","v":9400000},{"$f":"SUM(D10:D13)","v":1050000},0,0,0,0,0,{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":1050000},1700000,1789000]
["Roads",null,9000000,1000000,0,0,0,0,0,0,1000000,1500000,1569000]
["Road Structures",null,null,null,null,null,null,null,null,0,0]
["Road Furniture",null,400000,50000,0,0,0,0,0,0,50000,200000,220000]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Storm water Infrastructure",null,{"$f":"SUM(C15:C17)","v":2000000},450000,0,0,0,0,0,0,450000,{"$f":"SUM(L15:L17)","v":760000},{"$f":"SUM(M15:M17)","v":820000}]
["Drainage Collection",null,null,null,null,null,null,null,null,0,0]
["Storm water Conveyance",null,2000000,450000,0,0,0,0,0,0,450000,760000,820000]
["Attenuation",null,null,null,null,null,null,null,null,0,0]
["Electrical Infrastructure",null,{"$f":"SUM(C19:C27)","v":6000000},1000000,0,0,0,0,0,0,1000000,2000000,2092000]
["Power Plants",null,null,null,null,null,null,null,null,0,0]
["HV Substations",null,null,null,null,null,null,null,null,0,0]
["HV Switching Station",null,null,null,null,null,null,null,null,0,0]
["HV Transmission Conductors",null,null,null,null,null,null,null,null,0,0]
["MV Substations",null,null,null,null,null,null,null,null,0,0]
["MV Switching Stations",null,null,null,null,null,null,null,null,0,0]
["MV Networks",null,null,null,null,null,null,null,null,0,0]
["LV Networks",null,6000000,1000000,0,0,0,0,0,0,1000000,2000000,2092000]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Water Supply Infrastructure",null,{"$f":"SUM(C29:C38)","v":300000},150000,0,0,0,0,0,0,150000,300000,320000]
["Dams and Weirs",null,null,null,null,null,null,null,null,0,0]
["Boreholes",null,null,null,null,null,null,null,null,0,0]
["Reservoirs",null,300000,150000,0,0,0,0,0,0,150000,300000,320000]
["Pump Stations",null,null,null,null,null,null,null,null,0,0]
["Water Treatment Works",null,null,null,null,null,null,null,null,0,0]
["Bulk Mains",null,null,null,null,null,null,null,null,0,0]
["Distribution",null,null,null,null,null,null,null,null,0,0]
["Distribution Points",null,null,null,null,null,null,null,null,0,0]
["PRV Stations",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Sanitation Infrastructure",null,{"$f":"SUM(C40:C45)","v":0},{"$f":"SUM(D40:D45)","v":0},0,0,0,0,0,0,0,0,0]
["Pump Station",null,null,null,null,null,null,null,null,0,0]
["Reticulation",null,null,null,null,null,null,null,null,0,0]
["Waste Water Treatment Works",null,null,null,null,null,null,null,null,0,0]
["Outfall Sewers",null,null,null,null,null,null,null,null,0,0]
["Toilet Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Infrastructure",null,{"$f":"SUM(C47:C53)","v":30210000},{"$f":"SUM(D47:D53)","v":33688475},0,0,0,0,0,0,33688475,24310000,27106000]
["Landfill Sites",null,30210000,33688475,0,0,0,0,0,0,33688475,24310000,27106000]
["Waste Transfer Stations",null,0,0,0,0,0,0,0,0,0,0,0]
["Waste Processing Facilities",null,null,null,null,null,null,null,null,0,0]
["Waste Drop-off Points",null,null,null,null,null,null,null,null,0,0]
["Waste Separation Facilities",null,null,null,null,null,null,null,null,0,0]
["Electricity Generation Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Rail Infrastructure",null,{"$f":"SUM(C55:C63)","v":0},{"$f":"SUM(D55:D63)","v":0},0,0,0,0,0,0,0,0,0]
["Rail Lines",null,null,null,null,null,null,null,null,0,0]
["Rail Structures",null,null,null,null,null,null,null,null,0,0]
["Rail Furniture",null,null,null,null,null,null,null,null,0,0]
["Drainage Collection",null,null,null,null,null,null,null,null,0,0]
["Storm water Conveyance",null,null,null,null,null,null,null,null,0,0]
["Attenuation",null,null,null,null,null,null,null,null,0,0]
["MV Substations",null,null,null,null,null,null,null,null,0,0]
["LV Networks",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Coastal Infrastructure",null,{"$f":"SUM(C65:C69)","v":0},0,0,0,0,0,0,0,0,0,0]
["Sand Pumps",null,null,null,null,null,null,null,null,0,0]
["Piers",null,null,null,null,null,null,null,null,0,0]
["Revetments",null,null,null,null,null,null,null,null,0,0]
["Promenades",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Information and Communication Infrastructure",null,{"$f":"SUM(C71:C74)","v":0},0,0,0,0,0,0,0,0,0,0]
["Data Centres",null,null,null,null,null,null,null,null,0,0]
["Core Layers",null,null,null,null,null,null,null,null,0,0]
["Distribution Layers",null,null,null,null,null,null,null,null,{"$f":"SUM(E73:I73)","v":0},{"$f":"IF(D73=0,C73+J73,D73+J73)","v":0}]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Community Assets",null,{"$f":"+C77+C100","v":500000},{"$f":"+D77+D100","v":200000},{"$f":"+E77+E100","v":0},0,0,0,0,0,200000,400000,420000]
["Community Facilities",null,{"$f":"SUM(C78:C99)","v":0},{"$f":"SUM(D78:D99)","v":0},{"$f":"SUM(E78:E99)","v":0},0,0,0,0,0,0,0,0]
["Halls",null,null,null,null,null,null,null,null,0,0]
["Centres",null,null,null,null,null,null,null,null,0,0]
["Crèches",null,null,null,null,null,null,null,null,0,0]
["Clinics/Care Centres",null,null,null,null,null,null,null,null,0,0]
["Fire/Ambulance Stations",null,null,null,null,null,null,null,null,0,0]
["Testing Stations",null,0,0,0,0,0,0,0,0,0,0,0]
["Museums",null,null,null,null,null,null,null,null,0,0]
["Galleries",null,null,null,null,null,null,null,null,0,0]
["Theatres",null,null,null,null,null,null,null,null,0,0]
["Libraries",null,null,null,null,null,null,null,null,0,0]
["Cemeteries/Crematoria",null,0,0,0,0,0,0,0,0,0,0,0]
["Police",null,null,null,null,null,null,null,null,0,0]
["Purls",null,null,null,null,null,null,null,null,0,0]
["Public Open Space",null,null,null,null,null,null,null,null,0,0]
["Nature Reserves",null,null,null,null,null,null,null,null,0,0]
["Public Ablution Facilities",null,null,null,null,null,null,null,null,0,0]
["Markets",null,null,null,null,null,null,null,null,0,0]
["Stalls",null,null,null,null,null,null,null,null,0,0]
["Abattoirs",null,null,null,null,null,null,null,null,0,0]
["Airports",null,null,null,null,null,null,null,null,0,0]
["Taxi Ranks/Bus Terminals",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Sport and Recreation Facilities",null,{"$f":"SUM(C101:C103)","v":500000},{"$f":"SUM(D101:D103)","v":200000},0,0,0,0,0,0,200000,400000,420000]
["Indoor Facilities",null,null,null,null,null,null,null,null,0,0]
["Outdoor Facilities",null,500000,200000,0,0,0,0,0,0,200000,400000,420000]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Heritage assets",null,{"$f":"SUM(C106:C110)","v":0},0,0,0,0,0,0,0,0,0,0]
["Monuments",null,null,null,null,null,null,null,null,0,0]
["Historic Buildings",null,null,null,null,null,null,null,null,0,0]
["Works of Art",null,null,null,null,null,null,null,null,0,0]
["Conservation Areas",null,null,null,null,null,null,null,null,0,0]
["Other Heritage",null,null,null,null,null,null,null,null,0,0]
[]
["Investment properties",null,{"$f":"+C113+C116","v":0},{"$f":"+D113+D116","v":0},0,0,0,0,0,0,0,{"$f":"+L113+L116","v":0},{"$f":"+M113+M116","v":0}]
["Revenue Generating",null,{"$f":"SUM(C114:C115)","v":0},{"$f":"SUM(D114:D115)","v":0},{"$f":"SUM(E114:E115)","v":0},0,0,0,0,0,0,0,0]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
["Non-revenue Generating",null,{"$f":"SUM(C117:C118)","v":0},{"$f":"SUM(D117:D118)","v":0},{"$f":"SUM(E117:E118)","v":0},0,0,0,0,0,0,0,0]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
[]
["Other assets",null,{"$f":"+C121+C133","v":7800000},{"$f":"+D121+D133","v":2500000},0,0,0,0,0,0,2500000,{"$f":"+L121+L133","v":5800000},{"$f":"+M121+M133","v":6066800}]
["Operational Buildings",null,{"$f":"SUM(C122:C132)","v":7800000},{"$f":"SUM(D122:D132)","v":2500000},0,0,0,0,0,0,2500000,{"$f":"SUM(L122:L132)","v":5800000},{"$f":"SUM(M122:M132)","v":6066800}]
["Municipal Offices",null,7800000,2500000,0,0,0,0,0,0,2500000,5800000,6066800]
["Pay/Enquiry Points",null,null,null,null,null,null,null,null,0,0]
["Building Plan Offices",null,null,null,null,null,null,null,null,0,0]
["Workshops",null,null,null,null,null,null,null,null,0,0]
["Yards",null,null,null,null,null,null,null,null,0,0]
["Stores",null,null,null,null,null,null,null,null,0,0]
["Laboratories",null,null,null,null,null,null,null,null,0,0]
["Training Centres",null,null,null,null,null,null,null,null,0,0]
["Manufacturing Plant",null,null,null,null,null,null,null,null,0,0]
["Depots",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Housing",null,{"$f":"SUM(C134:C136)","v":0},{"$f":"SUM(D134:D136)","v":0},{"$f":"SUM(E134:E136)","v":0},0,0,0,0,0,0,0,0]
["Staff Housing",null,null,null,null,null,null,null,null,0,0]
["Social Housing",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Biological or Cultivated Assets",null,{"$f":"SUM(C139:C139)","v":0},0,0,0,0,0,0,{"$f":"SUM(E138:I138)","v":0},{"$f":"IF(D138=0,C138+J138,D138+J138)","v":0},0,0]
["Biological or Cultivated Assets",null,null,null,null,null,null,null,null,0,0]
[]
["Intangible Assets",null,{"$f":"SUM(C142:C143)","v":3000000},{"$f":"SUM(D142:D143)","v":2000000},{"$f":"SUM(E142:E143)","v":0},0,0,0,0,0,2000000,0,0]
["Servitudes",null,null,null,null,null,null,null,null,0,0]
["Licences and Rights",null,{"$f":"SUM(C144:C149)","v":3000000},{"$f":"SUM(D144:D149)","v":2000000},{"$f":"SUM(E144:E149)","v":0},0,0,0,0,0,2000000,0,0]
["Water Rights",null,null,null,null,null,null,null,null,0,0]
["Effluent Licenses",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Licenses",null,null,null,null,null,null,null,null,0,0]
["Computer Software and Applications",null,3000000,2000000,0,0,0,0,0,0,2000000,0,0]
["Load Settlement Software Applications",null,null,null,null,null,null,null,null,0,0]
["Unspecified",null,null,null,null,null,null,null,null,0,0]
[]
["Computer Equipment",null,{"$f":"SUM(C152:C152)","v":80000},50000.01,0,0,0,0,0,0,50000.01,50000,55000]
["Computer Equipment",null,80000,50000.01,0,0,0,0,0,0,50000.01,50000,55000]
[]
["Furniture and Office Equipment",null,{"$f":"SUM(C155:C155)","v":0},0,0,0,0,0,0,0,0,0,0]
["Furniture and Office Equipment",null,null,null,null,null,null,null,null,0,0]
[]
["Machinery and Equipment",null,{"$f":"SUM(C158:C158)","v":0},0,0,0,0,0,0,0,0,0,0]
["Machinery and Equipment",null,0,0,0,0,0,0,0,0,0,0,0]
[]
["Transport Assets",null,{"$f":"SUM(C161:C161)","v":5850000},5950000.0099999998,0,0,0,0,0,0,5950000.0099999998,7160000,7920000]
["Transport Assets",null,5850000,5950000.0099999998,0,0,0,0,0,0,5950000.0099999998,7160000,7920000]
[]
["Land",null,{"$f":"SUM(C164:C164)","v":0},0,0,0,0,0,0,0,0,0,0]
["Land",null,null,null,null,null,null,null,null,0,0]
[]
["Zoo's, Marine and Non-biological Animals",null,{"$f":"SUM(C167:C167)","v":0},0,0,0,0,0,0,0,0,0,0]
["Zoo's, Marine and Non-biological Animals",null,null,null,null,null,null,null,null,0,0]
[]
["Total Repairs and Maintenance Expenditure to be adjusted",1,{"$f":"C8+C76+C105+C112+C120+C151+C138+C141+C154+C157+C160+C163+C166","v":65140000},{"$f":"D8+D76+D105+D112+D120+D151+D138+D141+D154+D157+D160+D163+D166","v":47038475.019999996},{"$f":"E8+E76+E105+E112+E120+E151+E138+E141+E154+E157+E160+E163+E166","v":0},0,0,0,0,0,47038475.019999996,42480000,46588800]
[{"$f":"head27a","v":"References"}]
["1. Total Repairs and Maintenance Expenditure by Asset Category must reconcile to total repairs and maintenance expenditure on Table SB1"]
["7. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["8. Additional cash-backed accumulated funds/unspent funds (section 18(1)(b) and section 28(2)(e) MFMA) identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have for"]
["9. Increases of funds approved under section 31 MFMA"]
["10. Adjustments approved in accordance with section 29 MFMA"]
["11. Adjustments to funding allocations from National or Provincial Government"]
["12. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sec"]
["13. G = B + C + D + E + F"]
["14. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
[]
["check balance"]

{"sheet":"SB18d","index":39,"n_rows":182,"n_cols":13,"rows_kept":182,"cut":false,"hidden":false,"merged":[[174,0,174,12],[176,0,176,12],[178,0,178,12],[1,0,3,0],[1,1,3,1],[1,2,1,10],[171,0,171,12],[172,0,172,9],[173,0,173,9]]}
[{"$f":"muni&\" - \"&ADJB18d&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB18d Adjustments Budget - depreciation by asset class - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,7,8,9,10,11,12,13,14]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Depreciation by Asset Class/Sub-class"]
[]
["Infrastructure",null,{"$f":"C9+C14+C18+C28+C70+C39+C46+C54+C64","v":22482248},{"$f":"D9+D14+D18+D28+D70+D39+D46+D54+D64","v":22482248},0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":22482248},{"$f":"L9+L14+L18+L28+L70+L39+L46+L54+L64","v":5849303},{"$f":"M9+M14+M18+M28+M70+M39+M46+M54+M64","v":6118372}]
["Roads Infrastructure",null,{"$f":"SUM(C10:C13)","v":0},{"$f":"SUM(D10:D13)","v":0},0,0,0,0,0,{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":0},0,0]
["Roads",null,0,0,0,0,0,0,0,0,0,0,0]
["Road Structures",null,0,0,0,0,0,0,0,0,0,0,0]
["Road Furniture",null,0,0,0,0,0,0,0,0,0,0,0]
["Capital Spares",null,0,0,0,0,0,0,0,0,0,0,0]
["Storm water Infrastructure",null,{"$f":"SUM(C15:C17)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L15:L17)","v":0},{"$f":"SUM(M15:M17)","v":0}]
["Drainage Collection",null,0,0,0,0,0,0,0,0,0,0,0]
["Storm water Conveyance",null,0,0,0,0,0,0,0,0,0,0,0]
["Attenuation",null,0,0,0,0,0,0,0,0,0,0,0]
["Electrical Infrastructure",null,{"$f":"SUM(C19:C27)","v":8099870},8099870,0,0,0,0,0,0,8099870,2515474,2631186]
["Power Plants",null,8099870,8099870,0,0,0,0,0,0,8099870,2515474,2631186]
["HV Substations",null,0,0,0,0,0,0,0,0,0,0,0]
["HV Switching Station",null,0,0,0,0,0,0,0,0,0,0,0]
["HV Transmission Conductors",null,0,0,0,0,0,0,0,0,0,0,0]
["MV Substations",null,0,0,0,0,0,0,0,0,0,0,0]
["MV Switching Stations",null,0,0,0,0,0,0,0,0,0,0,0]
["MV Networks",null,0,0,0,0,0,0,0,0,0,0,0]
["LV Networks",null,0,0,0,0,0,0,0,0,0,0,0]
["Capital Spares",null,0,0,0,0,0,0,0,0,0,0,0]
["Water Supply Infrastructure",null,{"$f":"SUM(C29:C38)","v":0},0,0,0,0,0,0,0,0,0,0]
["Dams and Weirs",null,0,0,0,0,0,0,0,0,0,0,0]
["Boreholes",null,0,0,0,0,0,0,0,0,0,0,0]
["Reservoirs",null,0,0,0,0,0,0,0,0,0,0,0]
["Pump Stations",null,0,0,0,0,0,0,0,0,0,0,0]
["Water Treatment Works",null,0,0,0,0,0,0,0,0,0,0,0]
["Bulk Mains",null,0,0,0,0,0,0,0,0,0,0,0]
["Distribution",null,0,0,0,0,0,0,0,0,0,0,0]
["Distribution Points",null,0,0,0,0,0,0,0,0,0,0,0]
["PRV Stations",null,0,0,0,0,0,0,0,0,0,0,0]
["Capital Spares",null,0,0,0,0,0,0,0,0,0,0,0]
["Sanitation Infrastructure",null,{"$f":"SUM(C40:C45)","v":8686146},{"$f":"SUM(D40:D45)","v":8686146},0,0,0,0,0,0,8686146,2785714,2913857]
["Pump Station",null,0,0,0,0,0,0,0,0,0,0,0]
["Reticulation",null,0,0,0,0,0,0,0,0,0,0,0]
["Waste Water Treatment Works",null,8686146,8686146,0,0,0,0,0,0,8686146,2785714,2913857]
["Outfall Sewers",null,0,0,0,0,0,0,0,0,0,0,0]
["Toilet Facilities",null,0,0,0,0,0,0,0,0,0,0,0]
["Capital Spares",null,0,0,0,0,0,0,0,0,0,0,0]
["Solid Waste Infrastructure",null,{"$f":"SUM(C47:C53)","v":5696232},{"$f":"SUM(D47:D53)","v":5696232},0,0,0,0,0,0,5696232,548115,573329]
["Landfill Sites",null,5696232,5696232,0,0,0,0,0,0,5696232,548115,573329]
["Waste Transfer Stations",null,0,0,0,0,0,0,0,0,0,0,0]
["Waste Processing Facilities",null,0,0,0,0,0,0,0,0,0,0,0]
["Waste Drop-off Points",null,0,0,0,0,0,0,0,0,0,0,0]
["Waste Separation Facilities",null,0,0,0,0,0,0,0,0,0,0,0]
["Electricity Generation Facilities",null,0,0,0,0,0,0,0,0,0,0,0]
["Capital Spares",null,0,0,0,0,0,0,0,0,0,0,0]
["Rail Infrastructure",null,{"$f":"SUM(C55:C63)","v":0},{"$f":"SUM(D55:D63)","v":0},0,0,0,0,0,0,0,0,0]
["Rail Lines",null,null,null,null,null,null,null,null,0,0]
["Rail Structures",null,null,null,null,null,null,null,null,0,0]
["Rail Furniture",null,null,null,null,null,null,null,null,0,0]
["Drainage Collection",null,null,null,null,null,null,null,null,0,0]
["Storm water Conveyance",null,null,null,null,null,null,null,null,0,0]
["Attenuation",null,null,null,null,null,null,null,null,0,0]
["MV Substations",null,null,null,null,null,null,null,null,0,0]
["LV Networks",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Coastal Infrastructure",null,{"$f":"SUM(C65:C69)","v":0},0,0,0,0,0,0,0,0,0,0]
["Sand Pumps",null,null,null,null,null,null,null,null,0,0]
["Piers",null,null,null,null,null,null,null,null,0,0]
["Revetments",null,null,null,null,null,null,null,null,0,0]
["Promenades",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Information and Communication Infrastructure",null,{"$f":"SUM(C71:C74)","v":0},0,0,0,0,0,0,0,0,0,0]
["Data Centres",null,null,null,null,null,null,null,null,0,0]
["Core Layers",null,null,null,null,null,null,null,null,0,0]
["Distribution Layers",null,null,null,null,null,null,null,null,{"$f":"SUM(E73:I73)","v":0},{"$f":"IF(D73=0,C73+J73,D73+J73)","v":0}]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Community Assets",null,{"$f":"+C77+C100","v":3671000},{"$f":"+D77+D100","v":3671000},{"$f":"+E77+E100","v":0},0,0,0,0,0,3671000,17007132,17789460]
["Community Facilities",null,{"$f":"SUM(C78:C99)","v":3671000},{"$f":"SUM(D78:D99)","v":3671000},{"$f":"SUM(E78:E99)","v":0},0,0,0,0,0,3671000,17007132,17789460]
["Halls",null,3671000,3671000,0,0,0,0,0,0,3671000,17007132,17789460]
["Centres",null,0,0,0,0,0,0,0,0,0,0,0]
["Crèches",null,0,0,0,0,0,0,0,0,0,0,0]
["Clinics/Care Centres",null,0,0,0,0,0,0,0,0,0,0,0]
["Fire/Ambulance Stations",null,0,0,0,0,0,0,0,0,0,0,0]
["Testing Stations",null,0,0,0,0,0,0,0,0,0,0,0]
["Museums",null,0,0,0,0,0,0,0,0,0,0,0]
["Galleries",null,0,0,0,0,0,0,0,0,0,0,0]
["Theatres",null,0,0,0,0,0,0,0,0,0,0,0]
["Libraries",null,0,0,0,0,0,0,0,0,0,0,0]
["Cemeteries/Crematoria",null,0,0,0,0,0,0,0,0,0,0,0]
["Police",null,0,0,0,0,0,0,0,0,0,0,0]
["Purls",null,0,0,0,0,0,0,0,0,0,0,0]
["Public Open Space",null,0,0,0,0,0,0,0,0,0,0,0]
["Nature Reserves",null,0,0,0,0,0,0,0,0,0,0,0]
["Public Ablution Facilities",null,0,0,0,0,0,0,0,0,0,0,0]
["Markets",null,0,0,0,0,0,0,0,0,0,0,0]
["Stalls",null,0,0,0,0,0,0,0,0,0,0,0]
["Abattoirs",null,0,0,0,0,0,0,0,0,0,0,0]
["Airports",null,0,0,0,0,0,0,0,0,0,0,0]
["Taxi Ranks/Bus Terminals",null,0,0,0,0,0,0,0,0,0,0,0]
["Capital Spares",null,0,0,0,0,0,0,0,0,0,0,0]
["Sport and Recreation Facilities",null,{"$f":"SUM(C101:C103)","v":0},{"$f":"SUM(D101:D103)","v":0},0,0,0,0,0,0,0,0,0]
["Indoor Facilities",null,null,null,null,null,null,null,null,0,0]
["Outdoor Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Heritage assets",null,{"$f":"SUM(C106:C110)","v":0},0,0,0,0,0,0,0,0,0,0]
["Monuments",null,null,null,null,null,null,null,null,0,0]
["Historic Buildings",null,null,null,null,null,null,null,null,0,0]
["Works of Art",null,null,null,null,null,null,null,null,0,0]
["Conservation Areas",null,null,null,null,null,null,null,null,0,0]
["Other Heritage",null,null,null,null,null,null,null,null,0,0]
[]
["Investment properties",null,{"$f":"+C113+C116","v":0},{"$f":"+D113+D116","v":0},0,0,0,0,0,0,0,{"$f":"+L113+L116","v":0},{"$f":"+M113+M116","v":0}]
["Revenue Generating",null,{"$f":"SUM(C114:C115)","v":0},{"$f":"SUM(D114:D115)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(L114:L115)","v":0},{"$f":"SUM(M114:M115)","v":0}]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
["Non-revenue Generating",null,{"$f":"SUM(C117:C118)","v":0},{"$f":"SUM(D117:D118)","v":0},{"$f":"SUM(E117:E118)","v":0},0,0,0,0,0,0,0,0]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
[]
["Other assets",null,{"$f":"+C121+C133","v":0},{"$f":"+D121+D133","v":0},0,0,0,0,0,0,0,{"$f":"+L121+L133","v":0},{"$f":"+M121+M133","v":0}]
["Operational Buildings",null,{"$f":"SUM(C122:C132)","v":0},{"$f":"SUM(D122:D132)","v":0},{"$f":"SUM(E122:E132)","v":0},0,0,0,0,0,0,0,0]
["Municipal Offices",null,0,0,0,0,0,0,0,0,0,0,0]
["Pay/Enquiry Points",null,0,0,0,0,0,0,0,0,0,0,0]
["Building Plan Offices",null,0,0,0,0,0,0,0,0,0,0,0]
["Workshops",null,0,0,0,0,0,0,0,0,0,0,0]
["Yards",null,0,0,0,0,0,0,0,0,0,0,0]
["Stores",null,0,0,0,0,0,0,0,0,0,0,0]
["Laboratories",null,0,0,0,0,0,0,0,0,0,0,0]
["Training Centres",null,0,0,0,0,0,0,0,0,0,0,0]
["Manufacturing Plant",null,0,0,0,0,0,0,0,0,0,0,0]
["Depots",null,0,0,0,0,0,0,0,0,0,0,0]
["Capital Spares",null,0,0,0,0,0,0,0,0,0,0,0]
["Housing",null,{"$f":"SUM(C134:C136)","v":0},{"$f":"SUM(D134:D136)","v":0},{"$f":"SUM(E134:E136)","v":0},0,0,0,0,0,0,0,0]
["Staff Housing",null,0,0,0,0,0,0,0,0,0,0,0]
["Social Housing",null,0,0,0,0,0,0,0,0,0,0,0]
["Capital Spares",null,0,0,0,0,0,0,0,0,0,0,0]
[]
["Biological or Cultivated Assets",null,{"$f":"SUM(C139:C139)","v":6183000},6183000,0,0,0,0,0,{"$f":"SUM(E138:I138)","v":0},{"$f":"IF(D138=0,C138+J138,D138+J138)","v":6183000},9741941,10190070]
["Biological or Cultivated Assets",null,6183000,6183000,0,0,0,0,0,0,6183000,9741941,10190070]
[]
["Intangible Assets",null,{"$f":"SUM(C142:C143)","v":0},{"$f":"SUM(D142:D143)","v":0},{"$f":"SUM(E142:E143)","v":0},0,0,0,0,0,0,0,0]
["Servitudes",null,null,null,null,null,null,null,null,0,0]
["Licences and Rights",null,{"$f":"SUM(C144:C149)","v":0},{"$f":"SUM(D144:D149)","v":0},{"$f":"SUM(E144:E149)","v":0},0,0,0,0,0,0,0,0]
["Water Rights",null,null,null,null,null,null,null,null,0,0]
["Effluent Licenses",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Licenses",null,null,null,null,null,null,null,null,0,0]
["Computer Software and Applications",null,0,0,0,0,0,0,0,0,0,0,0]
["Load Settlement Software Applications",null,null,null,null,null,null,null,null,0,0]
["Unspecified",null,0,0,0,0,0,0,0,0,0,0,0]
[]
["Computer Equipment",null,{"$f":"SUM(C152:C152)","v":61201556},61201556,0,0,0,0,0,0,61201556,47960853,50167052]
["Computer Equipment",null,61201556,61201556,0,0,0,0,0,0,61201556,47960853,50167052]
[]
["Furniture and Office Equipment",null,{"$f":"SUM(C155:C155)","v":56675929},56675929,0,0,0,0,0,0,56675929,47265806,49440032]
["Furniture and Office Equipment",null,56675929,56675929,0,0,0,0,0,0,56675929,47265806,49440032]
[]
["Machinery and Equipment",null,{"$f":"SUM(C158:C158)","v":865000},865000,0,0,0,0,0,0,865000,427683,447358]
["Machinery and Equipment",null,865000,865000,0,0,0,0,0,0,865000,427683,447358]
[]
["Transport Assets",null,{"$f":"SUM(C161:C161)","v":3458000},3458000,0,0,0,0,0,0,3458000,5250598,5492125]
["Transport Assets",null,3458000,3458000,0,0,0,0,0,0,3458000,5250598,5492125]
[]
["Land",null,{"$f":"SUM(C164:C164)","v":0},0,0,0,0,0,0,0,0,0,0]
["Land",null,null,null,null,null,null,null,null,0,0]
[]
["Zoo's, Marine and Non-biological Animals",null,{"$f":"SUM(C167:C167)","v":0},0,0,0,0,0,0,0,0,0,0]
["Zoo's, Marine and Non-biological Animals",null,null,null,null,null,null,null,null,0,0]
[]
["Total Depreciation to be adjusted",1,{"$f":"C8+C76+C105+C112+C120+C151+C138+C141+C154+C157+C160+C163+C166","v":154536733},{"$f":"D8+D76+D105+D112+D120+D151+D138+D141+D154+D157+D160+D163+D166","v":154536733},0,0,0,0,0,0,154536733,133503316,139644469]
[{"$f":"head27a","v":"References"}]
["1. Total Repairs and Maintenance Expenditure by Asset Category must reconcile to total repairs and maintenance expenditure on Table SB1"]
["7. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["8. Additional cash-backed accumulated funds/unspent funds (section 18(1)(b) and section 28(2)(e) MFMA) identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have for"]
["9. Increases of funds approved under section 31 MFMA"]
["10. Adjustments approved in accordance with section 29 MFMA"]
["11. Adjustments to funding allocations from National or Provincial Government"]
["12. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sec"]
["13. G = B + C + D + E + F"]
["14. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
[]
["check balance",null,{"$f":"C169-'B4-FinPerf RE'!C29","v":0},null,null,null,null,null,null,null,null,{"$f":"L169-'B4-FinPerf RE'!L29","v":0},{"$f":"M169-'B4-FinPerf RE'!M29","v":0}]

{"sheet":"SB18e","index":40,"n_rows":183,"n_cols":13,"rows_kept":183,"cut":false,"hidden":false,"merged":[[175,0,175,12],[177,0,177,12],[179,0,179,12],[1,0,3,0],[1,1,3,1],[1,2,1,10],[172,0,172,12],[173,0,173,9],[174,0,174,9]]}
[{"$f":"muni&\" - \"&ADJB18e&\" - \"&Date","v":"NW375 Moses Kotane - Adjustments Budget - capital expenditure on upgrading of existing assets by asset class - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,7,8,9,10,11,12,13,14]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Capital expenditure on upgrading of existing assets by Asset Class/Sub-class"]
[]
["Infrastructure",null,{"$f":"C9+C14+C18+C28+C70+C39+C46+C54+C64","v":56000000},{"$f":"D9+D14+D18+D28+D70+D39+D46+D54+D64","v":61188317},0,0,0,0,0,{"$f":"SUM(E8:I8)","v":0},{"$f":"IF(D8=0,C8+J8,D8+J8)","v":61188317},{"$f":"L9+L14+L18+L28+L70+L39+L46+L54+L64","v":60981783},{"$f":"M9+M14+M18+M28+M70+M39+M46+M54+M64","v":60000000}]
["Roads Infrastructure",null,{"$f":"SUM(C10:C13)","v":56000000},{"$f":"SUM(D10:D13)","v":61188317},0,0,0,0,0,{"$f":"SUM(E9:I9)","v":0},{"$f":"IF(D9=0,C9+J9,D9+J9)","v":61188317},60981783,60000000]
["Roads",null,56000000,61188317,0,0,0,0,0,0,61188317,60981783,60000000]
["Road Structures",null,null,null,null,null,null,null,null,0,0]
["Road Furniture",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Storm water Infrastructure",null,{"$f":"SUM(C15:C17)","v":0},0,0,0,0,0,0,0,0,{"$f":"SUM(L15:L17)","v":0},{"$f":"SUM(M15:M17)","v":0}]
["Drainage Collection",null,0,0,0,0,0,0,0,0,0,0,0]
["Storm water Conveyance",null,null,null,null,null,null,null,null,0,0]
["Attenuation",null,null,null,null,null,null,null,null,0,0]
["Electrical Infrastructure",null,{"$f":"SUM(C19:C27)","v":0},0,0,0,0,0,0,0,0,0,0]
["Power Plants",null,null,null,null,null,null,null,null,0,0]
["HV Substations",null,null,null,null,null,null,null,null,0,0]
["HV Switching Station",null,null,null,null,null,null,null,null,0,0]
["HV Transmission Conductors",null,null,null,null,null,null,null,null,0,0]
["MV Substations",null,null,null,null,null,null,null,null,0,0]
["MV Switching Stations",null,null,null,null,null,null,null,null,0,0]
["MV Networks",null,null,null,null,null,null,null,null,0,0]
["LV Networks",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Water Supply Infrastructure",null,{"$f":"SUM(C29:C38)","v":0},0,0,0,0,0,0,0,0,0,0]
["Dams and Weirs",null,null,null,null,null,null,null,null,0,0]
["Boreholes",null,null,null,null,null,null,null,null,0,0]
["Reservoirs",null,0,0,0,0,0,0,0,0,0,0,0]
["Pump Stations",null,null,null,null,null,null,null,null,0,0]
["Water Treatment Works",null,null,null,null,null,null,null,null,0,0]
["Bulk Mains",null,null,null,null,null,null,null,null,0,0]
["Distribution",null,null,null,null,null,null,null,null,0,0]
["Distribution Points",null,null,null,null,null,null,null,null,0,0]
["PRV Stations",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Sanitation Infrastructure",null,{"$f":"SUM(C40:C45)","v":0},{"$f":"SUM(D40:D45)","v":0},0,0,0,0,0,0,0,0,0]
["Pump Station",null,null,null,null,null,null,null,null,0,0]
["Reticulation",null,null,null,null,null,null,null,null,0,0]
["Waste Water Treatment Works",null,null,null,null,null,null,null,null,0,0]
["Outfall Sewers",null,null,null,null,null,null,null,null,0,0]
["Toilet Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Infrastructure",null,{"$f":"SUM(C47:C53)","v":0},{"$f":"SUM(D47:D53)","v":0},0,0,0,0,0,0,0,0,0]
["Landfill Sites",null,null,null,null,null,null,null,null,0,0]
["Waste Transfer Stations",null,null,null,null,null,null,null,null,0,0]
["Waste Processing Facilities",null,null,null,null,null,null,null,null,0,0]
["Waste Drop-off Points",null,null,null,null,null,null,null,null,0,0]
["Waste Separation Facilities",null,null,null,null,null,null,null,null,0,0]
["Electricity Generation Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Rail Infrastructure",null,{"$f":"SUM(C55:C63)","v":0},{"$f":"SUM(D55:D63)","v":0},0,0,0,0,0,0,0,0,0]
["Rail Lines",null,null,null,null,null,null,null,null,0,0]
["Rail Structures",null,null,null,null,null,null,null,null,0,0]
["Rail Furniture",null,null,null,null,null,null,null,null,0,0]
["Drainage Collection",null,null,null,null,null,null,null,null,0,0]
["Storm water Conveyance",null,null,null,null,null,null,null,null,0,0]
["Attenuation",null,null,null,null,null,null,null,null,0,0]
["MV Substations",null,null,null,null,null,null,null,null,0,0]
["LV Networks",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Coastal Infrastructure",null,{"$f":"SUM(C65:C69)","v":0},0,0,0,0,0,0,0,0,0,0]
["Sand Pumps",null,null,null,null,null,null,null,null,0,0]
["Piers",null,null,null,null,null,null,null,null,0,0]
["Revetments",null,null,null,null,null,null,null,null,0,0]
["Promenades",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Information and Communication Infrastructure",null,{"$f":"SUM(C71:C74)","v":0},0,0,0,0,0,0,0,0,0,0]
["Data Centres",null,null,null,null,null,null,null,null,0,0]
["Core Layers",null,null,null,null,null,null,null,null,0,0]
["Distribution Layers",null,null,null,null,null,null,null,null,{"$f":"SUM(E73:I73)","v":0},{"$f":"IF(D73=0,C73+J73,D73+J73)","v":0}]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Community Assets",null,{"$f":"+C77+C100","v":0},{"$f":"+D77+D100","v":0},{"$f":"+E77+E100","v":0},0,0,0,0,0,0,0,0]
["Community Facilities",null,{"$f":"SUM(C78:C99)","v":0},{"$f":"SUM(D78:D99)","v":0},{"$f":"SUM(E78:E99)","v":0},0,0,0,0,0,0,0,0]
["Halls",null,null,null,null,null,null,null,null,0,0]
["Centres",null,null,null,null,null,null,null,null,0,0]
["Crèches",null,null,null,null,null,null,null,null,0,0]
["Clinics/Care Centres",null,null,null,null,null,null,null,null,0,0]
["Fire/Ambulance Stations",null,null,null,null,null,null,null,null,0,0]
["Testing Stations",null,null,null,null,null,null,null,null,0,0]
["Museums",null,null,null,null,null,null,null,null,0,0]
["Galleries",null,null,null,null,null,null,null,null,0,0]
["Theatres",null,null,null,null,null,null,null,null,0,0]
["Libraries",null,null,null,null,null,null,null,null,0,0]
["Cemeteries/Crematoria",null,null,null,null,null,null,null,null,0,0]
["Police",null,null,null,null,null,null,null,null,0,0]
["Purls",null,null,null,null,null,null,null,null,0,0]
["Public Open Space",null,null,null,null,null,null,null,null,0,0]
["Nature Reserves",null,null,null,null,null,null,null,null,0,0]
["Public Ablution Facilities",null,null,null,null,null,null,null,null,0,0]
["Markets",null,null,null,null,null,null,null,null,0,0]
["Stalls",null,null,null,null,null,null,null,null,0,0]
["Abattoirs",null,null,null,null,null,null,null,null,0,0]
["Airports",null,null,null,null,null,null,null,null,0,0]
["Taxi Ranks/Bus Terminals",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Sport and Recreation Facilities",null,{"$f":"SUM(C101:C103)","v":0},{"$f":"SUM(D101:D103)","v":0},0,0,0,0,0,0,0,0,0]
["Indoor Facilities",null,null,null,null,null,null,null,null,0,0]
["Outdoor Facilities",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Heritage assets",null,{"$f":"SUM(C106:C110)","v":0},0,0,0,0,0,0,0,0,0,0]
["Monuments",null,null,null,null,null,null,null,null,0,0]
["Historic Buildings",null,null,null,null,null,null,null,null,0,0]
["Works of Art",null,null,null,null,null,null,null,null,0,0]
["Conservation Areas",null,null,null,null,null,null,null,null,0,0]
["Other Heritage",null,null,null,null,null,null,null,null,0,0]
[]
["Investment properties",null,{"$f":"+C113+C116","v":0},{"$f":"+D113+D116","v":0},0,0,0,0,0,0,0,{"$f":"+L113+L116","v":0},{"$f":"+M113+M116","v":0}]
["Revenue Generating",null,{"$f":"SUM(C114:C115)","v":0},{"$f":"SUM(D114:D115)","v":0},{"$f":"SUM(E114:E115)","v":0},0,0,0,0,0,0,0,0]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
["Non-revenue Generating",null,{"$f":"SUM(C117:C118)","v":0},{"$f":"SUM(D117:D118)","v":0},{"$f":"SUM(E117:E118)","v":0},0,0,0,0,0,0,0,0]
["Improved Property",null,null,null,null,null,null,null,null,0,0]
["Unimproved Property",null,null,null,null,null,null,null,null,0,0]
[]
["Other assets",null,{"$f":"+C121+C133","v":0},{"$f":"+D121+D133","v":0},0,0,0,0,0,0,0,{"$f":"+L121+L133","v":0},{"$f":"+M121+M133","v":0}]
["Operational Buildings",null,{"$f":"SUM(C122:C132)","v":0},{"$f":"SUM(D122:D132)","v":0},0,0,0,0,0,0,0,{"$f":"SUM(L122:L132)","v":0},{"$f":"SUM(M122:M132)","v":0}]
["Municipal Offices",null,null,null,null,null,null,null,null,0,0]
["Pay/Enquiry Points",null,null,null,null,null,null,null,null,0,0]
["Building Plan Offices",null,null,null,null,null,null,null,null,0,0]
["Workshops",null,null,null,null,null,null,null,null,0,0]
["Yards",null,null,null,null,null,null,null,null,0,0]
["Stores",null,null,null,null,null,null,null,null,0,0]
["Laboratories",null,null,null,null,null,null,null,null,0,0]
["Training Centres",null,null,null,null,null,null,null,null,0,0]
["Manufacturing Plant",null,null,null,null,null,null,null,null,0,0]
["Depots",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
["Housing",null,{"$f":"SUM(C134:C136)","v":0},{"$f":"SUM(D134:D136)","v":0},{"$f":"SUM(E134:E136)","v":0},0,0,0,0,0,0,0,0]
["Staff Housing",null,null,null,null,null,null,null,null,0,0]
["Social Housing",null,null,null,null,null,null,null,null,0,0]
["Capital Spares",null,null,null,null,null,null,null,null,0,0]
[]
["Biological or Cultivated Assets",null,{"$f":"SUM(C139:C139)","v":0},0,0,0,0,0,0,{"$f":"SUM(E138:I138)","v":0},{"$f":"IF(D138=0,C138+J138,D138+J138)","v":0},0,0]
["Biological or Cultivated Assets",null,null,null,null,null,null,null,null,0,0]
[]
["Intangible Assets",null,{"$f":"SUM(C142:C143)","v":0},{"$f":"SUM(D142:D143)","v":0},{"$f":"SUM(E142:E143)","v":0},0,0,0,0,0,0,0,0]
["Servitudes",null,null,null,null,null,null,null,null,0,0]
["Licences and Rights",null,{"$f":"SUM(C144:C149)","v":0},{"$f":"SUM(D144:D149)","v":0},{"$f":"SUM(E144:E149)","v":0},0,0,0,0,0,0,0,0]
["Water Rights",null,null,null,null,null,null,null,null,0,0]
["Effluent Licenses",null,null,null,null,null,null,null,null,0,0]
["Solid Waste Licenses",null,null,null,null,null,null,null,null,0,0]
["Computer Software and Applications",null,null,null,null,null,null,null,null,0,0]
["Load Settlement Software Applications",null,null,null,null,null,null,null,null,0,0]
["Unspecified",null,null,null,null,null,null,null,null,0,0]
[]
["Computer Equipment",null,{"$f":"SUM(C152:C152)","v":0},0,0,0,0,0,0,0,0,0,0]
["Computer Equipment",null,null,null,null,null,null,null,null,0,0]
[]
["Furniture and Office Equipment",null,{"$f":"SUM(C155:C155)","v":0},0,0,0,0,0,0,0,0,0,0]
["Furniture and Office Equipment",null,null,null,null,null,null,null,null,0,0]
[]
["Machinery and Equipment",null,{"$f":"SUM(C158:C158)","v":0},0,0,0,0,0,0,0,0,0,0]
["Machinery and Equipment",null,null,null,null,null,null,null,null,0,0]
[]
["Transport Assets",null,{"$f":"SUM(C161:C161)","v":0},0,0,0,0,0,0,0,0,0,0]
["Transport Assets",null,null,null,null,null,null,null,null,0,0]
[]
["Land",null,{"$f":"SUM(C164:C164)","v":0},0,0,0,0,0,0,0,0,0,0]
["Land",null,null,null,null,null,null,null,null,0,0]
[]
["Zoo's, Marine and Non-biological Animals",null,{"$f":"SUM(C167:C167)","v":0},0,0,0,0,0,0,0,0,0,0]
["Zoo's, Marine and Non-biological Animals",null,null,null,null,null,null,null,null,0,0]
[]
["Total Capital Expenditure on upgrading of existing assets to be adjusted",1,{"$f":"C8+C76+C105+C112+C120+C151+C138+C141+C154+C157+C160+C163+C166","v":56000000},{"$f":"D8+D76+D105+D112+D120+D151+D138+D141+D154+D157+D160+D163+D166","v":61188317},0,0,0,0,0,0,61188317,60981783,60000000]
[]
[{"$f":"head27a","v":"References"}]
["1. Total Capital Expenditure  on renewal of existing assets (SB18b) plus Total Capital Expenditure on new assets (SB18a) plus Total Capital Expenditure on upgrading of existing assets (SB18e) must reconcile to total capital expenditure in Budgeted Capital Expenditure"]
["7. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["8. Additional cash-backed accumulated funds/unspent funds (section 18(1)(b) and section 28(2)(e) MFMA) identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have for"]
["9. Increases of funds approved under section 31 MFMA"]
["10. Adjustments approved in accordance with section 29 MFMA"]
["11. Adjustments to funding allocations from National or Provincial Government"]
["12. Adjusts. = 'Other' Adjustments proposed to be approved; including revenue under-collection (MFMA section 28(2)(a)); additional revenue appropriation on existing programmes (section 28(2))(b); projected savings (section 28(2)(d)); error correction (sec"]
["13. G = B + C + D + E + F"]
["14. Adjusted Budget H = (A or A1/2 etc) + G"]
[]
[]
["check balance",null,{"$f":"(C169+SB18a!C169+SB18b!C169)-'B5-Capex'!C65","v":0},null,null,null,null,null,null,null,null,{"$f":"(L169+SB18a!L169+SB18b!L169)-'B5-Capex'!L65","v":0},{"$f":"(M169+SB18a!M169+SB18b!M169)-'B5-Capex'!M65","v":0}]

{"sheet":"SB19","index":41,"n_rows":152,"n_cols":18,"rows_kept":152,"cut":false,"hidden":false,"merged":[[1,12,1,17],[2,12,2,13],[2,14,2,15],[2,16,2,17]]}
[{"$f":"muni&\" - \"&ADJB19&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB19 List of capital programmes and projects affected by Adjustments Budget - 44171"}]
["Function","Project Description","Project Number","Type","MTSF Service Outcome","IUDF","Own Strategic Objectives","Asset Class","Asset Sub-Class ","Ward Location","GPS Longitude","GPS Lattitude",{"$f":"Head3a","v":"Medium Term Revenue and Expenditure Framework"}]
[null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"Head9","v":"Budget Year 2019/20"},null,{"$f":"Head10","v":"Budget Year +1 2020/21"},null,{"$f":"Head11","v":"Budget Year +2 2021/22"}]
["R thousands",null,null,null,null,null,null,null,null,null,null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head6","v":"Original Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head6","v":"Original Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
["Parent municipality:"]
["List all capital projects grouped by Function"]
["Finance And Administration","Capital:Infrastructure:New:Storm Water Infrastructure:Drainage Collection",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Storm Water Infrastructure","Drainage Collection","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Finance And Administration","Capital:Infrastructure:New:Storm Water Infrastructure:Drainage Collection",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Storm Water Infrastructure","Drainage Collection","R - ADMIN OR HEAD OFFICE",0,0,0,0,0,0,0,0]
["Finance And Administration","Astructure:Existing:Renewal:Intangible Assets:Licences And Rights:Computer Software And Applications",null,"RENEWAL","An efficient; effective and development-oriented public service","Governance",null,"Licences And Rights","Computer Software And Applications","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Finance And Administration","Astructure:Existing:Renewal:Intangible Assets:Licences And Rights:Computer Software And Applications",null,"RENEWAL","An efficient; effective and development-oriented public service","Governance",null,"Licences And Rights","Computer Software And Applications","R - ADMIN OR HEAD OFFICE",0,0,250000,0,0,0,0,0]
["Finance And Administration","Capital:Non-Infrastructure:New:Furniture And Office Equipment",null,"NEW","An efficient; effective and development-oriented public service","Growth",null,"Furniture And Office Equipment","Furniture And Office Equipment","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Finance And Administration","Capital:Non-Infrastructure:New:Furniture And Office Equipment",null,"NEW","An efficient; effective and development-oriented public service","Growth",null,"Furniture And Office Equipment","Furniture And Office Equipment","R - ADMIN OR HEAD OFFICE",0,0,300000,113975,0,0,0,0]
["Finance And Administration","Capital:Non-Infrastructure:New:Intangible Assets:Computer Software And Applications",null,"NEW","An efficient; effective and development-oriented public service","Growth",null,"Licences And Rights","Computer Software And Applications","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Finance And Administration","Capital:Non-Infrastructure:New:Machinery And Equipment",null,"NEW",null,"Growth",null,"Machinery And Equipment","Machinery And Equipment","R - ADMIN OR HEAD OFFICE",0,0,0,0,0,0,0,0]
["Finance And Administration","Capital:Non-Infrastructure:New:Machinery And Equipment",null,"NEW",null,"Growth",null,"Machinery And Equipment","Machinery And Equipment","R - WARD 27",0,0,100000,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 12",0,0,6000000,6258966,0,0,8000000,8000000]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 17",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 23",0,0,0,302338,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 24",0,0,0,1738343,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 25",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 28",0,0,0,4996000,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 29",0,0,0,566055,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 3",0,0,6000000,6244607,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 9",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Testing Stations",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Testing Stations","R - WARD 33",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Public Open Space",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Public Open Space","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Public Open Space",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Public Open Space","R - WHOLE OF MUNICIPALITY",0,0,0,0,0,0,0,0]
["Community And Social Services","L:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Taxi Ranks/Bus Terminals",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Taxi Ranks/Bus Terminals","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Other Assets:Operational Buildings:Municipal Offices",null,"RENEWAL","An efficient; effective and development-oriented public service","Governance",null,"Operational Buildings","Municipal Offices","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Other Assets:Operational Buildings:Stores",null,"RENEWAL","An efficient; effective and development-oriented public service","Governance",null,"Operational Buildings","Stores","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:Existing:Renewal:Other Assets:Operational Buildings:Stores",null,"RENEWAL","An efficient; effective and development-oriented public service","Governance",null,"Operational Buildings","Stores","R - ADMIN OR HEAD OFFICE",0,0,2590253,10620445,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:New:Furniture And Office Equipment",null,"NEW","An efficient; effective and development-oriented public service","Growth",null,"Furniture And Office Equipment","Furniture And Office Equipment","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:New:Furniture And Office Equipment",null,"NEW","An efficient; effective and development-oriented public service","Growth",null,"Furniture And Office Equipment","Furniture And Office Equipment","R - ADMIN OR HEAD OFFICE",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:New:Other Assets:Operational Buildings:Municipal Offices",null,"NEW","An efficient; effective and development-oriented public service","Growth",null,"Operational Buildings","Municipal Offices","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Community And Social Services","Capital:Non-Infrastructure:New:Other Assets:Operational Buildings:Municipal Offices",null,"NEW","An efficient; effective and development-oriented public service","Growth",null,"Operational Buildings","Municipal Offices","R - ADMIN OR HEAD OFFICE",0,0,0,0,0,0,0,0]
["Sport And Recreation","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","HEAD OFFICE",0,0,0,0,0,0,0,0]
["Sport And Recreation","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 12",0,0,0,0,9864475,9864475,0,0]
["Sport And Recreation","Capital:Non-Infrastructure:New:Machinery And Equipment",null,"NEW",null,"Growth",null,"Machinery And Equipment","Machinery And Equipment","R - ADMIN OR HEAD OFFICE",0,0,200000,0,0,0,0,0]
["Public Safety","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Testing Stations",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Testing Stations","R - ADMIN OR HEAD OFFICE",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 1",0,0,0,3736887,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 11",0,0,14000000,11412443,3478391,3478391,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 12",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 14",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 16",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 17",0,0,14000000,21225746,3478392,3478392,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 2",0,0,14000000,13615787,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 22",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 28",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 3",0,0,0,931357,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 30",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 32",0,0,14000000,10266097,54025000,54025000,60000000,60000000]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 4",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 5",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 6",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Roads Infrastructure:Roads",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Roads Infrastructure","Roads","R - WARD 9",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Storm Water Infrastructure:Drainage Collection",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Storm Water Infrastructure","Drainage Collection","R - WARD 14",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:Existing:Upgrading:Storm Water Infrastructure:Drainage Collection",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Storm Water Infrastructure","Drainage Collection","R - WARD 17",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:New:Roads Infrastructure:Roads",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Roads Infrastructure","Roads","R - WARD 5",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:New:Storm Water Infrastructure:Drainage Collection",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Storm Water Infrastructure","Drainage Collection","R - WARD 13",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:New:Storm Water Infrastructure:Drainage Collection",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Storm Water Infrastructure","Drainage Collection","R - WARD 2",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:New:Storm Water Infrastructure:Drainage Collection",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Storm Water Infrastructure","Drainage Collection","R - WARD 32",0,0,0,0,0,0,0,0]
["Road Transport","Capital:Infrastructure:New:Storm Water Infrastructure:Drainage Collection",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Storm Water Infrastructure","Drainage Collection","R - WARD 9",0,0,6193238,0,0,0,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 1",0,0,2142855,2475295,306225,306225,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 10",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 11",0,0,1714284,1351030,244980,244980,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 12",0,0,1714284,1688823,305225,305225,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 13",0,0,0,0,0,0,837158,837158]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 15",0,0,7015662,5103065,9067695,9067695,11720212,11720212]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 17",0,0,2999996,3593671,551205,551205,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 2",0,0,3016448,2957014,489960,489960,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 20",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 22",0,0,428571,0,0,0,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 28",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 32",0,0,0,864557,183735,183735,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 6",0,0,825711,942590,122490,122490,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WARD 9",0,0,2587877,1440928,306225,306225,0,0]
["Energy Sources","Capital:Infrastructure:New:Electrical Infrastructure:Lv Networks",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Electrical Infrastructure","Lv Networks","R - WHOLE OF MUNICIPALITY",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 1",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 15",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 2",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 23",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 24",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 26",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 3",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 30",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 32",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 6",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 8",0,0,0,0,0,0,0,0]
["Energy Sources","Capital:Non-Infrastructure:Existing:Renewal:Community Assets:Community Facilities:Halls",null,"RENEWAL","An efficient; effective and development-oriented public service","Inclusion and Access",null,"Community Facilities","Halls","R - WARD 9",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 1",0,0,0,6835940,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 12",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 2",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 22",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 23",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 27",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 3",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 4",0,0,0,4087653,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 6",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WARD 8",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Renewal:Water Supply Infrastructure:Boreholes",null,"RENEWAL","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Boreholes","R - WHOLE OF MUNICIPALITY",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:Existing:Upgrading:Water Supply Infrastructure:Reservoirs",null,"UPGRADING","An efficient; competitive and responsive economic infrastructure network","Inclusion and Access",null,"Water Supply Infrastructure","Reservoirs","R - ADMIN OR HEAD OFFICE",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Reservoirs",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Reservoirs","R - WARD 13",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Reservoirs",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Reservoirs","R - WARD 15",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Bulk Mains",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Bulk Mains","R - WARD 17",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Bulk Mains",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Bulk Mains","R - WARD 18",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Bulk Mains",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Bulk Mains","R - WARD 20",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 11",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 12",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 16",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 17",0,0,7314603,5029925,27789437,27789437,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 18",0,0,5500000,7367933,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 20",0,0,26524926,45592081,42019367,42019367,72263844,72263844]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 22",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 29",0,0,25475074,12367550,21375074,21375074,22000000,22000000]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 3",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 33",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 4",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 5",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 6",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WARD 8",0,0,0,0,0,0,0,0]
["Water Management","Capital:Infrastructure:New:Water Supply Infrastructure:Distribution",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Water Supply Infrastructure","Distribution","R - WHOLE OF MUNICIPALITY",0,0,0,0,0,0,0,0]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 1",0,0,0,0,0,0,0,0]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 17",0,0,0,0,0,0,4166667,4166667]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 2",0,0,21497052,10290253,23272953,23272953,8333332,8333332]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 22",0,0,0,0,0,0,4166667,4166667]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 24",0,0,2614404,0,2614404,2614404,4166667,4166667]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 26",0,0,0,0,0,0,4166667,4166667]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 3",0,0,0,2201983,0,0,0,0]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 34",0,0,0,0,0,0,0,0]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 5",0,0,0,0,0,0,0,0]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WARD 6",0,0,0,0,0,0,0,0]
["Waste Water Management","Capital:Infrastructure:New:Sanitation Infrastructure:Toilet Facilities",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Sanitation Infrastructure","Toilet Facilities","R - WHOLE OF MUNICIPALITY",0,0,0,0,0,0,0,0]
["Waste Management","Capital:Infrastructure:New:Solid Waste Infrastructure:Landfill Sites",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Solid Waste Infrastructure","Landfill Sites","R - WARD 15",0,0,0,0,0,0,0,0]
["Waste Management","Capital:Infrastructure:New:Solid Waste Infrastructure:Landfill Sites",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Solid Waste Infrastructure","Landfill Sites","R - WARD 19",0,0,15796909,0,3000000,3000000,19104155,19104155]
["Waste Management","Capital:Infrastructure:New:Solid Waste Infrastructure:Landfill Sites",null,"NEW","An efficient; competitive and responsive economic infrastructure network","Growth",null,"Solid Waste Infrastructure","Landfill Sites","R - WARD 23",0,0,0,0,0,0,0,0]
[]
["Entities:"]
["List all capital projects grouped by Municipal Entity"]
[]
["Entity Name"]
["Project name"]
[]
[]
[]
[]
["References"]
["List all projects where approved budgets have been adjusted"]
["Refer MFMA s30"]
["Asset class as per table B9 and asset sub-class as per table SB18"]
["GPS coordinates correct to seconds. Provide a logical starting point on networked infrastructure."]
["Distinguish projects approved in terms of MFMA section 19(1)(b) and MRRR Regulation 13"]
["Project Number consists of MSCOA Project Longcode and seq No (sample PC001002006002_00002)"]

{"sheet":"SB20","index":42,"n_rows":55,"n_cols":13,"rows_kept":55,"cut":false,"hidden":false,"merged":[[0,0,0,12],[1,0,3,0],[1,1,3,1],[1,2,1,10],[52,0,52,12],[48,0,48,12],[49,0,49,12],[46,0,46,12],[47,0,47,12]]}
[{"$f":"muni&\" - \"&ADJB20&\" - \"&Date","v":"NW375 Moses Kotane - Supporting Table SB20 Not required - 44171"}]
[{"$f":"desc","v":"Description"},{"$f":"head27","v":"Ref"},{"$f":"Head2","v":"Budget Year 2019/20"},null,null,null,null,null,null,null,null,{"$f":"Head10","v":"Budget Year +1 2020/21"},{"$f":"Head11","v":"Budget Year +2 2021/22"}]
[null,null,{"$f":"Head6","v":"Original Budget"},{"$f":"Head54","v":"Prior Adjusted"},{"$f":"Head51","v":"Accum. Funds"},{"$f":"Head52","v":"Multi-year capital"},{"$f":"Head53","v":"Unfore. Unavoid."},{"$f":"Head55","v":"Nat. or Prov. Govt"},{"$f":"Head50","v":"Other Adjusts."},{"$f":"Head56","v":"Total Adjusts."},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"},{"$f":"Head7","v":"Adjusted Budget"}]
[null,null,null,3,4,5,6,8,9,10,11]
["R thousands",null,"A","A1","B","C","D","E","F","G","H"]
["Revenue By Municipal Entity"]
["Entity 1 total revenue",null,null,null,null,null,null,null,null,{"$f":"SUM(E7:I7)","v":0},{"$f":"IF(D7=0,C7+J7,D7+J7)","v":0}]
["Entity 2 total revenue",null,null,null,null,null,null,null,null,0,0]
["Entity 3 (etc) total revenue",null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
["Total Operating Revenue",1,{"$f":"SUM(C7:C16)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Expenditure By Municipal Entity"]
["Entity 1 total operating expenditure",null,null,null,null,null,null,null,null,{"$f":"SUM(E20:I20)","v":0},{"$f":"IF(D20=0,C20+J20,D20+J20)","v":0}]
["Entity 2 total operating expenditure",null,null,null,null,null,null,null,null,0,0]
["Entity 3 etc. total operating expenditure",null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
["Total Operating Expenditure",2,{"$f":"SUM(C20:C29)","v":0},0,0,0,0,0,0,0,0,0,0]
[]
["Capital Expenditure By Municipal Entity"]
["Entity 1 total capital expenditure",null,null,null,null,null,null,null,null,{"$f":"SUM(E33:I33)","v":0},{"$f":"IF(D33=0,C33+J33,D33+J33)","v":0}]
["Entity 2 total capital expenditure",null,null,null,null,null,null,null,null,0,0]
["Entity 3 etc. total capital expenditure",null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
[null,null,null,null,null,null,null,null,null,0,0]
["Total Capital Expenditure",2,{"$f":"SUM(C32:C42)","v":0},0,0,0,0,0,0,0,0,0,0]
[{"$f":"head27a","v":"References"}]
["1. Must reconcile to the sum of all municipal entity monthly revenue reports"]
["2. Must reconcile to the sum of all municipal entity monthly expenditure reports"]
["3. Only complete if a previous adjusted budget has been approved in the same financial year. Reflect most recent adjusted budget."]
["4. Additional cash-backed accumulated funds/unspent funds identified after Original Budget approved and after annual financial statements audited (note: only where underspending could not reasonably be have foreseen)"]
["5. Increases of funds approved under section 87 MFMA"]
["6. Adjustments approved in accordance with section 87 MFMA"]
["7. Adjustments made under delegation by the AO since the budget was approved or since a previously 'approved' Adjustments Budget in the same financial year"]
["8. Adjustments to funding allocations by National or Provincial Government"]
["9. Adjusts. = 'Other' Adjustments approved by entity Board; including revenue under-collection ; additional revenue appropriation on existing programmes; projected savings; error correction"]
["10. H = B + C + D + E + F + G"]
["11. Adjusted Budget (I) = (A or A1/2 etc) + H"]